{"id":100653,"date":"2022-03-17T16:36:02","date_gmt":"2022-03-17T19:36:02","guid":{"rendered":"https:\/\/folhapopular.info\/?p=100653"},"modified":"2022-03-18T05:52:33","modified_gmt":"2022-03-18T08:52:33","slug":"amador-de-estrela-tem-complemento-da-jornada-de-estreia","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/","title":{"rendered":"<strong>Amador de Estrela tem complemento da jornada de estreia<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ap\u00f3s a estreia no \u00faltimo final de semana, o Campeonato Municipal de Futebol Amador de Estrela ter\u00e1, neste domingo (20\/3), o complemento da sua primeira rodada. A competi\u00e7\u00e3o, que volta a movimentar comunidades, torcededores e atletas locais ap\u00f3s uma d\u00e9cada, registrar\u00e1 as duas partidas que fechar\u00e3o a jornada inicial da promo\u00e7\u00e3o do Governo de Estrela atrav\u00e9s da Secretaria Municipal de Turismo, Cultura, Esporte e Lazer (Setcel). E ser\u00e3o dez rodadas e 34 partidas at\u00e9 se conhecer o melhor entre os oito times participantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O domingo marcar\u00e1 a estreia dos outros quatro elencos da disputa, que ao todo movimenta mais de 240 jogadores. No campo do XV de Novembro da Linha Lenz, jogar\u00e3o a partir das 13h30 os times do Gavi\u00f5es do BI\/Marmitt e da Delfinense. No mesmo local, mas a partir das 15h30, se confrontar\u00e3o Atl\u00e9tico Estrelense x Geraldense. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No \u00faltimo domingo, na abertura do certame, realizada na sede do Alto da Bronze, as equipes do Atl\u00e2ntico ficaram no empate em 1 a 1 no cl\u00e1ssico da comunidade de Cost\u00e3o. Em seguida, o anfitri\u00e3o Alto da Bronze e \u00faltimo campe\u00e3o acabou derrotado por 2 a 1 pelo Aimor\u00e9, que assim j\u00e1 lidera o campeonato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrada franca para todos os confrontos. A partir da segunda rodada, dia 27, os quatro jogos ocorrer\u00e3o aos domingos, dois por sede, nos hor\u00e1rios padr\u00f5es. A arbitragem ficar\u00e1 por conta da Associa\u00e7\u00e3o Regional de \u00c1rbitros (ARA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Equipes<\/strong><br>Participam as equipes do Gr\u00eamio Esportivo Atl\u00e2ntico de Cost\u00e3o A; Gr\u00eamio Esportivo Atl\u00e2ntico de Cost\u00e3o B; Sociedade Cultural Esportiva Delfinense; Gr\u00eamio Esportivo Geraldense; Sociedade Esportiva Alto da Bronze; Sociedade Esportiva e Recreativa Aimor\u00e9 da Delfina; Atl\u00e9tico Estrelense (Bairro Marmitt\/Moinhos); Gavi\u00f5es do B.I (Bairro das Ind\u00fastrias).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>F\u00f3rmula de disputa<\/strong><br>O sistema do campeonato prev\u00ea jogos de todos contra todos em turno \u00fanico. Ap\u00f3s os primeiros 28 confrontos se classificar\u00e3o para a segunda fase os seis melhores, sendo que os dois melhores j\u00e1 estar\u00e3o automaticamente classificados para as semifinais. Os seus advers\u00e1rios sair\u00e3o dos confrontos entre os quatro demais: 3\u00b0x 6\u00ba; 4\u00ba x 5\u00ba. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nas semifinais e decis\u00e3o (na casa de equipe de melhor disciplina entre os finalistas), tamb\u00e9m partidas somente de ida. Nos crit\u00e9rios de desempate, em sequ\u00eancia, n\u00famero de vit\u00f3rias, disciplina, saldo de gols, gols \u00e0 favor, gols contra e sorteio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e3o premiados os quatro primeiros colocados, sendo os tr\u00eas primeiros com trof\u00e9us e medalhas. Outras premia\u00e7\u00f5es ainda s\u00e3o estudadas junto a apoiadores. Tamb\u00e9m ser\u00e3o premiados o campe\u00e3o da disciplina, artilheiro, goleiro e atleta destaque, al\u00e9m de jogador revela\u00e7\u00e3o. E a cada jornada ser\u00e1 eleito o craque da rodada por campo sede \u2013 melhor das duas partidas do respectivo local de jogos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1\u00aa Rodada<\/strong><br>Dia 13<br><br><strong>Alto da Bronze<br><\/strong>Atl\u00e2ntico A 1&#215;1 Atl\u00e2ntico B<br>Alto da Bronze 1&#215;2 Aimor\u00e9<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dia 20<br><strong>Linha Lenz<br><\/strong>13h30min \u2013 Gavi\u00f5es do BI\/Marmitt x Delfinense<br>15h30min \u2013 Atl\u00e9tico Estrelense x Geraldense<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2\u00aa Rodada<\/strong><br>Dia 27<br><strong>Ambi<\/strong><br>13h30min \u2013 Atl\u00e2ntico de Cost\u00e3o A x Alto da Bronze<br>15h30min \u2013 Gavi\u00f5es do BI x Aimor\u00e9 da Delfina<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Geraldense<\/strong><br>13h30min \u2013 Atl\u00e9tico Estrelense x Atl\u00e2ntico de Cost\u00e3o B<br>15h30min \u2013 Geraldense x Atl\u00e2ntico de Cost\u00e3o B<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a estreia no \u00faltimo final de semana, o Campeonato Municipal de Futebol Amador de Estrela ter\u00e1, neste domingo (20\/3), o complemento da sua primeira rodada. A competi\u00e7\u00e3o, que volta a movimentar comunidades, torcededores e atletas locais ap\u00f3s uma d\u00e9cada, registrar\u00e1 as duas partidas que fechar\u00e3o a jornada inicial da promo\u00e7\u00e3o do Governo de Estrela [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":100654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,5,240],"tags":[8187,7572,8,5063],"class_list":["post-100653","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-esportes","category-futebol-amador","tag-amador","tag-estreia","tag-estrela","tag-jogos","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amador de Estrela tem complemento da jornada de estreia - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amador de Estrela tem complemento da jornada de estreia - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Ap\u00f3s a estreia no \u00faltimo final de semana, o Campeonato Municipal de Futebol Amador de Estrela ter\u00e1, neste domingo (20\/3), o complemento da sua primeira rodada. A competi\u00e7\u00e3o, que volta a movimentar comunidades, torcededores e atletas locais ap\u00f3s uma d\u00e9cada, registrar\u00e1 as duas partidas que fechar\u00e3o a jornada inicial da promo\u00e7\u00e3o do Governo de Estrela [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-17T19:36:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-18T08:52:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Amador de Estrela tem complemento da jornada de estreia\",\"datePublished\":\"2022-03-17T19:36:02+00:00\",\"dateModified\":\"2022-03-18T08:52:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/\"},\"wordCount\":567,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg\",\"keywords\":[\"Amador\",\"Estreia\",\"Estrela\",\"jogos\"],\"articleSection\":[\"Destaques\",\"Esportes\",\"Futebol Amador\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/\",\"name\":\"Amador de Estrela tem complemento da jornada de estreia - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg\",\"datePublished\":\"2022-03-17T19:36:02+00:00\",\"dateModified\":\"2022-03-18T08:52:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg\",\"width\":800,\"height\":535,\"caption\":\"Disputa movimentar\u00e1 mais de 240 atletas por dez rodadas \\\/ Cr\u00e9dito: Pablo Reis \\\/ Governo de Estrela\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/17\\\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amador de Estrela tem complemento da jornada de estreia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amador de Estrela tem complemento da jornada de estreia - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/","og_locale":"pt_BR","og_type":"article","og_title":"Amador de Estrela tem complemento da jornada de estreia - Folha Popular","og_description":"Ap\u00f3s a estreia no \u00faltimo final de semana, o Campeonato Municipal de Futebol Amador de Estrela ter\u00e1, neste domingo (20\/3), o complemento da sua primeira rodada. A competi\u00e7\u00e3o, que volta a movimentar comunidades, torcededores e atletas locais ap\u00f3s uma d\u00e9cada, registrar\u00e1 as duas partidas que fechar\u00e3o a jornada inicial da promo\u00e7\u00e3o do Governo de Estrela [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/","og_site_name":"Folha Popular","article_published_time":"2022-03-17T19:36:02+00:00","article_modified_time":"2022-03-18T08:52:33+00:00","og_image":[{"width":800,"height":535,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Amador de Estrela tem complemento da jornada de estreia","datePublished":"2022-03-17T19:36:02+00:00","dateModified":"2022-03-18T08:52:33+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/"},"wordCount":567,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg","keywords":["Amador","Estreia","Estrela","jogos"],"articleSection":["Destaques","Esportes","Futebol Amador"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/","name":"Amador de Estrela tem complemento da jornada de estreia - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg","datePublished":"2022-03-17T19:36:02+00:00","dateModified":"2022-03-18T08:52:33+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg","width":800,"height":535,"caption":"Disputa movimentar\u00e1 mais de 240 atletas por dez rodadas \/ Cr\u00e9dito: Pablo Reis \/ Governo de Estrela"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/17\/amador-de-estrela-tem-complemento-da-jornada-de-estreia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Amador de Estrela tem complemento da jornada de estreia"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Amador-de-Estrela-RODADA-1-abertura-Pablo-Reis-8-e1647545754410.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/100653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=100653"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/100653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/100654"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=100653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=100653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=100653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}