{"id":101290,"date":"2022-03-28T14:40:33","date_gmt":"2022-03-28T17:40:33","guid":{"rendered":"https:\/\/folhapopular.info\/?p=101290"},"modified":"2022-03-28T14:40:40","modified_gmt":"2022-03-28T17:40:40","slug":"avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/","title":{"rendered":"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei"},"content":{"rendered":"\n<p>A equipe infantojuvenil da Avates participou da Copa RS Adulto Feminino de V\u00f4lei que ocorreu no domingo (27\/3) no Gin\u00e1sio Ito Snel em Estrela. O time saiu de l\u00e1 como vice-campe\u00e3o. <\/p>\n\n\n\n<p>Al\u00e9m da Avates outras cinco equipes vindas de Lajeado, Teut\u00f4nia, Porto Alegre, Santa Maria e Passo Fundo tamb\u00e9m participaram dos jogos. As atletas da Avates disputaram a semifinal com a equipe de Sogipa (POA) e venceram por dois sets a zero. Por\u00e9m na disputada contra a equipe\u00a0BSBios\/UPF, de Passo Fundo, a Avates perdeu por dois sets a\u00a0zero.<\/p>\n\n\n\n<p>O\u00a0t\u00e9cnico da equipe infantojuvenil, Estanislao Vachino (Vacho), classificou como muito bom o desempenho da equipe.\u00a0&#8220;Chegamos \u00e0 semifinal ganhando todos os jogos. Este foi o primeiro campeonato do ano e ficamos muito felizes pelo desempenho das meninas. Temos muito trabalho pela frente, mas deu para perceber que estamos no caminho certo\u201d, destacou Vacho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A equipe infantojuvenil da Avates participou da Copa RS Adulto Feminino de V\u00f4lei que ocorreu no domingo (27\/3) no Gin\u00e1sio Ito Snel em Estrela. O time saiu de l\u00e1 como vice-campe\u00e3o. Al\u00e9m da Avates outras cinco equipes vindas de Lajeado, Teut\u00f4nia, Porto Alegre, Santa Maria e Passo Fundo tamb\u00e9m participaram dos jogos. As atletas da [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":101292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,5],"tags":[2144,5210,8,5063,398],"class_list":{"0":"post-101290","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-esportes","9":"tag-avates","10":"tag-copa-rs","11":"tag-estrela","12":"tag-jogos","13":"tag-volei","14":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A equipe infantojuvenil da Avates participou da Copa RS Adulto Feminino de V\u00f4lei que ocorreu no domingo (27\/3) no Gin\u00e1sio Ito Snel em Estrela. O time saiu de l\u00e1 como vice-campe\u00e3o. Al\u00e9m da Avates outras cinco equipes vindas de Lajeado, Teut\u00f4nia, Porto Alegre, Santa Maria e Passo Fundo tamb\u00e9m participaram dos jogos. As atletas da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-28T17:40:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-28T17:40:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Equipe-Infantojuvenil-e1648488732151.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei\",\"datePublished\":\"2022-03-28T17:40:33+00:00\",\"dateModified\":\"2022-03-28T17:40:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/\"},\"wordCount\":164,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Equipe-Infantojuvenil-e1648488732151.jpeg\",\"keywords\":[\"Avates\",\"Copa RS\",\"Estrela\",\"jogos\",\"V\u00f4lei\"],\"articleSection\":[\"Destaques\",\"Esportes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/\",\"name\":\"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Equipe-Infantojuvenil-e1648488732151.jpeg\",\"datePublished\":\"2022-03-28T17:40:33+00:00\",\"dateModified\":\"2022-03-28T17:40:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Equipe-Infantojuvenil-e1648488732151.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Equipe-Infantojuvenil-e1648488732151.jpeg\",\"width\":800,\"height\":600,\"caption\":\"Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/03\\\/28\\\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/","og_locale":"pt_BR","og_type":"article","og_title":"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei - Folha Popular","og_description":"A equipe infantojuvenil da Avates participou da Copa RS Adulto Feminino de V\u00f4lei que ocorreu no domingo (27\/3) no Gin\u00e1sio Ito Snel em Estrela. O time saiu de l\u00e1 como vice-campe\u00e3o. Al\u00e9m da Avates outras cinco equipes vindas de Lajeado, Teut\u00f4nia, Porto Alegre, Santa Maria e Passo Fundo tamb\u00e9m participaram dos jogos. As atletas da [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/","og_site_name":"Folha Popular","article_published_time":"2022-03-28T17:40:33+00:00","article_modified_time":"2022-03-28T17:40:40+00:00","og_image":[{"width":800,"height":600,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Equipe-Infantojuvenil-e1648488732151.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei","datePublished":"2022-03-28T17:40:33+00:00","dateModified":"2022-03-28T17:40:40+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/"},"wordCount":164,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Equipe-Infantojuvenil-e1648488732151.jpeg","keywords":["Avates","Copa RS","Estrela","jogos","V\u00f4lei"],"articleSection":["Destaques","Esportes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/","name":"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Equipe-Infantojuvenil-e1648488732151.jpeg","datePublished":"2022-03-28T17:40:33+00:00","dateModified":"2022-03-28T17:40:40+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Equipe-Infantojuvenil-e1648488732151.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Equipe-Infantojuvenil-e1648488732151.jpeg","width":800,"height":600,"caption":"Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/03\/28\/avates-fica-em-segundo-lugar-na-copa-rs-adulto-feminino-de-volei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Avates fica em segundo lugar na Copa RS Adulto Feminino de V\u00f4lei"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/03\/Equipe-Infantojuvenil-e1648488732151.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/101290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=101290"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/101290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/101292"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=101290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=101290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=101290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}