{"id":101917,"date":"2022-04-08T11:49:56","date_gmt":"2022-04-08T14:49:56","guid":{"rendered":"https:\/\/folhapopular.info\/?p=101917"},"modified":"2022-04-08T11:50:00","modified_gmt":"2022-04-08T14:50:00","slug":"cic-teutonia-participa-do-gramado-summit","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/","title":{"rendered":"CIC Teut\u00f4nia participa do Gramado Summit"},"content":{"rendered":"\n<p>A C\u00e2mara de Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (CIC) de Teut\u00f4nia marcou presen\u00e7a, de 6 a 8 de abril, no Gramado Summit, reconhecido como o maior evento de <em>brainstorming<\/em> da Am\u00e9rica Latina. O evento se baseia em tr\u00eas pilares: disrup\u00e7\u00e3o, inova\u00e7\u00e3o e resili\u00eancia.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o intensa de tr\u00eas dias contou com mais de 140 palestrantes em quatro palcos simult\u00e2neos, al\u00e9m de uma feira de inova\u00e7\u00e3o com mais de 100 expositores, e com a participa\u00e7\u00e3o de mais de 6 mil pessoas.<\/p>\n\n\n\n<p>A entidade acompanhou o evento com a presen\u00e7a do presidente, Airton Kist, do vice-presidente do com\u00e9rcio, Samuel Eduardo Maders e de tr\u00eas funcion\u00e1rios, Alexander Bl\u00f6mker, Carina Schulte Bolfe e Elaine Wegner.<\/p>\n\n\n\n<p>A participa\u00e7\u00e3o teve por objetivo identificar novas iniciativas, palestrantes e inova\u00e7\u00f5es em eventos que podem ser trazidas para a entidade, o que tem de novo no mercado de inova\u00e7\u00e3o e tecnologia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara de Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (CIC) de Teut\u00f4nia marcou presen\u00e7a, de 6 a 8 de abril, no Gramado Summit, reconhecido como o maior evento de brainstorming da Am\u00e9rica Latina. O evento se baseia em tr\u00eas pilares: disrup\u00e7\u00e3o, inova\u00e7\u00e3o e resili\u00eancia. A programa\u00e7\u00e3o intensa de tr\u00eas dias contou com mais de 140 palestrantes em [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":101918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[178,8619,26],"class_list":{"0":"post-101917","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-geral","9":"tag-cic-teutonia","10":"tag-gramado-summit","11":"tag-teutonia","12":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CIC Teut\u00f4nia participa do Gramado Summit - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIC Teut\u00f4nia participa do Gramado Summit - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A C\u00e2mara de Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (CIC) de Teut\u00f4nia marcou presen\u00e7a, de 6 a 8 de abril, no Gramado Summit, reconhecido como o maior evento de brainstorming da Am\u00e9rica Latina. O evento se baseia em tr\u00eas pilares: disrup\u00e7\u00e3o, inova\u00e7\u00e3o e resili\u00eancia. A programa\u00e7\u00e3o intensa de tr\u00eas dias contou com mais de 140 palestrantes em [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-08T14:49:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-08T14:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"884\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"CIC Teut\u00f4nia participa do Gramado Summit\",\"datePublished\":\"2022-04-08T14:49:56+00:00\",\"dateModified\":\"2022-04-08T14:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/\"},\"wordCount\":168,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg\",\"keywords\":[\"CIC Teut\u00f4nia\",\"Gramado Summit\",\"Teut\u00f4nia\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/\",\"name\":\"CIC Teut\u00f4nia participa do Gramado Summit - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg\",\"datePublished\":\"2022-04-08T14:49:56+00:00\",\"dateModified\":\"2022-04-08T14:50:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg\",\"width\":800,\"height\":884,\"caption\":\"Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/04\\\/08\\\/cic-teutonia-participa-do-gramado-summit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CIC Teut\u00f4nia participa do Gramado Summit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CIC Teut\u00f4nia participa do Gramado Summit - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/","og_locale":"pt_BR","og_type":"article","og_title":"CIC Teut\u00f4nia participa do Gramado Summit - Folha Popular","og_description":"A C\u00e2mara de Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (CIC) de Teut\u00f4nia marcou presen\u00e7a, de 6 a 8 de abril, no Gramado Summit, reconhecido como o maior evento de brainstorming da Am\u00e9rica Latina. O evento se baseia em tr\u00eas pilares: disrup\u00e7\u00e3o, inova\u00e7\u00e3o e resili\u00eancia. A programa\u00e7\u00e3o intensa de tr\u00eas dias contou com mais de 140 palestrantes em [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/","og_site_name":"Folha Popular","article_published_time":"2022-04-08T14:49:56+00:00","article_modified_time":"2022-04-08T14:50:00+00:00","og_image":[{"width":800,"height":884,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"CIC Teut\u00f4nia participa do Gramado Summit","datePublished":"2022-04-08T14:49:56+00:00","dateModified":"2022-04-08T14:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/"},"wordCount":168,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg","keywords":["CIC Teut\u00f4nia","Gramado Summit","Teut\u00f4nia"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/","name":"CIC Teut\u00f4nia participa do Gramado Summit - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg","datePublished":"2022-04-08T14:49:56+00:00","dateModified":"2022-04-08T14:50:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg","width":800,"height":884,"caption":"Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/04\/08\/cic-teutonia-participa-do-gramado-summit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"CIC Teut\u00f4nia participa do Gramado Summit"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.32.30-1-e1649429315115.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/101917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=101917"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/101917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/101918"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=101917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=101917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=101917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}