{"id":108913,"date":"2022-07-18T17:09:32","date_gmt":"2022-07-18T20:09:32","guid":{"rendered":"https:\/\/folhapopular.info\/?p=108913"},"modified":"2022-07-18T17:09:37","modified_gmt":"2022-07-18T20:09:37","slug":"feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/","title":{"rendered":"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nos dias 14 e 15 de julho o Munic\u00edpio de Po\u00e7o das Antas promoveu a <a href=\"https:\/\/folhapopular.info\/index.php\/2022\/07\/01\/feira-do-livro-de-poco-das-antas-acontece-nos-dias-14-e-15-de-julho\/\">Feira do Livro<\/a>. A programa\u00e7\u00e3o, concentrada a maior parte do tempo na Sascpa, contou com diversas atra\u00e7\u00f5es especiais, tanto para a comunidade escolar, quanto para o p\u00fablico em geral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na noite de quinta-feira (14\/7) a programa\u00e7\u00e3o iniciou com abertura solene na Sascpa com a presen\u00e7a de autoridades do Executivo, Legislativo, secretarias municipais e escolas. A secret\u00e1ria da Educa\u00e7\u00e3o, Cultura, Desporto e Turismo, Jaqueline Klein, e a prefeita de Po\u00e7o das Antas, V\u00e2nia Brackmann, deixaram sua sauda\u00e7\u00e3o. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na sequ\u00eancia, a Banda Rosa\u2019s apresentou a Palestra Show \u201cMelodia das Palavras\u201d, com participa\u00e7\u00e3o especial de Dirce Becker Delwing e Ivete Kist. Dirce \u00e9 escritora, psicoterapeuta e jornalista, enquanto Ivete \u00e9 doutora em letras, professora e escritora. Todos juntos proporcionaram uma mescla de m\u00fasica e provoca\u00e7\u00f5es sobre a escrita e leitura, com inspira\u00e7\u00f5es importantes para o desenvolvimento desses h\u00e1bitos entre as fam\u00edlias.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 na sexta-feira (15\/7), a programa\u00e7\u00e3o teve como foco as escolas, que ap\u00f3s o momento c\u00edvico, prestigiaram apresenta\u00e7\u00f5es das turmas do Ensino Fundamental, realizadas de acordo com os turnos de aula das escolas. Livros de autoria do escritor Eliandro Rocha foram inspira\u00e7\u00e3o e autor esteve presente nas duas oportunidades para conversar com os estudantes. <\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, as crian\u00e7as e jovens tiveram um momento de conta\u00e7\u00e3o de hist\u00f3ria e intera\u00e7\u00e3o com o Elefante Letrado e seu mascote, o Senhor Elefante, que fez a alegria da crian\u00e7ada. Os alunos da Escola Estadual de Ensino M\u00e9dio (EEEM) Po\u00e7o das Antas tamb\u00e9m foram contemplados na programa\u00e7\u00e3o da feira. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 tarde, no audit\u00f3rio da Prefeitura os alunos do Ensino Fundamental assistiram a Pe\u00e7a Teatral \u201cCidade das Cores\u201d, de Marcos Cardoso Produ\u00e7\u00f5es e a noite o Ensino M\u00e9dio participou de uma gincana de integra\u00e7\u00e3o no gin\u00e1sio da escola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m da programa\u00e7\u00e3o especial, a feira tamb\u00e9m teve outros atrativos concentrados durante os dois dias de programa\u00e7\u00e3o, que foram visitados pelos alunos e tamb\u00e9m pela comunidade, como a exposi\u00e7\u00e3o fotogr\u00e1fica &#8220;Fios d&#8217;alma&#8221; de Tatiane Ertel e vendas de livros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos dias 14 e 15 de julho o Munic\u00edpio de Po\u00e7o das Antas promoveu a Feira do Livro. A programa\u00e7\u00e3o, concentrada a maior parte do tempo na Sascpa, contou com diversas atra\u00e7\u00f5es especiais, tanto para a comunidade escolar, quanto para o p\u00fablico em geral. Na noite de quinta-feira (14\/7) a programa\u00e7\u00e3o iniciou com abertura solene [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":108922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[5155,5366,344,322,40],"class_list":["post-108913","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-alunos","tag-comunidade","tag-cultura","tag-feira-do-livro","tag-poco-das-antas","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Nos dias 14 e 15 de julho o Munic\u00edpio de Po\u00e7o das Antas promoveu a Feira do Livro. A programa\u00e7\u00e3o, concentrada a maior parte do tempo na Sascpa, contou com diversas atra\u00e7\u00f5es especiais, tanto para a comunidade escolar, quanto para o p\u00fablico em geral. Na noite de quinta-feira (14\/7) a programa\u00e7\u00e3o iniciou com abertura solene [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-18T20:09:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-18T20:09:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/07\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o\",\"datePublished\":\"2022-07-18T20:09:32+00:00\",\"dateModified\":\"2022-07-18T20:09:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/\"},\"wordCount\":391,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg\",\"keywords\":[\"alunos\",\"Comunidade\",\"Cultura\",\"Feira do Livro\",\"Po\u00e7o das Antas\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/\",\"name\":\"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg\",\"datePublished\":\"2022-07-18T20:09:32+00:00\",\"dateModified\":\"2022-07-18T20:09:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg\",\"width\":1200,\"height\":800,\"caption\":\"A Livraria Wessel compareceu com diversos t\u00edtulos de livros \\\/ Cr\u00e9dito: Assessoria de Comunica\u00e7\u00e3o (ASCOM) de Po\u00e7o das Antas \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/07\\\/18\\\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/","og_locale":"pt_BR","og_type":"article","og_title":"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o - Folha Popular","og_description":"Nos dias 14 e 15 de julho o Munic\u00edpio de Po\u00e7o das Antas promoveu a Feira do Livro. A programa\u00e7\u00e3o, concentrada a maior parte do tempo na Sascpa, contou com diversas atra\u00e7\u00f5es especiais, tanto para a comunidade escolar, quanto para o p\u00fablico em geral. Na noite de quinta-feira (14\/7) a programa\u00e7\u00e3o iniciou com abertura solene [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/","og_site_name":"Folha Popular","article_published_time":"2022-07-18T20:09:32+00:00","article_modified_time":"2022-07-18T20:09:37+00:00","og_image":[{"width":1200,"height":800,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/07\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o","datePublished":"2022-07-18T20:09:32+00:00","dateModified":"2022-07-18T20:09:37+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/"},"wordCount":391,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/07\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg","keywords":["alunos","Comunidade","Cultura","Feira do Livro","Po\u00e7o das Antas"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/","name":"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/07\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg","datePublished":"2022-07-18T20:09:32+00:00","dateModified":"2022-07-18T20:09:37+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/07\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/07\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg","width":1200,"height":800,"caption":"A Livraria Wessel compareceu com diversos t\u00edtulos de livros \/ Cr\u00e9dito: Assessoria de Comunica\u00e7\u00e3o (ASCOM) de Po\u00e7o das Antas \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/07\/18\/feira-do-livro-de-poco-das-antas-proporciona-momentos-de-conhecimento-e-inspiracao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Feira do Livro de Po\u00e7o das Antas proporciona momentos de conhecimento e inspira\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/07\/8-Feira-do-Livro-proporciona-momentos-de-conhecimento-e-inspiracao-scaled-e1658173478348.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/108913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=108913"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/108913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/108922"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=108913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=108913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=108913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}