{"id":110389,"date":"2022-08-10T10:48:17","date_gmt":"2022-08-10T13:48:17","guid":{"rendered":"https:\/\/folhapopular.info\/?p=110389"},"modified":"2022-08-10T10:48:28","modified_gmt":"2022-08-10T13:48:28","slug":"brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/","title":{"rendered":"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quatro homens (25, 39, 40 e 25) e uma mulher (19) foram presos pelos crimes de contrabando e descaminho nessa ter\u00e7a-feira (9\/8), em Anta Gorda. Policiais militares realizaram abordagem de um caminh\u00e3o que carregava uma carga de milho. O caminh\u00e3o era conduzido pelo indiv\u00edduo (39), natural de Santa Catarina. Em vistoria, em meio a carga de milho, foram encontrados 75 gal\u00f5es de 20 litros de agrot\u00f3xico, que tem sua comercializa\u00e7\u00e3o proibida no Brasil e teria origem Argentina. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dois ve\u00edculos acompanhavam a carga como batedores. Eles fugiram ao perceberem a aproxima\u00e7\u00e3o da viatura. Um dos ve\u00edculos foi encontrado em uma resid\u00eancia e abordado pela guarni\u00e7\u00e3o. No momento da a\u00e7\u00e3o, um dos indiv\u00edduos correu para o interior da casa e saltou por uma janela. No ve\u00edculo encontrava-se o condutor (25) e tr\u00eas passageiros, dois homens (40 e 25) e uma mulher (19). Os passageiros eram estrangeiros da Argentina. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No interior da resid\u00eancia foram encontradas diversas caixas de bebidas, uma espingarda, uma pistola e outros produtos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diante dos fatos foi dada voz de pris\u00e3o aos indiv\u00edduos e eles foram encaminhados \u00e0 Pol\u00edcia Federal de Santa Cruz do Sul. O motorista (25) j\u00e1 possu\u00eda antecedentes criminais por roubo de ve\u00edculo e roubo a pedestre. O motorista do caminh\u00e3o (39) n\u00e3o possu\u00eda antecedentes. Sobre os outros criminosos n\u00e3o foi poss\u00edvel identificar devido \u00e0 origem estrangeira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quatro homens (25, 39, 40 e 25) e uma mulher (19) foram presos pelos crimes de contrabando e descaminho nessa ter\u00e7a-feira (9\/8), em Anta Gorda. Policiais militares realizaram abordagem de um caminh\u00e3o que carregava uma carga de milho. O caminh\u00e3o era conduzido pelo indiv\u00edduo (39), natural de Santa Catarina. Em vistoria, em meio a carga [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":110390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[3596,251,1073],"class_list":["post-110389","post","type-post","status-publish","format-standard","has-post-thumbnail","category-seguranca","tag-anta-gorda","tag-brigada-militar","tag-contrabando","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Quatro homens (25, 39, 40 e 25) e uma mulher (19) foram presos pelos crimes de contrabando e descaminho nessa ter\u00e7a-feira (9\/8), em Anta Gorda. Policiais militares realizaram abordagem de um caminh\u00e3o que carregava uma carga de milho. O caminh\u00e3o era conduzido pelo indiv\u00edduo (39), natural de Santa Catarina. Em vistoria, em meio a carga [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-10T13:48:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-10T13:48:28+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda\",\"datePublished\":\"2022-08-10T13:48:17+00:00\",\"dateModified\":\"2022-08-10T13:48:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/\"},\"wordCount\":242,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg\",\"keywords\":[\"Anta Gorda\",\"Brigada Militar\",\"Contrabando\"],\"articleSection\":[\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/\",\"name\":\"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg\",\"datePublished\":\"2022-08-10T13:48:17+00:00\",\"dateModified\":\"2022-08-10T13:48:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg\",\"width\":900,\"height\":1200,\"caption\":\"Cr\u00e9dito: Brigada Militar \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/10\\\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/","og_locale":"pt_BR","og_type":"article","og_title":"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda - Folha Popular","og_description":"Quatro homens (25, 39, 40 e 25) e uma mulher (19) foram presos pelos crimes de contrabando e descaminho nessa ter\u00e7a-feira (9\/8), em Anta Gorda. Policiais militares realizaram abordagem de um caminh\u00e3o que carregava uma carga de milho. O caminh\u00e3o era conduzido pelo indiv\u00edduo (39), natural de Santa Catarina. Em vistoria, em meio a carga [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/","og_site_name":"Folha Popular","article_published_time":"2022-08-10T13:48:17+00:00","article_modified_time":"2022-08-10T13:48:28+00:00","og_image":[{"width":900,"height":1200,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda","datePublished":"2022-08-10T13:48:17+00:00","dateModified":"2022-08-10T13:48:28+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/"},"wordCount":242,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg","keywords":["Anta Gorda","Brigada Militar","Contrabando"],"articleSection":["Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/","name":"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg","datePublished":"2022-08-10T13:48:17+00:00","dateModified":"2022-08-10T13:48:28+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg","width":900,"height":1200,"caption":"Cr\u00e9dito: Brigada Militar \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/10\/brigada-militar-realiza-prisao-por-contrabando-e-descaminho-em-anta-gorda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Brigada Militar realiza pris\u00e3o por contrabando e descaminho em Anta Gorda"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-00.00.11-e1660139230270.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/110389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=110389"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/110389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/110390"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=110389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=110389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=110389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}