{"id":111281,"date":"2022-08-22T17:35:00","date_gmt":"2022-08-22T20:35:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=111281"},"modified":"2022-08-22T17:18:56","modified_gmt":"2022-08-22T20:18:56","slug":"16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/","title":{"rendered":"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A 16\u00aa Feira do Livro de Lajeado chegou ao fim nesse domingo (21\/8), e durante seus cinco dias de programa\u00e7\u00e3o contou com a presen\u00e7a de mais de 18 mil visitantes e 10,5 mil obras vendidas. O evento, realizado pelo Sesc e pelas secretarias da Cultura, Esporte e Lazer (Secel) e da Educa\u00e7\u00e3o (SED), teve como tema \u201cJanelas Liter\u00e1rias \u2013 Abra-se para a literatura\u201d, em alus\u00e3o ao centen\u00e1rio de nascimento do autor portugu\u00eas Jos\u00e9 Saramago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O evento contou com encontros com escritores, espet\u00e1culos teatrais, mostras pedag\u00f3gicas, esquetes, oficinas, horas do conto, shows e lan\u00e7amento coletivo de livros. Foram 10 livrarias participantes na Pra\u00e7a Marechal Floriano (conhecida como Pra\u00e7a da Matriz). Al\u00e9m de atividades paralelas na Casa de Cultura, na Biblioteca P\u00fablica Municipal, no Audit\u00f3rio do Sesc, no Audit\u00f3rio do Col\u00e9gio Estadual Presidente Castelo Branco, no Teatro do Ceat, no Teatro Univates e no Labi-L\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O titular da Secel, Carlos Reckziegel, caracteriza feira como festa da cultura. &#8220;\u00c9 muito gratificante ver a pra\u00e7a cercada de cultura, celebrando a literatura. A feira foi um sucesso, e a participa\u00e7\u00e3o do p\u00fablico comprovou isso. Oferecemos uma programa\u00e7\u00e3o diversificada, atendendo toda a comunidade&#8221;, destaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No domingo de encerramento, o grupo &#8220;Os Alquimistas&#8221; fizeram o show em comemora\u00e7\u00e3o aos 31 anos da Casa de Cultura, e apresenta\u00e7\u00e3o da Oclaje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 16\u00aa Feira do Livro de Lajeado chegou ao fim nesse domingo (21\/8), e durante seus cinco dias de programa\u00e7\u00e3o contou com a presen\u00e7a de mais de 18 mil visitantes e 10,5 mil obras vendidas. O evento, realizado pelo Sesc e pelas secretarias da Cultura, Esporte e Lazer (Secel) e da Educa\u00e7\u00e3o (SED), teve como [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":111285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[5366,6466,322,27,32],"class_list":["post-111281","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-comunidade","tag-evento","tag-feira-do-livro","tag-lajeado","tag-obras","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A 16\u00aa Feira do Livro de Lajeado chegou ao fim nesse domingo (21\/8), e durante seus cinco dias de programa\u00e7\u00e3o contou com a presen\u00e7a de mais de 18 mil visitantes e 10,5 mil obras vendidas. O evento, realizado pelo Sesc e pelas secretarias da Cultura, Esporte e Lazer (Secel) e da Educa\u00e7\u00e3o (SED), teve como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-22T20:35:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/Feira-do-Livro-scaled-e1661199427532.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos\",\"datePublished\":\"2022-08-22T20:35:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/\"},\"wordCount\":237,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Feira-do-Livro-scaled-e1661199427532.jpg\",\"keywords\":[\"Comunidade\",\"Evento\",\"Feira do Livro\",\"Lajeado\",\"Obras\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/\",\"name\":\"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Feira-do-Livro-scaled-e1661199427532.jpg\",\"datePublished\":\"2022-08-22T20:35:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Feira-do-Livro-scaled-e1661199427532.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Feira-do-Livro-scaled-e1661199427532.jpg\",\"width\":1200,\"height\":800,\"caption\":\"O tema deste ano foi: \u201cJanelas Liter\u00e1rias \u2013 Abra-se para a literatura\u201d \\\/ Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/08\\\/22\\\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/","og_locale":"pt_BR","og_type":"article","og_title":"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos - Folha Popular","og_description":"A 16\u00aa Feira do Livro de Lajeado chegou ao fim nesse domingo (21\/8), e durante seus cinco dias de programa\u00e7\u00e3o contou com a presen\u00e7a de mais de 18 mil visitantes e 10,5 mil obras vendidas. O evento, realizado pelo Sesc e pelas secretarias da Cultura, Esporte e Lazer (Secel) e da Educa\u00e7\u00e3o (SED), teve como [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/","og_site_name":"Folha Popular","article_published_time":"2022-08-22T20:35:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/Feira-do-Livro-scaled-e1661199427532.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos","datePublished":"2022-08-22T20:35:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/"},"wordCount":237,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/Feira-do-Livro-scaled-e1661199427532.jpg","keywords":["Comunidade","Evento","Feira do Livro","Lajeado","Obras"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/","name":"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/Feira-do-Livro-scaled-e1661199427532.jpg","datePublished":"2022-08-22T20:35:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/Feira-do-Livro-scaled-e1661199427532.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/Feira-do-Livro-scaled-e1661199427532.jpg","width":1200,"height":800,"caption":"O tema deste ano foi: \u201cJanelas Liter\u00e1rias \u2013 Abra-se para a literatura\u201d \/ Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/08\/22\/16a-feira-do-livro-de-lajeado-tem-exito-em-comercializacao-de-obras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"16\u00aa Feira do Livro de Lajeado alcan\u00e7a n\u00fameros positivos"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/08\/Feira-do-Livro-scaled-e1661199427532.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/111281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=111281"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/111281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/111285"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=111281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=111281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=111281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}