{"id":113071,"date":"2022-09-21T06:50:45","date_gmt":"2022-09-21T09:50:45","guid":{"rendered":"https:\/\/folhapopular.info\/?p=113071"},"modified":"2022-09-21T06:50:49","modified_gmt":"2022-09-21T09:50:49","slug":"14a-rustica-de-estrela-reune-mais-de-450-participantes","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/","title":{"rendered":"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A 14\u00aa R\u00fastica de Estrela aconteceu na manh\u00e3 desse domingo (18\/9). A movimenta\u00e7\u00e3o iniciou no Parque Princesa do Vale. O evento contou com mais de 450 participantes de cerca de 40 munic\u00edpios nas linhas de largada das suas quatro categorias gerais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A r\u00fastica ocorreu em quatro dist\u00e2ncias de corrida com 16 faixas et\u00e1rias adulto e infantil: 200 metros (iniciantes at\u00e9 8 anos); 2 quil\u00f4metros (infantil \u2013 tr\u00eas faixas et\u00e1rias de 9 a 15 anos); adulto 5 quil\u00f4metros e 10 quil\u00f4metros, masculinas e femininas (12 faixas et\u00e1rias); al\u00e9m da caminhada adulta \u2013 5 quil\u00f4metros.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A categoria \u201cIniciantes\u201d reuniu dezenas de crian\u00e7as com 8 anos ou menos. Para muitos, a primeira prova.\u00a0Foi o caso de Henrique Ferronato Dotto. Com apenas 3.3 anos, correu pela primeira vez. Cansado, precisou por alguns metros ganhar o colo da m\u00e3e. Mas n\u00e3o desistiu e, sob incentivo da irm\u00e3 Betina \u2013 que tamb\u00e9m correria a categoria Infantil\u00a0\u2013, do pai, da m\u00e3e e de todo o p\u00fablico, cruzou sozinho a linha de chegada, para ent\u00e3o, orgulhoso, receber a primeira medalha da vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O vencedor geral foi Henrique Augusto Shure (8), de Arroio do Meio. Depois de correr, o menino foi apoiar os pais Fernando e \u00c2ngela, que correriam a prova adulto. \u201cO Henrique correu aqui pela primeira vez. Eu e o Fernando sempre viemos. Que bom que a prova voltou ap\u00f3s a pandemia. Aqui \u00e9 muito organizado, tem muitas atra\u00e7\u00f5es, \u00e9 gostoso participar\u201d, resumiu a m\u00e3e do garoto. Ela, por final, foi a segunda colocada geral feminino nos 10 quil\u00f4metros.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>For\u00e7a e supera\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais de 350 pessoas largaram para as provas adultas de corrida e caminhada. Muitos deles, velhos conhecidos da prova, como seu Ruberto Horn, que aos 85 anos foi o homenageado com o nome do trof\u00e9u deste ano, e mais uma vez foi tamb\u00e9m o mais idoso entre todos; e dona Maria Bispo Rodrigues, 78 anos, com a sua j\u00e1 inconfund\u00edvel regata do Gr\u00eamio, seu time do cora\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alegria e emo\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As fei\u00e7\u00f5es nas chegadas eram as mais diversas. A maioria de rosto fechado, sin\u00f4nimo do esfor\u00e7o utilizado, mas sem esconder a satisfa\u00e7\u00e3o pela meta alcan\u00e7ada. Enquanto uns abriram sorrisos, outros ca\u00edram em l\u00e1grimas. Daniela Rodrigues da Silva foi um caso. A estrelense, que participou de todas as 14 edi\u00e7\u00f5es da prova at\u00e9 hoje, reconheceu nunca ter se emocionado tanto. \u201c\u00c9 uma s\u00e9rie de fatores. A come\u00e7ar porque perdi minha av\u00f3, que faleceu h\u00e1 30 dias. Ela sempre me apoiou muito e vinha aqui torcer por mim. Tamb\u00e9m por minha pr\u00f3pria supera\u00e7\u00e3o\u201d, disse ela. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>De Estrela para Boston-EUA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos 10 quil\u00f4metros, o mais r\u00e1pido entre os homens foi Ramon Anschau, com 00:33m:11s. Entre elas, a vencedora foi Cassiana Hauschild Stringhini, com 00:41m:06s. Com 32 anos, ela come\u00e7ou a correr h\u00e1 menos de dez, mas j\u00e1 tem feito hist\u00f3ria. Em Estrela, estreou este ano. \u201cFoi minha primeira R\u00fastica de Estrela. Adorei. Recentemente, na maratona de Porto Alegre alcancei o \u00edndice para a Maratona de Boston-EUA, que ocorre em abril, e onde s\u00f3 participa quem justamente tem o \u00edndice\u201d, explica ela. \u201cVou ir, estou treinando muito, mesmo sem poder abandonar a rotina de vida de quem n\u00e3o \u00e9 atleta profissional\u201d, confessa a dentista de Lajeado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os resultados oficiais, tempos e outros detalhes podem ser conferidos no <a href=\"https:\/\/www.trichipcronometragem.com.br\/resultados\/g-live.html?f=eventos\/2022\/14rusticadeestrela\/poa.14rusticadeestrela2022.clax\">link<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 14\u00aa R\u00fastica de Estrela aconteceu na manh\u00e3 desse domingo (18\/9). A movimenta\u00e7\u00e3o iniciou no Parque Princesa do Vale. O evento contou com mais de 450 participantes de cerca de 40 munic\u00edpios nas linhas de largada das suas quatro categorias gerais. A r\u00fastica ocorreu em quatro dist\u00e2ncias de corrida com 16 faixas et\u00e1rias adulto e [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":113072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[9977,2323,8,4535,5373],"class_list":["post-113071","post","type-post","status-publish","format-standard","has-post-thumbnail","category-esportes","tag-14a-rustica-de-estrela","tag-corrida","tag-estrela","tag-governo-de-estrela","tag-municipios","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A 14\u00aa R\u00fastica de Estrela aconteceu na manh\u00e3 desse domingo (18\/9). A movimenta\u00e7\u00e3o iniciou no Parque Princesa do Vale. O evento contou com mais de 450 participantes de cerca de 40 munic\u00edpios nas linhas de largada das suas quatro categorias gerais. A r\u00fastica ocorreu em quatro dist\u00e2ncias de corrida com 16 faixas et\u00e1rias adulto e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-21T09:50:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-21T09:50:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/09\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes\",\"datePublished\":\"2022-09-21T09:50:45+00:00\",\"dateModified\":\"2022-09-21T09:50:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/\"},\"wordCount\":571,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg\",\"keywords\":[\"14\u00aa R\u00fastica de Estrela\",\"Corrida\",\"Estrela\",\"Governo de Estrela\",\"munic\u00edpios\"],\"articleSection\":[\"Esportes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/\",\"name\":\"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg\",\"datePublished\":\"2022-09-21T09:50:45+00:00\",\"dateModified\":\"2022-09-21T09:50:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg\",\"width\":1800,\"height\":1200,\"caption\":\"Ao todo foram distribu\u00eddos 150 trof\u00e9us e mais de 520 medalhas \\\/ Cr\u00e9dito: FS Imagens \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/09\\\/21\\\/14a-rustica-de-estrela-reune-mais-de-450-participantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/","og_locale":"pt_BR","og_type":"article","og_title":"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes - Folha Popular","og_description":"A 14\u00aa R\u00fastica de Estrela aconteceu na manh\u00e3 desse domingo (18\/9). A movimenta\u00e7\u00e3o iniciou no Parque Princesa do Vale. O evento contou com mais de 450 participantes de cerca de 40 munic\u00edpios nas linhas de largada das suas quatro categorias gerais. A r\u00fastica ocorreu em quatro dist\u00e2ncias de corrida com 16 faixas et\u00e1rias adulto e [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/","og_site_name":"Folha Popular","article_published_time":"2022-09-21T09:50:45+00:00","article_modified_time":"2022-09-21T09:50:49+00:00","og_image":[{"width":1800,"height":1200,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2022\/09\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes","datePublished":"2022-09-21T09:50:45+00:00","dateModified":"2022-09-21T09:50:49+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/"},"wordCount":571,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/09\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg","keywords":["14\u00aa R\u00fastica de Estrela","Corrida","Estrela","Governo de Estrela","munic\u00edpios"],"articleSection":["Esportes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/","name":"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/09\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg","datePublished":"2022-09-21T09:50:45+00:00","dateModified":"2022-09-21T09:50:49+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/09\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/09\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg","width":1800,"height":1200,"caption":"Ao todo foram distribu\u00eddos 150 trof\u00e9us e mais de 520 medalhas \/ Cr\u00e9dito: FS Imagens \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/09\/21\/14a-rustica-de-estrela-reune-mais-de-450-participantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"14\u00aa R\u00fastica de Estrela re\u00fane mais de 450 participantes"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2022\/09\/Rustica-Estrela-corrida-ADULTO-GERAL-FS-Imagens-33.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/113071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=113071"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/113071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/113072"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=113071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=113071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=113071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}