{"id":117953,"date":"2022-12-17T12:02:39","date_gmt":"2022-12-17T15:02:39","guid":{"rendered":"https:\/\/folhapopular.info\/?p=117953"},"modified":"2022-12-17T12:03:24","modified_gmt":"2022-12-17T15:03:24","slug":"auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/","title":{"rendered":"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Os auditores-fiscais do Trabalho, da Ger\u00eancia Regional do Trabalho e Emprego de Lajeado (GRTE\/RS), realizaram, na quarta-feira (14\/12), uma a\u00e7\u00e3o no munic\u00edpio de Teut\u00f4nia (RS),&nbsp;juntamente com o Minist\u00e9rio P\u00fablico do Trabalho, a Vigil\u00e2ncia em Sa\u00fade do Trabalhador e o Centro de Refer\u00eancia Especializado de Assist\u00eancia Social<strong>&nbsp;<\/strong>(CREAS), do munic\u00edpio de Teut\u00f4nia, e resgataram sete atletas jovens e adolescentes submetidos a condi\u00e7\u00f5es an\u00e1logas de escravid\u00e3o.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foi constatado que os jovens e adolescentes de outros estados (Par\u00e1, Minas Gerais e Santa Catarina) eram aliciados por captadores, conhecidos como \u201colheiros\u201d, em processos seletivos, competi\u00e7\u00f5es ou por meio de redes sociais, que prometiam oportunidade de forma\u00e7\u00e3o e profissionaliza\u00e7\u00e3o em clube de futebol no interior do Estado do Rio Grande do Sul, al\u00e9m de alojamento, alimenta\u00e7\u00e3o, estrutura para treinos e, ainda, a coloca\u00e7\u00e3o em outros clubes de futebol expressivos.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na origem, os atletas efetuavam o pagamento de taxa de inscri\u00e7\u00e3o, parte destinada ao captador e parte destinada ao suposto clube no munic\u00edpio de Teut\u00f4nia. Al\u00e9m disso, arcavam com os custos do deslocamento e&nbsp;com quantia&nbsp;mensal de R$ 700,00 pelo alojamento, treinamento e pela alimenta\u00e7\u00e3o. Os maiores de 18 anos que n\u00e3o possu\u00edssem condi\u00e7\u00f5es financeiras de custear os valores&nbsp;cobrados eram encaminhados para vaga de trabalho em f\u00e1brica de cal\u00e7ados ou frigor\u00edfico da regi\u00e3o. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os atletas, que tinham&nbsp;idades entre 15 e 23 anos, eram provenientes de fam\u00edlias humildes, tendo visto&nbsp;na proposta a possibilidade de realizar o sonho da profissionaliza\u00e7\u00e3o no futebol. A realidade, todavia, era outra: o suposto clube, na verdade, era uma associa\u00e7\u00e3o rec\u00e9m-criada sem a m\u00ednima estrutura e sem profissionais especializados para forma\u00e7\u00e3o dos atletas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os treinos eram realizados em pracinhas e campos p\u00fablicos, os treinadores n\u00e3o possu\u00edam forma\u00e7\u00e3o adequada e n\u00e3o havia material esportivo de qualidade. A&nbsp;alimenta\u00e7\u00e3o fornecida era inadequada ao desenvolvimento sadio de adolescentes e atletas em forma\u00e7\u00e3o. A limpeza do alojamento era realizada pelos pr\u00f3prios atletas, e, por diversas vezes, o jantar foi preparado por um dos adolescentes. Os jogadores arcavam, ainda, com os custos das inscri\u00e7\u00f5es em campeonatos e deslocamento para jogos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o era ofertado acompanhamento m\u00e9dico e odontol\u00f3gico e sequer havia avalia\u00e7\u00e3o m\u00e9dica pr\u00e9via. Quando o atleta se machucava, tinha que pagar&nbsp;com os custos do tratamento para sua recupera\u00e7\u00e3o. Os treinos eram pouco efetivos, principalmente para aqueles que desenvolviam jornadas de trabalho de 44 horas semanais em outras atividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A esse quadro somou-se a contrata\u00e7\u00e3o de pessoa suspeita de crimes de estelionato, roubo e ass\u00e9dio sexual, com ampla divulga\u00e7\u00e3o na internet, e sempre envolvendo jovens e adolescentes que sonhavam com a profissionaliza\u00e7\u00e3o no futebol. O suspeito foi contratado para captar atletas, administrar o alojamento, que na \u00e9poca contava com cerca de 22 jovens e adolescentes, muitos deles com idades entre 13 e 16 anos, e treinar o time que compunha a categoria sub-17. O comportamento do suposto treinador chamava a aten\u00e7\u00e3o dos demais, como, por exemplo, pelo fato de inscrever atletas em campeonatos nas categorias sub-17 e sub-20 com idades superiores \u00e0quelas permitidas, valendo-se de documentos de identidade falsificados.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 24 de novembro de 2022, a for\u00e7a-tarefa culminou na interdi\u00e7\u00e3o da cozinha do alojamento, em face&nbsp;das inadequadas condi\u00e7\u00f5es encontradas, entre eles, alimentos estragados, bem como no abrigamento dos menores de 18 (dezoito) anos, conforme pedido formulado pela Promotoria de Justi\u00e7a de Teut\u00f4nia e determina\u00e7\u00e3o da Ju\u00edza da 2\u00aa Vara Judicial de Teut\u00f4nia. Tr\u00eas adolescentes foram para um abrigo do munic\u00edpio, e os demais permaneceram no alojamento sem condi\u00e7\u00f5es financeiras de retornar aos locais de origem, quais sejam, cidades do interior do Rio Grande do Sul, e os estados do Par\u00e1 e Minas Gerais.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A auditoria-fiscal do Trabalho entendeu que os jovens e adolescentes foram v\u00edtimas do tr\u00e1fico de pessoas e das condi\u00e7\u00f5es degradantes de trabalho, indicadores da condi\u00e7\u00e3o an\u00e1loga \u00e0 de escravo e que significavam graves viola\u00e7\u00f5es aos direitos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O suposto clube se valia da vulnerabilidade econ\u00f4mica e social desses atletas e de suas fam\u00edlias, e lan\u00e7ava m\u00e3o de pr\u00e1ticas enganosas com vistas \u00e0 explora\u00e7\u00e3o dos atletas em forma\u00e7\u00e3o, n\u00e3o cumprindo os requisitos m\u00ednimos previstos na Lei n\u00ba 9.615, de 24 de mar\u00e7o de 1998, conhecida por \u201cLei Pel\u00e9\u201d, para contratar, manter em alojamento e formar atletas para o futebol, o que significa fraude \u00e0 condi\u00e7\u00e3o de atleta em forma\u00e7\u00e3o. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A associa\u00e7\u00e3o foi notificada a efetuar o pagamento das verbas rescis\u00f3rias e a devolver os valores cobrados de forma indevida dos atletas, o que representou&nbsp;R$ 38.728,95. Os jovens e adolescentes receber\u00e3o tr\u00eas parcelas do Seguro-Desemprego do Trabalhador Resgatado, al\u00e9m do custeio da viagem de retorno a seus locais de origem. Cumpre registrar que, por interveni\u00eancia do Minist\u00e9rio P\u00fablico do Trabalho, quatro passagens a\u00e9reas de retorno dos atletas para os estados de Minas Gerais e Par\u00e1 est\u00e3o sendo custeadas pelas Federa\u00e7\u00e3o Ga\u00facha de Futebol.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Den\u00fancias<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Den\u00fancias de trabalho escravo podem ser feitas, de forma remota e sigilosa, no Sistema Ip\u00ea (<a href=\"https:\/\/ipe.sit.trabalho.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/ipe.sit.trabalho.gov.br\/<\/a>). Den\u00fancias de trabalho infantil, no Sistema Ip\u00ea Trabalho Infantil (<a href=\"https:\/\/ipetrabalhoinfantil.trabalho.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/ipetrabalhoinfantil.trabalho.gov.br<\/a>).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As queixas podem ser feitas tamb\u00e9m pelo&nbsp;<a href=\"https:\/\/denuncia.sit.trabalho.gov.br\/home\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/denuncia.sit.trabalho.gov.br\/home<\/a>, Sistema de Den\u00fancias DETRAE\/SIT, Minist\u00e9rio P\u00fablico do Trabalho, ou disque 100.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os auditores-fiscais do Trabalho, da Ger\u00eancia Regional do Trabalho e Emprego de Lajeado (GRTE\/RS), realizaram, na quarta-feira (14\/12), uma a\u00e7\u00e3o no munic\u00edpio de Teut\u00f4nia (RS),&nbsp;juntamente com o Minist\u00e9rio P\u00fablico do Trabalho, a Vigil\u00e2ncia em Sa\u00fade do Trabalhador e o Centro de Refer\u00eancia Especializado de Assist\u00eancia Social&nbsp;(CREAS), do munic\u00edpio de Teut\u00f4nia, e resgataram sete atletas jovens [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":58538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[5632,10449,5966,26],"class_list":["post-117953","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-atletas","tag-auditores-fiscais","tag-escravidao","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Os auditores-fiscais do Trabalho, da Ger\u00eancia Regional do Trabalho e Emprego de Lajeado (GRTE\/RS), realizaram, na quarta-feira (14\/12), uma a\u00e7\u00e3o no munic\u00edpio de Teut\u00f4nia (RS),&nbsp;juntamente com o Minist\u00e9rio P\u00fablico do Trabalho, a Vigil\u00e2ncia em Sa\u00fade do Trabalhador e o Centro de Refer\u00eancia Especializado de Assist\u00eancia Social&nbsp;(CREAS), do munic\u00edpio de Teut\u00f4nia, e resgataram sete atletas jovens [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-17T15:02:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-17T15:03:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Noticias-e1567961441371.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia\",\"datePublished\":\"2022-12-17T15:02:39+00:00\",\"dateModified\":\"2022-12-17T15:03:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/\"},\"wordCount\":979,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Noticias-e1567961441371.jpg\",\"keywords\":[\"Atletas\",\"Auditores-fiscais\",\"escravid\u00e3o\",\"Teut\u00f4nia\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/\",\"name\":\"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Noticias-e1567961441371.jpg\",\"datePublished\":\"2022-12-17T15:02:39+00:00\",\"dateModified\":\"2022-12-17T15:03:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Noticias-e1567961441371.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Noticias-e1567961441371.jpg\",\"width\":800,\"height\":563,\"caption\":\"Cr\u00e9dito da arte: J\u00falia Caroline Geib \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2022\\\/12\\\/17\\\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/","og_locale":"pt_BR","og_type":"article","og_title":"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia - Folha Popular","og_description":"Os auditores-fiscais do Trabalho, da Ger\u00eancia Regional do Trabalho e Emprego de Lajeado (GRTE\/RS), realizaram, na quarta-feira (14\/12), uma a\u00e7\u00e3o no munic\u00edpio de Teut\u00f4nia (RS),&nbsp;juntamente com o Minist\u00e9rio P\u00fablico do Trabalho, a Vigil\u00e2ncia em Sa\u00fade do Trabalhador e o Centro de Refer\u00eancia Especializado de Assist\u00eancia Social&nbsp;(CREAS), do munic\u00edpio de Teut\u00f4nia, e resgataram sete atletas jovens [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/","og_site_name":"Folha Popular","article_published_time":"2022-12-17T15:02:39+00:00","article_modified_time":"2022-12-17T15:03:24+00:00","og_image":[{"width":800,"height":563,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Noticias-e1567961441371.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia","datePublished":"2022-12-17T15:02:39+00:00","dateModified":"2022-12-17T15:03:24+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/"},"wordCount":979,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Noticias-e1567961441371.jpg","keywords":["Atletas","Auditores-fiscais","escravid\u00e3o","Teut\u00f4nia"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/","url":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/","name":"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Noticias-e1567961441371.jpg","datePublished":"2022-12-17T15:02:39+00:00","dateModified":"2022-12-17T15:03:24+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Noticias-e1567961441371.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Noticias-e1567961441371.jpg","width":800,"height":563,"caption":"Cr\u00e9dito da arte: J\u00falia Caroline Geib \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2022\/12\/17\/auditores-fiscais-do-trabalho-resgatam-atletas-em-situacao-analoga-a-de-escravo-em-teutonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Auditores-fiscais do Trabalho resgatam atletas em situa\u00e7\u00e3o an\u00e1loga \u00e0 de escravo em Teut\u00f4nia"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2019\/09\/Noticias-e1567961441371.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/117953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=117953"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/117953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/58538"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=117953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=117953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=117953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}