{"id":120608,"date":"2023-02-06T15:55:25","date_gmt":"2023-02-06T18:55:25","guid":{"rendered":"https:\/\/folhapopular.info\/?p=120608"},"modified":"2023-02-06T15:57:43","modified_gmt":"2023-02-06T18:57:43","slug":"univates-abre-processo-seletivo-continuo-para-diplomados-da-saude","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/","title":{"rendered":"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Funda\u00e7\u00e3o Univates lan\u00e7ou edital de processo seletivo cont\u00ednuo para diplomados nos cursos de Odontologia, Fisioterapia, Nutri\u00e7\u00e3o e Psicologia interessados em atuar como prestadores de servi\u00e7o pelo programa <a href=\"https:\/\/www.univates.br\/trabalhe-conosco\/partner-saude-univates\"><em>Partner<\/em> Sa\u00fade<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.univates.br\/media\/wsdl_editais\/1672419312.1602.pdf\">Conforme o edital<\/a>, o parceiro poder\u00e1 realizar atendimentos na modalidade particular, atendendo sempre nos hor\u00e1rios ou turnos vagos na agenda das aulas pr\u00e1ticas. O processo seletivo inclui a an\u00e1lise de curr\u00edculo e entrevista individual, e os interessados devem realizar a inscri\u00e7\u00e3o gratuitamente <a href=\"https:\/\/www.univates.br\/trabalhe-conosco\/partner-saude-univates\" target=\"_blank\" rel=\"noreferrer noopener\">neste link<\/a>. Os profissionais ser\u00e3o contratados \u00e0 medida que houver vagas dispon\u00edveis. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Programa <em>Partner<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O programa<em> Partner<\/em> Sa\u00fade Univates oportuniza aos profissionais da \u00e1rea da Sa\u00fade diplomados pela Univates a realiza\u00e7\u00e3o de atendimentos nas cl\u00ednicas de Odontologia, Nutri\u00e7\u00e3o, Fisioterapia e Psicologia da institui\u00e7\u00e3o de ensino. Al\u00e9m de contar com os equipamentos f\u00edsicos e a estrutura moderna da institui\u00e7\u00e3o, os <em>partners<\/em> encontram um ambiente prop\u00edcio para o <em>networking<\/em> e prestam um servi\u00e7o atrelado \u00e0 credibilidade da Univates.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os atendimentos ocorrem nos hor\u00e1rios dispon\u00edveis entre as atividades acad\u00eamicas e os servi\u00e7os j\u00e1 prestados \u00e0 comunidade por profissionais e estudantes (estagi\u00e1rios) da universidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais informa\u00e7\u00f5es sobre o processo seletivo e a modalidade de atendimento podem ser obtidas pelo <em>e-mail<\/em> <a href=\"mailto:saude@univates.br\" target=\"_blank\" rel=\"noreferrer noopener\">saude@univates.br<\/a> ou atrav\u00e9s da p\u00e1gina do <a href=\"https:\/\/www.univates.br\/trabalhe-conosco\/partner-saude-univates\" target=\"_blank\" rel=\"noreferrer noopener\">Partner Sa\u00fade Univates<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Funda\u00e7\u00e3o Univates lan\u00e7ou edital de processo seletivo cont\u00ednuo para diplomados nos cursos de Odontologia, Fisioterapia, Nutri\u00e7\u00e3o e Psicologia interessados em atuar como prestadores de servi\u00e7o pelo programa Partner Sa\u00fade. Conforme o edital, o parceiro poder\u00e1 realizar atendimentos na modalidade particular, atendendo sempre nos hor\u00e1rios ou turnos vagos na agenda das aulas pr\u00e1ticas. O processo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":120610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[10188,10753,812,3303,481,10754,10752,10751,761,5515,83,7615],"class_list":["post-120608","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-dentistas","tag-diplomados","tag-fisioterapia","tag-odontologia","tag-processo-seletivo","tag-processo-seletivo-continuo","tag-programa-partner","tag-programa-partner-saude-univates","tag-psicologia","tag-saude-univates","tag-univates","tag-universidade-do-vale-do-taquari","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade<\/title>\n<meta name=\"description\" content=\"A Univates disponibiliza, em parceria comercial, as depend\u00eancias e os equipamentos f\u00edsicos para atendimentos na modalidade particular.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade\" \/>\n<meta property=\"og:description\" content=\"A Univates disponibiliza, em parceria comercial, as depend\u00eancias e os equipamentos f\u00edsicos para atendimentos na modalidade particular.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-06T18:55:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-06T18:57:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/02\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade\",\"datePublished\":\"2023-02-06T18:55:25+00:00\",\"dateModified\":\"2023-02-06T18:57:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/\"},\"wordCount\":240,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg\",\"keywords\":[\"Dentistas\",\"diplomados\",\"Fisioterapia\",\"Odontologia\",\"Processo Seletivo\",\"processo seletivo cont\u00ednuo\",\"programa partner\",\"programa partner sa\u00fade univates\",\"Psicologia\",\"Sa\u00fade Univates\",\"Univates\",\"Universidade do Vale do Taquari\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/\",\"name\":\"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg\",\"datePublished\":\"2023-02-06T18:55:25+00:00\",\"dateModified\":\"2023-02-06T18:57:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"description\":\"A Univates disponibiliza, em parceria comercial, as depend\u00eancias e os equipamentos f\u00edsicos para atendimentos na modalidade particular.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg\",\"width\":2560,\"height\":1703,\"caption\":\"Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/02\\\/06\\\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade","description":"A Univates disponibiliza, em parceria comercial, as depend\u00eancias e os equipamentos f\u00edsicos para atendimentos na modalidade particular.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/","og_locale":"pt_BR","og_type":"article","og_title":"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade","og_description":"A Univates disponibiliza, em parceria comercial, as depend\u00eancias e os equipamentos f\u00edsicos para atendimentos na modalidade particular.","og_url":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/","og_site_name":"Folha Popular","article_published_time":"2023-02-06T18:55:25+00:00","article_modified_time":"2023-02-06T18:57:43+00:00","og_image":[{"width":2560,"height":1703,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/02\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade","datePublished":"2023-02-06T18:55:25+00:00","dateModified":"2023-02-06T18:57:43+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/"},"wordCount":240,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/02\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg","keywords":["Dentistas","diplomados","Fisioterapia","Odontologia","Processo Seletivo","processo seletivo cont\u00ednuo","programa partner","programa partner sa\u00fade univates","Psicologia","Sa\u00fade Univates","Univates","Universidade do Vale do Taquari"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/","url":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/","name":"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/02\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg","datePublished":"2023-02-06T18:55:25+00:00","dateModified":"2023-02-06T18:57:43+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"description":"A Univates disponibiliza, em parceria comercial, as depend\u00eancias e os equipamentos f\u00edsicos para atendimentos na modalidade particular.","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/02\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/02\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg","width":2560,"height":1703,"caption":"Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2023\/02\/06\/univates-abre-processo-seletivo-continuo-para-diplomados-da-saude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Univates abre processo seletivo cont\u00ednuo para diplomados da Sa\u00fade"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/02\/1-Profissionais-irao-atuar-nas-clinicas-de-Odontologia-Nutricao-Fisioterapia-e-Psicologia-da-Univates-Credito-Mateus-Scheibel-scaled.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/120608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=120608"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/120608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/120610"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=120608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=120608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=120608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}