{"id":123123,"date":"2023-03-14T16:42:30","date_gmt":"2023-03-14T19:42:30","guid":{"rendered":"https:\/\/folhapopular.info\/?p=123123"},"modified":"2023-03-14T16:44:36","modified_gmt":"2023-03-14T19:44:36","slug":"encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/","title":{"rendered":"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A poucos dias do <a href=\"https:\/\/folhapopular.info\/index.php\/2023\/02\/20\/confira-a-programacao-do-13o-encontro-nacional-de-veiculos-antigos-de-teutonia\/\" target=\"_blank\" rel=\"noreferrer noopener\">13\u00ba Encontro Nacional de Ve\u00edculos Antigos de Teut\u00f4nia<\/a>, que ocorre neste fim de semana (17 a 19\/3), no Centro Administrativo Municipal, a procura dos antigomobilistas para exposi\u00e7\u00e3o de rel\u00edquias \u00e9 grande. Segundo a comiss\u00e3o organizadora, as inscri\u00e7\u00f5es antecipadas aumentam diariamente, o que confirma a expectativa de que esse possa ser o maior evento j\u00e1 realizado, superando os 600 ve\u00edculos da edi\u00e7\u00e3o passada, realizada em 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA procura \u00e9 consideravelmente maior em rela\u00e7\u00e3o ao ano passado, grupos est\u00e3o se organizando, muitos contatos e inscri\u00e7\u00f5es antecipadas pelo site do evento\u201d, destaca o gerente financeiro e de eventos da CIC Teut\u00f4nia, realizadora do encontro, Alexander Bl\u00f6mker.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele afirma que pessoas de diferentes regi\u00f5es do Estado j\u00e1 confirmaram participa\u00e7\u00e3o, como de Novo Hamburgo, Porto Alegre, Flores da Cunha, Bento Gon\u00e7alves, Vale Real, Santa Cruz do Sul, Nova Petr\u00f3polis, Lajeado, Estrela, al\u00e9m dos anfitri\u00f5es de Teut\u00f4nia. Entre os exemplares j\u00e1 inscritos est\u00e3o, por exemplo, Ford F-1 1951, Ford Perfect 1951, MP Lafer 1973, Ford Modelo T 1928, Santa Matilde 1986, Bel Air 1957, os ic\u00f4nicos Maverick, Landau e Crysler, entre outras marcas e modelos hist\u00f3ricos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ingresso para o p\u00fablico \u00e9 gratuito na noite de sexta-feira e no s\u00e1bado at\u00e9 \u00e0s 13h. Depois desse hor\u00e1rio e no domingo ingressos custar\u00e3o R$ 10,00 por pessoa. O 13\u00ba Encontro Nacional de Ve\u00edculos Antigos \u00e9 uma realiza\u00e7\u00e3o da CIC Teut\u00f4nia, com patroc\u00ednio de Certel e Sicredi, apoio de Veteran Car Teut\u00f4nia, Federa\u00e7\u00e3o Brasileira de Ve\u00edculos Antigos e Prefeitura de Teut\u00f4nia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Desde a primeira edi\u00e7\u00e3o<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O antigomobilista Adriano Bortolotto, de Lajeado, participa desde a primeira edi\u00e7\u00e3o, em 2002. Na \u00e9poca ele ainda residia em Carlos Barbosa e descia a Serra com amigos para prestigiar o evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este ano ir\u00e1 expor dois autom\u00f3veis: VW Variant 1976 e GM Chevette SE 1987. \u201cJ\u00e1 participo da programa\u00e7\u00e3o na sexta-feira, levando os autom\u00f3veis. Considero o encontro de Teut\u00f4nia um dos melhores, com excelente organiza\u00e7\u00e3o e num local especial, espa\u00e7o acolhedor e din\u00e2mico aos participantes. Esse evento \u00e9 sempre muito esperado por aqueles que amam o antigomobilismo\u201d, avalia, acrescentando que a fam\u00edlia sempre o acompanha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bortolotto tamb\u00e9m elogia a aten\u00e7\u00e3o aos detalhes. \u201cO evento se destaca pela recep\u00e7\u00e3o aos inscritos, nos convidando para um saboroso caf\u00e9 da manh\u00e3; pela \u00e1rea destinada \u00e0 alimenta\u00e7\u00e3o, onde encontramos diversas op\u00e7\u00f5es; pela variedade em shows. Percebemos a equipe da organiza\u00e7\u00e3o sempre circulando e sol\u00edcita com as pessoas que est\u00e3o chegando. Para quem procura pe\u00e7as para seus projetos, artigos decorativos, itens antigos colecion\u00e1veis ou ve\u00edculos \u00e0 venda, tamb\u00e9m \u00e9 um \u00f3timo evento\u201d, acrescenta.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"803\" height=\"1024\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/Adriano-Bortolotto-JORNAL-e1678823020394-803x1024.jpeg\" alt=\"\" class=\"wp-image-123126\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/Adriano-Bortolotto-JORNAL-e1678823020394-803x1024.jpeg 803w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/Adriano-Bortolotto-JORNAL-e1678823020394-235x300.jpeg 235w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/Adriano-Bortolotto-JORNAL-e1678823020394-768x979.jpeg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/Adriano-Bortolotto-JORNAL-e1678823020394-696x887.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/Adriano-Bortolotto-JORNAL-e1678823020394.jpeg 829w\" sizes=\"auto, (max-width: 803px) 100vw, 803px\" \/><figcaption class=\"wp-element-caption\">Adriano Bortolotto participa dos encontros de Teut\u00f4nia desde a primeira edi\u00e7\u00e3o, em 2002\n Cr\u00e9dito: Arquivo pessoal<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>Confira a programa\u00e7\u00e3o <\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Na sexta-feira (17\/3) das 8h \u00e0s 18h estar\u00e3o abertas as inscri\u00e7\u00f5es dos antigomobilistas; e \u00e0s 20h30 ocorre show com a Banda Apple.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No s\u00e1bado (18\/3), das 8h \u00e0s 18h inscri\u00e7\u00f5es dos antigomobilistas; 8h \u00e0s 10h caf\u00e9 da manh\u00e3 de recep\u00e7\u00e3o dos antigomobilistas; 14h abertura oficial; 15h30 show com Trio Marco, Nando e N\u00edcolas (Pop e Rock Nacional e Internacional); 18h show com Rafa Haas (Country, Rock, Southern e Blues); e 20h30 show com a Banda Gramof\u00f4nica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No domingo (19\/3) das 8h \u00e0s 15h30 inscri\u00e7\u00f5es dos antigomobilistas; 8h \u00e0s 10h caf\u00e9 da manh\u00e3 de recep\u00e7\u00e3o dos antigomobilistas; 14h30 solenidade de premia\u00e7\u00e3o dos ve\u00edculos destaque; 16h show com a Banda Rock and Beer; e 18h encerramento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1308-JORNAL-1024x607.jpg\" alt=\"\" class=\"wp-image-123128\" width=\"1024\" height=\"607\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1308-JORNAL-1024x607.jpg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1308-JORNAL-300x178.jpg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1308-JORNAL-768x456.jpg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1308-JORNAL-1536x911.jpg 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1308-JORNAL-2048x1215.jpg 2048w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1308-JORNAL-696x413.jpg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1308-JORNAL-1068x634.jpg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1308-JORNAL-1920x1139.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">&nbsp;Evento atrai as fam\u00edlias e seus \u201cdiversos integrantes\u201d. Visitantes s\u00e3o acolhidos no ambiente especial do Centro Administrativo de Teut\u00f4nia, um dos principais pontos tur\u00edsticos do Vale do Taquari Cr\u00e9dito: AI<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Inscri\u00e7\u00e3o<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O encontro \u00e9 aberto a todas as categorias de ve\u00edculos antigos e afins (autom\u00f3veis, motos, utilit\u00e1rios, caminh\u00f5es e \u00f4nibus) com mais de 30 anos de fabrica\u00e7\u00e3o, nacionais e importados, com exce\u00e7\u00e3o para ve\u00edculos considerados cl\u00e1ssicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inscri\u00e7\u00f5es antecipadas podem ser efetuadas pelo site oficial do evento (<a href=\"http:\/\/www.carrosantigosteutonia.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.carrosantigosteutonia.com.br<\/a>), junto \u00e0 Secretaria da CIC Teut\u00f4nia pelo fone (51) 3762-1233 e e-mail&nbsp;<a href=\"mailto:carrosantigos@cicteutonia.com.br\" target=\"_blank\" rel=\"noreferrer noopener\">carrosantigos@cicteutonia.com.br<\/a>, ou ainda pelo WhatsApp (51) 99828-5340. O investimento \u00e9 de R$ 60,00 por ve\u00edculo participante, o que d\u00e1 direito a caf\u00e9 da manh\u00e3 no s\u00e1bado ou no domingo para uma pessoa, entrada gratuita para o motorista e um acompanhante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A inscri\u00e7\u00e3o antecipada garante ao expositor um melhor posicionamento dos seus ve\u00edculos no local da exposi\u00e7\u00e3o, conforme crit\u00e9rios da organiza\u00e7\u00e3o. Os clubes de marcas podem efetuar inscri\u00e7\u00e3o antecipada de todos os participantes para que a organiza\u00e7\u00e3o garanta um local para todos os ve\u00edculos ficarem no mesmo espa\u00e7o. O regulamento completo tamb\u00e9m est\u00e1 dispon\u00edvel no site do evento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A poucos dias do 13\u00ba Encontro Nacional de Ve\u00edculos Antigos de Teut\u00f4nia, que ocorre neste fim de semana (17 a 19\/3), no Centro Administrativo Municipal, a procura dos antigomobilistas para exposi\u00e7\u00e3o de rel\u00edquias \u00e9 grande. Segundo a comiss\u00e3o organizadora, as inscri\u00e7\u00f5es antecipadas aumentam diariamente, o que confirma a expectativa de que esse possa ser o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":123129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,10999],"tags":[11230,4720,369,6466,26,2614,10921],"class_list":["post-123123","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-entretenimento","tag-antigos","tag-carros","tag-encontro","tag-evento","tag-teutonia","tag-veiculos","tag-veiculos-antigos","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira - Folha Popular<\/title>\n<meta name=\"description\" content=\"O encontro \u00e9 aberto a todas as categorias de ve\u00edculos antigos e afins-autom\u00f3veis, motos, utilit\u00e1rios, caminh\u00f5es e \u00f4nibus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O encontro \u00e9 aberto a todas as categorias de ve\u00edculos antigos e afins-autom\u00f3veis, motos, utilit\u00e1rios, caminh\u00f5es e \u00f4nibus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-14T19:42:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-14T19:44:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1172-JORNAL-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira\",\"datePublished\":\"2023-03-14T19:42:30+00:00\",\"dateModified\":\"2023-03-14T19:44:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/\"},\"wordCount\":823,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/DSC_1172-JORNAL-scaled.jpg\",\"keywords\":[\"antigos\",\"Carros\",\"Encontro\",\"Evento\",\"Teut\u00f4nia\",\"Ve\u00edculos\",\"ve\u00edculos antigos\"],\"articleSection\":[\"Destaques\",\"Entretenimento\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/\",\"name\":\"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/DSC_1172-JORNAL-scaled.jpg\",\"datePublished\":\"2023-03-14T19:42:30+00:00\",\"dateModified\":\"2023-03-14T19:44:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"description\":\"O encontro \u00e9 aberto a todas as categorias de ve\u00edculos antigos e afins-autom\u00f3veis, motos, utilit\u00e1rios, caminh\u00f5es e \u00f4nibus\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/DSC_1172-JORNAL-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/DSC_1172-JORNAL-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Encontro \u00e9 aberto a todas as categorias de ve\u00edculos antigos e afins (autom\u00f3veis, motos, utilit\u00e1rios, caminh\u00f5es e \u00f4nibus) com mais de 30 anos de fabrica\u00e7\u00e3o, nacionais e importados, exce\u00e7\u00e3o para ve\u00edculos considerados cl\u00e1ssicos Cr\u00e9dito: AI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/03\\\/14\\\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira - Folha Popular","description":"O encontro \u00e9 aberto a todas as categorias de ve\u00edculos antigos e afins-autom\u00f3veis, motos, utilit\u00e1rios, caminh\u00f5es e \u00f4nibus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/","og_locale":"pt_BR","og_type":"article","og_title":"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira - Folha Popular","og_description":"O encontro \u00e9 aberto a todas as categorias de ve\u00edculos antigos e afins-autom\u00f3veis, motos, utilit\u00e1rios, caminh\u00f5es e \u00f4nibus","og_url":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/","og_site_name":"Folha Popular","article_published_time":"2023-03-14T19:42:30+00:00","article_modified_time":"2023-03-14T19:44:36+00:00","og_image":[{"width":2560,"height":1707,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1172-JORNAL-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira","datePublished":"2023-03-14T19:42:30+00:00","dateModified":"2023-03-14T19:44:36+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/"},"wordCount":823,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1172-JORNAL-scaled.jpg","keywords":["antigos","Carros","Encontro","Evento","Teut\u00f4nia","Ve\u00edculos","ve\u00edculos antigos"],"articleSection":["Destaques","Entretenimento"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/","url":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/","name":"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1172-JORNAL-scaled.jpg","datePublished":"2023-03-14T19:42:30+00:00","dateModified":"2023-03-14T19:44:36+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"description":"O encontro \u00e9 aberto a todas as categorias de ve\u00edculos antigos e afins-autom\u00f3veis, motos, utilit\u00e1rios, caminh\u00f5es e \u00f4nibus","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1172-JORNAL-scaled.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1172-JORNAL-scaled.jpg","width":2560,"height":1707,"caption":"Encontro \u00e9 aberto a todas as categorias de ve\u00edculos antigos e afins (autom\u00f3veis, motos, utilit\u00e1rios, caminh\u00f5es e \u00f4nibus) com mais de 30 anos de fabrica\u00e7\u00e3o, nacionais e importados, exce\u00e7\u00e3o para ve\u00edculos considerados cl\u00e1ssicos Cr\u00e9dito: AI"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2023\/03\/14\/encontro-de-veiculos-antigos-em-teutonia-comeca-nesta-sexta-feira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Encontro de ve\u00edculos antigos em Teut\u00f4nia come\u00e7a nesta sexta-feira"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/03\/DSC_1172-JORNAL-scaled.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/123123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=123123"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/123123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/123129"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=123123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=123123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=123123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}