{"id":126182,"date":"2023-04-19T14:24:01","date_gmt":"2023-04-19T17:24:01","guid":{"rendered":"https:\/\/folhapopular.info\/?p=126182"},"modified":"2023-04-19T14:24:47","modified_gmt":"2023-04-19T17:24:47","slug":"agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/","title":{"rendered":"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Na manh\u00e3 desta quarta-feira (19\/04) representantes sindicais realizaram uma manifesta\u00e7\u00e3o em Estrela, pedindo por recursos por conta da estiagem. Coordenador da Regional Sindical\u00a0Vale do Taquari,\u00a0Marcos\u00a0Hinrichsen, diz que h\u00e1 tr\u00eas meses o grupo est\u00e1 tentando negociar solu\u00e7\u00f5es para esses preju\u00edzos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele cita que neste a agricultura familiar teve perdas, altos de investimento, custo de produ\u00e7\u00e3o, eleva\u00e7\u00e3o nesses valores e tudo deixou a produ\u00e7\u00e3o mais cara. &#8220;A estiagem junto, fez com quem o agricultor se descapitalize.&#8221; Esse tema, conforme o coordenador est\u00e1 desde janeiro em pauta, com mobiliza\u00e7\u00f5es feita na capital e demais reuni\u00f5es para tentar amenizar. &#8220;Ainda n\u00e3o tivemos o avan\u00e7o necess\u00e1rio ent\u00e3o hoje 15 regi\u00f5es do estado pararam para fazer mais um momento pedindo por aux\u00edlio&#8221;, comenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cerca de 200 pessoas da regi\u00e3o participaram da manifesta\u00e7\u00e3o em Estrela. Al\u00e9m de ir em institui\u00e7\u00f5es como Caixa e STR, o grupo tamb\u00e9m teve reunido com o presidente da Amvat e prefeito do munic\u00edpio, Elmar Schneider. &#8220;Hoje nos atingimos a meta do dia e ficamos esperando o retorno das negocia\u00e7\u00f5es que acontecem a n\u00edvel federal.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>*Colabora\u00e7\u00e3o: J\u00falio C\u00e9sar Lenhardt <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Leia mais:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-folha-popular wp-block-embed-folha-popular\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"tZRnYTOExj\"><a href=\"https:\/\/folhapopular.info\/index.php\/2023\/04\/16\/perdas-pela-estiagem-passam-de-55-milhoes-na-regiao\/\">Perdas pela estiagem passam de R$ 55 milh\u00f5es na regi\u00e3o<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Perdas pela estiagem passam de R$ 55 milh\u00f5es na regi\u00e3o&#8221; &#8212; Folha Popular\" src=\"https:\/\/folhapopular.info\/index.php\/2023\/04\/16\/perdas-pela-estiagem-passam-de-55-milhoes-na-regiao\/embed\/#?secret=YihEkRNKy7#?secret=tZRnYTOExj\" data-secret=\"tZRnYTOExj\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta quarta-feira (19\/04) representantes sindicais realizaram uma manifesta\u00e7\u00e3o em Estrela, pedindo por recursos por conta da estiagem. Coordenador da Regional Sindical\u00a0Vale do Taquari,\u00a0Marcos\u00a0Hinrichsen, diz que h\u00e1 tr\u00eas meses o grupo est\u00e1 tentando negociar solu\u00e7\u00f5es para esses preju\u00edzos. Ele cita que neste a agricultura familiar teve perdas, altos de investimento, custo de produ\u00e7\u00e3o, eleva\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":644,"featured_media":126184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,10994],"tags":[5726,4308,5162,11894,4101,11027],"class_list":["post-126182","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-rural","tag-estiagem","tag-fetag","tag-manifestacao","tag-perda","tag-produtores","tag-rural","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem - Folha Popular<\/title>\n<meta name=\"description\" content=\"Coordenador da Regional Sindical\u00a0Vale do Taquari,\u00a0Marcos\u00a0Hinrichsen, diz que h\u00e1 tr\u00eas meses o grupo est\u00e1 tentando negociar solu\u00e7\u00f5es para esses preju\u00edzos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Coordenador da Regional Sindical\u00a0Vale do Taquari,\u00a0Marcos\u00a0Hinrichsen, diz que h\u00e1 tr\u00eas meses o grupo est\u00e1 tentando negociar solu\u00e7\u00f5es para esses preju\u00edzos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-19T17:24:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-19T17:24:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduarda Wenzel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduarda Wenzel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/\"},\"author\":{\"name\":\"Eduarda Wenzel\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/56503b37bb37e34ad83486450c8dd536\"},\"headline\":\"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem\",\"datePublished\":\"2023-04-19T17:24:01+00:00\",\"dateModified\":\"2023-04-19T17:24:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/\"},\"wordCount\":225,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg\",\"keywords\":[\"Estiagem\",\"FETAG\",\"manifesta\u00e7\u00e3o\",\"perda\",\"Produtores\",\"rural\"],\"articleSection\":[\"Destaques\",\"Rural\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/\",\"name\":\"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg\",\"datePublished\":\"2023-04-19T17:24:01+00:00\",\"dateModified\":\"2023-04-19T17:24:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/56503b37bb37e34ad83486450c8dd536\"},\"description\":\"Coordenador da Regional Sindical\u00a0Vale do Taquari,\u00a0Marcos\u00a0Hinrichsen, diz que h\u00e1 tr\u00eas meses o grupo est\u00e1 tentando negociar solu\u00e7\u00f5es para esses preju\u00edzos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg\",\"width\":1600,\"height\":900,\"caption\":\"Movimento contou com cerca de 200 pessoas \\\/ Cr\u00e9dito: J\u00falio C\u00e9sar Lenhrdt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/19\\\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/56503b37bb37e34ad83486450c8dd536\",\"name\":\"Eduarda Wenzel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84a92258d5ebb7523b3978df951af09337f402d618cba5001aa8b2a2fc633090?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84a92258d5ebb7523b3978df951af09337f402d618cba5001aa8b2a2fc633090?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84a92258d5ebb7523b3978df951af09337f402d618cba5001aa8b2a2fc633090?s=96&d=mm&r=g\",\"caption\":\"Eduarda Wenzel\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/eduarda-wenzeluniverso-univates-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem - Folha Popular","description":"Coordenador da Regional Sindical\u00a0Vale do Taquari,\u00a0Marcos\u00a0Hinrichsen, diz que h\u00e1 tr\u00eas meses o grupo est\u00e1 tentando negociar solu\u00e7\u00f5es para esses preju\u00edzos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/","og_locale":"pt_BR","og_type":"article","og_title":"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem - Folha Popular","og_description":"Coordenador da Regional Sindical\u00a0Vale do Taquari,\u00a0Marcos\u00a0Hinrichsen, diz que h\u00e1 tr\u00eas meses o grupo est\u00e1 tentando negociar solu\u00e7\u00f5es para esses preju\u00edzos.","og_url":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/","og_site_name":"Folha Popular","article_published_time":"2023-04-19T17:24:01+00:00","article_modified_time":"2023-04-19T17:24:47+00:00","og_image":[{"width":1600,"height":900,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg","type":"image\/jpeg"}],"author":"Eduarda Wenzel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduarda Wenzel","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/"},"author":{"name":"Eduarda Wenzel","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/56503b37bb37e34ad83486450c8dd536"},"headline":"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem","datePublished":"2023-04-19T17:24:01+00:00","dateModified":"2023-04-19T17:24:47+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/"},"wordCount":225,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg","keywords":["Estiagem","FETAG","manifesta\u00e7\u00e3o","perda","Produtores","rural"],"articleSection":["Destaques","Rural"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/","url":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/","name":"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg","datePublished":"2023-04-19T17:24:01+00:00","dateModified":"2023-04-19T17:24:47+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/56503b37bb37e34ad83486450c8dd536"},"description":"Coordenador da Regional Sindical\u00a0Vale do Taquari,\u00a0Marcos\u00a0Hinrichsen, diz que h\u00e1 tr\u00eas meses o grupo est\u00e1 tentando negociar solu\u00e7\u00f5es para esses preju\u00edzos.","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg","width":1600,"height":900,"caption":"Movimento contou com cerca de 200 pessoas \/ Cr\u00e9dito: J\u00falio C\u00e9sar Lenhrdt"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/19\/agricultores-pedem-auxilio-do-governo-federal-para-arcar-com-prejuizos-da-estiagem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Agricultores pedem aux\u00edlio do Governo Federal para arcar com preju\u00edzos da estiagem"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/56503b37bb37e34ad83486450c8dd536","name":"Eduarda Wenzel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/84a92258d5ebb7523b3978df951af09337f402d618cba5001aa8b2a2fc633090?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84a92258d5ebb7523b3978df951af09337f402d618cba5001aa8b2a2fc633090?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84a92258d5ebb7523b3978df951af09337f402d618cba5001aa8b2a2fc633090?s=96&d=mm&r=g","caption":"Eduarda Wenzel"},"url":"https:\/\/folhapopular.info\/index.php\/author\/eduarda-wenzeluniverso-univates-br\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-19-at-13.59.52.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/126182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/644"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=126182"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/126182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/126184"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=126182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=126182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=126182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}