{"id":126633,"date":"2023-04-28T07:30:00","date_gmt":"2023-04-28T10:30:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=126633"},"modified":"2023-04-27T16:47:44","modified_gmt":"2023-04-27T19:47:44","slug":"parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/","title":{"rendered":"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade"},"content":{"rendered":"\n<p><span style=\"background-color: transparent; font-size: 12pt; font-family: Arial; font-variant-numeric: normal; font-variant-east-asian: normal; vertical-align: baseline;\">O Programa Sa\u00fade na Escola (PSE) \u00e9 uma iniciativa do Minist\u00e9rio da Sa\u00fade para integrar e articular a\u00e7\u00f5es de educa\u00e7\u00e3o e sa\u00fade para melhorar a qualidade de vida da popula\u00e7\u00e3o escolar e ampliar o acesso aos servi\u00e7os de sa\u00fade. E em parceria com a Secretaria Municipal de Sa\u00fade de Lajeado (Sesa), estudantes do curso de Medicina da <\/span><a data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.univates.br&amp;source=gmail&amp;ust=1682710814947000&amp;usg=AOvVaw3s5B9m_IVhes3YEInLa4e6\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: small; white-space: normal; color: rgb(17, 85, 204);\" href=\"http:\/\/www.univates.br\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 12pt; font-family: Arial; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; text-decoration-line: underline; vertical-align: baseline; white-space: pre-wrap;\">Universidade do Vale do Taquari  (Univates)<\/span><\/a><span style=\"background-color: transparent; font-size: 12pt; font-family: Arial; font-variant-numeric: normal; font-variant-east-asian: normal; vertical-align: baseline;\"> participam do programa desenvolvendo a\u00e7\u00f5es em escolas p\u00fablicas do munic\u00edpio.<\/span><\/p>\n\n\n\n<p><p dir=\"ltr\" style=\"color: rgb(34, 34, 34); font-family: Arial, Helvetica, sans-serif; font-size: small; white-space: normal; line-height: 1.38; margin-top: 0pt; margin-bottom: 0pt;\"><span style=\"font-size: 12pt; font-family: Arial; color: rgb(0, 0, 0); background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; vertical-align: baseline; white-space: pre-wrap;\">Conforme a professora C\u00e1ssia Regina Gotler Medeiros, que coordena o m\u00f3dulo Sa\u00fade e Sociedade III do curso de Medicina, o PSE prop\u00f5e 13 tipos de a\u00e7\u00f5es de sa\u00fade. No final do m\u00eas de mar\u00e7o, 39 estudantes do terceiro semestre do curso participaram de uma a\u00e7\u00e3o de educa\u00e7\u00e3o em sa\u00fade na Escola Municipal de Ensino Fundamental (Emef) Lauro Mathias M\u00fcller. Alunos do 4\u00ba ao 9\u00ba ano foram beneficiados.Uma turma do 12\u00ba semestre do curso tamb\u00e9m realizou testes de acuidade visual e antropometria para alunos da Escola Estadual de Ensino Fundamental Ind\u00edgena (Gaten). A atividade faz parte do est\u00e1gio de Sa\u00fade Coletiva, que \u00e9 coordenado pela professora C\u00e1ssia e orientado pelo preceptor Bernardo Paulino Sotero.<\/span><\/p><\/p>\n\n\n\n<p><p dir=\"ltr\" style=\"color: rgb(34, 34, 34); font-family: Arial, Helvetica, sans-serif; font-size: small; white-space: normal; line-height: 1.38; margin-top: 0pt; margin-bottom: 0pt;\"><span style=\"font-size: 12pt; font-family: Arial; color: rgb(0, 0, 0); background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; vertical-align: baseline; white-space: pre-wrap;\">J\u00e1 Luana Wollinger, coordenadora do PSE no munic\u00edpio, diz que a participa\u00e7\u00e3o dos estudantes de Medicina da Univates no Programa foi articulada com o objetivo de qualificar as a\u00e7\u00f5es nas escolas e auxiliar as equipes de sa\u00fade, al\u00e9m de oportunizar aos estudantes a pr\u00e1tica na aten\u00e7\u00e3o prim\u00e1ria em sa\u00fade. <\/span><span style=\"font-size: 12pt; font-family: Arial; color: rgb(0, 0, 0); background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; vertical-align: baseline; white-space: pre-wrap;\"><\/span><span style=\"font-size: 12pt; font-family: Arial; color: rgb(0, 0, 0); background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; vertical-align: baseline; white-space: pre-wrap;\">&#8220;Os alunos participaram da reuni\u00e3o geral do Programa em mar\u00e7o e j\u00e1 foram proativos em conversar com as equipes de sa\u00fade e orientadores das escolas, a fim de organizar um cronograma de a\u00e7\u00f5es nos bairros e escolas espec\u00edficas com mais demandas no momento. Os relatos recebidos das escolas nas quais os alunos foram s\u00e3o os melhores poss\u00edveis. Estou muito feliz com essa parceria&#8221;, destaca Luana.<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Programa Sa\u00fade na Escola (PSE) \u00e9 uma iniciativa do Minist\u00e9rio da Sa\u00fade para integrar e articular a\u00e7\u00f5es de educa\u00e7\u00e3o e sa\u00fade para melhorar a qualidade de vida da popula\u00e7\u00e3o escolar e ampliar o acesso aos servi\u00e7os de sa\u00fade. E em parceria com a Secretaria Municipal de Sa\u00fade de Lajeado (Sesa), estudantes do curso de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":126634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,10986],"tags":[5155,5366,940,83],"class_list":{"0":"post-126633","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-saude","9":"tag-alunos","10":"tag-comunidade","11":"tag-medicina","12":"tag-univates","13":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O Programa Sa\u00fade na Escola (PSE) \u00e9 uma iniciativa do Minist\u00e9rio da Sa\u00fade para integrar e articular a\u00e7\u00f5es de educa\u00e7\u00e3o e sa\u00fade para melhorar a qualidade de vida da popula\u00e7\u00e3o escolar e ampliar o acesso aos servi\u00e7os de sa\u00fade. E em parceria com a Secretaria Municipal de Sa\u00fade de Lajeado (Sesa), estudantes do curso de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-28T10:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1528\" \/>\n\t<meta property=\"og:image:height\" content=\"1528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade\",\"datePublished\":\"2023-04-28T10:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/\"},\"wordCount\":357,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg\",\"keywords\":[\"alunos\",\"Comunidade\",\"Medicina\",\"Univates\"],\"articleSection\":[\"Destaques\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/\",\"name\":\"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg\",\"datePublished\":\"2023-04-28T10:30:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg\",\"width\":1528,\"height\":1528,\"caption\":\"1, 2 e 3) A\u00e7\u00f5es desenvolvidas pelos estudantes de Medicina. \\\/ Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/04\\\/28\\\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade - Folha Popular","og_description":"O Programa Sa\u00fade na Escola (PSE) \u00e9 uma iniciativa do Minist\u00e9rio da Sa\u00fade para integrar e articular a\u00e7\u00f5es de educa\u00e7\u00e3o e sa\u00fade para melhorar a qualidade de vida da popula\u00e7\u00e3o escolar e ampliar o acesso aos servi\u00e7os de sa\u00fade. E em parceria com a Secretaria Municipal de Sa\u00fade de Lajeado (Sesa), estudantes do curso de [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/","og_site_name":"Folha Popular","article_published_time":"2023-04-28T10:30:00+00:00","og_image":[{"width":1528,"height":1528,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade","datePublished":"2023-04-28T10:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/"},"wordCount":357,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg","keywords":["alunos","Comunidade","Medicina","Univates"],"articleSection":["Destaques","Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/","url":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/","name":"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg","datePublished":"2023-04-28T10:30:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg","width":1528,"height":1528,"caption":"1, 2 e 3) A\u00e7\u00f5es desenvolvidas pelos estudantes de Medicina. \/ Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2023\/04\/28\/parceria-da-univates-com-a-secretaria-municipal-de-saude-reforca-insercao-de-estudantes-comunidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Parceria da Univates com a Secretaria Municipal de Sa\u00fade refor\u00e7a inser\u00e7\u00e3o de estudantes comunidade"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/04\/3-Acoes-desenvolvidas-pelos-estudantes-de-Medicina-Credito-Divulgacao.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/126633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=126633"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/126633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/126634"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=126633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=126633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=126633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}