{"id":137619,"date":"2023-08-14T16:56:16","date_gmt":"2023-08-14T19:56:16","guid":{"rendered":"https:\/\/folhapopular.info\/?p=137619"},"modified":"2023-08-14T16:56:19","modified_gmt":"2023-08-14T19:56:19","slug":"tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/","title":{"rendered":"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela"},"content":{"rendered":"\n<p>Tr\u00eas pessoas ficaram feridas em uma colis\u00e3o envolvendo dois ve\u00edculos em Estrela nesta segunda-feira (14\/8). O fato ocorreu por volta das 10h25 na ERS-129, na localidade de S\u00e3o Jos\u00e9. Colidiram os ve\u00edculos Volvo XC60 e uma Montana. <\/p>\n\n\n\n<p>O condutor da Montana, de 55 anos, e a passageira, de 71 anos, foram encaminhados para atendimento no Hospital Estrela pelo SAMU e Bombeiros. A condutora do Volvo, por meios pr\u00f3prios, buscou atendimento no Hospital Bruno Born, em Lajeado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas pessoas ficaram feridas em uma colis\u00e3o envolvendo dois ve\u00edculos em Estrela nesta segunda-feira (14\/8). O fato ocorreu por volta das 10h25 na ERS-129, na localidade de S\u00e3o Jos\u00e9. Colidiram os ve\u00edculos Volvo XC60 e uma Montana. O condutor da Montana, de 55 anos, e a passageira, de 71 anos, foram encaminhados para atendimento no [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":137620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7,10983],"tags":[],"class_list":{"0":"post-137619","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-seguranca","8":"category-transito","9":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Tr\u00eas pessoas ficaram feridas em uma colis\u00e3o envolvendo dois ve\u00edculos em Estrela nesta segunda-feira (14\/8). O fato ocorreu por volta das 10h25 na ERS-129, na localidade de S\u00e3o Jos\u00e9. Colidiram os ve\u00edculos Volvo XC60 e uma Montana. O condutor da Montana, de 55 anos, e a passageira, de 71 anos, foram encaminhados para atendimento no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-14T19:56:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-14T19:56:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela\",\"datePublished\":\"2023-08-14T19:56:16+00:00\",\"dateModified\":\"2023-08-14T19:56:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/\"},\"wordCount\":90,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg\",\"articleSection\":[\"Seguran\u00e7a\",\"Tr\u00e2nsito\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/\",\"name\":\"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg\",\"datePublished\":\"2023-08-14T19:56:16+00:00\",\"dateModified\":\"2023-08-14T19:56:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg\",\"width\":1200,\"height\":900,\"caption\":\"Ve\u00edculos colidiram de frante \\\/ Cr\u00e9dito da foto: Divulga\u00e7\u00e3o Bombeiros\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/08\\\/14\\\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/","og_locale":"pt_BR","og_type":"article","og_title":"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela - Folha Popular","og_description":"Tr\u00eas pessoas ficaram feridas em uma colis\u00e3o envolvendo dois ve\u00edculos em Estrela nesta segunda-feira (14\/8). O fato ocorreu por volta das 10h25 na ERS-129, na localidade de S\u00e3o Jos\u00e9. Colidiram os ve\u00edculos Volvo XC60 e uma Montana. O condutor da Montana, de 55 anos, e a passageira, de 71 anos, foram encaminhados para atendimento no [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/","og_site_name":"Folha Popular","article_published_time":"2023-08-14T19:56:16+00:00","article_modified_time":"2023-08-14T19:56:19+00:00","og_image":[{"width":1200,"height":900,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela","datePublished":"2023-08-14T19:56:16+00:00","dateModified":"2023-08-14T19:56:19+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/"},"wordCount":90,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg","articleSection":["Seguran\u00e7a","Tr\u00e2nsito"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/","url":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/","name":"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg","datePublished":"2023-08-14T19:56:16+00:00","dateModified":"2023-08-14T19:56:19+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg","width":1200,"height":900,"caption":"Ve\u00edculos colidiram de frante \/ Cr\u00e9dito da foto: Divulga\u00e7\u00e3o Bombeiros"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2023\/08\/14\/tres-pessoas-ficam-feridas-em-acidente-na-ers-129-em-estrela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Tr\u00eas pessoas ficam feridas em acidente na ERS-129 em Estrela"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-14-at-13.07.25-e1692042968480.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/137619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=137619"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/137619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/137620"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=137619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=137619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=137619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}