{"id":138903,"date":"2023-09-01T16:22:02","date_gmt":"2023-09-01T19:22:02","guid":{"rendered":"https:\/\/folhapopular.info\/?p=138903"},"modified":"2023-09-01T17:28:56","modified_gmt":"2023-09-01T20:28:56","slug":"feira-estrelas-do-conhecimento-encerra-como-sucesso-regional","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/","title":{"rendered":"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Estrelas do Conhecimento, feira educacional dedicada \u00e0 inova\u00e7\u00e3o, ci\u00eancia e tecnologia, encerrou nesta quinta-feira (31\/8) com grande sucesso sua segunda edi\u00e7\u00e3o, com a premia\u00e7\u00e3o dos vencedores da Etapa Regional. A exposi\u00e7\u00e3o, realizada no Porto de Estrela, foi marcada por apresenta\u00e7\u00f5es e premia\u00e7\u00f5es, que destacaram o talento e a dedica\u00e7\u00e3o dos estudantes da regi\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um dos pontos altos do encerramento foi a assinatura do Protocolo de Ades\u00e3o ao Programa Educar para Inovar da Secretaria do Estado de Inova\u00e7\u00e3o, Ci\u00eancia e Tecnologia, com a presen\u00e7a de algumas autoridades da regi\u00e3o. Em seguida foi realizada a apresenta\u00e7\u00e3o da Orquestra Martin Luther, que encantou o p\u00fablico com suas melodias.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A escolha se deu atrav\u00e9s de j\u00fari independente, formado por profissionais de diversos setores, em especial da educa\u00e7\u00e3o, que considerou crit\u00e9rios como a criatividade, a originalidade e o impacto social de cada proposta. Em algumas categorias, como no caso da 5, houve empate entre os trabalhos, e apenas a te\u00f3rica posi\u00e7\u00e3o final em raz\u00e3o da premia\u00e7\u00e3o foi definida por sorteio atrav\u00e9s de pequenas crian\u00e7as presentes ao evento. Tamb\u00e9m foram condecoradas as escolas participantes do espa\u00e7o \u201cEstrelinhas do Conhecimento\u201d, outra novidade da atual edi\u00e7\u00e3o e que foi voltado para a Educa\u00e7\u00e3o Infantil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confira os vencedores em suas respectivas categorias<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Categoria Especial<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Projeto &#8220;Alimenta\u00e7\u00e3o: Qualidade de Vida&#8221; da Escola de Educa\u00e7\u00e3o Especial Cantinho do Sorriso &#8211; Apae, de Estrela.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Anos Iniciais (1\u00ba ao 3\u00ba ano)<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Projeto &#8220;Pequenos Cientistas&#8221; da Emef Leo Joas, de Estrela;<\/li>\n\n\n\n<li>Projeto &#8220;Metamorfose das Borboletas&#8221; da Emef Jos\u00e9 Bonif\u00e1cio, de Estrela;<\/li>\n\n\n\n<li>Projeto &#8220;Borboletas&#8221; da Emef C\u00f4nego Sereno Hugo Wolkmer, de Estrela.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Anos Iniciais (4\u00ba e 5\u00ba ano)<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Projeto &#8220;O Que N\u00f3s Podemos Fazer com a Falta de \u00c1gua em \u00c9poca de Estiagem?&#8221; da Emef Ad\u00e9lia Corbellini, de S\u00e9rio.<\/li>\n\n\n\n<li>Projeto &#8220;Compostagem: Uso Consciente do Res\u00edduo Org\u00e2nico, Garantindo uma Vida \u00datil Prolongada aos Nossos Aterros Sanit\u00e1rios&#8221; da Emef Pinheiros, de Estrela.<\/li>\n\n\n\n<li>Projeto &#8220;Compreendendo a Rob\u00f3tica nas Aulas do 4\u00ba Ano: Observa\u00e7\u00e3o e Cria\u00e7\u00e3o&#8221; da Emef C\u00f4nego Sereno Hugo Wolkmer, de Estrela.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Anos Finais (6\u00ba e 7\u00ba ano)<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Projeto &#8220;Preconceito Lingu\u00edstico&#8221; da Emef Leo Joas, de Estrela.<\/li>\n\n\n\n<li>Projeto &#8220;Descarte de Res\u00edduos&#8221; na Emef Mundo Encantado, de Encantado.<\/li>\n\n\n\n<li>Projeto &#8220;Ecolocaliza\u00e7\u00e3o Humana: Investiga\u00e7\u00e3o Bibliogr\u00e1fica e Sua Aplicabilidade&#8221; da Emef C\u00f4nego Sereno Hugo Wolkmer, de Estrela.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Anos Finais (8\u00ba e 9\u00ba ano)<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Projeto &#8220;A Introdu\u00e7\u00e3o da Leitura e os Impactos no Desenvolvimento Escolar e Pessoal das Crian\u00e7as&#8221; da Emef Leo Joas, de Estrela.<\/li>\n\n\n\n<li>Projeto &#8220;Per\u00edcia Criminal&#8221; da Emef Frei Henrique de Coimbra, de Santa Clara do Sul.<\/li>\n\n\n\n<li>Projeto &#8220;\u00c1caros Predadores: Um M\u00e9todo Sustent\u00e1vel que Ir\u00e1 Revolucionar a Agricultura&#8221; da Emef Arnaldo Jos\u00e9 Diel, de Estrela.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">1\u00ba ao 3\u00ba ano &#8211; Ensino M\u00e9dio<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Projeto &#8220;Divulga\u00e7\u00e3o Cient\u00edfica das Teorias Evolucionistas&#8221; da Eeem Estrela, de Estrela.<\/li>\n\n\n\n<li>Projeto &#8220;A Rela\u00e7\u00e3o Entre Cora\u00e7\u00e3o e Emo\u00e7\u00e3o: Gl\u00e2ndula Timo e Cortisol&#8221; da Eeem Estrela, de Estrela.<\/li>\n\n\n\n<li>Projeto &#8220;Constru\u00e7\u00e3o de Rede de Energia E\u00f3lica para Sustentabilidade de Edif\u00edcios Verdes&#8221; da Eeem Vespasiano Corr\u00eaa, de Vespasiano Corr\u00eaa.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Confira a galeria de imagens <\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-folha-popular wp-block-embed-folha-popular\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"c1hr8aEqcB\"><a href=\"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/2a-estrelas-do-conhecimento-confira-a-galeria-de-imagens\/\">2\u00aa Estrelas do Conhecimento: confira a galeria de imagens<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;2\u00aa Estrelas do Conhecimento: confira a galeria de imagens&#8221; &#8212; Folha Popular\" src=\"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/2a-estrelas-do-conhecimento-confira-a-galeria-de-imagens\/embed\/#?secret=yye53unEKc#?secret=c1hr8aEqcB\" data-secret=\"c1hr8aEqcB\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A Estrelas do Conhecimento, feira educacional dedicada \u00e0 inova\u00e7\u00e3o, ci\u00eancia e tecnologia, encerrou nesta quinta-feira (31\/8) com grande sucesso sua segunda edi\u00e7\u00e3o, com a premia\u00e7\u00e3o dos vencedores da Etapa Regional. A exposi\u00e7\u00e3o, realizada no Porto de Estrela, foi marcada por apresenta\u00e7\u00f5es e premia\u00e7\u00f5es, que destacaram o talento e a dedica\u00e7\u00e3o dos estudantes da regi\u00e3o. Um [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":138921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12732,2,10988,3],"tags":[8774,12708],"class_list":["post-138903","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ciencia-e-tecnologia","category-featured","category-educacao","category-geral","tag-estrelas-do-conhecimento","tag-feira-de-inovacao-ciencia-e-tecnologia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0 - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0 - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Estrelas do Conhecimento, feira educacional dedicada \u00e0 inova\u00e7\u00e3o, ci\u00eancia e tecnologia, encerrou nesta quinta-feira (31\/8) com grande sucesso sua segunda edi\u00e7\u00e3o, com a premia\u00e7\u00e3o dos vencedores da Etapa Regional. A exposi\u00e7\u00e3o, realizada no Porto de Estrela, foi marcada por apresenta\u00e7\u00f5es e premia\u00e7\u00f5es, que destacaram o talento e a dedica\u00e7\u00e3o dos estudantes da regi\u00e3o. Um [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-01T19:22:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-01T20:28:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/IMG_6276.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0\",\"datePublished\":\"2023-09-01T19:22:02+00:00\",\"dateModified\":\"2023-09-01T20:28:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/\"},\"wordCount\":551,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_6276.jpeg\",\"keywords\":[\"Estrelas do Conhecimento\",\"feira de inova\u00e7\u00e3o ci\u00eancia e tecnologia\"],\"articleSection\":[\"Ci\u00eancia e tecnologia\",\"Destaques\",\"Educa\u00e7\u00e3o\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/\",\"name\":\"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0 - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_6276.jpeg\",\"datePublished\":\"2023-09-01T19:22:02+00:00\",\"dateModified\":\"2023-09-01T20:28:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_6276.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_6276.jpeg\",\"width\":2048,\"height\":1536,\"caption\":\"Cr\u00e9dito: Camille Lenz da Silva\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/01\\\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0 - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/","og_locale":"pt_BR","og_type":"article","og_title":"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0 - Folha Popular","og_description":"A Estrelas do Conhecimento, feira educacional dedicada \u00e0 inova\u00e7\u00e3o, ci\u00eancia e tecnologia, encerrou nesta quinta-feira (31\/8) com grande sucesso sua segunda edi\u00e7\u00e3o, com a premia\u00e7\u00e3o dos vencedores da Etapa Regional. A exposi\u00e7\u00e3o, realizada no Porto de Estrela, foi marcada por apresenta\u00e7\u00f5es e premia\u00e7\u00f5es, que destacaram o talento e a dedica\u00e7\u00e3o dos estudantes da regi\u00e3o. Um [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/","og_site_name":"Folha Popular","article_published_time":"2023-09-01T19:22:02+00:00","article_modified_time":"2023-09-01T20:28:56+00:00","og_image":[{"width":2048,"height":1536,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/IMG_6276.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0","datePublished":"2023-09-01T19:22:02+00:00","dateModified":"2023-09-01T20:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/"},"wordCount":551,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/IMG_6276.jpeg","keywords":["Estrelas do Conhecimento","feira de inova\u00e7\u00e3o ci\u00eancia e tecnologia"],"articleSection":["Ci\u00eancia e tecnologia","Destaques","Educa\u00e7\u00e3o","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/","url":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/","name":"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0 - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/IMG_6276.jpeg","datePublished":"2023-09-01T19:22:02+00:00","dateModified":"2023-09-01T20:28:56+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/IMG_6276.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/IMG_6276.jpeg","width":2048,"height":1536,"caption":"Cr\u00e9dito: Camille Lenz da Silva"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/01\/feira-estrelas-do-conhecimento-encerra-como-sucesso-regional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Feira Estrelas do Conhecimento encerra como sucesso regional\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/IMG_6276.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/138903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=138903"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/138903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/138921"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=138903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=138903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=138903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}