{"id":139365,"date":"2023-09-07T17:17:35","date_gmt":"2023-09-07T20:17:35","guid":{"rendered":"https:\/\/folhapopular.info\/?p=139365"},"modified":"2023-09-07T17:17:38","modified_gmt":"2023-09-07T20:17:38","slug":"situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/","title":{"rendered":"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O governo do Estado monitora, continuamente, o n\u00edvel dos rios em todo o Rio Grande do Sul. Neste momento, alguns rios come\u00e7am a baixar, ao passo que outros est\u00e3o subindo. A situa\u00e7\u00e3o, portanto, ainda requer aten\u00e7\u00e3o. Conforme o boletim de monitoramento hidrol\u00f3gico, fechado por volta das 10h desta quinta-feira (7\/9), boa parte dos rios do Estado apresentam n\u00edveis de aten\u00e7\u00e3o, com diferentes desdobramentos da situa\u00e7\u00e3o, conforme as regi\u00f5es. A situa\u00e7\u00e3o que requer mais aten\u00e7\u00e3o \u00e9 a do Gua\u00edba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acompanhamento \u00e9 realizado pela Sala de Situa\u00e7\u00e3o da Secretaria do Meio Ambiente e Infraestrutura (Sema), em articula\u00e7\u00e3o com a Defesa Civil estadual. A partir da medi\u00e7\u00e3o do n\u00edvel dos rios em diversas esta\u00e7\u00f5es do Estado, os profissionais realizam as an\u00e1lises, que levam em considera\u00e7\u00e3o tr\u00eas limiares: aten\u00e7\u00e3o, alerta e inunda\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A medi\u00e7\u00e3o do Rio Gua\u00edba na Esta\u00e7\u00e3o Cais Mau\u00e1 C6 marcou, nesta quinta, 2,43 metros. O hidr\u00f3logo Pedro Camargo, da Sala de Situa\u00e7\u00e3o, aponta que a tend\u00eancia \u00e9 de o Gua\u00edba continuar subindo nas pr\u00f3ximas 24 horas, com reflexos nas ilhas do Delta do Jacu\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO principal problema agora \u00e9 a evolu\u00e7\u00e3o dos n\u00edveis do Gua\u00edba. Ele acabar\u00e1 recebendo o pico das cheias do Taquari e dos Sinos. Permaneceremos analisando o comportamento do Gua\u00edba, que \u00e9 influenciado por v\u00e1rios fatores, inclusive a dire\u00e7\u00e3o dos ventos. Naturalmente, com o escoamento da \u00e1gua, ele subir\u00e1 um pouco, podendo atingir, no m\u00e1ximo, tr\u00eas metros, que \u00e9 a cota de extravasamento dele no cais\u201d, explicou Camargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Rio dos Sinos est\u00e1 acima da cota de inunda\u00e7\u00e3o e apresenta eleva\u00e7\u00e3o. Os rios Taquari, Jacu\u00ed e Ca\u00ed, que tamb\u00e9m est\u00e3o acima da cota, apresentam estabilidade ou decl\u00ednio. As bacias do M\u00e9dio Uruguai, Ibicu\u00ed, Gravata\u00ed e Gua\u00edba apresentam n\u00edveis em alerta.\u00a0O Sinos marcou 4,48 metros na esta\u00e7\u00e3o de S\u00e3o Leopoldo e 7,26 metros na de Campo Bom. A perspectiva \u00e9 de que essa eleva\u00e7\u00e3o se converta em estabilidade nesta quinta-feira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Gravata\u00ed, que apresenta uma eleva\u00e7\u00e3o considerada bastante lenta, subindo menos de um cent\u00edmetro por hora, deve entrar em estabilidade e depois em decl\u00ednio, nos pr\u00f3ximos dias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No Vale do Taquari, regi\u00e3o bastante afetada pelas enxurradas, o pico da cheia j\u00e1 passou, e a tend\u00eancia agora \u00e9 decl\u00ednio, at\u00e9 os rios voltarem a limiares normais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O alerta para inunda\u00e7\u00e3o do Rio Jacu\u00ed, a partir de Triunfo at\u00e9 o Delta do Jacu\u00ed e ilhas do Gua\u00edba, foi renovado na manh\u00e3 desta quinta, com vig\u00eancia at\u00e9 as 9h de sexta (8\/9). \u201cEm Triunfo, o rio j\u00e1 est\u00e1 come\u00e7ando a apresentar decl\u00ednio, por\u00e9m a onda de cheia que veio desde o Taquari ainda continua fluindo, chegando ao Delta do Jacu\u00ed e ao Gua\u00edba. Ent\u00e3o, requer aten\u00e7\u00e3o, principalmente em rela\u00e7\u00e3o \u00e0s ilhas do Gua\u00edba\u201d, ressaltou Camargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O alerta para o rio dos Sinos, emitido na quarta-feira (6\/9) pela Defesa Civil, tem vig\u00eancia at\u00e9 a tarde desta quinta. Segundo a Sala de Situa\u00e7\u00e3o, esse alerta deve ser renovado porque, em S\u00e3o Leopoldo, o rio est\u00e1 em eleva\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As bacias do Ibicu\u00ed e do M\u00e9dio Uruguai est\u00e3o com esta\u00e7\u00f5es em alerta. O Rio Uruguai, em S\u00e3o Borja, apresenta uma lenta, mas persistente, eleva\u00e7\u00e3o. H\u00e1 possibilidade de emiss\u00e3o de alerta, nesta quinta, para inunda\u00e7\u00e3o em S\u00e3o Borja, mas sem grandes propor\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Rio Ibirapuit\u00e3, em Alegrete, que estava apresentando limiar de alerta, entrou em decl\u00ednio, mas seguir\u00e1 sob monitoramento, devido \u00e0s previs\u00f5es de chuvas no Sul e na Campanha. Diante dessas precipita\u00e7\u00f5es, \u00e9 poss\u00edvel que esse rio apresente alguma resposta mais significativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo do Estado monitora, continuamente, o n\u00edvel dos rios em todo o Rio Grande do Sul. Neste momento, alguns rios come\u00e7am a baixar, ao passo que outros est\u00e3o subindo. A situa\u00e7\u00e3o, portanto, ainda requer aten\u00e7\u00e3o. Conforme o boletim de monitoramento hidrol\u00f3gico, fechado por volta das 10h desta quinta-feira (7\/9), boa parte dos rios do [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":139366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[2582,4818,10757],"class_list":["post-139365","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-atencao","tag-guaiba","tag-rio","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O governo do Estado monitora, continuamente, o n\u00edvel dos rios em todo o Rio Grande do Sul. Neste momento, alguns rios come\u00e7am a baixar, ao passo que outros est\u00e3o subindo. A situa\u00e7\u00e3o, portanto, ainda requer aten\u00e7\u00e3o. Conforme o boletim de monitoramento hidrol\u00f3gico, fechado por volta das 10h desta quinta-feira (7\/9), boa parte dos rios do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-07T20:17:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-07T20:17:38+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/07084628_2083833_GDO-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento\",\"datePublished\":\"2023-09-07T20:17:35+00:00\",\"dateModified\":\"2023-09-07T20:17:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/\"},\"wordCount\":653,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/07084628_2083833_GDO-1.jpg\",\"keywords\":[\"Aten\u00e7\u00e3o\",\"Gua\u00edba\",\"Rio\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/\",\"name\":\"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/07084628_2083833_GDO-1.jpg\",\"datePublished\":\"2023-09-07T20:17:35+00:00\",\"dateModified\":\"2023-09-07T20:17:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/07084628_2083833_GDO-1.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/07084628_2083833_GDO-1.jpg\",\"width\":800,\"height\":453,\"caption\":\"Cr\u00e9dito: Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/09\\\/07\\\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/","og_locale":"pt_BR","og_type":"article","og_title":"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento - Folha Popular","og_description":"O governo do Estado monitora, continuamente, o n\u00edvel dos rios em todo o Rio Grande do Sul. Neste momento, alguns rios come\u00e7am a baixar, ao passo que outros est\u00e3o subindo. A situa\u00e7\u00e3o, portanto, ainda requer aten\u00e7\u00e3o. Conforme o boletim de monitoramento hidrol\u00f3gico, fechado por volta das 10h desta quinta-feira (7\/9), boa parte dos rios do [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/","og_site_name":"Folha Popular","article_published_time":"2023-09-07T20:17:35+00:00","article_modified_time":"2023-09-07T20:17:38+00:00","og_image":[{"width":800,"height":453,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/07084628_2083833_GDO-1.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento","datePublished":"2023-09-07T20:17:35+00:00","dateModified":"2023-09-07T20:17:38+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/"},"wordCount":653,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/07084628_2083833_GDO-1.jpg","keywords":["Aten\u00e7\u00e3o","Gua\u00edba","Rio"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/","url":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/","name":"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/07084628_2083833_GDO-1.jpg","datePublished":"2023-09-07T20:17:35+00:00","dateModified":"2023-09-07T20:17:38+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/07084628_2083833_GDO-1.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/07084628_2083833_GDO-1.jpg","width":800,"height":453,"caption":"Cr\u00e9dito: Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2023\/09\/07\/situacao-do-nivel-do-guaiba-e-a-que-requer-mais-atencao-no-momento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Situa\u00e7\u00e3o do n\u00edvel do Gua\u00edba \u00e9 a que requer mais aten\u00e7\u00e3o no momento"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/09\/07084628_2083833_GDO-1.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/139365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=139365"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/139365\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/139366"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=139365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=139365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=139365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}