{"id":142083,"date":"2023-10-20T23:10:05","date_gmt":"2023-10-21T02:10:05","guid":{"rendered":"https:\/\/folhapopular.info\/?p=142083"},"modified":"2023-10-20T23:11:39","modified_gmt":"2023-10-21T02:11:39","slug":"colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/","title":{"rendered":"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dois carros bateram por volta das 18h20 desta sexta-feira (20\/10), no km 27 da ERS-128, no trevo da Lactalis, em Teut\u00f4nia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No Oroch, com placas de Teut\u00f4nia, havia quatro ocupantes. O motorista e uma das passageiras recusaram atendimento m\u00e9dico. As demais ocupantes, uma menina de 11 anos e uma mulher de 55 anos, tiveram ferimentos leves e foram encaminhadas para atendimento m\u00e9dico no Hospital Ouro Brano.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O outro ve\u00edculo envolvido, um HB20, tamb\u00e9m de Teut\u00f4nia, era conduzido por um homem que tamb\u00e9m recusou atendimento m\u00e9dico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atenderam a ocorr\u00eancia o Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia e a Pol\u00edcia Rodovi\u00e1ria Estadual.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-20.48.28-768x1024.jpeg\" alt=\"\" class=\"wp-image-142085\" width=\"511\" height=\"695\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dois carros bateram por volta das 18h20 desta sexta-feira (20\/10), no km 27 da ERS-128, no trevo da Lactalis, em Teut\u00f4nia.&nbsp; No Oroch, com placas de Teut\u00f4nia, havia quatro ocupantes. O motorista e uma das passageiras recusaram atendimento m\u00e9dico. As demais ocupantes, uma menina de 11 anos e uma mulher de 55 anos, tiveram ferimentos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":142084,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10984,7,10983],"tags":[195,1430,13211,26,2614],"class_list":["post-142083","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bombeiros","category-seguranca","category-transito","tag-acidente","tag-colisao","tag-ocorrencia","tag-teutonia","tag-veiculos","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Dois carros bateram por volta das 18h20 desta sexta-feira (20\/10), no km 27 da ERS-128, no trevo da Lactalis, em Teut\u00f4nia.&nbsp; No Oroch, com placas de Teut\u00f4nia, havia quatro ocupantes. O motorista e uma das passageiras recusaram atendimento m\u00e9dico. As demais ocupantes, uma menina de 11 anos e uma mulher de 55 anos, tiveram ferimentos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-21T02:10:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-21T02:11:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia\",\"datePublished\":\"2023-10-21T02:10:05+00:00\",\"dateModified\":\"2023-10-21T02:11:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/\"},\"wordCount\":124,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg\",\"keywords\":[\"Acidente\",\"Colis\u00e3o\",\"Ocorr\u00eancia\",\"Teut\u00f4nia\",\"Ve\u00edculos\"],\"articleSection\":[\"Bombeiros\",\"Seguran\u00e7a\",\"Tr\u00e2nsito\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/\",\"name\":\"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg\",\"datePublished\":\"2023-10-21T02:10:05+00:00\",\"dateModified\":\"2023-10-21T02:11:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg\",\"width\":1200,\"height\":1600,\"caption\":\"Cr\u00e9dito: Bombeiros Volunt\u00e1rios \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/10\\\/20\\\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/","og_locale":"pt_BR","og_type":"article","og_title":"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia - Folha Popular","og_description":"Dois carros bateram por volta das 18h20 desta sexta-feira (20\/10), no km 27 da ERS-128, no trevo da Lactalis, em Teut\u00f4nia.&nbsp; No Oroch, com placas de Teut\u00f4nia, havia quatro ocupantes. O motorista e uma das passageiras recusaram atendimento m\u00e9dico. As demais ocupantes, uma menina de 11 anos e uma mulher de 55 anos, tiveram ferimentos [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/","og_site_name":"Folha Popular","article_published_time":"2023-10-21T02:10:05+00:00","article_modified_time":"2023-10-21T02:11:39+00:00","og_image":[{"width":1200,"height":1600,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia","datePublished":"2023-10-21T02:10:05+00:00","dateModified":"2023-10-21T02:11:39+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/"},"wordCount":124,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg","keywords":["Acidente","Colis\u00e3o","Ocorr\u00eancia","Teut\u00f4nia","Ve\u00edculos"],"articleSection":["Bombeiros","Seguran\u00e7a","Tr\u00e2nsito"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/","url":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/","name":"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg","datePublished":"2023-10-21T02:10:05+00:00","dateModified":"2023-10-21T02:11:39+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg","width":1200,"height":1600,"caption":"Cr\u00e9dito: Bombeiros Volunt\u00e1rios \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2023\/10\/20\/colisao-de-carro-deixa-duas-pessoas-feridas-em-teutonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Colis\u00e3o de carros deixa duas pessoas feridas em Teut\u00f4nia"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-20.48.23.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/142083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=142083"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/142083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/142084"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=142083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=142083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=142083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}