{"id":143939,"date":"2023-11-23T15:57:30","date_gmt":"2023-11-23T18:57:30","guid":{"rendered":"https:\/\/folhapopular.info\/?p=143939"},"modified":"2023-11-23T15:57:35","modified_gmt":"2023-11-23T18:57:35","slug":"languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/","title":{"rendered":"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Na ter\u00e7a-feira (21\/11) as cooperativas Languiru e Agropan, de Tupanciret\u00e3, assinaram o distrato de aquisi\u00e7\u00e3o de instala\u00e7\u00f5es na \u00e1rea portu\u00e1ria do munic\u00edpio de Estrela. O investimento previsto at\u00e9 novembro de 2029 era de mais de R$ 40 milh\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com isso, a Languiru redireciona toda sua capacidade de armazenamento de gr\u00e3os \u00e0s instala\u00e7\u00f5es pr\u00f3prias de silos na F\u00e1brica de Ra\u00e7\u00f5es, tamb\u00e9m no munic\u00edpio de Estrela, e no Bairro Alesgut, em Teut\u00f4nia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o liquidante da Languiru, Paulo Roberto Birck, havia incerteza sobre a capacidade de manter estrutura desse porte para as necessidades atuais da cooperativa. &#8220;O distrato foi uma decis\u00e3o em comum acordo, deixamos de ter esse compromisso. Al\u00e9m da quest\u00e3o financeira, o fato das instala\u00e7\u00f5es terem sido afetadas pelas duas \u00faltimas grandes cheias do Rio Taquari tamb\u00e9m foi decisivo para esse encaminhamento. A dire\u00e7\u00e3o da Agropan foi solid\u00e1ria e parceira nesse momento. A Languiru n\u00e3o teria a condi\u00e7\u00e3o e a justificativa para efetivar a compra desse espa\u00e7o\u201d, explica. O distrato n\u00e3o gerou novos custos ou multas \u00e0 Languiru.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Retrospectiva<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Languiru anunciou investimento na \u00e1rea portu\u00e1ria de Estrela em novembro de 2022, por ocasi\u00e3o das comemora\u00e7\u00f5es de 67 anos da cooperativa. O desenlace da fita inaugural da estrutura para recebimento, processamento, limpeza, secagem, armazenamento e expedi\u00e7\u00e3o de gr\u00e3os, especialmente milho e soja, contou com a participa\u00e7\u00e3o de lideran\u00e7as pol\u00edticas, associados e convidados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A infraestrutura conta com dez silos verticais met\u00e1licos com capacidade para tr\u00eas mil toneladas cada, e mais um armaz\u00e9m graneleiro, com capacidade para 30 mil toneladas de gr\u00e3os, totalizando 60 mil toneladas de capacidade est\u00e1tica, dois secadores de gr\u00e3os, duas moegas, uma delas com tombador para caminh\u00e3o bitrem, balan\u00e7a rodovi\u00e1ria e pr\u00e9dios anexos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O complexo portu\u00e1rio de Estrela foi constru\u00eddo na d\u00e9cada de 1970. Pertenceu a diferentes grupos empresariais e tamb\u00e9m passou por per\u00edodos de inatividade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na ter\u00e7a-feira (21\/11) as cooperativas Languiru e Agropan, de Tupanciret\u00e3, assinaram o distrato de aquisi\u00e7\u00e3o de instala\u00e7\u00f5es na \u00e1rea portu\u00e1ria do munic\u00edpio de Estrela. O investimento previsto at\u00e9 novembro de 2029 era de mais de R$ 40 milh\u00f5es. Com isso, a Languiru redireciona toda sua capacidade de armazenamento de gr\u00e3os \u00e0s instala\u00e7\u00f5es pr\u00f3prias de silos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":143940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10992,2,10991],"tags":[13648,13647,406,1278,13649],"class_list":["post-143939","post","type-post","status-publish","format-standard","has-post-thumbnail","category-coopop","category-featured","category-economia","tag-agropan","tag-distrato","tag-languiru","tag-porto-de-estrela","tag-silos","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Na ter\u00e7a-feira (21\/11) as cooperativas Languiru e Agropan, de Tupanciret\u00e3, assinaram o distrato de aquisi\u00e7\u00e3o de instala\u00e7\u00f5es na \u00e1rea portu\u00e1ria do munic\u00edpio de Estrela. O investimento previsto at\u00e9 novembro de 2029 era de mais de R$ 40 milh\u00f5es. Com isso, a Languiru redireciona toda sua capacidade de armazenamento de gr\u00e3os \u00e0s instala\u00e7\u00f5es pr\u00f3prias de silos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-23T18:57:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-23T18:57:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/11\/DJI_0306-JORNAL-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela\",\"datePublished\":\"2023-11-23T18:57:30+00:00\",\"dateModified\":\"2023-11-23T18:57:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/\"},\"wordCount\":351,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/DJI_0306-JORNAL-1-scaled.jpg\",\"keywords\":[\"Agropan\",\"Distrato\",\"Languiru\",\"Porto de Estrela\",\"Silos\"],\"articleSection\":[\"Coopop\",\"Destaques\",\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/\",\"name\":\"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/DJI_0306-JORNAL-1-scaled.jpg\",\"datePublished\":\"2023-11-23T18:57:30+00:00\",\"dateModified\":\"2023-11-23T18:57:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/DJI_0306-JORNAL-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/DJI_0306-JORNAL-1-scaled.jpg\",\"width\":2560,\"height\":1638,\"caption\":\"Cr\u00e9dito: Maciel Fischer \\\/ Divulga\u00e7\u00e3o Cooperativa Languiru\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2023\\\/11\\\/23\\\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/","og_locale":"pt_BR","og_type":"article","og_title":"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela - Folha Popular","og_description":"Na ter\u00e7a-feira (21\/11) as cooperativas Languiru e Agropan, de Tupanciret\u00e3, assinaram o distrato de aquisi\u00e7\u00e3o de instala\u00e7\u00f5es na \u00e1rea portu\u00e1ria do munic\u00edpio de Estrela. O investimento previsto at\u00e9 novembro de 2029 era de mais de R$ 40 milh\u00f5es. Com isso, a Languiru redireciona toda sua capacidade de armazenamento de gr\u00e3os \u00e0s instala\u00e7\u00f5es pr\u00f3prias de silos [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/","og_site_name":"Folha Popular","article_published_time":"2023-11-23T18:57:30+00:00","article_modified_time":"2023-11-23T18:57:35+00:00","og_image":[{"width":2560,"height":1638,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2023\/11\/DJI_0306-JORNAL-1-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela","datePublished":"2023-11-23T18:57:30+00:00","dateModified":"2023-11-23T18:57:35+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/"},"wordCount":351,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/11\/DJI_0306-JORNAL-1-scaled.jpg","keywords":["Agropan","Distrato","Languiru","Porto de Estrela","Silos"],"articleSection":["Coopop","Destaques","Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/","url":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/","name":"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/11\/DJI_0306-JORNAL-1-scaled.jpg","datePublished":"2023-11-23T18:57:30+00:00","dateModified":"2023-11-23T18:57:35+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/11\/DJI_0306-JORNAL-1-scaled.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/11\/DJI_0306-JORNAL-1-scaled.jpg","width":2560,"height":1638,"caption":"Cr\u00e9dito: Maciel Fischer \/ Divulga\u00e7\u00e3o Cooperativa Languiru"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2023\/11\/23\/languiru-e-agropan-assinam-distrato-da-negociacao-de-area-portuaria-de-estrela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Languiru e Agropan assinam distrato da negocia\u00e7\u00e3o de \u00e1rea portu\u00e1ria de Estrela"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2023\/11\/DJI_0306-JORNAL-1-scaled.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/143939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=143939"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/143939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/143940"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=143939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=143939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=143939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}