{"id":148262,"date":"2024-01-20T14:05:13","date_gmt":"2024-01-20T17:05:13","guid":{"rendered":"https:\/\/folhapopular.info\/?p=148262"},"modified":"2024-01-20T14:05:16","modified_gmt":"2024-01-20T17:05:16","slug":"cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/","title":{"rendered":"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia atendeu, na manh\u00e3 deste s\u00e1bado (20\/1) uma ocorr\u00eancia de inc\u00eandio veicular. Chegando no local, na Rua Tiradentes, no Bairro Canabarro, na altura do Kakak&#8217;s e do Posto da Dani, o ve\u00edculo Fiesta estava totalmente tomado pelas chamas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A guarni\u00e7\u00e3o iniciou o combate \u00e0s chamas e resfriamento do ve\u00edculo, utilizando mil litros de \u00e1gua. N\u00e3o houve v\u00edtimas no incidente, e o CBVT n\u00e3o tem conhecimento das causas do sinistro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia atendeu, na manh\u00e3 deste s\u00e1bado (20\/1) uma ocorr\u00eancia de inc\u00eandio veicular. Chegando no local, na Rua Tiradentes, no Bairro Canabarro, na altura do Kakak&#8217;s e do Posto da Dani, o ve\u00edculo Fiesta estava totalmente tomado pelas chamas. A guarni\u00e7\u00e3o iniciou o combate \u00e0s chamas e resfriamento do ve\u00edculo, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":148263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10984,7],"tags":[837,1309,26],"class_list":["post-148262","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bombeiros","category-seguranca","tag-canabarro","tag-incendio-veicular","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia atendeu, na manh\u00e3 deste s\u00e1bado (20\/1) uma ocorr\u00eancia de inc\u00eandio veicular. Chegando no local, na Rua Tiradentes, no Bairro Canabarro, na altura do Kakak&#8217;s e do Posto da Dani, o ve\u00edculo Fiesta estava totalmente tomado pelas chamas. A guarni\u00e7\u00e3o iniciou o combate \u00e0s chamas e resfriamento do ve\u00edculo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-20T17:05:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-20T17:05:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro\",\"datePublished\":\"2024-01-20T17:05:13+00:00\",\"dateModified\":\"2024-01-20T17:05:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/\"},\"wordCount\":98,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg\",\"keywords\":[\"Canabarro\",\"Inc\u00eandio Veicular\",\"Teut\u00f4nia\"],\"articleSection\":[\"Bombeiros\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/\",\"name\":\"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg\",\"datePublished\":\"2024-01-20T17:05:13+00:00\",\"dateModified\":\"2024-01-20T17:05:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg\",\"width\":1280,\"height\":960,\"caption\":\"Cr\u00e9dito: CBV Teut\u00f4nia \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/01\\\/20\\\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/","og_locale":"pt_BR","og_type":"article","og_title":"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro - Folha Popular","og_description":"O Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia atendeu, na manh\u00e3 deste s\u00e1bado (20\/1) uma ocorr\u00eancia de inc\u00eandio veicular. Chegando no local, na Rua Tiradentes, no Bairro Canabarro, na altura do Kakak&#8217;s e do Posto da Dani, o ve\u00edculo Fiesta estava totalmente tomado pelas chamas. A guarni\u00e7\u00e3o iniciou o combate \u00e0s chamas e resfriamento do ve\u00edculo, [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/","og_site_name":"Folha Popular","article_published_time":"2024-01-20T17:05:13+00:00","article_modified_time":"2024-01-20T17:05:16+00:00","og_image":[{"width":1280,"height":960,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro","datePublished":"2024-01-20T17:05:13+00:00","dateModified":"2024-01-20T17:05:16+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/"},"wordCount":98,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg","keywords":["Canabarro","Inc\u00eandio Veicular","Teut\u00f4nia"],"articleSection":["Bombeiros","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/","url":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/","name":"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg","datePublished":"2024-01-20T17:05:13+00:00","dateModified":"2024-01-20T17:05:16+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg","width":1280,"height":960,"caption":"Cr\u00e9dito: CBV Teut\u00f4nia \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2024\/01\/20\/cbv-de-teutonia-atende-incendio-em-veiculo-em-canabarro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"CBV de Teut\u00f4nia atende inc\u00eandio em ve\u00edculo em Canabarro"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-20-at-14.00.04.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/148262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=148262"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/148262\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/148263"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=148262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=148262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=148262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}