{"id":154932,"date":"2024-04-06T10:47:16","date_gmt":"2024-04-06T13:47:16","guid":{"rendered":"https:\/\/folhapopular.info\/?p=154932"},"modified":"2024-04-06T10:47:18","modified_gmt":"2024-04-06T13:47:18","slug":"vereadores-denunciam-focos-de-dengue","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/","title":{"rendered":"Vereadores denunciam focos de dengue"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O vereador Valdir Griebeler (MDB) indicou a pulveriza\u00e7\u00e3o do produto Cielo-ULV no munic\u00edpio para diminuir a popula\u00e7\u00e3o de mosquito <em>Aedes aegypti<\/em>, transmissor da dengue. \u201c\u00c9 um pedido de mun\u00edcipes, principalmente do Bairro Alesgut, que viram na televis\u00e3o em cidades com surtos graves. Alguns est\u00e3o preocupados e at\u00e9 apavorados com a gravidade em todo pa\u00eds\u201d, disse na tribuna. Como foi o primeiro a se pronunciar na sess\u00e3o ordin\u00e1ria de ter\u00e7a-feira (2\/4), outros colegas tamb\u00e9m abordaram o tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA Vigil\u00e2ncia Sanit\u00e1ria tem equipe competente e est\u00e1 muito empenhada para minimizar os problemas. Talvez j\u00e1 estejam avaliando a quest\u00e3o do produto. No Bairro Alesgut h\u00e1 foco muito grande pr\u00f3ximo \u00e0 capatazia. Temos que continuar alertas, cuidar e tomar precau\u00e7\u00f5es para eliminar o momento delicado da dengue\u201d, completa Griebeler.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luias Wermann (PSD) foi mais incisivo. Pede aten\u00e7\u00e3o do governo municipal e parabenizou o trabalho da Vigil\u00e2ncia Sanit\u00e1ria. \u201cO pr\u00e9dio da Capatazia do Alesgut est\u00e1 sem telhado desde o temporal de janeiro. Colocaram lonas, que acumulam \u00e1gua. \u00c9 foco de mosquito. Se a pr\u00f3pria Visa faz a den\u00fancia e a Prefeitura n\u00e3o acata, cabe den\u00fancia por neglig\u00eancia\u201d, aponta o vereador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wermann cobrou a limpeza das \u00e1reas de lazer de Teut\u00f4nia e pediu mutir\u00e3o no Bairro Alesgut, \u201cporque \u00e9 quest\u00e3o de Sa\u00fade. J\u00e1 foi perdida uma vida. Quantas vidas precisar\u00e3o ser perdidas? Estamos criando mosquito dentro do patrim\u00f4nio p\u00fablico!\u201d, critica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em aparte, Cleudori Paniz (PSD) tamb\u00e9m pediu a retirada de entulho na capatazia do Bairro Canabarro para evitar prolifera\u00e7\u00e3o do mosquito. Sem ser muito espec\u00edfico, H\u00e9lio Brand\u00e3o da Silva (PSDB) tamb\u00e9m falou sobre o descaso nos fundos da Picky, no Bairro Canabarro. \u201cCom tanta \u00e1rea que tem, quantos m\u00f3veis e entulhos t\u00eam l\u00e1. Por que fazer dois trabalhos: levar l\u00e1 e depois remover?\u201d, questiona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1rcio Cristiano Vogel (MDB) classifica o cen\u00e1rio de \u201cpreocupante\u201d. \u201cVivemos um per\u00edodo dif\u00edcil e cr\u00edtico na regi\u00e3o e estado. Temos que nos prevenir. Eliminar focos de \u00e1gua parada para o mosquito n\u00e3o se proliferar\u201d, sustenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nenhum vereador da base de governo comentou ou defendeu a situa\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vereador Valdir Griebeler (MDB) indicou a pulveriza\u00e7\u00e3o do produto Cielo-ULV no munic\u00edpio para diminuir a popula\u00e7\u00e3o de mosquito Aedes aegypti, transmissor da dengue. \u201c\u00c9 um pedido de mun\u00edcipes, principalmente do Bairro Alesgut, que viram na televis\u00e3o em cidades com surtos graves. Alguns est\u00e3o preocupados e at\u00e9 apavorados com a gravidade em todo pa\u00eds\u201d, disse [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":151290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[1562,26,6260],"class_list":["post-154932","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-dengue","tag-teutonia","tag-vereadores","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vereadores denunciam focos de dengue - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vereadores denunciam focos de dengue - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O vereador Valdir Griebeler (MDB) indicou a pulveriza\u00e7\u00e3o do produto Cielo-ULV no munic\u00edpio para diminuir a popula\u00e7\u00e3o de mosquito Aedes aegypti, transmissor da dengue. \u201c\u00c9 um pedido de mun\u00edcipes, principalmente do Bairro Alesgut, que viram na televis\u00e3o em cidades com surtos graves. Alguns est\u00e3o preocupados e at\u00e9 apavorados com a gravidade em todo pa\u00eds\u201d, disse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-06T13:47:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-06T13:47:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2024\/02\/IMG_5552-scaled-e1631366067529.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucas Leandro Brune\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Leandro Brune\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/\"},\"author\":{\"name\":\"Lucas Leandro Brune\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\"},\"headline\":\"Vereadores denunciam focos de dengue\",\"datePublished\":\"2024-04-06T13:47:16+00:00\",\"dateModified\":\"2024-04-06T13:47:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/\"},\"wordCount\":382,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_5552-scaled-e1631366067529.jpeg\",\"keywords\":[\"Dengue\",\"Teut\u00f4nia\",\"vereadores\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/\",\"name\":\"Vereadores denunciam focos de dengue - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_5552-scaled-e1631366067529.jpeg\",\"datePublished\":\"2024-04-06T13:47:16+00:00\",\"dateModified\":\"2024-04-06T13:47:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_5552-scaled-e1631366067529.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/IMG_5552-scaled-e1631366067529.jpeg\",\"width\":800,\"height\":600,\"caption\":\"Cr\u00e9dito: Arquivo FP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/04\\\/06\\\/vereadores-denunciam-focos-de-dengue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vereadores denunciam focos de dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\",\"name\":\"Lucas Leandro Brune\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"caption\":\"Lucas Leandro Brune\"},\"description\":\"Jornalista Profissional Diplomado MTB\\\/RS 14.333\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/lucas-brune\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vereadores denunciam focos de dengue - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/","og_locale":"pt_BR","og_type":"article","og_title":"Vereadores denunciam focos de dengue - Folha Popular","og_description":"O vereador Valdir Griebeler (MDB) indicou a pulveriza\u00e7\u00e3o do produto Cielo-ULV no munic\u00edpio para diminuir a popula\u00e7\u00e3o de mosquito Aedes aegypti, transmissor da dengue. \u201c\u00c9 um pedido de mun\u00edcipes, principalmente do Bairro Alesgut, que viram na televis\u00e3o em cidades com surtos graves. Alguns est\u00e3o preocupados e at\u00e9 apavorados com a gravidade em todo pa\u00eds\u201d, disse [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/","og_site_name":"Folha Popular","article_published_time":"2024-04-06T13:47:16+00:00","article_modified_time":"2024-04-06T13:47:18+00:00","og_image":[{"width":800,"height":600,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2024\/02\/IMG_5552-scaled-e1631366067529.jpeg","type":"image\/jpeg"}],"author":"Lucas Leandro Brune","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Leandro Brune","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/"},"author":{"name":"Lucas Leandro Brune","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36"},"headline":"Vereadores denunciam focos de dengue","datePublished":"2024-04-06T13:47:16+00:00","dateModified":"2024-04-06T13:47:18+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/"},"wordCount":382,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/02\/IMG_5552-scaled-e1631366067529.jpeg","keywords":["Dengue","Teut\u00f4nia","vereadores"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/","url":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/","name":"Vereadores denunciam focos de dengue - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/02\/IMG_5552-scaled-e1631366067529.jpeg","datePublished":"2024-04-06T13:47:16+00:00","dateModified":"2024-04-06T13:47:18+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/02\/IMG_5552-scaled-e1631366067529.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/02\/IMG_5552-scaled-e1631366067529.jpeg","width":800,"height":600,"caption":"Cr\u00e9dito: Arquivo FP"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2024\/04\/06\/vereadores-denunciam-focos-de-dengue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Vereadores denunciam focos de dengue"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36","name":"Lucas Leandro Brune","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","caption":"Lucas Leandro Brune"},"description":"Jornalista Profissional Diplomado MTB\/RS 14.333","url":"https:\/\/folhapopular.info\/index.php\/author\/lucas-brune\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/02\/IMG_5552-scaled-e1631366067529.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/154932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=154932"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/154932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/151290"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=154932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=154932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=154932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}