{"id":166284,"date":"2024-08-20T09:25:18","date_gmt":"2024-08-20T12:25:18","guid":{"rendered":"https:\/\/folhapopular.info\/?p=166284"},"modified":"2024-08-20T09:25:21","modified_gmt":"2024-08-20T12:25:21","slug":"prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/","title":{"rendered":"PRF prende dois homens com 46 kg de maconha em Paverama"},"content":{"rendered":"\n<p>A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu 46kg de maconha e prendeu dois homens na noite desta segunda-feira (19\/8). A droga estava sendo transportada no porta-malas de um carro abordado na BR-386, em Paverama. <\/p>\n\n\n\n<p>Os policiais rodovi\u00e1rios federais realizavam uma a\u00e7\u00e3o de combate ao crime quando abordaram um Fiat Mobi emplacado em Canoas. Ao verificarem o porta-malas, encontraram dezenas de tabletes de maconha, totalizando 46kg. Segundo a dupla que estava no carro, a carga seria levada para a regi\u00e3o metropolitana de Porto Alegre.<\/p>\n\n\n\n<p>Os dois homens, naturais de Canoas, com 38 anos, possu\u00edam diversos antecedentes por crimes como roubo de ve\u00edculo, recepta\u00e7\u00e3o, roubo a estabelecimento comercial, porte ilegal de arma de fogo, tr\u00e1fico de drogas e estelionato.<\/p>\n\n\n\n<p>A droga apreendida foi encaminhada para a Delegacia de Pol\u00edcia Judici\u00e1ria, junto com o ve\u00edculo e os homens, que foram presos em flagrante por tr\u00e1fico de drogas e associa\u00e7\u00e3o para o tr\u00e1fico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu 46kg de maconha e prendeu dois homens na noite desta segunda-feira (19\/8). A droga estava sendo transportada no porta-malas de um carro abordado na BR-386, em Paverama. Os policiais rodovi\u00e1rios federais realizavam uma a\u00e7\u00e3o de combate ao crime quando abordaram um Fiat Mobi emplacado em Canoas. Ao verificarem o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":166285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10982,7],"tags":[1027,46,294,107],"class_list":{"0":"post-166284","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia","8":"category-seguranca","9":"tag-maconha","10":"tag-paverama","11":"tag-prf","12":"tag-prisao","13":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRF prende dois homens com 46 kg de maconha em Paverama - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRF prende dois homens com 46 kg de maconha em Paverama - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu 46kg de maconha e prendeu dois homens na noite desta segunda-feira (19\/8). A droga estava sendo transportada no porta-malas de um carro abordado na BR-386, em Paverama. Os policiais rodovi\u00e1rios federais realizavam uma a\u00e7\u00e3o de combate ao crime quando abordaram um Fiat Mobi emplacado em Canoas. Ao verificarem o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-20T12:25:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-20T12:25:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"PRF prende dois homens com 46 kg de maconha em Paverama\",\"datePublished\":\"2024-08-20T12:25:18+00:00\",\"dateModified\":\"2024-08-20T12:25:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/\"},\"wordCount\":171,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg\",\"keywords\":[\"Maconha\",\"Paverama\",\"PRF\",\"Pris\u00e3o\"],\"articleSection\":[\"Pol\u00edcia\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/\",\"name\":\"PRF prende dois homens com 46 kg de maconha em Paverama - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg\",\"datePublished\":\"2024-08-20T12:25:18+00:00\",\"dateModified\":\"2024-08-20T12:25:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"Cr\u00e9dito: PRF \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2024\\\/08\\\/20\\\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRF prende dois homens com 46 kg de maconha em Paverama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRF prende dois homens com 46 kg de maconha em Paverama - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/","og_locale":"pt_BR","og_type":"article","og_title":"PRF prende dois homens com 46 kg de maconha em Paverama - Folha Popular","og_description":"A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) apreendeu 46kg de maconha e prendeu dois homens na noite desta segunda-feira (19\/8). A droga estava sendo transportada no porta-malas de um carro abordado na BR-386, em Paverama. Os policiais rodovi\u00e1rios federais realizavam uma a\u00e7\u00e3o de combate ao crime quando abordaram um Fiat Mobi emplacado em Canoas. Ao verificarem o [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/","og_site_name":"Folha Popular","article_published_time":"2024-08-20T12:25:18+00:00","article_modified_time":"2024-08-20T12:25:21+00:00","og_image":[{"width":1280,"height":720,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"PRF prende dois homens com 46 kg de maconha em Paverama","datePublished":"2024-08-20T12:25:18+00:00","dateModified":"2024-08-20T12:25:21+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/"},"wordCount":171,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg","keywords":["Maconha","Paverama","PRF","Pris\u00e3o"],"articleSection":["Pol\u00edcia","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/","url":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/","name":"PRF prende dois homens com 46 kg de maconha em Paverama - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg","datePublished":"2024-08-20T12:25:18+00:00","dateModified":"2024-08-20T12:25:21+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg","width":1280,"height":720,"caption":"Cr\u00e9dito: PRF \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2024\/08\/20\/prf-prende-dois-homens-com-46-kg-de-maconha-em-paverama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"PRF prende dois homens com 46 kg de maconha em Paverama"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-20-at-09.08.25.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/166284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=166284"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/166284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/166285"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=166284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=166284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=166284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}