{"id":180352,"date":"2025-02-10T16:37:02","date_gmt":"2025-02-10T19:37:02","guid":{"rendered":"https:\/\/folhapopular.info\/?p=180352"},"modified":"2025-02-10T16:37:05","modified_gmt":"2025-02-10T19:37:05","slug":"incendio-florestal-atinge-linha-brasil-em-paverama","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/","title":{"rendered":"Inc\u00eandio florestal atinge Linha Brasil, em Paverama"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Na tarde desta segunda-feira (10), um inc\u00eandio florestal atingiu a localidade de Linha Brasil, no munic\u00edpio de Paverama. O fogo come\u00e7ou por volta das 12h43, ap\u00f3s o propriet\u00e1rio de um terreno colocar fogo pr\u00f3ximo a um galp\u00e3o. Com o aumento da for\u00e7a do vento, as chamas se espalharam rapidamente e sa\u00edram de controle, invadindo a \u00e1rea de mata nativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cerca de 2,5 hectares de vegeta\u00e7\u00e3o foram consumidos pelo fogo antes que as equipes do Corpo de Bombeiros Volunt\u00e1rios de Teut\u00f4nia conseguissem conter as chamas. Para o combate ao inc\u00eandio, foram utilizados aproximadamente 5 mil litros de \u00e1gua, al\u00e9m do apoio de moradores da regi\u00e3o e da administra\u00e7\u00e3o p\u00fablica. Uma retroescavadeira foi empregada para a cria\u00e7\u00e3o de aceiros, impedindo que o fogo se alastrasse ainda mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s intenso trabalho, os focos principais foram controlados e n\u00e3o houve registro de feridos. As autoridades alertam para os riscos de queimadas em per\u00edodos secos e refor\u00e7am a necessidade de medidas preventivas para evitar novos incidentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde desta segunda-feira (10), um inc\u00eandio florestal atingiu a localidade de Linha Brasil, no munic\u00edpio de Paverama. O fogo come\u00e7ou por volta das 12h43, ap\u00f3s o propriet\u00e1rio de um terreno colocar fogo pr\u00f3ximo a um galp\u00e3o. Com o aumento da for\u00e7a do vento, as chamas se espalharam rapidamente e sa\u00edram de controle, invadindo a [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":180353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10984,7],"tags":[],"class_list":["post-180352","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bombeiros","category-seguranca","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inc\u00eandio florestal atinge Linha Brasil, em Paverama - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inc\u00eandio florestal atinge Linha Brasil, em Paverama - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Na tarde desta segunda-feira (10), um inc\u00eandio florestal atingiu a localidade de Linha Brasil, no munic\u00edpio de Paverama. O fogo come\u00e7ou por volta das 12h43, ap\u00f3s o propriet\u00e1rio de um terreno colocar fogo pr\u00f3ximo a um galp\u00e3o. Com o aumento da for\u00e7a do vento, as chamas se espalharam rapidamente e sa\u00edram de controle, invadindo a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-10T19:37:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T19:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Inc\u00eandio florestal atinge Linha Brasil, em Paverama\",\"datePublished\":\"2025-02-10T19:37:02+00:00\",\"dateModified\":\"2025-02-10T19:37:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/\"},\"wordCount\":188,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg\",\"articleSection\":[\"Bombeiros\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/\",\"name\":\"Inc\u00eandio florestal atinge Linha Brasil, em Paverama - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg\",\"datePublished\":\"2025-02-10T19:37:02+00:00\",\"dateModified\":\"2025-02-10T19:37:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/10\\\/incendio-florestal-atinge-linha-brasil-em-paverama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inc\u00eandio florestal atinge Linha Brasil, em Paverama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inc\u00eandio florestal atinge Linha Brasil, em Paverama - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/","og_locale":"pt_BR","og_type":"article","og_title":"Inc\u00eandio florestal atinge Linha Brasil, em Paverama - Folha Popular","og_description":"Na tarde desta segunda-feira (10), um inc\u00eandio florestal atingiu a localidade de Linha Brasil, no munic\u00edpio de Paverama. O fogo come\u00e7ou por volta das 12h43, ap\u00f3s o propriet\u00e1rio de um terreno colocar fogo pr\u00f3ximo a um galp\u00e3o. Com o aumento da for\u00e7a do vento, as chamas se espalharam rapidamente e sa\u00edram de controle, invadindo a [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/","og_site_name":"Folha Popular","article_published_time":"2025-02-10T19:37:02+00:00","article_modified_time":"2025-02-10T19:37:05+00:00","og_image":[{"width":1920,"height":2560,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Inc\u00eandio florestal atinge Linha Brasil, em Paverama","datePublished":"2025-02-10T19:37:02+00:00","dateModified":"2025-02-10T19:37:05+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/"},"wordCount":188,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg","articleSection":["Bombeiros","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/","name":"Inc\u00eandio florestal atinge Linha Brasil, em Paverama - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg","datePublished":"2025-02-10T19:37:02+00:00","dateModified":"2025-02-10T19:37:05+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/10\/incendio-florestal-atinge-linha-brasil-em-paverama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Inc\u00eandio florestal atinge Linha Brasil, em Paverama"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-10-at-16.31.23-scaled.jpeg","_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/180352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=180352"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/180352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/180353"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=180352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=180352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=180352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}