{"id":181012,"date":"2025-02-21T10:00:00","date_gmt":"2025-02-21T13:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=181012"},"modified":"2025-02-21T10:19:55","modified_gmt":"2025-02-21T13:19:55","slug":"prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/","title":{"rendered":"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cExistem alguns valores que norteiam o nosso trabalho na administra\u00e7\u00e3o municipal e, entre eles, est\u00e1 transpar\u00eancia, efici\u00eancia e liderar Lajeado como a cidade polo que ela \u00e9&#8221;. A declara\u00e7\u00e3o foi feita na quarta-feira (19) pela prefeita Gl\u00e1ucia Schumacher, durante a primeira reuni\u00e3o-almo\u00e7o (RA) de 2025 promovida pela Associa\u00e7\u00e3o Comercial e Industrial de Lajeado (Acil). Ela e o vice-prefeito, Guilherme C\u00e9, compartilharam com os presentes os projetos e as a\u00e7\u00f5es da nova gest\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00e9 comentou sobre o crescimento da popula\u00e7\u00e3o de Lajeado, que, segundo o IBGE, conta atualmente com 96.651 habitantes, destacando que o munic\u00edpio est\u00e1 entre os de maior crescimento no Rio Grande do Sul. &#8220;\u00c9 essencial que a cidade continue atraente, criando condi\u00e7\u00f5es para que o crescimento seja sustent\u00e1vel&#8221;, destacou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Macro Compromissos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a reuni\u00e3o, os gestores apresentaram o andamento das a\u00e7\u00f5es com base nos compromissos assumidos durante a campanha. &#8220;Nosso foco est\u00e1 na reconstru\u00e7\u00e3o e preven\u00e7\u00e3o, infraestrutura e mobilidade, e nos cuidados com a cidade&#8221;, explicaram.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gl\u00e1ucia refor\u00e7ou a necessidade de um planejamento urbano de longo prazo, j\u00e1 que Lajeado n\u00e3o tem mais espa\u00e7o para expans\u00e3o. &#8220;Precisamos planejar as obras pensando no futuro, considerando como as \u00e1reas estar\u00e3o daqui a 5 ou 10 anos&#8221;, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reconstru\u00e7\u00e3o e Preven\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre reconstru\u00e7\u00e3o e preven\u00e7\u00e3o, a prefeita e o vice-prefeito destacaram a\u00e7\u00f5es para recuperar as conex\u00f5es vi\u00e1rias, tanto dentro da cidade quanto com munic\u00edpios vizinhos. &#8220;Esperamos entregar as obras da ponte sobre o rio Taquari e a conex\u00e3o com Arroio do Meio em mar\u00e7o&#8221;, adiantaram.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00e9 tamb\u00e9m mencionou a atualiza\u00e7\u00e3o do plano de conting\u00eancia do munic\u00edpio, que foi reformulado ap\u00f3s a enchente de maio de 2024. &#8220;Vamos apresentar o plano \u00e0 comunidade em breve, para que todos possam contribuir e opinar&#8221;, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cuidados com a Cidade<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gl\u00e1ucia tamb\u00e9m anunciou a cria\u00e7\u00e3o da Secretaria de Servi\u00e7os Urbanos, que ser\u00e1 respons\u00e1vel pela manuten\u00e7\u00e3o e conserva\u00e7\u00e3o das pra\u00e7as, parques e espa\u00e7os p\u00fablicos. &#8220;Esta secretaria ser\u00e1 fundamental para zelarmos pela cidade, garantindo que os espa\u00e7os p\u00fablicos sejam bem cuidados&#8221;, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00e9 falou sobre o projeto de ado\u00e7\u00e3o de pra\u00e7as e \u00e1reas de lazer, que ser\u00e1 reformulado para evitar que os espa\u00e7os fiquem abandonados, como ocorreu em algumas \u00e1reas da cidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Corsan e Stacione<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao final da reuni\u00e3o, a prefeita comentou sobre dois contratos que est\u00e3o sendo analisados: o da Corsan, que explora o servi\u00e7o de \u00e1gua e esgoto, e o da Stacione, respons\u00e1vel pelo estacionamento rotativo. Ela adiantou que ambos os contratos precisam de ajustes antes de serem assinados. &#8220;Estamos buscando solu\u00e7\u00f5es para as demandas da comunidade e, em breve, teremos reuni\u00f5es com o FEL e as associa\u00e7\u00f5es de bairros&#8221;, explicou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As reuni\u00f5es-almo\u00e7o de 2025 t\u00eam o patroc\u00ednio do Banco Regional de Desenvolvimento do Extremo Sul (BRDE), CBM Materiais El\u00e9tricos, Excellence Gar\u00e7ons, Florestal Alimentos, Fruki Bebidas, Grupo Imec, Grupo RBS, Kappel Im\u00f3veis, Olicenter, Rhodoss Implementos Rodovi\u00e1rios, Sicredi Integra\u00e7\u00e3o RS\/MG, Tecnosom Sonoriza\u00e7\u00e3o, Unimed VTRP, Vincere Construtora e Wep Compliance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cExistem alguns valores que norteiam o nosso trabalho na administra\u00e7\u00e3o municipal e, entre eles, est\u00e1 transpar\u00eancia, efici\u00eancia e liderar Lajeado como a cidade polo que ela \u00e9&#8221;. A declara\u00e7\u00e3o foi feita na quarta-feira (19) pela prefeita Gl\u00e1ucia Schumacher, durante a primeira reuni\u00e3o-almo\u00e7o (RA) de 2025 promovida pela Associa\u00e7\u00e3o Comercial e Industrial de Lajeado (Acil). Ela [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":181013,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,10991],"tags":[214,27,2218,18040],"class_list":["post-181012","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-economia","tag-acil","tag-lajeado","tag-politica","tag-ra","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"\u201cExistem alguns valores que norteiam o nosso trabalho na administra\u00e7\u00e3o municipal e, entre eles, est\u00e1 transpar\u00eancia, efici\u00eancia e liderar Lajeado como a cidade polo que ela \u00e9&#8221;. A declara\u00e7\u00e3o foi feita na quarta-feira (19) pela prefeita Gl\u00e1ucia Schumacher, durante a primeira reuni\u00e3o-almo\u00e7o (RA) de 2025 promovida pela Associa\u00e7\u00e3o Comercial e Industrial de Lajeado (Acil). Ela [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-21T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-21T13:19:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil\",\"datePublished\":\"2025-02-21T13:00:00+00:00\",\"dateModified\":\"2025-02-21T13:19:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/\"},\"wordCount\":546,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg\",\"keywords\":[\"Acil\",\"Lajeado\",\"pol\u00edtica\",\"RA\"],\"articleSection\":[\"Destaques\",\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/\",\"name\":\"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg\",\"datePublished\":\"2025-02-21T13:00:00+00:00\",\"dateModified\":\"2025-02-21T13:19:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg\",\"width\":860,\"height\":590,\"caption\":\"Para cerca de 140 pessoas, os gestores municipais falaram sobre o trabalho que vem sendo realizado pela administra\u00e7\u00e3o e alguns projetos que est\u00e3o sendo elaborados \\\/ Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/02\\\/21\\\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil - Folha Popular","og_description":"\u201cExistem alguns valores que norteiam o nosso trabalho na administra\u00e7\u00e3o municipal e, entre eles, est\u00e1 transpar\u00eancia, efici\u00eancia e liderar Lajeado como a cidade polo que ela \u00e9&#8221;. A declara\u00e7\u00e3o foi feita na quarta-feira (19) pela prefeita Gl\u00e1ucia Schumacher, durante a primeira reuni\u00e3o-almo\u00e7o (RA) de 2025 promovida pela Associa\u00e7\u00e3o Comercial e Industrial de Lajeado (Acil). Ela [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/","og_site_name":"Folha Popular","article_published_time":"2025-02-21T13:00:00+00:00","article_modified_time":"2025-02-21T13:19:55+00:00","og_image":[{"width":860,"height":590,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil","datePublished":"2025-02-21T13:00:00+00:00","dateModified":"2025-02-21T13:19:55+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/"},"wordCount":546,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg","keywords":["Acil","Lajeado","pol\u00edtica","RA"],"articleSection":["Destaques","Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/","name":"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg","datePublished":"2025-02-21T13:00:00+00:00","dateModified":"2025-02-21T13:19:55+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg","width":860,"height":590,"caption":"Para cerca de 140 pessoas, os gestores municipais falaram sobre o trabalho que vem sendo realizado pela administra\u00e7\u00e3o e alguns projetos que est\u00e3o sendo elaborados \/ Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/02\/21\/prefeita-e-vice-prefeito-de-lajeado-palestram-na-primeira-ra-da-acil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Prefeita e vice-prefeito de Lajeado palestram no primeiro RA da Acil"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-21-at-08.13.37-e1740136600454.jpeg","_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/181012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=181012"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/181012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/181013"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=181012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=181012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=181012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}