{"id":185992,"date":"2025-05-07T14:00:00","date_gmt":"2025-05-07T17:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=185992"},"modified":"2025-05-07T11:12:48","modified_gmt":"2025-05-07T14:12:48","slug":"corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/","title":{"rendered":"Corais realizam encontros e cultivam o canto coral em Imigrante"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Em 8 dias, o munic\u00edpio de Imigrante contou com a realiza\u00e7\u00e3o de dois encontros de corais. No domingo (27\/4), o Coro Misto Conc\u00f3rdia da Seca Baixa realizou sua festa e, no domingo passado (4\/5), o Coral Vozes de Daltro Filho promoveu seu encontro de corais com almo\u00e7o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sete munic\u00edpios representados no encontro no Bairro Daltro Filho, pr\u00f3ximo ao Convento S\u00e3o Boa Ventura. As apresenta\u00e7\u00f5es ocorreram dentro da Igreja, com a participa\u00e7\u00e3o dos seguintes corais: o anfitri\u00e3o Vozes de Daltro Filho, Coro Misto Conc\u00f3rdia de Seca Baixa, Coro Misto Palmas Sul de Arroio do Meio, Coro S\u00e3o Carlo de Jacarezinho em Encantado, Coro Novo Brilho de Travesseiro, Coral Cultura e Arte de Carlos Barbosa, Coral Municipal de Imigrante, Coral Municipal de Mu\u00e7um e Coral Tramontina de Farroupilha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O p\u00fablico lotou o espa\u00e7o e aplaudiu as tr\u00eas can\u00e7\u00f5es apresentadas por coral. Com m\u00fasicas variadas, os grupos encantaram o p\u00fablico com a alegria de cantar. O Coral Municipal de Imigrante adentrou \u00e0 igreja cantando e interagindo com a plateia. O Coral Tramontina fez uma participa\u00e7\u00e3o especial ao final das apresenta\u00e7\u00f5es, de forma leve e descontra\u00edda, convocando o p\u00fablico para cantar junto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Coral Vozes \u00e9 presidido por Luiz Pozocco, tem reg\u00eancia de Paulo Roberto Haas e teve na condu\u00e7\u00e3o das apresenta\u00e7\u00f5es a cantora Edi Fassini, que elogiou a presen\u00e7a de jovens nos grupos e a qualidade dos cantos apresentados pelos grupos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Corais comunit\u00e1rios mant\u00eam a tradi\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">No \u00faltimo domingo de abril, no Centro Comunit\u00e1rio da Seca Baixa, a Sociedade Recreativa Mista Conc\u00f3rdia acolheu, em sua maioria, corais comunit\u00e1rios. Participaram do encontro, apresentando duas m\u00fasicas cada, os seguintes grupos: Coral de Linha S\u00e3o Jo\u00e3o -Salvador do Sul, Coral da Linha Paissandu &#8211; Westf\u00e1lia, Coro Frohsin de Boa Vista \u2013 Teut\u00f4nia, Coral de Linha Catarina \u2013 Teut\u00f4nia, Coral Vozes de Daltro Filho \u2013 Imigrante, Vozes da Forqueta &#8211; Arroio do Meio, Associa\u00e7\u00e3o de Cantores Inova\u00e7\u00e3o de Linha Wink \u2013 Teut\u00f4nia e o Coral Sete de Setembro de Linha Ano Bom \u2013 Colinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Coral \u00e9 presidido por Traudi Richter, que deu as boas-vindas aos visitantes e tamb\u00e9m convidou a pastora da comunidade, que trouxe nas palavras do Papa Francisco uma reflex\u00e3o sobre o poder da m\u00fasica e do canto coral.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"185995\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-1024x768.jpeg\" alt=\"\" class=\"wp-image-185995\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-1024x768.jpeg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-300x225.jpeg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-768x576.jpeg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-1536x1152.jpeg 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-2048x1536.jpeg 2048w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-560x420.jpeg 560w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-80x60.jpeg 80w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-696x522.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-1068x801.jpeg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Concordia-da-Seca-Baixa-1920x1440.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Coral Conc\u00f3rdia da Seca Baixa<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"185994\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-1024x768.jpeg\" alt=\"\" class=\"wp-image-185994\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-1024x768.jpeg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-300x225.jpeg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-768x576.jpeg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-1536x1152.jpeg 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-2048x1536.jpeg 2048w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-560x420.jpeg 560w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-80x60.jpeg 80w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-696x522.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-1068x801.jpeg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-da-Tramontina-foi-convidado-especial-1920x1440.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Coral da Tramontina foi convidado especial<\/figcaption><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Cr\u00e9dito: Luciana Brune<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 8 dias, o munic\u00edpio de Imigrante contou com a realiza\u00e7\u00e3o de dois encontros de corais. No domingo (27\/4), o Coro Misto Conc\u00f3rdia da Seca Baixa realizou sua festa e, no domingo passado (4\/5), o Coral Vozes de Daltro Filho promoveu seu encontro de corais com almo\u00e7o. Sete munic\u00edpios representados no encontro no Bairro Daltro [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":185993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,6],"tags":[553,414,34],"class_list":["post-185992","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-inclusive","tag-canto-coral","tag-coral","tag-imigrante","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corais realizam encontros e cultivam o canto coral em Imigrante - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corais realizam encontros e cultivam o canto coral em Imigrante - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Em 8 dias, o munic\u00edpio de Imigrante contou com a realiza\u00e7\u00e3o de dois encontros de corais. No domingo (27\/4), o Coro Misto Conc\u00f3rdia da Seca Baixa realizou sua festa e, no domingo passado (4\/5), o Coral Vozes de Daltro Filho promoveu seu encontro de corais com almo\u00e7o. Sete munic\u00edpios representados no encontro no Bairro Daltro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-07T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luciana Brune\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luciana Brune\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/\"},\"author\":{\"name\":\"Luciana Brune\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/0999cafa38c1fde22acd2026b3a3ec1f\"},\"headline\":\"Corais realizam encontros e cultivam o canto coral em Imigrante\",\"datePublished\":\"2025-05-07T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/\"},\"wordCount\":425,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg\",\"keywords\":[\"Canto Coral\",\"Coral\",\"Imigrante\"],\"articleSection\":[\"Destaques\",\"Inclusive\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/\",\"name\":\"Corais realizam encontros e cultivam o canto coral em Imigrante - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg\",\"datePublished\":\"2025-05-07T17:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/0999cafa38c1fde22acd2026b3a3ec1f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg\",\"width\":2560,\"height\":1920,\"caption\":\"Coral Vozes de Daltro Filho - Cr\u00e9dito: Luciana Brune\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/05\\\/07\\\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corais realizam encontros e cultivam o canto coral em Imigrante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/0999cafa38c1fde22acd2026b3a3ec1f\",\"name\":\"Luciana Brune\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCIANA-1-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCIANA-1-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCIANA-1-1.webp\",\"caption\":\"Luciana Brune\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/luciana-brune\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corais realizam encontros e cultivam o canto coral em Imigrante - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/","og_locale":"pt_BR","og_type":"article","og_title":"Corais realizam encontros e cultivam o canto coral em Imigrante - Folha Popular","og_description":"Em 8 dias, o munic\u00edpio de Imigrante contou com a realiza\u00e7\u00e3o de dois encontros de corais. No domingo (27\/4), o Coro Misto Conc\u00f3rdia da Seca Baixa realizou sua festa e, no domingo passado (4\/5), o Coral Vozes de Daltro Filho promoveu seu encontro de corais com almo\u00e7o. Sete munic\u00edpios representados no encontro no Bairro Daltro [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/","og_site_name":"Folha Popular","article_published_time":"2025-05-07T17:00:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg","type":"image\/jpeg"}],"author":"Luciana Brune","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luciana Brune","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/"},"author":{"name":"Luciana Brune","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/0999cafa38c1fde22acd2026b3a3ec1f"},"headline":"Corais realizam encontros e cultivam o canto coral em Imigrante","datePublished":"2025-05-07T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/"},"wordCount":425,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg","keywords":["Canto Coral","Coral","Imigrante"],"articleSection":["Destaques","Inclusive"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/","name":"Corais realizam encontros e cultivam o canto coral em Imigrante - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg","datePublished":"2025-05-07T17:00:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/0999cafa38c1fde22acd2026b3a3ec1f"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg","width":2560,"height":1920,"caption":"Coral Vozes de Daltro Filho - Cr\u00e9dito: Luciana Brune"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/05\/07\/corais-realizam-encontros-e-cultivam-o-canto-coral-em-imigrante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Corais realizam encontros e cultivam o canto coral em Imigrante"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/0999cafa38c1fde22acd2026b3a3ec1f","name":"Luciana Brune","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCIANA-1-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCIANA-1-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCIANA-1-1.webp","caption":"Luciana Brune"},"url":"https:\/\/folhapopular.info\/index.php\/author\/luciana-brune\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/05\/Coral-Vozes-de-Daltro-Filho-scaled.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/185992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=185992"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/185992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/185993"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=185992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=185992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=185992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}