{"id":189685,"date":"2025-07-05T11:12:55","date_gmt":"2025-07-05T14:12:55","guid":{"rendered":"https:\/\/folhapopular.info\/?p=189685"},"modified":"2025-07-05T11:12:58","modified_gmt":"2025-07-05T14:12:58","slug":"vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/","title":{"rendered":"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Os vereadores de Teut\u00f4nia se reuniram na ter\u00e7a-feira (1\u00ba\/7) para votar tr\u00eas projetos de lei do Executivo &#8211; todos aprovados por unanimidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O destaque foi para o projeto de lei n\u00ba 82\/2025, que cria o Programa Municipal de Insemina\u00e7\u00e3o Artificial de Bovinos. O servi\u00e7o ser\u00e1 prestado a produtores com tal\u00e3o de produtor rural no munic\u00edpio. O Executivo ser\u00e1 respons\u00e1vel pelo pagamento do valor do procedimento de insemina\u00e7\u00e3o artificial realizado, incluindo o deslocamento do profissional at\u00e9 a propriedade e a realiza\u00e7\u00e3o do servi\u00e7o. O valor foi renegociado para R$ 26 por chamado, conforme reajuste do IPCA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O secret\u00e1rio de Agricultura e Meio Ambiente de Teut\u00f4nia, Eloir R\u00fcckert, veio \u00e0 sess\u00e3o a pedido do vereador Werner Wiebusch \u201cFIF\u201d para explicar por que o programa demorou a ser renovado &#8211; o contrato venceu em meados de fevereiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cServidores de f\u00e9rias, muito trabalho, todos os programas vencendo de uma vez, governo novo. Fizemos tomada de pre\u00e7o, ficou um pouco acima do valor dispon\u00edvel, ent\u00e3o voltou para estudo. Reformulamos e hoje foi votado\u201d, apontou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frisou que nenhum agricultor foi cobrado pelos valores durante o per\u00edodo sem a lei vigente, pois as empresas absorveram esse custo. \u201cAssim que o prefeito sancionar, voltaremos a pagar\u201d, citou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comentou que a lei que autorizava o subs\u00eddio deste servi\u00e7o por parte do Munic\u00edpio (n\u00ba 1.134\/1997) foi revogada em 2018. \u201cTinha o programa, mas n\u00e3o a lei. Apesar disso, foi pago mesmo assim. N\u00f3s nos organizamos e fizemos o projeto de lei para estar de acordo\u201d, conta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milton Stahlh\u00f6fer \u201cXir\u00fa\u201d <\/strong>enalteceu o projeto de insemina\u00e7\u00e3o. \u201c\u00c9 importante que o agricultor tenha retorno, pois seu esfor\u00e7o \u00e9 imenso\u201d, disse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FIF<\/strong> cumprimentou o secret\u00e1rio por aceitar prestar esclarecimentos. Pediu que a prefeitura antecipe renova\u00e7\u00f5es para evitar que o produtor fique sem os programas de incentivo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"546\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/Secretario-de-Agricultura-Eloir-Ruckert-explicou-sobre-o-programa-de-incentivo_CLS-scaled-e1751724406262-1024x546.jpeg\" alt=\"\" class=\"wp-image-189687\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/Secretario-de-Agricultura-Eloir-Ruckert-explicou-sobre-o-programa-de-incentivo_CLS-scaled-e1751724406262-1024x546.jpeg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/Secretario-de-Agricultura-Eloir-Ruckert-explicou-sobre-o-programa-de-incentivo_CLS-scaled-e1751724406262-300x160.jpeg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/Secretario-de-Agricultura-Eloir-Ruckert-explicou-sobre-o-programa-de-incentivo_CLS-scaled-e1751724406262-768x410.jpeg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/Secretario-de-Agricultura-Eloir-Ruckert-explicou-sobre-o-programa-de-incentivo_CLS-scaled-e1751724406262-1536x819.jpeg 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/Secretario-de-Agricultura-Eloir-Ruckert-explicou-sobre-o-programa-de-incentivo_CLS-scaled-e1751724406262-788x420.jpeg 788w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/Secretario-de-Agricultura-Eloir-Ruckert-explicou-sobre-o-programa-de-incentivo_CLS-scaled-e1751724406262-696x371.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/Secretario-de-Agricultura-Eloir-Ruckert-explicou-sobre-o-programa-de-incentivo_CLS-scaled-e1751724406262-1068x570.jpeg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/Secretario-de-Agricultura-Eloir-Ruckert-explicou-sobre-o-programa-de-incentivo_CLS-scaled-e1751724406262.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Secret\u00e1rio de Agricultura, Eloir R\u00fcckert explicou sobre o programa de incentivo. Cr\u00e9dito: Camille Lenz da Silva<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Sa\u00fade<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Neide Schwarz<\/strong> desafiou o vereador Mois\u00e9s Bageston Cardozo \u201cCavalinho\u201da trazer dados oficiais do contrato do Munic\u00edpio com o Cons\u00f3rcio Intermunicipal de Sa\u00fade (Consisa), em investiga\u00e7\u00e3o pela Pol\u00edcia Federal. \u201cOs dados est\u00e3o sendo omitidos no portal da transpar\u00eancia de Teut\u00f4nia\u201d, alegou. Acusou Mois\u00e9s de saber das 60 vagas di\u00e1rias no PA+ e n\u00e3o ter falado nada, \u201cdeixando o povo esperando por atendimento com dor\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Relatou problemas no atendimento no HOB no fim de semana passado, com pessoas sem atendimento por horas que foram ao PA+ pagar pela consulta para uma consulta. Criticou a n\u00e3o renova\u00e7\u00e3o do conv\u00eanio com o PA+ e a tentativa de transferir a responsabilidade para o hospital, que n\u00e3o vence a demanda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comparou o custo-hora do PA+ (R$ 456) com o do Consisa (R$ 1.433), afirmando que a diferen\u00e7a n\u00e3o \u00e9 economia, \u201c\u00e9 300% a mais\u201d. Afirmou que procurar\u00e1 o Tribunal de Contas do Estado para investigar a situa\u00e7\u00e3o do Consisa e do munic\u00edpio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cavalinho<\/strong> argumentou que a popula\u00e7\u00e3o n\u00e3o quer ver acusa\u00e7\u00f5es. Defendeu o Hospital Ouro Branco, que apresentou seus n\u00fameros em uma reuni\u00e3o na qual Neide n\u00e3o estava presente, e prometeu fiscalizar a casa de sa\u00fade neste fim de semana. Afirma que os vereadores buscam o melhor para os mun\u00edcipes ao fiscalizar o hospital e os postos de sa\u00fade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>H\u00e9lio Brand\u00e3o <\/strong>voltou a falar sobre o PA+. Expressou preocupa\u00e7\u00e3o com o atendimento noturno e de fim de semana no hospital, especialmente para crian\u00e7as e moradores de \u00e1reas mais distantes. \u201cMais pessoas querem que a empresa fique em Teut\u00f4nia. Nem todo mundo de Canabarro consegue transporte e ir ao PA+ seria mais f\u00e1cil\u201d, defendeu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apontou que o Consisa \u00e9 uma empresa s\u00e9ria e destacou a agilidade na aquisi\u00e7\u00e3o de ambul\u00e2ncias, contrata\u00e7\u00e3o de profissionais e medica\u00e7\u00e3o para postos de sa\u00fade. Embora n\u00e3o tenha checado a investiga\u00e7\u00e3o da Pol\u00edcia Federal, torce para que a empresa continue prestando servi\u00e7os \u00e0 cidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Valdir do Amaral \u201cDirinho\u201d <\/strong>agradeceu os R$ 500 mil destinados \u00e0 sa\u00fade para cirurgias de ves\u00edcula, h\u00e9rnia e bexiga e pediu que a prefeitura acrescente recursos para uma segunda leva de procedimentos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Obras<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jeferson K\u00f6rner <\/strong>mencionou a indica\u00e7\u00e3o de travessia elevada na Rua Ernani J\u00falio Sippel, sentido Posses, em frente ao Super da Fam\u00edlia, no Bairro Canabarro. No local h\u00e1 travessia constante de alunos e o entroncamento \u00e9 considerado perigoso. Refor\u00e7ou a necessidade de pinturas e sinaliza\u00e7\u00e3o no interior, especificamente nas linhas Wink e Germano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m, reivindica a extens\u00e3o do asfalto na Germano at\u00e9 a Artur Costa e Silva, pr\u00f3ximo ao Flamenguinho. \u201cPedido antigo da comunidade e importante para o escoamento da produ\u00e7\u00e3o\u201d, disse. <strong>M\u00e1rcio Vogel <\/strong>apoiou: \u201c\u00c9 uma das \u00faltimas localidades sem asfalto\u201d, argumentou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FIF<\/strong>, como presidente da Associa\u00e7\u00e3o de Linha Clara, agradeceu pela renova\u00e7\u00e3o do contrato do aluguel com a Emef Dom Pedro I por mais 3 anos. Tamb\u00e9m, pela subcapatazia em Linha Clara. Anunciou o asfaltamento de 2 quil\u00f4metros da estrada de Linha Frank, entre Linha Clara e Westf\u00e1lia, que deve ser executado em 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Xir\u00fa<\/strong> agradeceu pela subcapatazia em Linha Clara e refor\u00e7ou a necessidade de travessia e bueiros no Travess\u00e3o, na UPL. Mencionou ainda que os produtores rurais cobram provid\u00eancias sobre a ponte que liga \u00e0 Transamaz\u00f4nica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Valdir do Amaral \u201cDirinho\u201d<\/strong> tamb\u00e9m mencionou o asfaltamento da Rua do Travess\u00e3o. Agradeceu o prefeito Renato por ter garantido a coloca\u00e7\u00e3o de tubos maiores para o escoamento de \u00e1gua, o que evita problemas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Brand\u00e3o<\/strong> pediu ao Executivo a revis\u00e3o dos extintores de inc\u00eandio das escolas de educa\u00e7\u00e3o infantil. Citou tamb\u00e9m que a Mundo Encantado deveria ter mais de uma sa\u00edda para emerg\u00eancias, conforme os PPCIs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cavalinho <\/strong>comentou sobre a falta de \u00e1gua no Loteamento 8. Disse que a prefeitura encaminha a instala\u00e7\u00e3o de duas caixas d\u2019\u00e1gua e mais um po\u00e7o artesiano para Canabarro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tr\u00eas projetos aprovados por unanimidade<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Projeto n\u00ba 80\/2025: <\/strong>Autoriza a abertura de cr\u00e9dito adicional especial deR$ 223.934,00 para investimento no Programa Sa\u00fade na Escola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Projeto n\u00ba 81\/2025: <\/strong>Autoriza a abertura de cr\u00e9dito adicional suplementar de R$ 220 mil para a manuten\u00e7\u00e3o da frota de ve\u00edculos da Secretaria Municipal de Sa\u00fade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P<\/strong><strong>rojeto de lei n\u00ba 82\/2025:<\/strong> Cria o Programa Municipal de Insemina\u00e7\u00e3o Artificial de Bovinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indica\u00e7\u00e3o n\u00b0 159\/2025 (Nerci Nicolau Engelmann): Travessia elevada na Rua Major Bandeira, no Bairro Alesgut, nas proximidades da ferrovia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pr\u00f3xima sess\u00e3o ordin\u00e1ria da C\u00e2mara de Vereadores de Teut\u00f4nia ocorre dia 8 de julho, a partir das 18h30.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os vereadores de Teut\u00f4nia se reuniram na ter\u00e7a-feira (1\u00ba\/7) para votar tr\u00eas projetos de lei do Executivo &#8211; todos aprovados por unanimidade. O destaque foi para o projeto de lei n\u00ba 82\/2025, que cria o Programa Municipal de Insemina\u00e7\u00e3o Artificial de Bovinos. O servi\u00e7o ser\u00e1 prestado a produtores com tal\u00e3o de produtor rural no munic\u00edpio. [&hellip;]<\/p>\n","protected":false},"author":639,"featured_media":189693,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18239,18240,2,10985],"tags":[646,32,12211,2218,18943,9548,26,6260],"class_list":["post-189685","post","type-post","status-publish","format-standard","has-post-thumbnail","category-camara-de-vereadores-de-teutonia","category-camaras-de-vereadores","category-featured","category-politica","tag-camara-de-vereadores","tag-obras","tag-pa","tag-politica","tag-programa-municipal-de-inseminacao-artificial-de-bovinos","tag-sessao","tag-teutonia","tag-vereadores","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Os vereadores de Teut\u00f4nia se reuniram na ter\u00e7a-feira (1\u00ba\/7) para votar tr\u00eas projetos de lei do Executivo &#8211; todos aprovados por unanimidade. O destaque foi para o projeto de lei n\u00ba 82\/2025, que cria o Programa Municipal de Insemina\u00e7\u00e3o Artificial de Bovinos. O servi\u00e7o ser\u00e1 prestado a produtores com tal\u00e3o de produtor rural no munic\u00edpio. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-05T14:12:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-05T14:12:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Lenz da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Lenz da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/\"},\"author\":{\"name\":\"Camille Lenz da Silva\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/f0b811f932ef2505faf473ffaef49df5\"},\"headline\":\"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras\",\"datePublished\":\"2025-07-05T14:12:55+00:00\",\"dateModified\":\"2025-07-05T14:12:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/\"},\"wordCount\":1138,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg\",\"keywords\":[\"C\u00e2mara de Vereadores\",\"Obras\",\"pa+\",\"pol\u00edtica\",\"Programa Municipal de Insemina\u00e7\u00e3o Artificial de Bovinos\",\"Sess\u00e3o\",\"Teut\u00f4nia\",\"vereadores\"],\"articleSection\":[\"C\u00e2mara de Vereadores de Teut\u00f4nia\",\"C\u00e2maras de Vereadores\",\"Destaques\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/\",\"name\":\"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg\",\"datePublished\":\"2025-07-05T14:12:55+00:00\",\"dateModified\":\"2025-07-05T14:12:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/f0b811f932ef2505faf473ffaef49df5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg\",\"width\":2560,\"height\":1920,\"caption\":\"Cr\u00e9dito: Camille Lenz da Silva\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/07\\\/05\\\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/f0b811f932ef2505faf473ffaef49df5\",\"name\":\"Camille Lenz da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g\",\"caption\":\"Camille Lenz da Silva\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/camillelenzgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/","og_locale":"pt_BR","og_type":"article","og_title":"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras - Folha Popular","og_description":"Os vereadores de Teut\u00f4nia se reuniram na ter\u00e7a-feira (1\u00ba\/7) para votar tr\u00eas projetos de lei do Executivo &#8211; todos aprovados por unanimidade. O destaque foi para o projeto de lei n\u00ba 82\/2025, que cria o Programa Municipal de Insemina\u00e7\u00e3o Artificial de Bovinos. O servi\u00e7o ser\u00e1 prestado a produtores com tal\u00e3o de produtor rural no munic\u00edpio. [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/","og_site_name":"Folha Popular","article_published_time":"2025-07-05T14:12:55+00:00","article_modified_time":"2025-07-05T14:12:58+00:00","og_image":[{"width":2560,"height":1920,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg","type":"image\/jpeg"}],"author":"Camille Lenz da Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Camille Lenz da Silva","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/"},"author":{"name":"Camille Lenz da Silva","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/f0b811f932ef2505faf473ffaef49df5"},"headline":"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras","datePublished":"2025-07-05T14:12:55+00:00","dateModified":"2025-07-05T14:12:58+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/"},"wordCount":1138,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg","keywords":["C\u00e2mara de Vereadores","Obras","pa+","pol\u00edtica","Programa Municipal de Insemina\u00e7\u00e3o Artificial de Bovinos","Sess\u00e3o","Teut\u00f4nia","vereadores"],"articleSection":["C\u00e2mara de Vereadores de Teut\u00f4nia","C\u00e2maras de Vereadores","Destaques","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/","name":"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg","datePublished":"2025-07-05T14:12:55+00:00","dateModified":"2025-07-05T14:12:58+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/f0b811f932ef2505faf473ffaef49df5"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg","width":2560,"height":1920,"caption":"Cr\u00e9dito: Camille Lenz da Silva"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/07\/05\/vereadores-de-teutonia-discutem-programa-de-inseminacao-pa-e-obras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Vereadores de Teut\u00f4nia discutem programa de insemina\u00e7\u00e3o, PA+ e obras"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/f0b811f932ef2505faf473ffaef49df5","name":"Camille Lenz da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g","caption":"Camille Lenz da Silva"},"url":"https:\/\/folhapopular.info\/index.php\/author\/camillelenzgmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-05-at-11.09.25-scaled.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/189685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/639"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=189685"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/189685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/189693"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=189685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=189685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=189685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}