{"id":192322,"date":"2025-08-18T17:58:13","date_gmt":"2025-08-18T20:58:13","guid":{"rendered":"https:\/\/folhapopular.info\/?p=192322"},"modified":"2025-08-18T17:58:17","modified_gmt":"2025-08-18T20:58:17","slug":"novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/","title":{"rendered":"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante"},"content":{"rendered":"\n<p>A Administra\u00e7\u00e3o Municipal de Imigrante, por meio da Secretaria de Sa\u00fade e Assist\u00eancia Social, convida a comunidade para a inaugura\u00e7\u00e3o do novo Centro de Sa\u00fade da Fam\u00edlia. O espa\u00e7o, moderno e acolhedor, foi projetado para oferecer um atendimento ainda melhor \u00e0 popula\u00e7\u00e3o. A cerim\u00f4nia ocorre na ter\u00e7a-feira, 19 de agosto, \u00e0s 15h, na Avenida Dr. Ito Jo\u00e3o Snel, 870.<\/p>\n\n\n\n<p>Viabilizado por meio da Rede Bem Cuidar RS, o novo centro contar\u00e1 com a presen\u00e7a da secret\u00e1ria estadual da Sa\u00fade, Arita Bergmann, e do vice-governador do Estado, Gabriel Souza. O momento representa um marco hist\u00f3rico para a sa\u00fade do munic\u00edpio, refor\u00e7ando o compromisso com o cuidado e o bem-estar da comunidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Administra\u00e7\u00e3o Municipal de Imigrante, por meio da Secretaria de Sa\u00fade e Assist\u00eancia Social, convida a comunidade para a inaugura\u00e7\u00e3o do novo Centro de Sa\u00fade da Fam\u00edlia. O espa\u00e7o, moderno e acolhedor, foi projetado para oferecer um atendimento ainda melhor \u00e0 popula\u00e7\u00e3o. A cerim\u00f4nia ocorre na ter\u00e7a-feira, 19 de agosto, \u00e0s 15h, na Avenida Dr. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":192325,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,10986],"tags":[34,545,19223],"class_list":{"0":"post-192322","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-geral","8":"category-saude","9":"tag-imigrante","10":"tag-inauguracao","11":"tag-novo-centro-de-saude-da-familia","12":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Administra\u00e7\u00e3o Municipal de Imigrante, por meio da Secretaria de Sa\u00fade e Assist\u00eancia Social, convida a comunidade para a inaugura\u00e7\u00e3o do novo Centro de Sa\u00fade da Fam\u00edlia. O espa\u00e7o, moderno e acolhedor, foi projetado para oferecer um atendimento ainda melhor \u00e0 popula\u00e7\u00e3o. A cerim\u00f4nia ocorre na ter\u00e7a-feira, 19 de agosto, \u00e0s 15h, na Avenida Dr. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-18T20:58:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-18T20:58:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante\",\"datePublished\":\"2025-08-18T20:58:13+00:00\",\"dateModified\":\"2025-08-18T20:58:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/\"},\"wordCount\":137,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg\",\"keywords\":[\"Imigrante\",\"Inaugura\u00e7\u00e3o\",\"Novo Centro de Sa\u00fade da Fam\u00edlia\"],\"articleSection\":[\"Geral\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/\",\"name\":\"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg\",\"datePublished\":\"2025-08-18T20:58:13+00:00\",\"dateModified\":\"2025-08-18T20:58:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg\",\"width\":1080,\"height\":1350,\"caption\":\"Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/08\\\/18\\\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/","og_locale":"pt_BR","og_type":"article","og_title":"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante - Folha Popular","og_description":"A Administra\u00e7\u00e3o Municipal de Imigrante, por meio da Secretaria de Sa\u00fade e Assist\u00eancia Social, convida a comunidade para a inaugura\u00e7\u00e3o do novo Centro de Sa\u00fade da Fam\u00edlia. O espa\u00e7o, moderno e acolhedor, foi projetado para oferecer um atendimento ainda melhor \u00e0 popula\u00e7\u00e3o. A cerim\u00f4nia ocorre na ter\u00e7a-feira, 19 de agosto, \u00e0s 15h, na Avenida Dr. [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/","og_site_name":"Folha Popular","article_published_time":"2025-08-18T20:58:13+00:00","article_modified_time":"2025-08-18T20:58:17+00:00","og_image":[{"width":1080,"height":1350,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante","datePublished":"2025-08-18T20:58:13+00:00","dateModified":"2025-08-18T20:58:17+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/"},"wordCount":137,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg","keywords":["Imigrante","Inaugura\u00e7\u00e3o","Novo Centro de Sa\u00fade da Fam\u00edlia"],"articleSection":["Geral","Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/","name":"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg","datePublished":"2025-08-18T20:58:13+00:00","dateModified":"2025-08-18T20:58:17+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg","width":1080,"height":1350,"caption":"Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/08\/18\/novo-centro-de-saude-da-familia-sera-inaugurado-em-imigrante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Novo Centro de Sa\u00fade da Fam\u00edlia ser\u00e1 inaugurado em Imigrante"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-18-at-13.47.03.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/192322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=192322"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/192322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/192325"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=192322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=192322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=192322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}