{"id":193985,"date":"2025-09-13T12:00:00","date_gmt":"2025-09-13T15:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=193985"},"modified":"2025-09-13T10:58:26","modified_gmt":"2025-09-13T13:58:26","slug":"coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/","title":{"rendered":"Coro Misto Lira celebra 125 anos e se prepara para festival internacional"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O dia 15 de setembro de 1900 est\u00e1 registrado como o in\u00edcio das atividades da Sociedade de Cantores Lira, do Bairro Teut\u00f4nia. A entidade cultural sempre celebra o anivers\u00e1rio no s\u00e1bado mais pr\u00f3ximo da data de funda\u00e7\u00e3o. Por isso, o Gr\u00eamio Cultural e Recreativo Teutoniense sediar\u00e1 o tradicional Jantar Baile de Corais do Lira hoje (13\/9).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A recep\u00e7\u00e3o aos 10 grupos convidados come\u00e7a \u00e0s 18h30, com in\u00edcio dos cantos \u00e0s 19h30. A parte cultural deve se estender at\u00e9 por volta das 21h30, quando ser\u00e1 servido o jantar em formato de buf\u00ea. Alguns cart\u00f5es ainda est\u00e3o dispon\u00edveis com a diretoria. E, depois, tem ainda o tradicional baile animado pela Fam\u00edlia Reis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jovem presidente da entidade e professor de Hist\u00f3ria, Joelmir R\u00fcckert (24) destaca o significado de presidir o Coro Misto Lira neste marco. \u201cPresidir um grupo de 125 anos \u00e9 uma honra para mim, ainda mais quando o apoio dentro do coral \u00e9 forte. S\u00e3o 125 anos de hist\u00f3ria e o sentimento \u00e9 de orgulho. A certeza da continuidade do canto coral no Bairro Teut\u00f4nia \u00e9 afirmada cada vez mais diante desse grupo\u201d, destaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joelmir entrou no Coro Lira em 2013 e, desde ent\u00e3o, est\u00e1 presente no cotidiano do coral e vice-versa. \u201cS\u00e3o mais de 10 anos cantando e, hoje, posso afirmar que o Coral Lira \u00e9 parte da minha vida. Sempre dizemos que \u00e9 nossa segunda fam\u00edlia, e isso \u00e9 realidade. O Lira tem peso para o Bairro Teut\u00f4nia e os membros do coral; \u00e9 visto como lugar de cultura, alegria e amizade, mas, principalmente, de acolhimento\u201d, complementa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Joelmir-Ruckert_Arquivo-Pessoal.jpg\" alt=\"\" class=\"wp-image-193987\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Joelmir-Ruckert_Arquivo-Pessoal.jpg 640w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Joelmir-Ruckert_Arquivo-Pessoal-300x300.jpg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Joelmir-Ruckert_Arquivo-Pessoal-150x150.jpg 150w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Joelmir-Ruckert_Arquivo-Pessoal-420x420.jpg 420w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Com 24 anos, Joelmir R\u00fcckert contribui para manter viva a for\u00e7a do canto coral \/ Cr\u00e9dito: Arquivo Pessoal &#8211; Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Festival em BC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o baile, o Coro Lira se prepara para viajar para o 9\u00ba Festival Internacional de Corais de Balne\u00e1rio Cambori\u00fa \u2013 Santa Catarina. A programa\u00e7\u00e3o ser\u00e1 no pr\u00f3ximo fim de semana, de 19 a 21 de setembro. Al\u00e9m do Lira de Teut\u00f4nia, os corais <em>Reverb<\/em> (Salvador do Sul), Santa Cec\u00edlia (Dois Irm\u00e3os) e Infantojuvenil de Cap\u00e3o da Canoa representam o Rio Grande do Sul no evento. Haver\u00e1 grupos de Santa Catarina, S\u00e3o Paulo, Mato Grosso do Sul e dos pa\u00edses vizinhos: Argentina, Uruguai e Chile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos dias 19 e 20 haver\u00e1 jantar de confraterniza\u00e7\u00e3o \u00e0s 19h, com apresenta\u00e7\u00f5es a partir das 20h no Teatro Municipal Bruno Nitz. Pelo programa oficial do evento, o Coro Lira \u00e9 o quinto na ordem a se apresentar na sexta-feira. A grava\u00e7\u00e3o do clipe no Complexo Cristo Luz ser\u00e1 \u00e0s 9h do dia 21, domingo, com a m\u00fasica A Paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta n\u00e3o \u00e9 a primeira vez que o Coro Lira canta em solo catarinense. O grupo viajou para Lages e participou do \u201cNatal Felicidade\u201d entre os dias 9 e 11 de dezembro de 2005, cantando m\u00fasicas natalinas para milhares de pessoas no Espet\u00e1culo Janelas Encantadas, no Centro Cultural Vidal Ramos \u2013 Sesc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O dia 15 de setembro de 1900 est\u00e1 registrado como o in\u00edcio das atividades da Sociedade de Cantores Lira, do Bairro Teut\u00f4nia. A entidade cultural sempre celebra o anivers\u00e1rio no s\u00e1bado mais pr\u00f3ximo da data de funda\u00e7\u00e3o. Por isso, o Gr\u00eamio Cultural e Recreativo Teutoniense sediar\u00e1 o tradicional Jantar Baile de Corais do Lira hoje [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":193986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10996,2,6],"tags":[19455,414,19454,4845,26],"class_list":["post-193985","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura","category-featured","category-inclusive","tag-balneario-camboriu","tag-coral","tag-coro-misto-lira","tag-festival","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coro Misto Lira celebra 125 anos e se prepara para festival internacional - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coro Misto Lira celebra 125 anos e se prepara para festival internacional - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O dia 15 de setembro de 1900 est\u00e1 registrado como o in\u00edcio das atividades da Sociedade de Cantores Lira, do Bairro Teut\u00f4nia. A entidade cultural sempre celebra o anivers\u00e1rio no s\u00e1bado mais pr\u00f3ximo da data de funda\u00e7\u00e3o. Por isso, o Gr\u00eamio Cultural e Recreativo Teutoniense sediar\u00e1 o tradicional Jantar Baile de Corais do Lira hoje [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-13T15:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"961\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucas Leandro Brune\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Leandro Brune\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/\"},\"author\":{\"name\":\"Lucas Leandro Brune\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\"},\"headline\":\"Coro Misto Lira celebra 125 anos e se prepara para festival internacional\",\"datePublished\":\"2025-09-13T15:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/\"},\"wordCount\":502,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg\",\"keywords\":[\"Balne\u00e1rio Cambori\u00fa\",\"Coral\",\"Coro Misto Lira\",\"Festival\",\"Teut\u00f4nia\"],\"articleSection\":[\"Cultura\",\"Destaques\",\"Inclusive\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/\",\"name\":\"Coro Misto Lira celebra 125 anos e se prepara para festival internacional - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg\",\"datePublished\":\"2025-09-13T15:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg\",\"width\":1366,\"height\":961,\"caption\":\"Coral Lira completa 125 anos de atividades em Teut\u00f4nia \\\/ Cr\u00e9dito: Arquivo do Coral\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/13\\\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coro Misto Lira celebra 125 anos e se prepara para festival internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\",\"name\":\"Lucas Leandro Brune\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"caption\":\"Lucas Leandro Brune\"},\"description\":\"Jornalista Profissional Diplomado MTB\\\/RS 14.333\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/lucas-brune\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coro Misto Lira celebra 125 anos e se prepara para festival internacional - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/","og_locale":"pt_BR","og_type":"article","og_title":"Coro Misto Lira celebra 125 anos e se prepara para festival internacional - Folha Popular","og_description":"O dia 15 de setembro de 1900 est\u00e1 registrado como o in\u00edcio das atividades da Sociedade de Cantores Lira, do Bairro Teut\u00f4nia. A entidade cultural sempre celebra o anivers\u00e1rio no s\u00e1bado mais pr\u00f3ximo da data de funda\u00e7\u00e3o. Por isso, o Gr\u00eamio Cultural e Recreativo Teutoniense sediar\u00e1 o tradicional Jantar Baile de Corais do Lira hoje [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/","og_site_name":"Folha Popular","article_published_time":"2025-09-13T15:00:00+00:00","og_image":[{"width":1366,"height":961,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg","type":"image\/jpeg"}],"author":"Lucas Leandro Brune","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Leandro Brune","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/"},"author":{"name":"Lucas Leandro Brune","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36"},"headline":"Coro Misto Lira celebra 125 anos e se prepara para festival internacional","datePublished":"2025-09-13T15:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/"},"wordCount":502,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg","keywords":["Balne\u00e1rio Cambori\u00fa","Coral","Coro Misto Lira","Festival","Teut\u00f4nia"],"articleSection":["Cultura","Destaques","Inclusive"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/","name":"Coro Misto Lira celebra 125 anos e se prepara para festival internacional - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg","datePublished":"2025-09-13T15:00:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg","width":1366,"height":961,"caption":"Coral Lira completa 125 anos de atividades em Teut\u00f4nia \/ Cr\u00e9dito: Arquivo do Coral"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/13\/coro-misto-lira-celebra-125-anos-e-se-prepara-para-festival-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Coro Misto Lira celebra 125 anos e se prepara para festival internacional"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36","name":"Lucas Leandro Brune","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","caption":"Lucas Leandro Brune"},"description":"Jornalista Profissional Diplomado MTB\/RS 14.333","url":"https:\/\/folhapopular.info\/index.php\/author\/lucas-brune\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Coral-Lira-completa-125-anos-de-atividades-em-Teutonia_Arquivo-do-Coral.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/193985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=193985"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/193985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/193986"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=193985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=193985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=193985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}