{"id":194251,"date":"2025-09-17T13:00:00","date_gmt":"2025-09-17T16:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=194251"},"modified":"2025-09-17T09:12:14","modified_gmt":"2025-09-17T12:12:14","slug":"coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/","title":{"rendered":"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Sociedade de Cantores Lira, do Bairro Teut\u00f4nia, completou 125 anos de funda\u00e7\u00e3o nessa segunda-feira (15\/9) e teve uma noite marcada por emo\u00e7\u00e3o e reconhecimento. O tradicional Jantar Baile de Corais, realizado s\u00e1bado (13\/9) no Gr\u00eamio Cultural e Recreativo Teutoniense, reuniu grupos convidados, associados e a comunidade em uma celebra\u00e7\u00e3o que refor\u00e7ou a import\u00e2ncia do canto coral para a identidade local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ponto alto da comemora\u00e7\u00e3o foi a s\u00e9rie de homenagens prestadas a integrantes e ex-integrantes que dedicaram d\u00e9cadas de suas vidas ao coral. Entre eles, o destaque foi para N\u00e9lson Stapenhorst, hoje com 93 anos, lembrado por cerca de 65 anos de dedica\u00e7\u00e3o ao grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSua contribui\u00e7\u00e3o vai muito al\u00e9m das apresenta\u00e7\u00f5es: atuou na diretoria e esteve presente em diversas frentes de apoio \u00e0 comunidade, simbolizando uma vida inteira dedicada \u00e0 m\u00fasica coral\u201d, destacou o atual presidente, Joelmir R\u00fcckert. Stapenhorst era o presidente mais jovem a assumir o Lira, quando tinha 26 anos. Ano passado, aos 23 anos, R\u00fcckert superou esta marca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m foram lembrados Nelson e Gonda Osterkamp, casal cuja atua\u00e7\u00e3o conjunta refor\u00e7ou a tradi\u00e7\u00e3o coral no munic\u00edpio. Nelson, com 10 anos na diretoria, e Gonda, com presen\u00e7a ativa nas atividades, deixaram um legado de parceria e compromisso. J\u00e1 Merida Huwe foi reconhecida por sua longa trajet\u00f3ria como cantora, lembrada com gratid\u00e3o mesmo ap\u00f3s encerrar sua participa\u00e7\u00e3o ativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre os atuais integrantes, o ex-presidente Danilo R\u00fcckert recebeu homenagem pelo trabalho de lideran\u00e7a que manteve firme a tradi\u00e7\u00e3o da Lira durante uma d\u00e9cada. Outra celebra\u00e7\u00e3o especial foi para Ivone Drebes (85), que segue cantando e encantando, sendo vista como exemplo de vitalidade e inspira\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A noite ainda reservou um momento de sil\u00eancio em mem\u00f3ria de Ot\u00e9cio Decker, falecido em agosto, lembrado pelo entusiasmo e dedica\u00e7\u00e3o ao grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPresidir um grupo de 125 anos \u00e9 uma honra, ainda mais quando o grupo de apoio dentro do coral \u00e9 forte. S\u00e3o 125 anos de hist\u00f3ria. O sentimento \u00e9 de orgulho e a certeza da continuidade do canto coral no Bairro Teut\u00f4nia \u00e9 afirmada cada vez mais diante desse grupo\u201d, afirmou R\u00fcckert. Para ele, o coral representa um espa\u00e7o de pertencimento: \u201cS\u00e3o mais de 10 anos cantando e, hoje, posso afirmar que o Coral Lira \u00e9 parte da minha vida. Sempre dizemos que \u00e9 nossa segunda fam\u00edlia e isso \u00e9 realidade. O Coral Lira tem peso para o Bairro Teut\u00f4nia. \u00c9 visto como lugar de cultura, alegria, amizade mas, principalmente, de acolhimento\u201d, refor\u00e7a o presidente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-1024x768.jpeg\" alt=\"\" class=\"wp-image-194253\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-1024x768.jpeg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-300x225.jpeg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-768x576.jpeg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-1536x1152.jpeg 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-2048x1536.jpeg 2048w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-560x420.jpeg 560w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-80x60.jpeg 80w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-696x522.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-1068x801.jpeg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Homenagens-reafirmaram-a-tradicao-do-canto-coral-em-Teutonia-1920x1440.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><br>Homenagens reafirmaram a tradi\u00e7\u00e3o do canto coral em Teut\u00f4nia \/ Cr\u00e9dito: Lucas Leandro Brune<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Subir para BC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O grupo se prepara para representar Teut\u00f4nia no 9\u00ba Festival Internacional de Corais de Balne\u00e1rio Cambori\u00fa (SC), de sexta-feira at\u00e9 domingo (19 a 21\/9). O evento reunir\u00e1 corais do Brasil, Argentina, Uruguai e Chile, reafirmando o papel do Lira como embaixador cultural da Capital Nacional do Canto Coral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Sociedade de Cantores Lira, do Bairro Teut\u00f4nia, completou 125 anos de funda\u00e7\u00e3o nessa segunda-feira (15\/9) e teve uma noite marcada por emo\u00e7\u00e3o e reconhecimento. O tradicional Jantar Baile de Corais, realizado s\u00e1bado (13\/9) no Gr\u00eamio Cultural e Recreativo Teutoniense, reuniu grupos convidados, associados e a comunidade em uma celebra\u00e7\u00e3o que refor\u00e7ou a import\u00e2ncia do [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":194252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,6],"tags":[553,414,19489,19488,26],"class_list":["post-194251","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-inclusive","tag-canto-coral","tag-coral","tag-coro-lira","tag-sociedade-de-cantores-lira","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Sociedade de Cantores Lira, do Bairro Teut\u00f4nia, completou 125 anos de funda\u00e7\u00e3o nessa segunda-feira (15\/9) e teve uma noite marcada por emo\u00e7\u00e3o e reconhecimento. O tradicional Jantar Baile de Corais, realizado s\u00e1bado (13\/9) no Gr\u00eamio Cultural e Recreativo Teutoniense, reuniu grupos convidados, associados e a comunidade em uma celebra\u00e7\u00e3o que refor\u00e7ou a import\u00e2ncia do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T16:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucas Leandro Brune\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Leandro Brune\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/\"},\"author\":{\"name\":\"Lucas Leandro Brune\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\"},\"headline\":\"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos\",\"datePublished\":\"2025-09-17T16:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/\"},\"wordCount\":505,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg\",\"keywords\":[\"Canto Coral\",\"Coral\",\"Coro Lira\",\"Sociedade de Cantores Lira\",\"Teut\u00f4nia\"],\"articleSection\":[\"Destaques\",\"Inclusive\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/\",\"name\":\"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg\",\"datePublished\":\"2025-09-17T16:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg\",\"width\":2560,\"height\":1920,\"caption\":\"Evento reuniu grupos convidados, associados e a comunidade e refor\u00e7ou a import\u00e2ncia do canto coral para a identidade local \\\/ Cr\u00e9dito: Lucas Leandro Brune\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/17\\\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\",\"name\":\"Lucas Leandro Brune\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"caption\":\"Lucas Leandro Brune\"},\"description\":\"Jornalista Profissional Diplomado MTB\\\/RS 14.333\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/lucas-brune\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/","og_locale":"pt_BR","og_type":"article","og_title":"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos - Folha Popular","og_description":"A Sociedade de Cantores Lira, do Bairro Teut\u00f4nia, completou 125 anos de funda\u00e7\u00e3o nessa segunda-feira (15\/9) e teve uma noite marcada por emo\u00e7\u00e3o e reconhecimento. O tradicional Jantar Baile de Corais, realizado s\u00e1bado (13\/9) no Gr\u00eamio Cultural e Recreativo Teutoniense, reuniu grupos convidados, associados e a comunidade em uma celebra\u00e7\u00e3o que refor\u00e7ou a import\u00e2ncia do [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/","og_site_name":"Folha Popular","article_published_time":"2025-09-17T16:00:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg","type":"image\/jpeg"}],"author":"Lucas Leandro Brune","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Leandro Brune","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/"},"author":{"name":"Lucas Leandro Brune","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36"},"headline":"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos","datePublished":"2025-09-17T16:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/"},"wordCount":505,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg","keywords":["Canto Coral","Coral","Coro Lira","Sociedade de Cantores Lira","Teut\u00f4nia"],"articleSection":["Destaques","Inclusive"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/","name":"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg","datePublished":"2025-09-17T16:00:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg","width":2560,"height":1920,"caption":"Evento reuniu grupos convidados, associados e a comunidade e refor\u00e7ou a import\u00e2ncia do canto coral para a identidade local \/ Cr\u00e9dito: Lucas Leandro Brune"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/17\/coro-lira-celebra-125-anos-com-homenagens-a-integrantes-historicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Coro Lira celebra 125 anos com homenagens a integrantes hist\u00f3ricos"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36","name":"Lucas Leandro Brune","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","caption":"Lucas Leandro Brune"},"description":"Jornalista Profissional Diplomado MTB\/RS 14.333","url":"https:\/\/folhapopular.info\/index.php\/author\/lucas-brune\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/Evento-reuniu-grupos-convidados-associados-e-a-comunidade-e-reforcou-a-importancia-do-canto-coral-para-a-identidade-local-scaled.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/194251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=194251"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/194251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/194252"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=194251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=194251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=194251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}