{"id":194879,"date":"2025-09-25T14:00:00","date_gmt":"2025-09-25T17:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=194879"},"modified":"2025-09-25T11:24:17","modified_gmt":"2025-09-25T14:24:17","slug":"feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/","title":{"rendered":"Feira do Livro de Imigrante acontece de 9 a 11 de outubro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Administra\u00e7\u00e3o Municipal de Imigrante, por meio da Secretaria de Educa\u00e7\u00e3o, promove entre os dias 9 e 11 de outubro a Feira do Livro 2025, que ocorre no Gin\u00e1sio Municipal e traz como tema \u201cFa\u00e7a a leitura florescer!\u201d. A programa\u00e7\u00e3o inclui a participa\u00e7\u00e3o de escritores, apresenta\u00e7\u00f5es culturais, teatro, m\u00fasica, feira de artesanato e atividades de integra\u00e7\u00e3o para todos os p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A abertura oficial ser\u00e1 na quarta-feira (9\/10) com a pe\u00e7a teatral \u201cA m\u00e3e natureza e o pacto secreto: uma aventura ecol\u00f3gica\u201d, seguida de palestra da escritora Eleonora Medeiros, voltada a estudantes da Educa\u00e7\u00e3o Infantil e dos Anos Iniciais. \u00c0 noite, a cerim\u00f4nia de abertura contar\u00e1 com a apresenta\u00e7\u00e3o da Orquestra Municipal de Imigrante e atividades culturais da Rede Municipal de Ensino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na quinta-feira (10\/10) o destaque ser\u00e1 a palestra do escritor Jonas Piccoli com alunos dos Anos Finais e Ensino M\u00e9dio. A programa\u00e7\u00e3o da tarde inclui a reapresenta\u00e7\u00e3o da pe\u00e7a teatral e, \u00e0 noite, apresenta\u00e7\u00f5es da Orquestra Jovem de Imigrante, atividades culturais dos Anos Iniciais e o espet\u00e1culo \u201cAs Aventuras do Fusca \u00e0 Vela\u201d, do Grupo UEBA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um diferencial da programa\u00e7\u00e3o \u00e9 a participa\u00e7\u00e3o dos propriet\u00e1rios de Fusca. Quem comparecer na sexta-feira \u00e0 noite com seu ve\u00edculo poder\u00e1 estacionar em local exclusivo e receber um vale de R$ 20,00 para compras na banca de livros da Feira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O encerramento ser\u00e1 no s\u00e1bado (11\/10) com atividades abertas \u00e0 comunidade em parceria com a Secretaria de Sa\u00fade e Assist\u00eancia Social. Entre as atra\u00e7\u00f5es est\u00e3o exposi\u00e7\u00e3o e venda de livros, brinquedos infl\u00e1veis, recrea\u00e7\u00e3o infantil, Tenda da Sa\u00fade, Tenda do CRAS, feira de artesanato e m\u00fasica ao vivo com voz e viol\u00e3o durante a tarde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A identidade visual da Feira foi desenvolvida a partir das produ\u00e7\u00f5es vencedoras do concurso escolar promovido pela Secretaria de Educa\u00e7\u00e3o. O desenho \u00e9 de Vit\u00f3ria Kesseler Cardoso, aluna do 5\u00ba ano da Emef Arco-\u00cdris, e o slogan foi criado por Gean Carlos Weirich, estudante do 8\u00ba ano da Emef Santo Ant\u00f4nio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Administra\u00e7\u00e3o Municipal de Imigrante, por meio da Secretaria de Educa\u00e7\u00e3o, promove entre os dias 9 e 11 de outubro a Feira do Livro 2025, que ocorre no Gin\u00e1sio Municipal e traz como tema \u201cFa\u00e7a a leitura florescer!\u201d. A programa\u00e7\u00e3o inclui a participa\u00e7\u00e3o de escritores, apresenta\u00e7\u00f5es culturais, teatro, m\u00fasica, feira de artesanato e atividades de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":194880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,6],"tags":[322,34,2002],"class_list":["post-194879","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-inclusive","tag-feira-do-livro","tag-imigrante","tag-livros","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feira do Livro de Imigrante acontece de 9 a 11 de outubro - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feira do Livro de Imigrante acontece de 9 a 11 de outubro - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Administra\u00e7\u00e3o Municipal de Imigrante, por meio da Secretaria de Educa\u00e7\u00e3o, promove entre os dias 9 e 11 de outubro a Feira do Livro 2025, que ocorre no Gin\u00e1sio Municipal e traz como tema \u201cFa\u00e7a a leitura florescer!\u201d. A programa\u00e7\u00e3o inclui a participa\u00e7\u00e3o de escritores, apresenta\u00e7\u00f5es culturais, teatro, m\u00fasica, feira de artesanato e atividades de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/CTS_5134-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Feira do Livro de Imigrante acontece de 9 a 11 de outubro\",\"datePublished\":\"2025-09-25T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/\"},\"wordCount\":358,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/CTS_5134-scaled.jpg\",\"keywords\":[\"Feira do Livro\",\"Imigrante\",\"Livros\"],\"articleSection\":[\"Destaques\",\"Inclusive\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/\",\"name\":\"Feira do Livro de Imigrante acontece de 9 a 11 de outubro - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/CTS_5134-scaled.jpg\",\"datePublished\":\"2025-09-25T17:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/CTS_5134-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/CTS_5134-scaled.jpg\",\"width\":2560,\"height\":1708,\"caption\":\"Cr\u00e9dito: Cris Thom\u00e9 \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/09\\\/25\\\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feira do Livro de Imigrante acontece de 9 a 11 de outubro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feira do Livro de Imigrante acontece de 9 a 11 de outubro - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/","og_locale":"pt_BR","og_type":"article","og_title":"Feira do Livro de Imigrante acontece de 9 a 11 de outubro - Folha Popular","og_description":"A Administra\u00e7\u00e3o Municipal de Imigrante, por meio da Secretaria de Educa\u00e7\u00e3o, promove entre os dias 9 e 11 de outubro a Feira do Livro 2025, que ocorre no Gin\u00e1sio Municipal e traz como tema \u201cFa\u00e7a a leitura florescer!\u201d. A programa\u00e7\u00e3o inclui a participa\u00e7\u00e3o de escritores, apresenta\u00e7\u00f5es culturais, teatro, m\u00fasica, feira de artesanato e atividades de [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/","og_site_name":"Folha Popular","article_published_time":"2025-09-25T17:00:00+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/CTS_5134-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Feira do Livro de Imigrante acontece de 9 a 11 de outubro","datePublished":"2025-09-25T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/"},"wordCount":358,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/CTS_5134-scaled.jpg","keywords":["Feira do Livro","Imigrante","Livros"],"articleSection":["Destaques","Inclusive"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/","name":"Feira do Livro de Imigrante acontece de 9 a 11 de outubro - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/CTS_5134-scaled.jpg","datePublished":"2025-09-25T17:00:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/CTS_5134-scaled.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/CTS_5134-scaled.jpg","width":2560,"height":1708,"caption":"Cr\u00e9dito: Cris Thom\u00e9 \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/09\/25\/feira-do-livro-de-imigrante-acontece-de-9-a-11-de-outubro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Feira do Livro de Imigrante acontece de 9 a 11 de outubro"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/09\/CTS_5134-scaled.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/194879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=194879"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/194879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/194880"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=194879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=194879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=194879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}