{"id":196465,"date":"2025-10-19T14:00:00","date_gmt":"2025-10-19T17:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=196465"},"modified":"2025-10-18T09:30:48","modified_gmt":"2025-10-18T12:30:48","slug":"fabiano-diehl-lanca-pre-candidatura-a-deputado","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/","title":{"rendered":"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Faltando pouco menos de um ano para as elei\u00e7\u00f5es, Fabiano Eug\u00eanio Diehl anunciou sua pr\u00e9-candidatura a deputado estadual pelo Uni\u00e3o Brasil. O atual assessor de comunica\u00e7\u00e3o da C\u00e2mara de Vereadores de Estrela possui uma bagagem pol\u00edtica que abrange tanto o Poder Executivo quanto o Legislativo, com atua\u00e7\u00e3o em n\u00edveis municipal e estadual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jornalista e graduando em Marketing, Diehl j\u00e1 prestou servi\u00e7os nas secretarias estaduais do Trabalho e Assist\u00eancia Social e de Economia Solid\u00e1ria e atuou nas gest\u00f5es dos ex-prefeitos de Estrela, Carlos Rafael Mallmann e Elmar Schneider, considerados por ele como duas grandes refer\u00eancias pol\u00edticas. J\u00e1 na Assembleia Legislativa, teve a oportunidade de trabalhar por 4anos com o ex-deputado Maur\u00edcio Dziedricki.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fabiano tamb\u00e9m \u00e9 irm\u00e3o de Felipe Diehl, atual vereador de Estrela, mas que j\u00e1 concorreu a deputado federal e tem forte atua\u00e7\u00e3o na pol\u00edtica regional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GP \u2013 Qual o motivo da sua candidatura?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diehl \u2013 A falta de \u00eaxito do Vale do Taquari em eleger deputados nas elei\u00e7\u00f5es recentes. Embora o Vale j\u00e1 tenha tido v\u00e1rios bons deputados que trabalharam muito pela regi\u00e3o, isso n\u00e3o ocorreu de novo recentemente. Lancei a candidatura justamente para florar esse debate aqui na regi\u00e3o. Precisamos come\u00e7ar a discutir elei\u00e7\u00f5es agora, porque se n\u00e3o, as entidades regionais ir\u00e3o para Porto Alegre buscar apoio e os vereadores seguir\u00e3o apoiando deputados de fora do Vale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GP \u2013 \u201cT\u00f4 por ti, t\u00f4 pelo Vale\u201d. O que esse slogan significa?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diehl \u2013 Nas cat\u00e1strofes, a regi\u00e3o esteve \u00f3rf\u00e3 de representa\u00e7\u00e3o. Tem mais de 5 mil pessoas sem casa 2 anos depois. O Vale precisa de uma voz no Parlamento Ga\u00facho para discutir temas cruciais, buscar experi\u00eancias que j\u00e1 deram certo em outras regi\u00f5es, estados e pa\u00edses. A proposta da minha pr\u00e9-candidatura \u00e9, atrav\u00e9s principalmente das redes sociais, chegar direto na dona Maria, no seu Jo\u00e3o, essa maioria que precisa ter suas demandas atendidas. Da mesma forma, a gente precisa trabalhar uma defesa civil regional forte, que fa\u00e7a um trabalho conjunto. Do outro lado, depois de tanto tempo de estiagem, n\u00e3o fizemos o tema de reter \u00e1gua da chuva. Precisa haver algu\u00e9m na Assembleia que defenda esses projetos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GP \u2013 Como furar a bolha para eleger algu\u00e9m do Vale?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diehl \u2013 Eu quero ser candidato a deputado para ser deputado, n\u00e3o para ir a prefeito ou vereador na pr\u00f3xima elei\u00e7\u00e3o ou para conseguir um cargo com outro deputado. N\u00e3o estou pelos poderosos e pelas raposas da pol\u00edtica. Estou por quem perdeu tudo na enchente e ainda est\u00e1 sem casa, por quem paga ped\u00e1gio e n\u00e3o tem estrada, que quer empreender na cidade e no interior e n\u00e3o tem apoio, que est\u00e1 cansado de ser esquecido pelos governos. Sou despojado de qualquer ego, se a regi\u00e3o entender que tem um nome com maior viabilidade eleitoral que consiga furar a bolha, vamos conversar, assim como tamb\u00e9m quero que conversem comigo. \u00c9 o nosso papel como l\u00edderes pol\u00edticos costurar essas conversas. O erro da regi\u00e3o \u00e9 ter pr\u00e9-candidatos de direita batendo nos de esquerda e vice-versa em vez de se ajudarem em prol do Vale. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faltando pouco menos de um ano para as elei\u00e7\u00f5es, Fabiano Eug\u00eanio Diehl anunciou sua pr\u00e9-candidatura a deputado estadual pelo Uni\u00e3o Brasil. O atual assessor de comunica\u00e7\u00e3o da C\u00e2mara de Vereadores de Estrela possui uma bagagem pol\u00edtica que abrange tanto o Poder Executivo quanto o Legislativo, com atua\u00e7\u00e3o em n\u00edveis municipal e estadual. Jornalista e graduando [&hellip;]<\/p>\n","protected":false},"author":639,"featured_media":196466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,10985],"tags":[2503,8,2218,9622],"class_list":["post-196465","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-politica","tag-deputado","tag-estrela","tag-politica","tag-pre-candidatura","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Faltando pouco menos de um ano para as elei\u00e7\u00f5es, Fabiano Eug\u00eanio Diehl anunciou sua pr\u00e9-candidatura a deputado estadual pelo Uni\u00e3o Brasil. O atual assessor de comunica\u00e7\u00e3o da C\u00e2mara de Vereadores de Estrela possui uma bagagem pol\u00edtica que abrange tanto o Poder Executivo quanto o Legislativo, com atua\u00e7\u00e3o em n\u00edveis municipal e estadual. Jornalista e graduando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-19T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Fabiano-Diehl_CLS.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Lenz da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Lenz da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/\"},\"author\":{\"name\":\"Camille Lenz da Silva\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/f0b811f932ef2505faf473ffaef49df5\"},\"headline\":\"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado\",\"datePublished\":\"2025-10-19T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/\"},\"wordCount\":557,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Fabiano-Diehl_CLS.jpeg\",\"keywords\":[\"Deputado\",\"Estrela\",\"pol\u00edtica\",\"Pr\u00e9-candidatura\"],\"articleSection\":[\"Destaques\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/\",\"name\":\"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Fabiano-Diehl_CLS.jpeg\",\"datePublished\":\"2025-10-19T17:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/f0b811f932ef2505faf473ffaef49df5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Fabiano-Diehl_CLS.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Fabiano-Diehl_CLS.jpeg\",\"width\":1280,\"height\":960,\"caption\":\"Fabiano Diehl \\\/ Cr\u00e9dito: Camille Lenz da Silva\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/19\\\/fabiano-diehl-lanca-pre-candidatura-a-deputado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/f0b811f932ef2505faf473ffaef49df5\",\"name\":\"Camille Lenz da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g\",\"caption\":\"Camille Lenz da Silva\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/camillelenzgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/","og_locale":"pt_BR","og_type":"article","og_title":"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado - Folha Popular","og_description":"Faltando pouco menos de um ano para as elei\u00e7\u00f5es, Fabiano Eug\u00eanio Diehl anunciou sua pr\u00e9-candidatura a deputado estadual pelo Uni\u00e3o Brasil. O atual assessor de comunica\u00e7\u00e3o da C\u00e2mara de Vereadores de Estrela possui uma bagagem pol\u00edtica que abrange tanto o Poder Executivo quanto o Legislativo, com atua\u00e7\u00e3o em n\u00edveis municipal e estadual. Jornalista e graduando [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/","og_site_name":"Folha Popular","article_published_time":"2025-10-19T17:00:00+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Fabiano-Diehl_CLS.jpeg","type":"image\/jpeg"}],"author":"Camille Lenz da Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Camille Lenz da Silva","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/"},"author":{"name":"Camille Lenz da Silva","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/f0b811f932ef2505faf473ffaef49df5"},"headline":"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado","datePublished":"2025-10-19T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/"},"wordCount":557,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Fabiano-Diehl_CLS.jpeg","keywords":["Deputado","Estrela","pol\u00edtica","Pr\u00e9-candidatura"],"articleSection":["Destaques","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/","name":"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Fabiano-Diehl_CLS.jpeg","datePublished":"2025-10-19T17:00:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/f0b811f932ef2505faf473ffaef49df5"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Fabiano-Diehl_CLS.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Fabiano-Diehl_CLS.jpeg","width":1280,"height":960,"caption":"Fabiano Diehl \/ Cr\u00e9dito: Camille Lenz da Silva"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/19\/fabiano-diehl-lanca-pre-candidatura-a-deputado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Fabiano Diehl lan\u00e7a pr\u00e9-candidatura a deputado"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/f0b811f932ef2505faf473ffaef49df5","name":"Camille Lenz da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g","caption":"Camille Lenz da Silva"},"url":"https:\/\/folhapopular.info\/index.php\/author\/camillelenzgmail-com\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Fabiano-Diehl_CLS.jpeg","_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/196465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/639"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=196465"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/196465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/196466"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=196465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=196465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=196465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}