{"id":196866,"date":"2025-10-25T14:00:00","date_gmt":"2025-10-25T17:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=196866"},"modified":"2025-10-25T08:20:09","modified_gmt":"2025-10-25T11:20:09","slug":"cidade-jardim-se-prepara-para-o-6o-festival-da-primavera","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/","title":{"rendered":"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O 6\u00ba Festival de Primavera de Colinas foi lan\u00e7ado na 32\u00aa <em>Blumentazfest<\/em>, o Baile das Flores, com a divulga\u00e7\u00e3o do resultado do concurso de jardim mais bonito da cidade. A programa\u00e7\u00e3o segue oficialmente de 30 de outubro a 2 de novembro na Pra\u00e7a dos P\u00e1ssaros. De acordo com a vice-prefeita e secret\u00e1ria de Cultura, Educa\u00e7\u00e3o e Turismo, Maristela Nicolodi, o munic\u00edpio espera um p\u00fablico de 10 mil pessoas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A abertura oficial ser\u00e1 na pr\u00f3xima quinta-feira (30\/10), \u00e0s 19h30, seguida pela apresenta\u00e7\u00e3o da Orquestra Municipal de Colinas e pela divulga\u00e7\u00e3o do resultado do concurso fotogr\u00e1fico \u201cRespira, Suspira\u201d. A noite encerra com o show de Wilceu Pause e Banda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na sexta-feira (31\/10), feriado, a programa\u00e7\u00e3o come\u00e7a com oficinas e segue com o Pagode da Kissa Braga, o Astronauta Jorge Maia e o cantor Kau\u00ea Brixner.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O s\u00e1bado (1\u00ba\/11) ter\u00e1 uma agenda intensa, com Feira do Produtor Rural, oficinas e shows com Rafa Haas, Banda Apple e Autom\u00f3vel Verde. O ponto alto da noite ser\u00e1 o show de Duca Leindecker, \u00e0s 21h30, seguido por DJ e participa\u00e7\u00e3o de vin\u00edcolas e cervejarias locais.<br>O encerramento acontece no domingo (2\/11), com novas oficinas, apresenta\u00e7\u00f5es da Banda Contato Show e <em>Star<\/em> 3. A atra\u00e7\u00e3o final fica por conta da Super Banda K\u2019necus, \u00e0s 18h.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os visitantes ainda poder\u00e3o prestigiar um espet\u00e1culo teatral. O projeto \u201cEntre bosques e jardins, muitas hist\u00f3rias para contar\u201d \u00e9 uma iniciativa em que as crian\u00e7as da Escola Municipal de Ensino Fundamental (Emef) Ipiranga encenam hist\u00f3rias nos jardins e p\u00e1tios da comunidade. As apresenta\u00e7\u00f5es j\u00e1 aconteceram na Linha 31 de Outubro, na Linha Santo Ant\u00f4nio e tamb\u00e9m no centro de Colinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda, haver\u00e1 a participa\u00e7\u00e3o de vin\u00edcolas e cervejarias locais e da feira do produtor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Oficinas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Emater e a Secretaria da Agricultura e Meio Ambiente tamb\u00e9m far\u00e3o parte da programa\u00e7\u00e3o, oferecendo tr\u00eas oficinas voltadas ao cultivo de plantas. Uma delas ser\u00e1 sobre compostagem e preparo de substrato para flores. Outra abordar\u00e1 o m\u00e9todo de estaquia, utilizado no replantio de mudas, t\u00e9cnica aplicada inclusive na propaga\u00e7\u00e3o da <em>Kalanchoe<\/em>, flor presente na bandeira do munic\u00edpio. No domingo, haver\u00e1 uma oficina especial dedicada ao cultivo de orqu\u00eddeas, com orienta\u00e7\u00f5es sobre substratos, adubos e cuidados essenciais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O evento \u00e9 promovido pela Prefeitura de Colinas, com apoio da <strong>Associa\u00e7\u00e3o Cultural, Esportiva e Recreativa de Colinas<\/strong> (Acerc), Sicredi e financiamento do Pr\u00f3-Cultura RS, atrav\u00e9s da Secretaria de Estado da Cultura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O 6\u00ba Festival de Primavera de Colinas foi lan\u00e7ado na 32\u00aa Blumentazfest, o Baile das Flores, com a divulga\u00e7\u00e3o do resultado do concurso de jardim mais bonito da cidade. A programa\u00e7\u00e3o segue oficialmente de 30 de outubro a 2 de novembro na Pra\u00e7a dos P\u00e1ssaros. De acordo com a vice-prefeita e secret\u00e1ria de Cultura, Educa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":673,"featured_media":196868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10996,2,6],"tags":[19785,183,7124],"class_list":["post-196866","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura","category-featured","category-inclusive","tag-6o-festival-de-primavera","tag-colinas","tag-festival-de-primavera","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cidade Jardim se prepara para o 6\u00ba Festival da Primavera - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O 6\u00ba Festival de Primavera de Colinas foi lan\u00e7ado na 32\u00aa Blumentazfest, o Baile das Flores, com a divulga\u00e7\u00e3o do resultado do concurso de jardim mais bonito da cidade. A programa\u00e7\u00e3o segue oficialmente de 30 de outubro a 2 de novembro na Pra\u00e7a dos P\u00e1ssaros. De acordo com a vice-prefeita e secret\u00e1ria de Cultura, Educa\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-25T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Let\u00edcia Echer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Let\u00edcia Echer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/\"},\"author\":{\"name\":\"Let\u00edcia Echer\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/52b95b9c1c41ec0e826e7518183d0cc0\"},\"headline\":\"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera\",\"datePublished\":\"2025-10-25T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/\"},\"wordCount\":434,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg\",\"keywords\":[\"6\u00ba Festival de Primavera\",\"Colinas\",\"Festival de Primavera\"],\"articleSection\":[\"Cultura\",\"Destaques\",\"Inclusive\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/\",\"name\":\"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg\",\"datePublished\":\"2025-10-25T17:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/52b95b9c1c41ec0e826e7518183d0cc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Programa\u00e7\u00e3o inclui oficinas, shows, feira do produtor rural e apresenta\u00e7\u00f5es culturais na Pra\u00e7a dos P\u00e1ssaros \\\/ Cr\u00e9dito: Prefeitura de Colinas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/10\\\/25\\\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/52b95b9c1c41ec0e826e7518183d0cc0\",\"name\":\"Let\u00edcia Echer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/303201b45d8f4e048c95808925ff8953fa7ebc0e52cb5b3af1fc9e3d52c95645?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/303201b45d8f4e048c95808925ff8953fa7ebc0e52cb5b3af1fc9e3d52c95645?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/303201b45d8f4e048c95808925ff8953fa7ebc0e52cb5b3af1fc9e3d52c95645?s=96&d=mm&r=g\",\"caption\":\"Let\u00edcia Echer\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/leticiaecher04gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/","og_locale":"pt_BR","og_type":"article","og_title":"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera - Folha Popular","og_description":"O 6\u00ba Festival de Primavera de Colinas foi lan\u00e7ado na 32\u00aa Blumentazfest, o Baile das Flores, com a divulga\u00e7\u00e3o do resultado do concurso de jardim mais bonito da cidade. A programa\u00e7\u00e3o segue oficialmente de 30 de outubro a 2 de novembro na Pra\u00e7a dos P\u00e1ssaros. De acordo com a vice-prefeita e secret\u00e1ria de Cultura, Educa\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/","og_site_name":"Folha Popular","article_published_time":"2025-10-25T17:00:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg","type":"image\/jpeg"}],"author":"Let\u00edcia Echer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Let\u00edcia Echer","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/"},"author":{"name":"Let\u00edcia Echer","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/52b95b9c1c41ec0e826e7518183d0cc0"},"headline":"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera","datePublished":"2025-10-25T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/"},"wordCount":434,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg","keywords":["6\u00ba Festival de Primavera","Colinas","Festival de Primavera"],"articleSection":["Cultura","Destaques","Inclusive"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/","name":"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg","datePublished":"2025-10-25T17:00:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/52b95b9c1c41ec0e826e7518183d0cc0"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg","width":2560,"height":1707,"caption":"Programa\u00e7\u00e3o inclui oficinas, shows, feira do produtor rural e apresenta\u00e7\u00f5es culturais na Pra\u00e7a dos P\u00e1ssaros \/ Cr\u00e9dito: Prefeitura de Colinas"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/10\/25\/cidade-jardim-se-prepara-para-o-6o-festival-da-primavera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Cidade Jardim se prepara para o 6\u00ba Festival da Primavera"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/52b95b9c1c41ec0e826e7518183d0cc0","name":"Let\u00edcia Echer","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/303201b45d8f4e048c95808925ff8953fa7ebc0e52cb5b3af1fc9e3d52c95645?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/303201b45d8f4e048c95808925ff8953fa7ebc0e52cb5b3af1fc9e3d52c95645?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/303201b45d8f4e048c95808925ff8953fa7ebc0e52cb5b3af1fc9e3d52c95645?s=96&d=mm&r=g","caption":"Let\u00edcia Echer"},"url":"https:\/\/folhapopular.info\/index.php\/author\/leticiaecher04gmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/10\/Programacao-inclui-oficinas-shows-feira-do-produtor-rural-e-apresentacoes-culturais-na-Praca-dos-Passaros-scaled.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/196866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/673"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=196866"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/196866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/196868"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=196866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=196866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=196866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}