{"id":197873,"date":"2025-11-08T16:00:00","date_gmt":"2025-11-08T19:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=197873"},"modified":"2025-11-08T08:14:44","modified_gmt":"2025-11-08T11:14:44","slug":"governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/","title":{"rendered":"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O governo do Estado do RS publicou nesta sexta-feira (7\/11) o edital de concess\u00e3o do Bloco 2 de rodovias, que ceder\u00e1 os servi\u00e7os de opera\u00e7\u00e3o, explora\u00e7\u00e3o, conserva\u00e7\u00e3o, manuten\u00e7\u00e3o, melhoramentos e amplia\u00e7\u00e3o da infraestrutura de transportes das rodovias ERS-130, ERS-129, RSC-453 (Rota do Sol), ERS-128 (Via L\u00e1ctea), ERS-135 e ERS-324 por 30 anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ato foi confirmado no Di\u00e1rio Oficial do Estado na manh\u00e3 de ontem e publicado \u00e0 tarde na Central de Licita\u00e7\u00f5es. O edital n<strong>\u00ba <\/strong>0097\/2025 ser\u00e1 na modalidade de parceria p\u00fablico-privada (PPP) atrav\u00e9s de concess\u00e3o patrocinada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O valor dos investimentos projetados para a concess\u00e3ototaliza R$ 5.976.963.353,84, com data-base em abril de 2025. Ainda, o edital deixa claro que o Estado far\u00e1 aporte de R$ 1,5 bilh\u00e3o para a realiza\u00e7\u00e3o de investimentos, via Funrigs. Para os primeiros 10 anos da concess\u00e3o, o investimento ser\u00e1 de R$ 4,6 bilh\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O recebimento dos envelopes com a documenta\u00e7\u00e3o das empresas ou cons\u00f3rcios interessados ser\u00e1 dia 9 de mar\u00e7o de 2026, das 10h \u00e0s 12h, na sede da B3, a Bolsa de Valores brasileira, localizada em S\u00e3o Paulo. J\u00e1 o leil\u00e3o ser\u00e1 dia 13, \u00e0s 14h, tamb\u00e9m na B3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O crit\u00e9rio de julgamento da melhor proposta econ\u00f4mica ser\u00e1 o de menor valor de tarifa de ped\u00e1gio, sendo que a tarifa m\u00ednima considerada pelo Estado \u00e9 de R$ 0,19 para trechos de pista simples.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Via L\u00e1ctea<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A ERS-128 ser\u00e1 concedida do Km 13,890 (BR-386) em Fazenda Vilanova at\u00e9 o Km 30,27 (RSC-453 Rota do Sol) em Teut\u00f4nia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Do km 22,1 (Posto Canteiros) at\u00e9 o 13,890 (BR-386) inicialmente est\u00e1 prevista pista simples.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ter\u00e1 duplica\u00e7\u00e3o desde o Bairro Canabarro (km 22,1) at\u00e9 o Bairro Teut\u00f4nia, na Rota do Sol (km 30,27), em um trecho total de 8,17 quil\u00f4metros. A obra ser\u00e1 executada no oitavo ano da concess\u00e3o. Cinco pontos deste trajeto receber\u00e3o implanta\u00e7\u00e3o de vias marginais, totalizando quase 3 quil\u00f4metros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No s\u00e9timo ano est\u00e3o previstas as constru\u00e7\u00f5es de quatro passarelas, previstas para os quil\u00f4metros 22,1 (Posto Canteiros) \u2013 26,5 \u2013 28,5 \u2013 29,5 (SER Ga\u00facho). Tamb\u00e9m ser\u00e3o 20 paradas de \u00f4nibus ao longo de todo o trajeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A concession\u00e1ria tamb\u00e9m dever\u00e1 adequar duas pontes e uma passagem inferior existents. Al\u00e9m de construir uma nova ponte no km 27,860 (Arroio Boa Vista) e um viaduto no km 23,617 (Ferrovia).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o oitavo ano tamb\u00e9m acontecer\u00e3o as implanta\u00e7\u00f5es de sete rotat\u00f3rias e dois acessos\/retornos em \u201cU\u201d. Ainda haver\u00e1 a adequa\u00e7\u00e3o de 12 acessos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O p\u00f3rtico de <em>free flow<\/em> que estava previsto para o Km 18 passou para o Km 19, no limite entre Teut\u00f4nia e Fazenda Vilanova, imedia\u00e7\u00f5es do acesso a Posses.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Rota do Sol<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A RSC-453 (Rota do Sol) ter\u00e1 dois trajetos abrangidos: do km 0 (Ven\u00e2ncio Aires) ao km 29,830 (Cruzeiro do Sul); do km 37,97 (Estrela) ao km 96,18 (Garibaldi). No total, s\u00e3o 88,040 quil\u00f4metros de extens\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A duplica\u00e7\u00e3o ser\u00e1 aplicada em cinco trechos, entre o quinto e o s\u00e9timo ano. H\u00e1 dois trajetos com possibilidade de duplica\u00e7\u00e3o, mas depender\u00e1 de um gatilho de tr\u00e1fego. No s\u00e9timo e oitavo ano est\u00e3o projetadas implanta\u00e7\u00f5es de terceiras faixas em sete pontos a partir do km 54, entre Westf\u00e1lia e Garibaldi, ou seja, na regi\u00e3o serrana. Nove pontos receber\u00e3o 8,83 quil\u00f4metros de vias marginais. Uma rampa de escape (caixa de brita) prevista no Km 62,4.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cinco pontes e um viaduto dever\u00e3o ser adequados. E cinco pontes e um viaduto novos devem ser constru\u00eddos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 previs\u00e3o de 11 passarelas para pedestres. S\u00e3o esperadas 29 rotat\u00f3rias, retornos, trombetas, diamantes ou passagens inferiores. Ainda h\u00e1 previs\u00e3o de tr\u00eas acessos especiais, adequa\u00e7\u00e3o de 51 acessos e coloca\u00e7\u00e3o de 71 paradas de \u00f4nibus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Estrela<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A concession\u00e1ria dever\u00e1 desenvolver um estudo alternativo sob forma de Anteprojeto para apresenta\u00e7\u00e3o ao Estado para fins de conectar a BR-386 com a RSC-453 (Rota do Sol), com o objetivo de desviar o tr\u00e1fego de ve\u00edculo pesados do segmento urbano dos bairros Pinheiros e Boa Uni\u00e3o, em Estrela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Anteprojeto dever\u00e1 ser apresentado at\u00e9 o final do 2\u00ba ano do contrato de concess\u00e3o. A partir da an\u00e1lise e decis\u00e3o do Estado, poder\u00e1 incluso nos trechos da concess\u00e3o, observado o procedimento de reequil\u00edbrio contratual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A duplica\u00e7\u00e3o do viaduto no km 37,96 (entroncamento com a BR-386), prevista para conclus\u00e3o at\u00e9 o terceiro ano da concess\u00e3o, dever\u00e1 prever a remodela\u00e7\u00e3o das al\u00e7as de acesso e retorno, bem como o prolongamento da duplica\u00e7\u00e3o da RSC-453 at\u00e9 o p\u00f3rtico de acesso a Estrela \u2013 na Avenida Rio Branco \u2013 localizado \u00e0 leste do viaduto existente, de modo a promover a concord\u00e2ncia com as faixas existentes na via local de acesso ao munic\u00edpio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O Bloco 2 <\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ao todo, 409 quil\u00f4metros de extens\u00e3o integram o bloco de rodovias, abrangendo trechos da ERS-128, ERS-129, ERS-130, ERS-135, ERS-324 e RSC-453. A concess\u00e3o prev\u00ea 182 quil\u00f4metros de duplica\u00e7\u00f5es, 71,5 quil\u00f4metros de terceiras faixas, 745 quil\u00f4metros de acostamentos e 37 passarelas de pedestres, entre outras benfeitorias. Atualmente, todas as rodovias s\u00e3o de pistas simples, com alguns trechos com terceiras faixas. O Bloco 2 contar\u00e1 com o sistema <em>free flow<\/em> e compreende 32 cidades, que abrangem 17,5% da popula\u00e7\u00e3o do Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo do Estado do RS publicou nesta sexta-feira (7\/11) o edital de concess\u00e3o do Bloco 2 de rodovias, que ceder\u00e1 os servi\u00e7os de opera\u00e7\u00e3o, explora\u00e7\u00e3o, conserva\u00e7\u00e3o, manuten\u00e7\u00e3o, melhoramentos e amplia\u00e7\u00e3o da infraestrutura de transportes das rodovias ERS-130, ERS-129, RSC-453 (Rota do Sol), ERS-128 (Via L\u00e1ctea), ERS-135 e ERS-324 por 30 anos. O ato foi [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":197874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[17091,1799,774,113,358],"class_list":["post-197873","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-bloco-2","tag-concessao","tag-rota-do-sol","tag-transito","tag-via-lactea","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O governo do Estado do RS publicou nesta sexta-feira (7\/11) o edital de concess\u00e3o do Bloco 2 de rodovias, que ceder\u00e1 os servi\u00e7os de opera\u00e7\u00e3o, explora\u00e7\u00e3o, conserva\u00e7\u00e3o, manuten\u00e7\u00e3o, melhoramentos e amplia\u00e7\u00e3o da infraestrutura de transportes das rodovias ERS-130, ERS-129, RSC-453 (Rota do Sol), ERS-128 (Via L\u00e1ctea), ERS-135 e ERS-324 por 30 anos. O ato foi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-08T19:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias\",\"datePublished\":\"2025-11-08T19:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/\"},\"wordCount\":892,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg\",\"keywords\":[\"Bloco 2\",\"Concess\u00e3o\",\"Rota do Sol\",\"Tr\u00e2nsito\",\"Via L\u00e1ctea\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/\",\"name\":\"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg\",\"datePublished\":\"2025-11-08T19:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg\",\"width\":945,\"height\":532,\"caption\":\"Governador Eduardo Leite anunciou programa de concesso\u0303es no final de outubro \\\/ Cr\u00e9dito: Vitor Rosa - Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/08\\\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias - Folha Popular","og_description":"O governo do Estado do RS publicou nesta sexta-feira (7\/11) o edital de concess\u00e3o do Bloco 2 de rodovias, que ceder\u00e1 os servi\u00e7os de opera\u00e7\u00e3o, explora\u00e7\u00e3o, conserva\u00e7\u00e3o, manuten\u00e7\u00e3o, melhoramentos e amplia\u00e7\u00e3o da infraestrutura de transportes das rodovias ERS-130, ERS-129, RSC-453 (Rota do Sol), ERS-128 (Via L\u00e1ctea), ERS-135 e ERS-324 por 30 anos. O ato foi [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/","og_site_name":"Folha Popular","article_published_time":"2025-11-08T19:00:00+00:00","og_image":[{"width":945,"height":532,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias","datePublished":"2025-11-08T19:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/"},"wordCount":892,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg","keywords":["Bloco 2","Concess\u00e3o","Rota do Sol","Tr\u00e2nsito","Via L\u00e1ctea"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/","name":"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg","datePublished":"2025-11-08T19:00:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg","width":945,"height":532,"caption":"Governador Eduardo Leite anunciou programa de concesso\u0303es no final de outubro \/ Cr\u00e9dito: Vitor Rosa - Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/08\/governo-lanca-edital-e-define-total-de-r-6-bilhoes-em-obras-nas-seis-rodovias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Governo lan\u00e7a edital e define total de R$ 6 bilh\u00f5es em obras nas seis rodovias"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Governador-Eduardo-Leite-anunciou-programa-de-concessoes-no-final-de-outubro-Foto-Vitor-Rosa-Secom.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/197873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=197873"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/197873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/197874"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=197873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=197873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=197873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}