{"id":198555,"date":"2025-11-19T10:06:52","date_gmt":"2025-11-19T13:06:52","guid":{"rendered":"https:\/\/folhapopular.info\/?p=198555"},"modified":"2025-11-19T10:06:55","modified_gmt":"2025-11-19T13:06:55","slug":"estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/","title":{"rendered":"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386"},"content":{"rendered":"<p>A concess\u00e3o do Bloco 2 de rodovias prev\u00ea a elabora\u00e7\u00e3o de um anteprojeto de conex\u00e3o entre a RSC-453 (Rota do Sol) e a BR-386, em Estrela. O estudo dever\u00e1 ser desenvolvido pela futura concession\u00e1ria e entregue at\u00e9 o fim do segundo ano de contrato. O objetivo \u00e9 criar uma alternativa de deslocamento para retirar o&#8230; <\/p>\n<div class=\"pmpro\">\n<div class=\"pmpro_card pmpro_content_message\">\n<div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular &#8211; Conte\u00fado Total Anual e Grupo Popular &#8211; Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div>\n<div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2025%2F11%2F19%2Festudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386%2F\">Acesse aqui<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A concess\u00e3o do Bloco 2 de rodovias prev\u00ea a elabora\u00e7\u00e3o de um anteprojeto de conex\u00e3o entre a RSC-453 (Rota do Sol) e a BR-386, em Estrela. O estudo dever\u00e1 ser desenvolvido pela futura concession\u00e1ria e entregue at\u00e9 o fim do segundo ano de contrato. O objetivo \u00e9 criar uma alternativa de deslocamento para retirar o... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular - Conte\u00fado Total Anual e Grupo Popular - Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2025%2F11%2F19%2Festudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386%2F\">Acesse aqui<\/a><\/div><\/div><\/div>","protected":false},"author":8,"featured_media":198556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11078,5990,2,3],"tags":[91,5344,2811,774],"class_list":["post-198555","post","type-post","status-publish","format-standard","has-post-thumbnail","category-assinantes","category-conteudo-exclusivo","category-featured","category-geral","tag-br-386","tag-ligacao","tag-rodovias","tag-rota-do-sol","pmpro-level-required","pmpro-level-2","pmpro-level-4","pmpro-level-5","pmpro-no-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386 - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386 - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A concess\u00e3o do Bloco 2 de rodovias prev\u00ea a elabora\u00e7\u00e3o de um anteprojeto de conex\u00e3o entre a RSC-453 (Rota do Sol) e a BR-386, em Estrela. O estudo dever\u00e1 ser desenvolvido pela futura concession\u00e1ria e entregue at\u00e9 o fim do segundo ano de contrato. O objetivo \u00e9 criar uma alternativa de deslocamento para retirar o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T13:06:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T13:06:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386\",\"datePublished\":\"2025-11-19T13:06:52+00:00\",\"dateModified\":\"2025-11-19T13:06:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/\"},\"wordCount\":632,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg\",\"keywords\":[\"BR-386\",\"liga\u00e7\u00e3o\",\"rodovias\",\"Rota do Sol\"],\"articleSection\":[\"Assinantes\",\"Conte\u00fado Exclusivo\",\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/\",\"name\":\"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386 - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg\",\"datePublished\":\"2025-11-19T13:06:52+00:00\",\"dateModified\":\"2025-11-19T13:06:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Trecho da RSC-453 entre os bairros Boa Uni\u00e3o e Pinheiros \u00e9 um dos mais cr\u00edticos do bloco 2 - Cr\u00e9dito: Anderson Lopes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/19\\\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386 - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/","og_locale":"pt_BR","og_type":"article","og_title":"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386 - Folha Popular","og_description":"A concess\u00e3o do Bloco 2 de rodovias prev\u00ea a elabora\u00e7\u00e3o de um anteprojeto de conex\u00e3o entre a RSC-453 (Rota do Sol) e a BR-386, em Estrela. O estudo dever\u00e1 ser desenvolvido pela futura concession\u00e1ria e entregue at\u00e9 o fim do segundo ano de contrato. O objetivo \u00e9 criar uma alternativa de deslocamento para retirar o [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/","og_site_name":"Folha Popular","article_published_time":"2025-11-19T13:06:52+00:00","article_modified_time":"2025-11-19T13:06:55+00:00","og_image":[{"width":2560,"height":1920,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386","datePublished":"2025-11-19T13:06:52+00:00","dateModified":"2025-11-19T13:06:55+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/"},"wordCount":632,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg","keywords":["BR-386","liga\u00e7\u00e3o","rodovias","Rota do Sol"],"articleSection":["Assinantes","Conte\u00fado Exclusivo","Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/","name":"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386 - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg","datePublished":"2025-11-19T13:06:52+00:00","dateModified":"2025-11-19T13:06:55+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg","width":2560,"height":1920,"caption":"Trecho da RSC-453 entre os bairros Boa Uni\u00e3o e Pinheiros \u00e9 um dos mais cr\u00edticos do bloco 2 - Cr\u00e9dito: Anderson Lopes"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/19\/estudo-definira-nova-ligacao-entre-a-rota-do-sol-e-a-br-386\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Estudo definir\u00e1 nova liga\u00e7\u00e3o entre a Rota do Sol e a BR-386"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Trecho-da-RSC-453-entre-os-bairros-Boa-Uniao-e-Pinheiros-e-um-dos-mais-criticos-do-bloco-2_AL-scaled.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/198555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=198555"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/198555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/198556"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=198555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=198555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=198555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}