{"id":198807,"date":"2025-11-23T16:00:00","date_gmt":"2025-11-23T19:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=198807"},"modified":"2025-11-24T10:53:51","modified_gmt":"2025-11-24T13:53:51","slug":"camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/","title":{"rendered":"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro"},"content":{"rendered":"<p>A C\u00e2mara de Vereadores de Westf\u00e1lia realizou, na quarta-feira (19\/11), sess\u00e3o ordin\u00e1ria marcada pela aprova\u00e7\u00e3o do primeiro projeto de lei legislativo do ano. A proposta denomina de Rua Paulo Osvaldo Gomes a atual Rua C, no Bairro do Parque. A iniciativa \u00e9 a primeira homenagem a um cidad\u00e3o negro no nome de uma via p\u00fablica&#8230; <\/p>\n<div class=\"pmpro\">\n<div class=\"pmpro_card pmpro_content_message\">\n<div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular &#8211; Conte\u00fado Total Anual e Grupo Popular &#8211; Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div>\n<div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2025%2F11%2F23%2Fcamara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro%2F\">Acesse aqui<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara de Vereadores de Westf\u00e1lia realizou, na quarta-feira (19\/11), sess\u00e3o ordin\u00e1ria marcada pela aprova\u00e7\u00e3o do primeiro projeto de lei legislativo do ano. A proposta denomina de Rua Paulo Osvaldo Gomes a atual Rua C, no Bairro do Parque. A iniciativa \u00e9 a primeira homenagem a um cidad\u00e3o negro no nome de uma via p\u00fablica... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular - Conte\u00fado Total Anual e Grupo Popular - Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2025%2F11%2F23%2Fcamara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro%2F\">Acesse aqui<\/a><\/div><\/div><\/div>","protected":false},"author":764,"featured_media":198808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11078,18237,2,10985],"tags":[646,3601,6260,25],"class_list":["post-198807","post","type-post","status-publish","format-standard","has-post-thumbnail","category-assinantes","category-camara-de-vereadores-de-westfalia","category-featured","category-politica","tag-camara-de-vereadores","tag-dia-da-consciencia-negra","tag-vereadores","tag-westfalia","pmpro-level-required","pmpro-level-2","pmpro-level-4","pmpro-level-5","pmpro-no-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro - Folha Popular<\/title>\n<meta name=\"description\" content=\"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-23T19:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-24T13:53:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00e9ssica Bayer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00e9ssica Bayer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/\"},\"author\":{\"name\":\"J\u00e9ssica Bayer\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/9c3bd49fe9d74793decad1d4c83fa974\"},\"headline\":\"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro\",\"datePublished\":\"2025-11-23T19:00:00+00:00\",\"dateModified\":\"2025-11-24T13:53:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/\"},\"wordCount\":917,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg\",\"keywords\":[\"C\u00e2mara de Vereadores\",\"Dia da Consci\u00eancia Negra\",\"vereadores\",\"Westf\u00e1lia\"],\"articleSection\":[\"Assinantes\",\"C\u00e2mara de Vereadores de Westf\u00e1lia\",\"Destaques\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/\",\"name\":\"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg\",\"datePublished\":\"2025-11-23T19:00:00+00:00\",\"dateModified\":\"2025-11-24T13:53:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/9c3bd49fe9d74793decad1d4c83fa974\"},\"description\":\"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg\",\"width\":2560,\"height\":1928,\"caption\":\"Entrega do of\u00edcio do projeto do legislativo \u00e0 fam\u00edlia de Paulo Osvaldo Gomes, homenageado com o nome da rua \\\/ Cr\u00e9dito: J\u00e9ssica Bayer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2025\\\/11\\\/23\\\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/9c3bd49fe9d74793decad1d4c83fa974\",\"name\":\"J\u00e9ssica Bayer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g\",\"caption\":\"J\u00e9ssica Bayer\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/jessicad-bayergmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro - Folha Popular","description":"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/","og_locale":"pt_BR","og_type":"article","og_title":"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro - Folha Popular","og_description":"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro","og_url":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/","og_site_name":"Folha Popular","article_published_time":"2025-11-23T19:00:00+00:00","article_modified_time":"2025-11-24T13:53:51+00:00","og_image":[{"width":2560,"height":1928,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg","type":"image\/jpeg"}],"author":"J\u00e9ssica Bayer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"J\u00e9ssica Bayer","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/"},"author":{"name":"J\u00e9ssica Bayer","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/9c3bd49fe9d74793decad1d4c83fa974"},"headline":"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro","datePublished":"2025-11-23T19:00:00+00:00","dateModified":"2025-11-24T13:53:51+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/"},"wordCount":917,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg","keywords":["C\u00e2mara de Vereadores","Dia da Consci\u00eancia Negra","vereadores","Westf\u00e1lia"],"articleSection":["Assinantes","C\u00e2mara de Vereadores de Westf\u00e1lia","Destaques","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/","url":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/","name":"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg","datePublished":"2025-11-23T19:00:00+00:00","dateModified":"2025-11-24T13:53:51+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/9c3bd49fe9d74793decad1d4c83fa974"},"description":"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg","width":2560,"height":1928,"caption":"Entrega do of\u00edcio do projeto do legislativo \u00e0 fam\u00edlia de Paulo Osvaldo Gomes, homenageado com o nome da rua \/ Cr\u00e9dito: J\u00e9ssica Bayer"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2025\/11\/23\/camara-de-westfalia-aprova-primeira-via-publica-com-nome-de-cidadao-negro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"C\u00e2mara de Westf\u00e1lia aprova primeira via p\u00fablica com nome de cidad\u00e3o negro"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/9c3bd49fe9d74793decad1d4c83fa974","name":"J\u00e9ssica Bayer","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g","caption":"J\u00e9ssica Bayer"},"url":"https:\/\/folhapopular.info\/index.php\/author\/jessicad-bayergmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2025\/11\/Entrega-do-oficio-do-projeto-do-legislativo-a-familia-de-Paulo-Osvaldo-Gomes-homenageado-com-o-nome-da-rua_JB-scaled.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/198807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/764"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=198807"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/198807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/198808"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=198807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=198807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=198807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}