{"id":204580,"date":"2026-02-25T14:00:00","date_gmt":"2026-02-25T17:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=204580"},"modified":"2026-02-26T17:01:25","modified_gmt":"2026-02-26T20:01:25","slug":"morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/","title":{"rendered":"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Moradores de Vila Esperan\u00e7a, no Bairro Canabarro, foram \u00e0s ruas em manifesta\u00e7\u00e3o pac\u00edfica no domingo (22\/2) para atentar sobre a morte de mais de 15 c\u00e3es e gatos. Apesar das suspeitas de envenenamento, ainda n\u00e3o h\u00e1 confirma\u00e7\u00e3o oficial sobre a causa das mortes. Os fatos estariam acontecendo h\u00e1 algumas semanas, segundo publica\u00e7\u00e3o do grupo de volunt\u00e1rios Patas Solid\u00e1rias nas redes sociais. Todos os animais possu\u00edam tutores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os cartazes contendo fotos de c\u00e3es e gatos com seus tutores ou j\u00e1 sem vida chamaram a aten\u00e7\u00e3o, bem como a frase \u201cJusti\u00e7a pelos nossos animais\u201d. Os manifestantes alertaram os vizinhos para redobrarem os cuidados com c\u00e3es e gatos, especialmente nas ruas Veleda Schaeffer e Balduino Ninow, onde ocorreram os casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O grupo defende a instala\u00e7\u00e3o de c\u00e2meras de monitoramento em diversos locais, tanto para a seguran\u00e7a dos animais quanto das pessoas, al\u00e9m de rondas constantes da Brigada Militar em busca de intimidar os agressores e at\u00e9 constatar um flagrante. \u201cSe tiveres alguma informa\u00e7\u00e3o sobre quem possa estar fazendo isso, nos chame no privado. Al\u00e9m disso, se seu animal foi uma das v\u00edtimas, fa\u00e7a um boletim de ocorr\u00eancia; isso \u00e9 importante para oficializar o caso e ajuda para que possamos cobrar provid\u00eancias\u201d, ressalta o Patas Solid\u00e1rias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Procedimentos adequados<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O presidente a Rede de Prote\u00e7\u00e3o Ambiental e a Animais (Repraas) de Teut\u00f4nia, Vladimir da Silva, relata n\u00e3o ter tomado conhecimento dos casos at\u00e9 o dia da manifesta\u00e7\u00e3o. Ele cita os procedimentos a serem seguidos em casos como estes: \u201cA primeira atitude deve ser procurar a Pol\u00edcia Civil, registrar ocorr\u00eancia, procurar o Munic\u00edpio, a Vigil\u00e2ncia Sanit\u00e1ria e tamb\u00e9m a n\u00f3s, que trabalhamos com crimes ambientais, para auxiliar nessa demanda.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo ele, quando come\u00e7am a ocorrer incidentes de \u00f3bitos de c\u00e3es ou gatos em grande quantidade, o procedimento \u00e9 coletar os animais e encaminh\u00e1-los para uma universidade ou veterin\u00e1rio especializado, como a Patologia da Universidade Federal do Rio Grande do Sul (UFRGS), para necr\u00f3psia e obten\u00e7\u00e3o de prova t\u00e9cnica dos fatos para que a pol\u00edcia inicie a investiga\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele tamb\u00e9m lembra que animais podem morrer devido a doen\u00e7as, como parvovirose, apesar de que as suspeitas diminuem tendo em vista serem duas esp\u00e9cies de animais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O que diz a Prefeitura<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Procurada, a Administra\u00e7\u00e3o Municipal relatou que as den\u00fancias devem ser realizadas junto \u00e0 Pol\u00edcia Civil, \u00f3rg\u00e3o respons\u00e1vel pela investiga\u00e7\u00e3o. \u201cO setor de Meio Ambiente n\u00e3o possui atribui\u00e7\u00e3o investigativa. Somente ap\u00f3s a identifica\u00e7\u00e3o do respons\u00e1vel, ap\u00f3s formaliza\u00e7\u00e3o da den\u00fancia por parte dos tutores dos animais agredidos junto \u00e0 Pol\u00edcia Civil, poder\u00e3o ser adotadas as medidas cab\u00edveis, tanto na esfera judicial quanto administrativa ambiental\u201d, diz a nota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Prefeitura ainda frisa que n\u00e3o havia recebido den\u00fancia formal de maus-tratos sobre esse assunto at\u00e9 a segunda-feira (23\/2).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O que diz a lei<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Lei de Crimes Ambientais (n\u00ba 9.605\/1998) prev\u00ea puni\u00e7\u00e3o para quem ferir, abusar ou maltratar qualquer animal silvestre, dom\u00e9stico, nativo ou ex\u00f3tico, com pena de deten\u00e7\u00e3o de 3 meses a 1 ano e multa. Para casos envolvendo c\u00e3es e gatos, a chamada Lei Sans\u00e3o (n\u00ba 14.064\/2020) ampliou a puni\u00e7\u00e3o para 2 a 5 anos de reclus\u00e3o, al\u00e9m de multa e proibi\u00e7\u00e3o da guarda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A legisla\u00e7\u00e3o tamb\u00e9m considera maus-tratos pr\u00e1ticas como abandono, agress\u00f5es f\u00edsicas, neglig\u00eancia com alimenta\u00e7\u00e3o e cuidados, manuten\u00e7\u00e3o em locais insalubres, mutila\u00e7\u00f5es e envenenamentos. A pena pode ser aumentada se o animal morrer em decorr\u00eancia da viol\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moradores de Vila Esperan\u00e7a, no Bairro Canabarro, foram \u00e0s ruas em manifesta\u00e7\u00e3o pac\u00edfica no domingo (22\/2) para atentar sobre a morte de mais de 15 c\u00e3es e gatos. Apesar das suspeitas de envenenamento, ainda n\u00e3o h\u00e1 confirma\u00e7\u00e3o oficial sobre a causa das mortes. Os fatos estariam acontecendo h\u00e1 algumas semanas, segundo publica\u00e7\u00e3o do grupo de [&hellip;]<\/p>\n","protected":false},"author":639,"featured_media":204592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[2338,216,6584,26],"class_list":["post-204580","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","tag-animais","tag-bairro-canabarro","tag-causa-animal","tag-teutonia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro - Folha Popular<\/title>\n<meta name=\"description\" content=\"Os cartazes contendo fotos de c\u00e3es e gatos chamaram a aten\u00e7\u00e3o, bem como a frase \u201cJusti\u00e7a pelos nossos animais\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Os cartazes contendo fotos de c\u00e3es e gatos chamaram a aten\u00e7\u00e3o, bem como a frase \u201cJusti\u00e7a pelos nossos animais\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-25T17:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T20:01:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/folhapopular.info\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"955\" \/>\n\t<meta property=\"og:image:height\" content=\"790\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Lenz da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Lenz da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/\"},\"author\":{\"name\":\"Camille Lenz da Silva\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/f0b811f932ef2505faf473ffaef49df5\"},\"headline\":\"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro\",\"datePublished\":\"2026-02-25T17:00:00+00:00\",\"dateModified\":\"2026-02-26T20:01:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/\"},\"wordCount\":635,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg\",\"keywords\":[\"Animais\",\"Bairro Canabarro\",\"causa animal\",\"Teut\u00f4nia\"],\"articleSection\":[\"Destaques\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/\",\"name\":\"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg\",\"datePublished\":\"2026-02-25T17:00:00+00:00\",\"dateModified\":\"2026-02-26T20:01:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/f0b811f932ef2505faf473ffaef49df5\"},\"description\":\"Os cartazes contendo fotos de c\u00e3es e gatos chamaram a aten\u00e7\u00e3o, bem como a frase \u201cJusti\u00e7a pelos nossos animais\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg\",\"width\":955,\"height\":790,\"caption\":\"Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/02\\\/25\\\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/f0b811f932ef2505faf473ffaef49df5\",\"name\":\"Camille Lenz da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g\",\"caption\":\"Camille Lenz da Silva\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/camillelenzgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro - Folha Popular","description":"Os cartazes contendo fotos de c\u00e3es e gatos chamaram a aten\u00e7\u00e3o, bem como a frase \u201cJusti\u00e7a pelos nossos animais\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/","og_locale":"pt_BR","og_type":"article","og_title":"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro - Folha Popular","og_description":"Os cartazes contendo fotos de c\u00e3es e gatos chamaram a aten\u00e7\u00e3o, bem como a frase \u201cJusti\u00e7a pelos nossos animais\u201d.","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/","og_site_name":"Folha Popular","article_published_time":"2026-02-25T17:00:00+00:00","article_modified_time":"2026-02-26T20:01:25+00:00","og_image":[{"width":955,"height":790,"url":"http:\/\/folhapopular.info\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg","type":"image\/jpeg"}],"author":"Camille Lenz da Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Camille Lenz da Silva","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/"},"author":{"name":"Camille Lenz da Silva","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/f0b811f932ef2505faf473ffaef49df5"},"headline":"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro","datePublished":"2026-02-25T17:00:00+00:00","dateModified":"2026-02-26T20:01:25+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/"},"wordCount":635,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg","keywords":["Animais","Bairro Canabarro","causa animal","Teut\u00f4nia"],"articleSection":["Destaques","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/","name":"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg","datePublished":"2026-02-25T17:00:00+00:00","dateModified":"2026-02-26T20:01:25+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/f0b811f932ef2505faf473ffaef49df5"},"description":"Os cartazes contendo fotos de c\u00e3es e gatos chamaram a aten\u00e7\u00e3o, bem como a frase \u201cJusti\u00e7a pelos nossos animais\u201d.","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg","width":955,"height":790,"caption":"Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/02\/25\/morte-de-caes-e-gatos-revolta-moradores-do-bairro-canabarro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Morte de c\u00e3es e gatos revolta moradores do Bairro Canabarro"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/f0b811f932ef2505faf473ffaef49df5","name":"Camille Lenz da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50be826d73ca259ec0e0a88a407f5de800c576c46cfdc57e50ef28551e216fff?s=96&d=mm&r=g","caption":"Camille Lenz da Silva"},"url":"https:\/\/folhapopular.info\/index.php\/author\/camillelenzgmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-13.01.23-e1772035328784.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/204580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/639"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=204580"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/204580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/204592"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=204580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=204580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=204580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}