{"id":207730,"date":"2026-04-02T09:49:01","date_gmt":"2026-04-02T12:49:01","guid":{"rendered":"https:\/\/folhapopular.info\/?p=207730"},"modified":"2026-05-18T16:04:34","modified_gmt":"2026-05-18T19:04:34","slug":"mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/","title":{"rendered":"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A forma\u00e7\u00e3o de m\u00e3o de obra e o fortalecimento da presen\u00e7a regional do <a href=\"https:\/\/folhapopular.info\/index.php\/2026\/02\/24\/programacao-confirmada-para-o-reload-sindilojas-2026\/\">Sindilojas Vale do Taquari<\/a> orientam a nova gest\u00e3o da entidade. Empossado nesta quarta-feira (01\/04), em Lajeado, o presidente Renan Borelli detalhou as prioridades para o ciclo 2026\u20132030, em um contexto de mudan\u00e7as no mercado de trabalho e desafios crescentes para o varejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principal frente de trabalho est\u00e1 no fortalecimento da qualifica\u00e7\u00e3o profissional. Segundo Borelli, a dificuldade de encontrar e reter trabalhadores preparados j\u00e1 impacta diretamente o desempenho das empresas. Para ele, a solu\u00e7\u00e3o passa por um esfor\u00e7o cont\u00ednuo de qualifica\u00e7\u00e3o, tanto de quem j\u00e1 est\u00e1 no mercado quanto de novos profissionais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAs empresas precisam investir constantemente em aperfei\u00e7oamento e tamb\u00e9m oferecer oportunidades para quem est\u00e1 chegando\u201d, aponta. Para o novo presidente, se a regi\u00e3o quiser m\u00e3o de obra mais qualificada, \u00e9 necess\u00e1rio criar um ambiente de incentivo \u00e0 forma\u00e7\u00e3o desses trabalhadores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A an\u00e1lise sobre a m\u00e3o de obra \u00e9 compartilhada pelo presidente da Fecom\u00e9rcio-RS, Luiz Carlos Bohn. Ao participar da posse de Borelli, ele destacou que o tema ultrapassa os limites regionais e estaduais. \u201c\u00c9 uma quest\u00e3o nacional, talvez mundial. Hoje convivemos com diferentes gera\u00e7\u00f5es e h\u00e1 menos jovens dispon\u00edveis para o mercado de trabalho, al\u00e9m de uma mudan\u00e7a de mentalidade em rela\u00e7\u00e3o ao emprego formal\u201d, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Bohn, o sistema Fecom\u00e9rcio atua diretamente na tentativa de reduzir esse descompasso por meio de suas estruturas de forma\u00e7\u00e3o. Lembra que o Senac e o Sesc t\u00eam papel fundamental na prepara\u00e7\u00e3o da m\u00e3o de obra para o setor terci\u00e1rio. \u201cTrabalhamos para atender as demandas do mercado e temos \u00edndices de empregabilidade em torno de 80% entre os egressos\u201d, destacou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Atua\u00e7\u00e3o ampliada&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Renan Borelli tamb\u00e9m enfatizou a responsabilidade de suceder uma gest\u00e3o j\u00e1 consolidada e indicou que a condu\u00e7\u00e3o do sindicato deve combinar continuidade e amplia\u00e7\u00e3o de frentes de atua\u00e7\u00e3o. \u201c\u00c9 um desafio grande, mas, quando se tem clareza de onde se quer chegar, o caminho fica mais f\u00e1cil\u201d, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com abrang\u00eancia em 34 munic\u00edpios, o novo presidente acredita que o Sindilojas deve ampliar sua capilaridade. Segundo Borelli, uma das metas \u00e9 aumentar o n\u00edvel de participa\u00e7\u00e3o das empresas associadas fora de Lajeado, fortalecendo a representatividade regional. \u201cQueremos estar mais presentes nesses munic\u00edpios, trazendo novos associados e consolidando o papel do sindicato como entidade de apoio ao com\u00e9rcio em toda a regi\u00e3o\u201d, disse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reload Sindilojas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre as iniciativas de qualifica\u00e7\u00e3o promovidas pelo <a href=\"https:\/\/sindilojas-valedotaquari.com.br\/\">Sindilojas VT<\/a>, Renan Borelli destaca o Reload Sindilojas, evento que chega \u00e0 11\u00aa edi\u00e7\u00e3o consolidado como refer\u00eancia estadual. \u201c\u00c9 o evento mais energizante do Vale do Taquari\u201d, refor\u00e7a.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Reload ocorre no dia 16 de abril, no Clube Tiro e Ca\u00e7a, em Lajeado, em programa\u00e7\u00e3o dedicada \u00e0 inova\u00e7\u00e3o, estrat\u00e9gia e desenvolvimento pessoal. A programa\u00e7\u00e3o inicia com Carolina Filipelli, l\u00edder de Desenvolvimento de Neg\u00f3cios no Lab Fecom\u00e9rcio-RS, que apresenta a palestra \u201cIA no Varejo \u2013 Seu Neg\u00f3cio ON\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na sequ\u00eancia, a economista-chefe da Fecom\u00e9rcio-RS, Patr\u00edcia Palermo, conduz a palestra \u201cS\u00f3 vende quem entende: Voc\u00ea est\u00e1 on?\u201d, trazendo an\u00e1lise sobre o cen\u00e1rio econ\u00f4mico e o comportamento do consumidor. O encerramento ser\u00e1 com Rafael Muller, diretor da franqueadora Vithall Treinamentos, que aborda o tema \u201cMente e Cora\u00e7\u00e3o \u2013 O poder da mente e da emo\u00e7\u00e3o no desempenho pessoal\u201d.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A forma\u00e7\u00e3o de m\u00e3o de obra e o fortalecimento da presen\u00e7a regional do Sindilojas Vale do Taquari orientam a nova gest\u00e3o da entidade. Empossado nesta quarta-feira (01\/04), em Lajeado, o presidente Renan Borelli detalhou as prioridades para o ciclo 2026\u20132030, em um contexto de mudan\u00e7as no mercado de trabalho e desafios crescentes para o varejo. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":213132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10991,10993],"tags":[20912,2672,20913,5774,156],"class_list":["post-207730","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia","category-empreender","tag-mao-de-obras","tag-qualificacao","tag-renan-borelli","tag-sindilojas","tag-vale-do-taquari","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A forma\u00e7\u00e3o de m\u00e3o de obra e o fortalecimento da presen\u00e7a regional do Sindilojas Vale do Taquari orientam a nova gest\u00e3o da entidade. Empossado nesta quarta-feira (01\/04), em Lajeado, o presidente Renan Borelli detalhou as prioridades para o ciclo 2026\u20132030, em um contexto de mudan\u00e7as no mercado de trabalho e desafios crescentes para o varejo. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-02T12:49:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-18T19:04:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463936_1196928_diretoria-1-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT\",\"datePublished\":\"2026-04-02T12:49:01+00:00\",\"dateModified\":\"2026-05-18T19:04:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/\"},\"wordCount\":595,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/463936_1196928_diretoria-1-scaled.webp\",\"keywords\":[\"M\u00e3o de Obras\",\"Qualifica\u00e7\u00e3o\",\"Renan Borelli\",\"Sindilojas\",\"Vale do Taquari\"],\"articleSection\":[\"Economia\",\"Empreender\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/\",\"name\":\"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/463936_1196928_diretoria-1-scaled.webp\",\"datePublished\":\"2026-04-02T12:49:01+00:00\",\"dateModified\":\"2026-05-18T19:04:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/463936_1196928_diretoria-1-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/463936_1196928_diretoria-1-scaled.webp\",\"width\":2560,\"height\":1920,\"caption\":\"Cr\u00e9dito: Simone Rockenbach \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/02\\\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/","og_locale":"pt_BR","og_type":"article","og_title":"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT - Folha Popular","og_description":"A forma\u00e7\u00e3o de m\u00e3o de obra e o fortalecimento da presen\u00e7a regional do Sindilojas Vale do Taquari orientam a nova gest\u00e3o da entidade. Empossado nesta quarta-feira (01\/04), em Lajeado, o presidente Renan Borelli detalhou as prioridades para o ciclo 2026\u20132030, em um contexto de mudan\u00e7as no mercado de trabalho e desafios crescentes para o varejo. [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/","og_site_name":"Folha Popular","article_published_time":"2026-04-02T12:49:01+00:00","article_modified_time":"2026-05-18T19:04:34+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463936_1196928_diretoria-1-scaled.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT","datePublished":"2026-04-02T12:49:01+00:00","dateModified":"2026-05-18T19:04:34+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/"},"wordCount":595,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463936_1196928_diretoria-1-scaled.webp","keywords":["M\u00e3o de Obras","Qualifica\u00e7\u00e3o","Renan Borelli","Sindilojas","Vale do Taquari"],"articleSection":["Economia","Empreender"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/","name":"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463936_1196928_diretoria-1-scaled.webp","datePublished":"2026-04-02T12:49:01+00:00","dateModified":"2026-05-18T19:04:34+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463936_1196928_diretoria-1-scaled.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463936_1196928_diretoria-1-scaled.webp","width":2560,"height":1920,"caption":"Cr\u00e9dito: Simone Rockenbach \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/02\/mao-de-obra-sera-foco-da-nova-direcao-do-sindilojas-vt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"M\u00e3o de obra ser\u00e1 foco da nova dire\u00e7\u00e3o do Sindilojas VT"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463936_1196928_diretoria-1-scaled.webp","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/207730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=207730"}],"version-history":[{"count":1,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/207730\/revisions"}],"predecessor-version":[{"id":213134,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/207730\/revisions\/213134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/213132"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=207730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=207730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=207730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}