{"id":207742,"date":"2026-04-01T17:00:00","date_gmt":"2026-04-01T20:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=207742"},"modified":"2026-05-18T16:02:05","modified_gmt":"2026-05-18T19:02:05","slug":"girando-sol-marca-35-anos-com-premios","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/","title":{"rendered":"Girando Sol marca 35 anos com pr\u00eamios"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A empresa Girando Sol completa 35 anos nesta ter\u00e7a-feira (1\u00ba\/4) e anuncia um reposicionamento de marca, al\u00e9m do lan\u00e7amento de uma campanha promocional com mais de R$ 1 milh\u00e3o em pr\u00eamios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com sede em Arroio do Meio, a empresa atua no segmento de produtos de limpeza e cuidados com a casa. Atualmente, possui mais de 700 funcion\u00e1rios diretos e cerca de 1,2 mil indiretos, al\u00e9m de um portf\u00f3lio com 15 fam\u00edlias de produtos e aproximadamente 190 itens, produzidos em um parque industrial com mais de 41 mil metros quadrados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A empresa mant\u00e9m presen\u00e7a consolidada na Regi\u00e3o Sul, em Mato Grosso e Mato Grosso do Sul, al\u00e9m de atua\u00e7\u00e3o internacional em pa\u00edses como Uruguai, Paraguai, Bol\u00edvia, Chile, Suriname e Cura\u00e7ao. Em 2026, iniciou tamb\u00e9m a comercializa\u00e7\u00e3o de produtos na Argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a empresa, as vendas mais do que dobraram nos \u00faltimos cinco anos, alcan\u00e7ando faturamento anual de R$ 1 bilh\u00e3o em 2025. O diretor Gilmar Borscheid afirmou que a empresa busca manter o foco no crescimento, aliado aos valores e \u00e0 cultura organizacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O novo posicionamento de marca \u00e9 marcado pelo slogan \u201cPrazer em Cada Cuidado\u201d e pela tagline \u201cCuidamos de Cada Momento do Seu Dia\u201d, com o objetivo de refor\u00e7ar a presen\u00e7a da marca no cotidiano dos consumidores. A mudan\u00e7a tamb\u00e9m inclui atualiza\u00e7\u00e3o da identidade visual e ajustes no portf\u00f3lio de produtos. Entre as novidades, est\u00e1 a reformula\u00e7\u00e3o do limpador perfumado, que passa a contar com fragr\u00e2ncia com dura\u00e7\u00e3o de at\u00e9 24 horas, segundo testes informados pela empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte das comemora\u00e7\u00f5es, a empresa lan\u00e7ou a promo\u00e7\u00e3o \u201cGirando Sol 35 anos\u201d, que ocorrer\u00e1 entre 15 de abril e 10 de agosto. A campanha abrange consumidores dos estados do Rio Grande do Sul, Santa Catarina, Paran\u00e1, Mato Grosso e Mato Grosso do Sul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A a\u00e7\u00e3o prev\u00ea a distribui\u00e7\u00e3o de mais de R$ 1 milh\u00e3o em pr\u00eamios, incluindo valores instant\u00e2neos di\u00e1rios entre R$ 100 e R$ 700, sorteios semanais de motos el\u00e9tricas pela Loteria Federal e um pr\u00eamio final de R$ 500 mil. Os valores ser\u00e3o pagos por meio da carteira digital PicPay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A empresa Girando Sol completa 35 anos nesta ter\u00e7a-feira (1\u00ba\/4) e anuncia um reposicionamento de marca, al\u00e9m do lan\u00e7amento de uma campanha promocional com mais de R$ 1 milh\u00e3o em pr\u00eamios. Com sede em Arroio do Meio, a empresa atua no segmento de produtos de limpeza e cuidados com a casa. Atualmente, possui mais de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":213130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,10991],"tags":[140,139,20914,1524,7813],"class_list":["post-207742","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-economia","tag-arroio-do-meio","tag-girando-sol","tag-girando-sol-35-anos","tag-premios","tag-promocao","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Girando Sol marca 35 anos com pr\u00eamios - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Girando Sol marca 35 anos com pr\u00eamios - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A empresa Girando Sol completa 35 anos nesta ter\u00e7a-feira (1\u00ba\/4) e anuncia um reposicionamento de marca, al\u00e9m do lan\u00e7amento de uma campanha promocional com mais de R$ 1 milh\u00e3o em pr\u00eamios. Com sede em Arroio do Meio, a empresa atua no segmento de produtos de limpeza e cuidados com a casa. Atualmente, possui mais de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-01T20:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-18T19:02:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463898_1196782_girando1-1-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Girando Sol marca 35 anos com pr\u00eamios\",\"datePublished\":\"2026-04-01T20:00:00+00:00\",\"dateModified\":\"2026-05-18T19:02:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/\"},\"wordCount\":371,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/463898_1196782_girando1-1-scaled.webp\",\"keywords\":[\"Arroio do Meio\",\"Girando Sol\",\"Girando Sol 35 anos\",\"Pr\u00eamios\",\"promo\u00e7\u00e3o\"],\"articleSection\":[\"Destaques\",\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/\",\"name\":\"Girando Sol marca 35 anos com pr\u00eamios - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/463898_1196782_girando1-1-scaled.webp\",\"datePublished\":\"2026-04-01T20:00:00+00:00\",\"dateModified\":\"2026-05-18T19:02:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/463898_1196782_girando1-1-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/463898_1196782_girando1-1-scaled.webp\",\"width\":2560,\"height\":1440,\"caption\":\"Cr\u00e9dito: Maicon Lu\u00eds \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/04\\\/01\\\/girando-sol-marca-35-anos-com-premios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Girando Sol marca 35 anos com pr\u00eamios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Girando Sol marca 35 anos com pr\u00eamios - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/","og_locale":"pt_BR","og_type":"article","og_title":"Girando Sol marca 35 anos com pr\u00eamios - Folha Popular","og_description":"A empresa Girando Sol completa 35 anos nesta ter\u00e7a-feira (1\u00ba\/4) e anuncia um reposicionamento de marca, al\u00e9m do lan\u00e7amento de uma campanha promocional com mais de R$ 1 milh\u00e3o em pr\u00eamios. Com sede em Arroio do Meio, a empresa atua no segmento de produtos de limpeza e cuidados com a casa. Atualmente, possui mais de [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/","og_site_name":"Folha Popular","article_published_time":"2026-04-01T20:00:00+00:00","article_modified_time":"2026-05-18T19:02:05+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463898_1196782_girando1-1-scaled.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Girando Sol marca 35 anos com pr\u00eamios","datePublished":"2026-04-01T20:00:00+00:00","dateModified":"2026-05-18T19:02:05+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/"},"wordCount":371,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463898_1196782_girando1-1-scaled.webp","keywords":["Arroio do Meio","Girando Sol","Girando Sol 35 anos","Pr\u00eamios","promo\u00e7\u00e3o"],"articleSection":["Destaques","Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/","name":"Girando Sol marca 35 anos com pr\u00eamios - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463898_1196782_girando1-1-scaled.webp","datePublished":"2026-04-01T20:00:00+00:00","dateModified":"2026-05-18T19:02:05+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463898_1196782_girando1-1-scaled.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463898_1196782_girando1-1-scaled.webp","width":2560,"height":1440,"caption":"Cr\u00e9dito: Maicon Lu\u00eds \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/04\/01\/girando-sol-marca-35-anos-com-premios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Girando Sol marca 35 anos com pr\u00eamios"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/463898_1196782_girando1-1-scaled.webp","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/207742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=207742"}],"version-history":[{"count":1,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/207742\/revisions"}],"predecessor-version":[{"id":213131,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/207742\/revisions\/213131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/213130"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=207742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=207742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=207742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}