{"id":212739,"date":"2026-05-13T08:00:00","date_gmt":"2026-05-13T11:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=212739"},"modified":"2026-05-13T07:58:54","modified_gmt":"2026-05-13T10:58:54","slug":"poco-das-antas-valoriza-conquistas-e-projeta-o-futuro","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/","title":{"rendered":"Po\u00e7o das Antas valoriza conquistas e projeta o futuro"},"content":{"rendered":"\n<p>Po\u00e7o das Antas comemorou seus 38 anos de emancipa\u00e7\u00e3o pol\u00edtico-administrativa nessa ter\u00e7a-feira (12\/5). A programa\u00e7\u00e3o festiva iniciou no s\u00e1bado (9\/5) com a escolha da nova corte de soberanas, e segue durante maio com atividades culturais, esportivas e inaugura\u00e7\u00f5es de obras importantes para a comunidade.<\/p>\n\n\n\n<p>Ao relembrar a trajet\u00f3ria do munic\u00edpio, o prefeito Glic\u00e9rio Ivo Junges destaca as dificuldades enfrentadas pela popula\u00e7\u00e3o antes da emancipa\u00e7\u00e3o, quando a localidade pertencia primeiro a Montenegro e, depois, a Salvador do Sul.<\/p>\n\n\n\n<p>\u201cEnquanto n\u00f3s pertenc\u00edamos a Montenegro, \u00e9ramos a divisa com Estrela, sempre o fim do munic\u00edpio, aqueles esquecidos. Depois, pertencendo a Salvador do Sul, novamente divisa com Teut\u00f4nia\u201d, afirma. Segundo ele, a realidade da \u00e9poca era marcada pela falta de infraestrutura: \u201cAs estradas quase n\u00e3o existiam. N\u00e3o t\u00ednhamos um metro de cal\u00e7amento, n\u00e3o tinha asfalto, nada\u201d.<\/p>\n\n\n\n<p>Glic\u00e9rio ressalta que a emancipa\u00e7\u00e3o representou um divisor de \u00e1guas para o desenvolvimento local, principalmente nas \u00e1reas de sa\u00fade, educa\u00e7\u00e3o e mobilidade. \u201cO agricultor quer estrada, sa\u00fade e educa\u00e7\u00e3o\u201d, afirma ele.<\/p>\n\n\n\n<p>Lembra o in\u00edcio da primeira Administra\u00e7\u00e3o Municipal, quando a prefeitura tinha pouca estrutura para atender a popula\u00e7\u00e3o. Mas as mudan\u00e7as ao longo das d\u00e9cadas ficaram evidentes, como na \u00e1rea da sa\u00fade.<\/p>\n\n\n\n<p>O prefeito recorda situa\u00e7\u00f5es enfrentadas antigamente pela comunidade e destaca o quanto os acessos melhoraram. \u201cLembro quando houve um acidente envolvendo um \u00f4nibus e n\u00f3s t\u00ednhamos que mandar vir ambul\u00e2ncia de Salvador do Sul para levar as pessoas ao hospital. Hoje, em poucos minutos se chega at\u00e9 Teut\u00f4nia\u201d, conta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Gera\u00e7\u00e3o de emprego segue como desafio<\/strong><\/h2>\n\n\n\n<p>Apesar dos avan\u00e7os conquistados, a gera\u00e7\u00e3o de empregos segue como um dos principais desafios do munic\u00edpio, principalmente ap\u00f3s a redu\u00e7\u00e3o das atividades do frigor\u00edfico da Cooperativa Languiru, que impactou diretamente a arrecada\u00e7\u00e3o e o mercado de trabalho local.<\/p>\n\n\n\n<p>Segundo Glic\u00e9rio, muitas pessoas trabalham fora de Po\u00e7o das Antas e existe dificuldade para atrair novas empresas, justamente pela escassez de m\u00e3o de obra dispon\u00edvel. \u201cQuem quer trabalhar est\u00e1 fora ou no munic\u00edpio. As pessoas t\u00eam medo de largar um emprego certo para come\u00e7ar algo novo\u201d, afirma.<\/p>\n\n\n\n<p>Mesmo diante desse cen\u00e1rio, a Administra\u00e7\u00e3o busca alternativas para fortalecer a economia local e criar oportunidades dentro da pr\u00f3pria cidade. \u201cQueremos atrair alguma coisa e criar m\u00e3o de obra dentro do munic\u00edpio\u201d, aponta o prefeito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Polo regional e infraestrutura<\/strong><\/h2>\n\n\n\n<p>Entre os projetos em andamento est\u00e1 a cria\u00e7\u00e3o de um polo regional junto \u00e0 estrutura do antigo hospital, iniciativa desenvolvida em parceria com a Univates. Glic\u00e9rio afirma que o projeto est\u00e1 em andamento e ressalta emenda de R$ 420 mil destinada pelo senador Hamilton Mour\u00e3o para come\u00e7ar a obra.<\/p>\n\n\n\n<p>O investimento previsto deve ficar perto de R$ 5 milh\u00f5es. Conforme o prefeito, a proposta ter\u00e1 impacto regional, incentivando principalmente novos empreendimentos ligados ao setor aliment\u00edcio.<\/p>\n\n\n\n<p>Al\u00e9m dos investimentos voltados ao desenvolvimento econ\u00f4mico, a Administra\u00e7\u00e3o projeta novas obras ligadas ao turismo para os pr\u00f3ximos anos: \u201cQueremos come\u00e7ar a investir mais. A ponte p\u00eansil de Linha Louren\u00e7o Dill at\u00e9 a gruta \u00e9 um ponto tur\u00edstico importante.\u201d.<\/p>\n\n\n\n<p>O Munic\u00edpio tamb\u00e9m prev\u00ea novos trechos de asfalto em comunidades do interior e melhorias em acessos considerados estrat\u00e9gicos. Uma das principais inaugura\u00e7\u00f5es previstas para este m\u00eas \u00e9 a da ponte do Cafund\u00f3, marcada para o dia 23 de maio. Ainda, na segunda-feira (11\/5) houve a entrega da pavimenta\u00e7\u00e3o do trecho da Rua H\u00e9dio Louren\u00e7o Dilli, no Bairro Boa Vista.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"875\" height=\"451\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Cidade-cresce-com-meta-de-se-tornar-polo-regional-de-desenvolvimento-2_Reproducao-Instagram.webp\" alt=\"\" class=\"wp-image-212741\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Cidade-cresce-com-meta-de-se-tornar-polo-regional-de-desenvolvimento-2_Reproducao-Instagram.webp 875w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Cidade-cresce-com-meta-de-se-tornar-polo-regional-de-desenvolvimento-2_Reproducao-Instagram-300x155.webp 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Cidade-cresce-com-meta-de-se-tornar-polo-regional-de-desenvolvimento-2_Reproducao-Instagram-768x396.webp 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Cidade-cresce-com-meta-de-se-tornar-polo-regional-de-desenvolvimento-2_Reproducao-Instagram-815x420.webp 815w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Cidade-cresce-com-meta-de-se-tornar-polo-regional-de-desenvolvimento-2_Reproducao-Instagram-696x359.webp 696w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><figcaption class=\"wp-element-caption\"><br>Cidade cresce com meta de se tornar polo regional de desenvolvimento \/ Cr\u00e9dito: Reprodu\u00e7\u00e3o Instagram<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Programa\u00e7\u00e3o segue<\/strong><\/h2>\n\n\n\n<p>As comemora\u00e7\u00f5es pelos 38 anos de Po\u00e7o das Antas seguem. Na sexta-feira (15\/5) ocorre o 6\u00ba Semin\u00e1rio Regional de Educa\u00e7\u00e3o Fiscal. A atividade ser\u00e1 no Audit\u00f3rio da Prefeitura Municipal e reunir\u00e1 especialistas, servidores p\u00fablicos, profissionais da \u00e1rea tribut\u00e1ria, educadores e a comunidade para debater temas relacionados \u00e0 cidadania fiscal, transpar\u00eancia, gest\u00e3o tribut\u00e1ria e educa\u00e7\u00e3o financeira.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o inicia \u00e0s 8h, com credenciamento e recep\u00e7\u00e3o. Na sequ\u00eancia, ocorre a abertura oficial, seguida por palestra com o tema \u201cEduca\u00e7\u00e3o Fiscal e Conv\u00edvio Social\u201d, ministrada pelo auditor fiscal Jo\u00e3o Carlos Loebens.<\/p>\n\n\n\n<p>O segundo painel da manh\u00e3 ser\u00e1 comandado por Lenise Regina Flach, que falar\u00e1 sobre \u201cEduca\u00e7\u00e3o Fiscal: Tributo, Transpar\u00eancia e Cidadania\u201d. Encerrando as atividades da manh\u00e3, as representantes da Sicredi Ouro Branco de Po\u00e7o das Antas, Viviane Patr\u00edcia Krindges Schneider e Francieli Maria Fritzen Klein, apresentar\u00e3o palestra sobre cooperativismo, educa\u00e7\u00e3o financeira e escolhas conscientes.<\/p>\n\n\n\n<p>Ap\u00f3s o intervalo, a programa\u00e7\u00e3o ser\u00e1 retomada \u00e0s 13h15 com a palestra \u201cFiscaliza\u00e7\u00e3o Tribut\u00e1ria, Tributos Municipais e a Nova Administra\u00e7\u00e3o Tribut\u00e1ria\u201d, conduzida pelo professor, instrutor e consultor Johnny Bertoletti Racic. Em seguida, o secret\u00e1rio da Administra\u00e7\u00e3o, Romeu Forneck, abordar\u00e1 o tema \u201cAs vari\u00e1veis tribut\u00e1rias end\u00f3genas e o pacto federativo\u201d. O encerramento est\u00e1 previsto para as 16h, com caf\u00e9 de confraterniza\u00e7\u00e3o.<\/p>\n\n\n\n<p>Secret\u00e1ria da Fazenda de Po\u00e7o das Antas, Merielin Dilli afirma que o evento foi pensado principalmente para conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia dos impostos e tributos no desenvolvimento das cidades. \u201cO objetivo \u00e9 capacitar o cidad\u00e3o a acompanhar a aplica\u00e7\u00e3o destes recursos important\u00edssimos para o nosso munic\u00edpio\u201d, conclui.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas-3-1024x768.webp\" alt=\"\" class=\"wp-image-212744\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas-3-1024x768.webp 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas-3-300x225.webp 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas-3-768x576.webp 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas-3-560x420.webp 560w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas-3-80x60.webp 80w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas-3-696x522.webp 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas-3-1068x801.webp 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas-3.webp 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: Prefeitura de Po\u00e7o das Antas<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Po\u00e7o das Antas comemorou seus 38 anos de emancipa\u00e7\u00e3o pol\u00edtico-administrativa nessa ter\u00e7a-feira (12\/5). A programa\u00e7\u00e3o festiva iniciou no s\u00e1bado (9\/5) com a escolha da nova corte de soberanas, e segue durante maio com atividades culturais, esportivas e inaugura\u00e7\u00f5es de obras importantes para a comunidade. Ao relembrar a trajet\u00f3ria do munic\u00edpio, o prefeito Glic\u00e9rio Ivo Junges [&hellip;]<\/p>\n","protected":false},"author":782,"featured_media":212740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,10991],"tags":[5524,223,529,40],"class_list":{"0":"post-212739","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-economia","9":"tag-aniversario-2","10":"tag-educacao-fiscal","11":"tag-infraestrutura","12":"tag-poco-das-antas","13":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Po\u00e7o das Antas valoriza conquistas e projeta o futuro - Folha Popular<\/title>\n<meta name=\"description\" content=\"Po\u00e7o das Antas celebra anivers\u00e1rio com programa\u00e7\u00e3o especial e projetos voltados \u00e0 gera\u00e7\u00e3o de emprego, turismo e qualidade de vida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Po\u00e7o das Antas valoriza conquistas e projeta o futuro - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Po\u00e7o das Antas celebra anivers\u00e1rio com programa\u00e7\u00e3o especial e projetos voltados \u00e0 gera\u00e7\u00e3o de emprego, turismo e qualidade de vida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rafaela Zappaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela Zappaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/\"},\"author\":{\"name\":\"Rafaela Zappaz\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/87aa1d7488478bf03a40dc0a852db19d\"},\"headline\":\"Po\u00e7o das Antas valoriza conquistas e projeta o futuro\",\"datePublished\":\"2026-05-13T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/\"},\"wordCount\":941,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp\",\"keywords\":[\"Anivers\u00e1rio\",\"Educa\u00e7\u00e3o Fiscal\",\"Infraestrutura\",\"Po\u00e7o das Antas\"],\"articleSection\":[\"Destaques\",\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/\",\"name\":\"Po\u00e7o das Antas valoriza conquistas e projeta o futuro - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp\",\"datePublished\":\"2026-05-13T11:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/87aa1d7488478bf03a40dc0a852db19d\"},\"description\":\"Po\u00e7o das Antas celebra anivers\u00e1rio com programa\u00e7\u00e3o especial e projetos voltados \u00e0 gera\u00e7\u00e3o de emprego, turismo e qualidade de vida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp\",\"width\":1280,\"height\":960,\"caption\":\"Feriado de anivers\u00e1rio reuniu fam\u00edlias com diversas atra\u00e7\u00f5es na Pra\u00e7a Municipal \\\/ Cr\u00e9dito: Paloma Valandro - AI Prefeitura de Po\u00e7o das Antas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Po\u00e7o das Antas valoriza conquistas e projeta o futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/87aa1d7488478bf03a40dc0a852db19d\",\"name\":\"Rafaela Zappaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b6259df2b1311e565e2e930bcf599e41eca901dc1e0e850d699f28cc7ea8de8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b6259df2b1311e565e2e930bcf599e41eca901dc1e0e850d699f28cc7ea8de8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b6259df2b1311e565e2e930bcf599e41eca901dc1e0e850d699f28cc7ea8de8?s=96&d=mm&r=g\",\"caption\":\"Rafaela Zappaz\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/rafaela-zappaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Po\u00e7o das Antas valoriza conquistas e projeta o futuro - Folha Popular","description":"Po\u00e7o das Antas celebra anivers\u00e1rio com programa\u00e7\u00e3o especial e projetos voltados \u00e0 gera\u00e7\u00e3o de emprego, turismo e qualidade de vida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/","og_locale":"pt_BR","og_type":"article","og_title":"Po\u00e7o das Antas valoriza conquistas e projeta o futuro - Folha Popular","og_description":"Po\u00e7o das Antas celebra anivers\u00e1rio com programa\u00e7\u00e3o especial e projetos voltados \u00e0 gera\u00e7\u00e3o de emprego, turismo e qualidade de vida.","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/","og_site_name":"Folha Popular","article_published_time":"2026-05-13T11:00:00+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp","type":"image\/webp"}],"author":"Rafaela Zappaz","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rafaela Zappaz","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/"},"author":{"name":"Rafaela Zappaz","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/87aa1d7488478bf03a40dc0a852db19d"},"headline":"Po\u00e7o das Antas valoriza conquistas e projeta o futuro","datePublished":"2026-05-13T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/"},"wordCount":941,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp","keywords":["Anivers\u00e1rio","Educa\u00e7\u00e3o Fiscal","Infraestrutura","Po\u00e7o das Antas"],"articleSection":["Destaques","Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/","name":"Po\u00e7o das Antas valoriza conquistas e projeta o futuro - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp","datePublished":"2026-05-13T11:00:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/87aa1d7488478bf03a40dc0a852db19d"},"description":"Po\u00e7o das Antas celebra anivers\u00e1rio com programa\u00e7\u00e3o especial e projetos voltados \u00e0 gera\u00e7\u00e3o de emprego, turismo e qualidade de vida.","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp","width":1280,"height":960,"caption":"Feriado de anivers\u00e1rio reuniu fam\u00edlias com diversas atra\u00e7\u00f5es na Pra\u00e7a Municipal \/ Cr\u00e9dito: Paloma Valandro - AI Prefeitura de Po\u00e7o das Antas"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/poco-das-antas-valoriza-conquistas-e-projeta-o-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Po\u00e7o das Antas valoriza conquistas e projeta o futuro"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/87aa1d7488478bf03a40dc0a852db19d","name":"Rafaela Zappaz","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7b6259df2b1311e565e2e930bcf599e41eca901dc1e0e850d699f28cc7ea8de8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7b6259df2b1311e565e2e930bcf599e41eca901dc1e0e850d699f28cc7ea8de8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b6259df2b1311e565e2e930bcf599e41eca901dc1e0e850d699f28cc7ea8de8?s=96&d=mm&r=g","caption":"Rafaela Zappaz"},"url":"https:\/\/folhapopular.info\/index.php\/author\/rafaela-zappaz\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/POCO-Feriado-de-aniversario-reuniu-familias-com-diversas-atracoes-na-Praca-Municipal_Paloma-Valandro_AI-Prefeitura-de-Poco-das-Antas.webp","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/212739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/782"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=212739"}],"version-history":[{"count":1,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/212739\/revisions"}],"predecessor-version":[{"id":212745,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/212739\/revisions\/212745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/212740"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=212739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=212739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=212739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}