{"id":212746,"date":"2026-05-13T10:00:00","date_gmt":"2026-05-13T13:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=212746"},"modified":"2026-05-13T11:19:37","modified_gmt":"2026-05-13T14:19:37","slug":"gramado-summit-expoe-tensao-entre-ia-mercado-e-social","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/","title":{"rendered":"Gramado Summit exp\u00f5e tens\u00e3o entre Intelig\u00eancia Artificial, mercado e social"},"content":{"rendered":"\n<p><strong>Por Anderson Lopes e Thiago Maurique<\/strong><\/p>\n\n\n\n<p>A intelig\u00eancia artificial foi um dos temas mais debatidos durante o <a href=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/09\/gramado-summit-inspira-inovacao-baseada-no-ser-humano\/\" type=\"link\" id=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/09\/gramado-summit-inspira-inovacao-baseada-no-ser-humano\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gramado <em>Summit <\/em>2026<\/a>, mas n\u00e3o apenas sob a \u00f3tica do entusiasmo tecnol\u00f3gico. Entre alertas sobre o futuro das marcas, disputas globais por infraestrutura estrat\u00e9gica e questionamentos sobre quem realmente se beneficia da inova\u00e7\u00e3o, o evento revelou uma vis\u00e3o mais complexa e menos otimista sobre a nova economia digital.<\/p>\n\n\n\n<p>Em diferentes palcos, especialistas apontaram que a corrida pela IA j\u00e1 provoca mudan\u00e7as profundas no consumo de informa\u00e7\u00e3o, na ind\u00fastria e at\u00e9 nas rela\u00e7\u00f5es sociais.<\/p>\n\n\n\n<p>O especialista em marketing digital e <em>principal executivo do Pinterest no Brasil, <\/em>Rog\u00e9rio Nicolai<em>, <\/em>afirmou que o SEO tradicional come\u00e7a a perder espa\u00e7o para o chamado AEO (<em>Agent Engine Optimization<\/em>), modelo voltado \u00e0 otimiza\u00e7\u00e3o de conte\u00fados para agentes de IA como ChatGPT e o modo inteligente do Google.<\/p>\n\n\n\n<p>De acordo com ele, o comportamento de busca do consumidor mudou radicalmente em 12 meses. \u201cMais de 50% das pessoas que fazem uma pesquisa hoje j\u00e1 n\u00e3o clicam nos <em>links<\/em> org\u00e2nicos. Elas obt\u00eam a resposta direto no modo AI do Google ou no ChatGPT e encerram a explora\u00e7\u00e3o por ali\u201d, alertou.<\/p>\n\n\n\n<p>Nicolai explica que o impacto \u00e9 devastador para quem construiu estrat\u00e9gias inteiras baseadas no SEO tradicional. \u201cAquele clique que acontecia l\u00e1 na frente n\u00e3o acontece mais. As marcas, os ve\u00edculos, os <em>publishers<\/em>, todos que trabalhavam com SEO precisam agora trabalhar tamb\u00e9m com AEO, que \u00e9 a otimiza\u00e7\u00e3o para agentes\u201d, disse.<\/p>\n\n\n\n<p>O conceito de AEO visa a uma nova disciplina que vai estruturar o conte\u00fado para que ele seja lido e recomendado por agentes de IA, em vez de depender da lista de <em>links<\/em> azuis do Google. O palestrante foi cauteloso: \u201cDias contados ainda n\u00e3o, est\u00e1 muito distante. Mas a mudan\u00e7a \u00e9 inevit\u00e1vel.\u201d<\/p>\n\n\n\n<p>O entusiasmo com a tecnologia, no entanto, veio acompanhado de um alerta sobre os riscos. Nicolai dedicou parte da fala \u00e0quilo que chamou de \u201cpasteuriza\u00e7\u00e3o das marcas\u201d. \u201cA IA tem que ser utilizada. O grande problema \u00e9 quando ela n\u00e3o \u00e9 bem gerenciada. As marcas come\u00e7am a seguir todas o mesmo caminho, os textos se tornam poeticamente lindos, mas longos, extensos e ningu\u00e9m quer ler\u201d, destacou.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL-1024x768.webp\" alt=\"\" class=\"wp-image-212748\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL-1024x768.webp 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL-300x225.webp 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL-768x576.webp 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL-1536x1152.webp 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL-560x420.webp 560w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL-80x60.webp 80w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL-696x522.webp 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL-1068x801.webp 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Rogerio-Nicolai_AL.webp 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><br>Rog\u00e9rio Nicolai abordou a r\u00e1pida transforma\u00e7\u00e3o provocada pela IA no comportamento dos consumidores \/ Cr\u00e9dito: Anderson Lopes<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>A face oculta da IA<\/strong><\/h2>\n\n\n\n<p>Se Nicolai falou de algoritmos e comportamento do consumidor, o cientista e comunicador S\u00e9rgio Sacani abordou a infraestrutura por tr\u00e1s da tecnologia. Em uma palestra que mesclou hist\u00f3ria, geopol\u00edtica e ci\u00eancia de ponta, Sacani tra\u00e7ou um panorama dos modelos de linguagem usados no dia a dia.<\/p>\n\n\n\n<p>Destacou o consumo energ\u00e9tico dos <em>data centers<\/em>. \u201cHoje, estamos batendo 1,7 trilh\u00e3o de par\u00e2metros treinados no GPT-4. Para treinar isso, voc\u00ea precisa de muitas m\u00e1quinas e muita \u00e1gua para resfriar tudo isso\u201d, disse.<\/p>\n\n\n\n<p>Ao abordar as terras raras, Sacani acendeu o alerta. O Brasil, dono da segunda maior reserva do mundo, com 23 milh\u00f5es de toneladas, atr\u00e1s apenas da China, com 44 milh\u00f5es, n\u00e3o possui capacidade de refino. \u201cA terra rara na rocha vale cerca de 5 d\u00f3lares a tonelada. Quando refinada, chega a 500 d\u00f3lares. E 90% do refino do planeta \u00e9 da China\u201d, refor\u00e7ou ele.<\/p>\n\n\n\n<p>Para Sacani, a depend\u00eancia \u00e9 estrat\u00e9gica e perigosa. Diante disso, o palestrante fez um apelo direto ao p\u00fablico: \u201cPergunte para o seu pol\u00edtico qual \u00e9 o plano para as terras raras do Brasil. Tem elei\u00e7\u00e3o este ano. Eu duvido que algum deles saiba o que \u00e9 terras raras\u201d, alertou o cientista.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Sergio-Sacani_AL-768x1024.webp\" alt=\"\" class=\"wp-image-212749\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Sergio-Sacani_AL-768x1024.webp 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Sergio-Sacani_AL-225x300.webp 225w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Sergio-Sacani_AL-1152x1536.webp 1152w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Sergio-Sacani_AL-315x420.webp 315w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Sergio-Sacani_AL-696x928.webp 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Sergio-Sacani_AL-1068x1424.webp 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Sergio-Sacani_AL.webp 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\"><br>O papel das chamadas terras raras e a infraestrutura tecnol\u00f3gica foram temas da palestra de S\u00e9rgio Sacani \/ Cr\u00e9dito: Anderson Lopes<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>A base da sociedade<\/strong><\/h2>\n\n\n\n<p>Em contraponto, a <em>designer<\/em> e jornalista Carol Anchieta, gestora do projeto Design Ativista, provocou o p\u00fablico ao questionar se a inova\u00e7\u00e3o debatida nos grandes eventos realmente alcan\u00e7a a base da sociedade ou apenas refor\u00e7a desigualdades j\u00e1 existentes.<\/p>\n\n\n\n<p>A palestrante representava a M\u00eddia Ninja, descrita por ela como \u201cuma floresta ativista\u201d onde diversos projetos, como Planeta Ella (feminismo), Poderes Pretos (quest\u00f5es raciais) e Ninja Esporte Clube s\u00e3o afluentes de um mesmo rio. \u201cInova\u00e7\u00e3o social \u00e9 mais do que solu\u00e7\u00e3o. \u00c9 escuta, afeto e reconstru\u00e7\u00e3o de v\u00ednculos\u201d, afirmou.<\/p>\n\n\n\n<p>Para ela, a inova\u00e7\u00e3o que n\u00e3o chega na base da pir\u00e2mide, pois gera lucro apenas para o topo. Ao ser perguntada sobre moda e sustentabilidade, Carol disse: \u201cMuita inova\u00e7\u00e3o sustent\u00e1vel roubou conhecimento ind\u00edgena, produ\u00e7\u00e3o amaz\u00f4nica. A senhorinha que faz a bolsa de tecido que sobra ganha R$ 20, enquanto a marca ganha os louros.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Anderson Lopes e Thiago Maurique A intelig\u00eancia artificial foi um dos temas mais debatidos durante o Gramado Summit 2026, mas n\u00e3o apenas sob a \u00f3tica do entusiasmo tecnol\u00f3gico. Entre alertas sobre o futuro das marcas, disputas globais por infraestrutura estrat\u00e9gica e questionamentos sobre quem realmente se beneficia da inova\u00e7\u00e3o, o evento revelou uma vis\u00e3o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":212747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,10991],"tags":[8619,21148,5526,2518],"class_list":{"0":"post-212746","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-economia","9":"tag-gramado-summit","10":"tag-gramado-summit-2026","11":"tag-inteligencia-artificial","12":"tag-tecnologia","13":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gramado Summit exp\u00f5e tens\u00e3o entre IA, mercado e social<\/title>\n<meta name=\"description\" content=\"Palestras abordaram desde a transforma\u00e7\u00e3o do marketing digital com intelig\u00eancia artificial at\u00e9 disputas geopol\u00edticas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gramado Summit exp\u00f5e tens\u00e3o entre IA, mercado e social\" \/>\n<meta property=\"og:description\" content=\"Palestras abordaram desde a transforma\u00e7\u00e3o do marketing digital com intelig\u00eancia artificial at\u00e9 disputas geopol\u00edticas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T14:19:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Carol-Anchieta-_AL.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Gramado Summit exp\u00f5e tens\u00e3o entre Intelig\u00eancia Artificial, mercado e social\",\"datePublished\":\"2026-05-13T13:00:00+00:00\",\"dateModified\":\"2026-05-13T14:19:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/\"},\"wordCount\":807,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GRAMADO-Carol-Anchieta-_AL.webp\",\"keywords\":[\"Gramado Summit\",\"Gramado Summit 2026\",\"Intelig\u00eancia Artificial\",\"Tecnologia\"],\"articleSection\":[\"Destaques\",\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/\",\"name\":\"Gramado Summit exp\u00f5e tens\u00e3o entre IA, mercado e social\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GRAMADO-Carol-Anchieta-_AL.webp\",\"datePublished\":\"2026-05-13T13:00:00+00:00\",\"dateModified\":\"2026-05-13T14:19:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"description\":\"Palestras abordaram desde a transforma\u00e7\u00e3o do marketing digital com intelig\u00eancia artificial at\u00e9 disputas geopol\u00edticas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GRAMADO-Carol-Anchieta-_AL.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GRAMADO-Carol-Anchieta-_AL.webp\",\"width\":1600,\"height\":1200,\"caption\":\"Carol Anchieta questionou se a inova\u00e7\u00e3o debatida nos grandes eventos realmente alcan\u00e7a a base da sociedade \\\/ Cr\u00e9dito: Anderson Lopes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gramado Summit exp\u00f5e tens\u00e3o entre Intelig\u00eancia Artificial, mercado e social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gramado Summit exp\u00f5e tens\u00e3o entre IA, mercado e social","description":"Palestras abordaram desde a transforma\u00e7\u00e3o do marketing digital com intelig\u00eancia artificial at\u00e9 disputas geopol\u00edticas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/","og_locale":"pt_BR","og_type":"article","og_title":"Gramado Summit exp\u00f5e tens\u00e3o entre IA, mercado e social","og_description":"Palestras abordaram desde a transforma\u00e7\u00e3o do marketing digital com intelig\u00eancia artificial at\u00e9 disputas geopol\u00edticas.","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/","og_site_name":"Folha Popular","article_published_time":"2026-05-13T13:00:00+00:00","article_modified_time":"2026-05-13T14:19:37+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Carol-Anchieta-_AL.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Gramado Summit exp\u00f5e tens\u00e3o entre Intelig\u00eancia Artificial, mercado e social","datePublished":"2026-05-13T13:00:00+00:00","dateModified":"2026-05-13T14:19:37+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/"},"wordCount":807,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Carol-Anchieta-_AL.webp","keywords":["Gramado Summit","Gramado Summit 2026","Intelig\u00eancia Artificial","Tecnologia"],"articleSection":["Destaques","Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/","name":"Gramado Summit exp\u00f5e tens\u00e3o entre IA, mercado e social","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Carol-Anchieta-_AL.webp","datePublished":"2026-05-13T13:00:00+00:00","dateModified":"2026-05-13T14:19:37+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"description":"Palestras abordaram desde a transforma\u00e7\u00e3o do marketing digital com intelig\u00eancia artificial at\u00e9 disputas geopol\u00edticas.","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Carol-Anchieta-_AL.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Carol-Anchieta-_AL.webp","width":1600,"height":1200,"caption":"Carol Anchieta questionou se a inova\u00e7\u00e3o debatida nos grandes eventos realmente alcan\u00e7a a base da sociedade \/ Cr\u00e9dito: Anderson Lopes"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/gramado-summit-expoe-tensao-entre-ia-mercado-e-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Gramado Summit exp\u00f5e tens\u00e3o entre Intelig\u00eancia Artificial, mercado e social"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/GRAMADO-Carol-Anchieta-_AL.webp","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/212746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=212746"}],"version-history":[{"count":2,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/212746\/revisions"}],"predecessor-version":[{"id":212802,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/212746\/revisions\/212802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/212747"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=212746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=212746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=212746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}