{"id":212847,"date":"2026-05-13T16:33:27","date_gmt":"2026-05-13T19:33:27","guid":{"rendered":"https:\/\/folhapopular.info\/?p=212847"},"modified":"2026-05-13T16:33:29","modified_gmt":"2026-05-13T19:33:29","slug":"internacional-vence-e-garante-classificacao-na-copa-do-brasil","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/","title":{"rendered":"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil"},"content":{"rendered":"\n<p>O Internacional confirmou vaga nas oitavas de final da Copa do Brasil ao vencer o Athletic Club por 3 a 2, na noite desta ter\u00e7a-feira (12\/5), no Est\u00e1dio Beira-Rio. Como havia triunfado por 1 a 0 no jogo de ida, o Colorado avan\u00e7ou na competi\u00e7\u00e3o nacional.<\/p>\n\n\n\n<p>Borr\u00e9, Allex e Bernabei marcaram os gols da equipe comandada por Paulo Pezzolano. Ian Luccas fez os dois gols do Athletic. Mais de 8 mil torcedores acompanharam a partida em Porto Alegre.<\/p>\n\n\n\n<p>O Inter abriu o placar aos 20min do primeiro tempo com Borr\u00e9, mas sofreu o empate ainda antes do intervalo. Pouco depois, Allex recolocou os ga\u00fachos em vantagem.<\/p>\n\n\n\n<p>Na segunda etapa, Gian Cabezas foi expulso pelo Athletic ap\u00f3s revis\u00e3o do VAR. Mesmo com um jogador a menos, os mineiros empataram novamente com Ian Luccas, mas Bernabei marcou logo na sequ\u00eancia e definiu a vit\u00f3ria colorada.<\/p>\n\n\n\n<p>Agora, o Internacional aguarda o sorteio da CBF para conhecer o advers\u00e1rio das oitavas de final. Pelo Campeonato Brasileiro S\u00e9rie A, o pr\u00f3ximo compromisso ser\u00e1 diante do Club de Regatas Vasco da Gama, no s\u00e1bado (16\/5), no Beira-Rio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Leia mais:<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-folha-popular wp-block-embed-folha-popular\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"LQHf9L0rSA\"><a href=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/11\/internacional-empata-fora-de-casa-pelo-brasileirao\/\">Internacional empata fora de casa pelo Brasileir\u00e3o<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Internacional empata fora de casa pelo Brasileir\u00e3o&#8221; &#8212; Folha Popular\" src=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/11\/internacional-empata-fora-de-casa-pelo-brasileirao\/embed\/#?secret=Bn4bPqwyHU#?secret=LQHf9L0rSA\" data-secret=\"LQHf9L0rSA\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O Internacional confirmou vaga nas oitavas de final da Copa do Brasil ao vencer o Athletic Club por 3 a 2, na noite desta ter\u00e7a-feira (12\/5), no Est\u00e1dio Beira-Rio. Como havia triunfado por 1 a 0 no jogo de ida, o Colorado avan\u00e7ou na competi\u00e7\u00e3o nacional. Borr\u00e9, Allex e Bernabei marcaram os gols da equipe [&hellip;]<\/p>\n","protected":false},"author":732,"featured_media":212848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,2243],"tags":[21217,6457,2407,1809],"class_list":{"0":"post-212847","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-esportes","8":"category-futebol-profissional","9":"tag-athletic","10":"tag-copa-do-brasil","11":"tag-futebol-profissional","12":"tag-internacional","13":"pmpro-has-access"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil - Folha Popular<\/title>\n<meta name=\"description\" content=\"O Internacional confirmou vaga nas oitavas de final da Copa do Brasil ao vencer o Athletic Club por 3 a 2, na noite desta ter\u00e7a-feira.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"O Internacional confirmou vaga nas oitavas de final da Copa do Brasil ao vencer o Athletic Club por 3 a 2, na noite desta ter\u00e7a-feira.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/luis.huppes\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T19:33:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T19:33:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Com-gol-de-Allex-Inter-triunfou-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Luis Augusto Huppes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Augusto Huppes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/\"},\"author\":{\"name\":\"Luis Augusto Huppes\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/e852c327371714676d02e58cf917fd9f\"},\"headline\":\"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil\",\"datePublished\":\"2026-05-13T19:33:27+00:00\",\"dateModified\":\"2026-05-13T19:33:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/\"},\"wordCount\":205,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Com-gol-de-Allex-Inter-triunfou-scaled.webp\",\"keywords\":[\"Athletic\",\"Copa do Brasil\",\"futebol profissional\",\"Internacional\"],\"articleSection\":[\"Esportes\",\"Futebol Profissional\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/\",\"name\":\"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Com-gol-de-Allex-Inter-triunfou-scaled.webp\",\"datePublished\":\"2026-05-13T19:33:27+00:00\",\"dateModified\":\"2026-05-13T19:33:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/e852c327371714676d02e58cf917fd9f\"},\"description\":\"O Internacional confirmou vaga nas oitavas de final da Copa do Brasil ao vencer o Athletic Club por 3 a 2, na noite desta ter\u00e7a-feira.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Com-gol-de-Allex-Inter-triunfou-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Com-gol-de-Allex-Inter-triunfou-scaled.webp\",\"width\":2560,\"height\":1706,\"caption\":\"Com gol de Allex, Inter triunfou - Cr\u00e9dito: Ricardo Duarte \\\/ Inter \\\/ Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/13\\\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/e852c327371714676d02e58cf917fd9f\",\"name\":\"Luis Augusto Huppes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Luis-Augusto-Huppes-1-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Luis-Augusto-Huppes-1-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Luis-Augusto-Huppes-1-1.webp\",\"caption\":\"Luis Augusto Huppes\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/luis.huppes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/luis.huppes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/luis-augusto-huppes-2554b52b7\\\/\"],\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/luis-augusto-huppes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil - Folha Popular","description":"O Internacional confirmou vaga nas oitavas de final da Copa do Brasil ao vencer o Athletic Club por 3 a 2, na noite desta ter\u00e7a-feira.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil - Folha Popular","og_description":"O Internacional confirmou vaga nas oitavas de final da Copa do Brasil ao vencer o Athletic Club por 3 a 2, na noite desta ter\u00e7a-feira.","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/","og_site_name":"Folha Popular","article_author":"https:\/\/www.facebook.com\/luis.huppes\/","article_published_time":"2026-05-13T19:33:27+00:00","article_modified_time":"2026-05-13T19:33:29+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Com-gol-de-Allex-Inter-triunfou-scaled.webp","type":"image\/webp"}],"author":"Luis Augusto Huppes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luis Augusto Huppes","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/"},"author":{"name":"Luis Augusto Huppes","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/e852c327371714676d02e58cf917fd9f"},"headline":"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil","datePublished":"2026-05-13T19:33:27+00:00","dateModified":"2026-05-13T19:33:29+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/"},"wordCount":205,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Com-gol-de-Allex-Inter-triunfou-scaled.webp","keywords":["Athletic","Copa do Brasil","futebol profissional","Internacional"],"articleSection":["Esportes","Futebol Profissional"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/","name":"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Com-gol-de-Allex-Inter-triunfou-scaled.webp","datePublished":"2026-05-13T19:33:27+00:00","dateModified":"2026-05-13T19:33:29+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/e852c327371714676d02e58cf917fd9f"},"description":"O Internacional confirmou vaga nas oitavas de final da Copa do Brasil ao vencer o Athletic Club por 3 a 2, na noite desta ter\u00e7a-feira.","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Com-gol-de-Allex-Inter-triunfou-scaled.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Com-gol-de-Allex-Inter-triunfou-scaled.webp","width":2560,"height":1706,"caption":"Com gol de Allex, Inter triunfou - Cr\u00e9dito: Ricardo Duarte \/ Inter \/ Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/13\/internacional-vence-e-garante-classificacao-na-copa-do-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Internacional vence e garante classifica\u00e7\u00e3o na Copa do Brasil"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/e852c327371714676d02e58cf917fd9f","name":"Luis Augusto Huppes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Luis-Augusto-Huppes-1-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Luis-Augusto-Huppes-1-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Luis-Augusto-Huppes-1-1.webp","caption":"Luis Augusto Huppes"},"sameAs":["https:\/\/www.facebook.com\/luis.huppes\/","https:\/\/www.instagram.com\/luis.huppes\/","https:\/\/www.linkedin.com\/in\/luis-augusto-huppes-2554b52b7\/"],"url":"https:\/\/folhapopular.info\/index.php\/author\/luis-augusto-huppes\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/Com-gol-de-Allex-Inter-triunfou-scaled.webp","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/212847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/732"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=212847"}],"version-history":[{"count":1,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/212847\/revisions"}],"predecessor-version":[{"id":212849,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/212847\/revisions\/212849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/212848"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=212847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=212847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=212847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}