{"id":213893,"date":"2026-05-30T00:00:00","date_gmt":"2026-05-30T03:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=213893"},"modified":"2026-05-29T19:19:56","modified_gmt":"2026-05-29T22:19:56","slug":"folha-popular-30-5-2026","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/","title":{"rendered":"Folha Popular &#8211; 30-5-2026"},"content":{"rendered":"<p>Na edi\u00e7\u00e3o da Folha Popular deste s\u00e1bado, voc\u00ea confere: Sul se prepara para reduzir preju\u00edzos com a volta do El Ni\u00f1o. La\u00e7os familiares: paix\u00e3o que vem de casa e atravessa gera\u00e7\u00f5es. Augustin oferta segunda turma do T\u00e9cnico em Administra\u00e7\u00e3o, em Teut\u00f4nia. Organiza\u00e7\u00e3o da Expofeira quer superar visitantes com mudan\u00e7as para a antiga Cal\u00e7ados Reifer, em&#8230; <\/p>\n<div class=\"pmpro\">\n<div class=\"pmpro_card pmpro_content_message\">\n<div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular &#8211; Conte\u00fado Total Anual e Grupo Popular &#8211; Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div>\n<div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2026%2F05%2F30%2Ffolha-popular-30-5-2026%2F\">Acesse aqui<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na edi\u00e7\u00e3o da Folha Popular deste s\u00e1bado, voc\u00ea confere: Sul se prepara para reduzir preju\u00edzos com a volta do El Ni\u00f1o. La\u00e7os familiares: paix\u00e3o que vem de casa e atravessa gera\u00e7\u00f5es. Augustin oferta segunda turma do T\u00e9cnico em Administra\u00e7\u00e3o, em Teut\u00f4nia. Organiza\u00e7\u00e3o da Expofeira quer superar visitantes com mudan\u00e7as para a antiga Cal\u00e7ados Reifer, em... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular - Conte\u00fado Total Anual e Grupo Popular - Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2026%2F05%2F30%2Ffolha-popular-30-5-2026%2F\">Acesse aqui<\/a><\/div><\/div><\/div>","protected":false},"author":8,"featured_media":213894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11078,5990,5364],"tags":[3559],"class_list":["post-213893","post","type-post","status-publish","format-standard","has-post-thumbnail","category-assinantes","category-conteudo-exclusivo","category-folha-popular-impressa","tag-folha-popular","pmpro-level-required","pmpro-level-2","pmpro-level-4","pmpro-level-5","pmpro-no-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Folha Popular - 30-5-2026 - Folha Popular<\/title>\n<meta name=\"description\" content=\"Na edi\u00e7\u00e3o da Folha Popular deste s\u00e1bado, voc\u00ea confere mat\u00e9rias exclusivas e conte\u00fados de credibilidade. Aproveite!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Folha Popular - 30-5-2026 - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Na edi\u00e7\u00e3o da Folha Popular deste s\u00e1bado, voc\u00ea confere mat\u00e9rias exclusivas e conte\u00fados de credibilidade. Aproveite!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-30T03:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/0-6.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1610\" \/>\n\t<meta property=\"og:image:height\" content=\"2154\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Folha Popular &#8211; 30-5-2026\",\"datePublished\":\"2026-05-30T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/\"},\"wordCount\":147,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/0-6.webp\",\"keywords\":[\"Folha Popular\"],\"articleSection\":[\"Assinantes\",\"Conte\u00fado Exclusivo\",\"Folha Popular Impressa\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/\",\"name\":\"Folha Popular - 30-5-2026 - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/0-6.webp\",\"datePublished\":\"2026-05-30T03:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"description\":\"Na edi\u00e7\u00e3o da Folha Popular deste s\u00e1bado, voc\u00ea confere mat\u00e9rias exclusivas e conte\u00fados de credibilidade. Aproveite!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/0-6.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/0-6.webp\",\"width\":1610,\"height\":2154,\"caption\":\"Folha Popular - 30-5-2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/folha-popular-30-5-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Folha Popular &#8211; 30-5-2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Folha Popular - 30-5-2026 - Folha Popular","description":"Na edi\u00e7\u00e3o da Folha Popular deste s\u00e1bado, voc\u00ea confere mat\u00e9rias exclusivas e conte\u00fados de credibilidade. Aproveite!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/","og_locale":"pt_BR","og_type":"article","og_title":"Folha Popular - 30-5-2026 - Folha Popular","og_description":"Na edi\u00e7\u00e3o da Folha Popular deste s\u00e1bado, voc\u00ea confere mat\u00e9rias exclusivas e conte\u00fados de credibilidade. Aproveite!","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/","og_site_name":"Folha Popular","article_published_time":"2026-05-30T03:00:00+00:00","og_image":[{"width":1610,"height":2154,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/0-6.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Folha Popular &#8211; 30-5-2026","datePublished":"2026-05-30T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/"},"wordCount":147,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/0-6.webp","keywords":["Folha Popular"],"articleSection":["Assinantes","Conte\u00fado Exclusivo","Folha Popular Impressa"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/","name":"Folha Popular - 30-5-2026 - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/0-6.webp","datePublished":"2026-05-30T03:00:00+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"description":"Na edi\u00e7\u00e3o da Folha Popular deste s\u00e1bado, voc\u00ea confere mat\u00e9rias exclusivas e conte\u00fados de credibilidade. Aproveite!","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/0-6.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/0-6.webp","width":1610,"height":2154,"caption":"Folha Popular - 30-5-2026"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/folha-popular-30-5-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Folha Popular &#8211; 30-5-2026"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/0-6.webp","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/213893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=213893"}],"version-history":[{"count":1,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/213893\/revisions"}],"predecessor-version":[{"id":213896,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/213893\/revisions\/213896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/213894"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=213893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=213893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=213893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}