{"id":213929,"date":"2026-05-30T10:55:48","date_gmt":"2026-05-30T13:55:48","guid":{"rendered":"https:\/\/folhapopular.info\/?p=213929"},"modified":"2026-05-30T16:48:57","modified_gmt":"2026-05-30T19:48:57","slug":"vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/","title":{"rendered":"Vereadores de Teut\u00f4nia aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores"},"content":{"rendered":"<p>A C\u00e2mara de Vereadores de Teut\u00f4nia aprovou, na sess\u00e3o ordin\u00e1ria de quarta-feira (27\/5), projetos voltados \u00e0s \u00e1reas de educa\u00e7\u00e3o, assist\u00eancia social, desenvolvimento econ\u00f4mico e administra\u00e7\u00e3o p\u00fablica. Tamb\u00e9m foram apreciadas tr\u00eas indica\u00e7\u00f5es apresentadas por parlamentares. Todas as mat\u00e9rias da pauta foram aprovadas com oito votos favor\u00e1veis e aus\u00eancia dos vereadores Werner Wiebusch (PDT) e Valdir Oliveira&#8230; <\/p>\n<div class=\"pmpro\">\n<div class=\"pmpro_card pmpro_content_message\">\n<div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular &#8211; Conte\u00fado Total Anual e Grupo Popular &#8211; Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div>\n<div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2026%2F05%2F30%2Fvereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores%2F\">Acesse aqui<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara de Vereadores de Teut\u00f4nia aprovou, na sess\u00e3o ordin\u00e1ria de quarta-feira (27\/5), projetos voltados \u00e0s \u00e1reas de educa\u00e7\u00e3o, assist\u00eancia social, desenvolvimento econ\u00f4mico e administra\u00e7\u00e3o p\u00fablica. Tamb\u00e9m foram apreciadas tr\u00eas indica\u00e7\u00f5es apresentadas por parlamentares. Todas as mat\u00e9rias da pauta foram aprovadas com oito votos favor\u00e1veis e aus\u00eancia dos vereadores Werner Wiebusch (PDT) e Valdir Oliveira... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular - Conte\u00fado Total Anual e Grupo Popular - Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2026%2F05%2F30%2Fvereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores%2F\">Acesse aqui<\/a><\/div><\/div><\/div>","protected":false},"author":764,"featured_media":213930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11078,18239,10985],"tags":[646,4442,2218,26],"class_list":["post-213929","post","type-post","status-publish","format-standard","has-post-thumbnail","category-assinantes","category-camara-de-vereadores-de-teutonia","category-politica","tag-camara-de-vereadores","tag-camara-de-vereadores-de-teutonia","tag-politica","tag-teutonia","pmpro-level-required","pmpro-level-2","pmpro-level-4","pmpro-level-5","pmpro-no-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vereadores aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores<\/title>\n<meta name=\"description\" content=\"A C\u00e2mara de Vereadores de Teut\u00f4nia aprovou projetos voltados \u00e0s \u00e1reas de educa\u00e7\u00e3o, assist\u00eancia social, desenvolvimento e administra\u00e7\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vereadores aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores\" \/>\n<meta property=\"og:description\" content=\"A C\u00e2mara de Vereadores de Teut\u00f4nia aprovou projetos voltados \u00e0s \u00e1reas de educa\u00e7\u00e3o, assist\u00eancia social, desenvolvimento e administra\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-30T13:55:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-30T19:48:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"J\u00e9ssica Bayer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00e9ssica Bayer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/\"},\"author\":{\"name\":\"J\u00e9ssica Bayer\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/9c3bd49fe9d74793decad1d4c83fa974\"},\"headline\":\"Vereadores de Teut\u00f4nia aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores\",\"datePublished\":\"2026-05-30T13:55:48+00:00\",\"dateModified\":\"2026-05-30T19:48:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/\"},\"wordCount\":868,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp\",\"keywords\":[\"C\u00e2mara de Vereadores\",\"C\u00e2mara de Vereadores de Teut\u00f4nia\",\"pol\u00edtica\",\"Teut\u00f4nia\"],\"articleSection\":[\"Assinantes\",\"C\u00e2mara de Vereadores de Teut\u00f4nia\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/\",\"name\":\"Vereadores aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp\",\"datePublished\":\"2026-05-30T13:55:48+00:00\",\"dateModified\":\"2026-05-30T19:48:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/9c3bd49fe9d74793decad1d4c83fa974\"},\"description\":\"A C\u00e2mara de Vereadores de Teut\u00f4nia aprovou projetos voltados \u00e0s \u00e1reas de educa\u00e7\u00e3o, assist\u00eancia social, desenvolvimento e administra\u00e7\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp\",\"width\":2560,\"height\":1707,\"caption\":\"Vereadores debateram ped\u00e1gios, Festa de Maio e situa\u00e7\u00e3o da ERS-419 na tribuna \\\/ Cr\u00e9dito: J\u00e9ssica Bayer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/05\\\/30\\\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vereadores de Teut\u00f4nia aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/9c3bd49fe9d74793decad1d4c83fa974\",\"name\":\"J\u00e9ssica Bayer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g\",\"caption\":\"J\u00e9ssica Bayer\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/jessicad-bayergmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vereadores aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores","description":"A C\u00e2mara de Vereadores de Teut\u00f4nia aprovou projetos voltados \u00e0s \u00e1reas de educa\u00e7\u00e3o, assist\u00eancia social, desenvolvimento e administra\u00e7\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/","og_locale":"pt_BR","og_type":"article","og_title":"Vereadores aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores","og_description":"A C\u00e2mara de Vereadores de Teut\u00f4nia aprovou projetos voltados \u00e0s \u00e1reas de educa\u00e7\u00e3o, assist\u00eancia social, desenvolvimento e administra\u00e7\u00e3o.","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/","og_site_name":"Folha Popular","article_published_time":"2026-05-30T13:55:48+00:00","article_modified_time":"2026-05-30T19:48:57+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp","type":"image\/webp"}],"author":"J\u00e9ssica Bayer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"J\u00e9ssica Bayer","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/"},"author":{"name":"J\u00e9ssica Bayer","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/9c3bd49fe9d74793decad1d4c83fa974"},"headline":"Vereadores de Teut\u00f4nia aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores","datePublished":"2026-05-30T13:55:48+00:00","dateModified":"2026-05-30T19:48:57+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/"},"wordCount":868,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp","keywords":["C\u00e2mara de Vereadores","C\u00e2mara de Vereadores de Teut\u00f4nia","pol\u00edtica","Teut\u00f4nia"],"articleSection":["Assinantes","C\u00e2mara de Vereadores de Teut\u00f4nia","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/","name":"Vereadores aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp","datePublished":"2026-05-30T13:55:48+00:00","dateModified":"2026-05-30T19:48:57+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/9c3bd49fe9d74793decad1d4c83fa974"},"description":"A C\u00e2mara de Vereadores de Teut\u00f4nia aprovou projetos voltados \u00e0s \u00e1reas de educa\u00e7\u00e3o, assist\u00eancia social, desenvolvimento e administra\u00e7\u00e3o.","breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp","width":2560,"height":1707,"caption":"Vereadores debateram ped\u00e1gios, Festa de Maio e situa\u00e7\u00e3o da ERS-419 na tribuna \/ Cr\u00e9dito: J\u00e9ssica Bayer"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/05\/30\/vereadores-de-teutonia-aprovam-contratacao-temporaria-de-servidores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Vereadores de Teut\u00f4nia aprovam contrata\u00e7\u00e3o tempor\u00e1ria de servidores"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/9c3bd49fe9d74793decad1d4c83fa974","name":"J\u00e9ssica Bayer","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/66a5b729e90fb69c858616142b10a981fcab7744c95a8bfabc31856b5c9df354?s=96&d=mm&r=g","caption":"J\u00e9ssica Bayer"},"url":"https:\/\/folhapopular.info\/index.php\/author\/jessicad-bayergmail-com\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/05\/CAMARA-Vereadores-debateram-pedagios-Festa-de-Maio-e-situacao-da-ERS-419-na-tribuna_JB-scaled.webp","_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/213929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/764"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=213929"}],"version-history":[{"count":1,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/213929\/revisions"}],"predecessor-version":[{"id":213931,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/213929\/revisions\/213931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/213930"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=213929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=213929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=213929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}