{"id":216376,"date":"2026-07-13T19:57:41","date_gmt":"2026-07-13T22:57:41","guid":{"rendered":"https:\/\/folhapopular.info\/?p=216376"},"modified":"2026-07-13T20:27:26","modified_gmt":"2026-07-13T23:27:26","slug":"westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/","title":{"rendered":"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Sele\u00e7\u00e3o de Westf\u00e1lia voltou a levantar um trof\u00e9u regional. Na noite da \u00faltima sexta-feira, dia 10 de julho, a equipe conquistou o bicampeonato da Ta\u00e7a dos Campe\u00f5es, ao vencer Salvador do Sul por 4 a 0, fora de casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Campe\u00e3 da 4\u00aa Copa Rota da Serra Sicoob de Futsal, Westf\u00e1lia enfrentou a sele\u00e7\u00e3o vencedora da 7\u00aa Copa Transcitrus Sicredi e confirmou mais uma vez sua for\u00e7a no cen\u00e1rio regional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A conquista tamb\u00e9m repetiu o roteiro da temporada passada. Assim como em 2025, Westf\u00e1lia venceu a Ta\u00e7a dos Campe\u00f5es na categoria For\u00e7a Livre, enquanto Paverama ficou com o t\u00edtulo do Sub-15 ao vencer Teut\u00f4nia por 2 a 1.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/westfalia.rs.gov.br\/wp-content\/uploads\/2026\/07\/IMG_8628-JORNAL-1024x768.jpg\" alt=\"\" class=\"wp-image-9714\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dois tempos distintos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A decis\u00e3o come\u00e7ou equilibrada, com Salvador do Sul criando boas oportunidades diante da torcida. A defesa de Westf\u00e1lia, por\u00e9m, suportou a press\u00e3o e a equipe abriu vantagem ainda na etapa inicial, em cobran\u00e7a de falta convertida por Gabriel dos Santos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na volta do intervalo, os donos da casa passaram a utilizar o goleiro-linha em busca da rea\u00e7\u00e3o. A estrat\u00e9gia abriu espa\u00e7os que foram muito bem aproveitados pela equipe comandada por Laudenor Brune. Com marca\u00e7\u00e3o consistente, roubadas de bola e contra-ataques r\u00e1pidos, Westf\u00e1lia ampliou o placar at\u00e9 fechar a partida em 4 a 0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gabriel dos Santos marcou duas vezes e Maiquel Kalkmann tamb\u00e9m balan\u00e7ou as redes em duas oportunidades, garantindo a goleada e o bicampeonato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comprometimento<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Laudenor Brune, a conquista \u00e9 fruto do comprometimento de todo o grupo. \u201cEstamos muito felizes com mais esse t\u00edtulo. A equipe entrou em quadra com muita garra e determina\u00e7\u00e3o. O primeiro tempo foi muito disputado, Salvador do Sul criou boas oportunidades, mas nossa defesa soube suportar a press\u00e3o. Conseguimos abrir o placar em uma cobran\u00e7a de falta do Gabriel e, no segundo tempo, aproveitamos muito bem os espa\u00e7os deixados pelo goleiro-linha para ampliar a vantagem\u201d, avaliou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O treinador destaca que a equipe repete a dobradinha conquistada em 2025 e agradece o apoio recebido ao longo da temporada. \u201cEncerramos mais uma temporada conquistando os dois t\u00edtulos disputados, assim como no ano passado. Agrade\u00e7o aos jogadores, \u00e0 comiss\u00e3o t\u00e9cnica, \u00e0 torcida, aos patrocinadores e, em especial, \u00e0 Prefeitura de Westf\u00e1lia pelo apoio durante toda essa caminhada.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Torcida faz a diferen\u00e7a<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O capit\u00e3o da equipe e coordenador municipal de Esportes e Turismo, Roger Werkhausen, faz quest\u00e3o de agradecer o apoio da comunidade, que novamente compareceu em grande n\u00famero para incentivar a equipe. \u201cNossa torcida fez a diferen\u00e7a mais uma vez. Ela esteve conosco do in\u00edcio ao fim da competi\u00e7\u00e3o e foi fundamental para conquistarmos novamente a Copa Rota da Serra e a Ta\u00e7a dos Campe\u00f5es.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Werkhausen tamb\u00e9m destaca o planejamento para a pr\u00f3xima temporada e a expectativa pela conclus\u00e3o do novo gin\u00e1sio de Westf\u00e1lia. \u201cSe tudo acontecer como planejado, em 2027 teremos um novo gin\u00e1sio de esportes, o que representa um grande incentivo para todos. Vamos continuar formando uma equipe competitiva, renovando o plantel e oportunizando espa\u00e7o para novos atletas. O Campeonato Municipal continua sendo a principal vitrine para revelar novos talentos que passam a integrar nossas sele\u00e7\u00f5es.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/westfalia.rs.gov.br\/wp-content\/uploads\/2026\/07\/IMG_8550-JORNAL-1024x699.jpg\" alt=\"\" class=\"wp-image-9716\"\/><figcaption class=\"wp-element-caption\"><em>Westf\u00e1lia abriu o placar em cobran\u00e7a de falta no primeiro tempo, marcando mais tr\u00eas vezes no segundo tempo<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Orgulho para o munic\u00edpio<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O prefeito C\u00e9sar Juliano Bloemker acompanhou a decis\u00e3o em Salvador do Sul e comemorou mais uma conquista da sele\u00e7\u00e3o westfaliana. \u201cNossa equipe demonstrou ra\u00e7a, organiza\u00e7\u00e3o e muita determina\u00e7\u00e3o dentro de quadra, enquanto a torcida fez sua parte nas arquibancadas. \u00c9 motivo de muito orgulho ver Westf\u00e1lia conquistar mais um bicampeonato e coroar uma temporada extremamente positiva para o esporte do munic\u00edpio.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O prefeito tamb\u00e9m agradeceu a todos que contribu\u00edram para a campanha. \u201cParabenizo os atletas, a comiss\u00e3o t\u00e9cnica, a coordena\u00e7\u00e3o de esportes e cada torcedor que acreditou e apoiou a equipe durante toda essa caminhada. Essa conquista pertence a toda a comunidade de Westf\u00e1lia e demonstra o quanto o esporte do munic\u00edpio vem evoluindo a cada ano.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Sele\u00e7\u00e3o de Westf\u00e1lia voltou a levantar um trof\u00e9u regional. Na noite da \u00faltima sexta-feira, dia 10 de julho, a equipe conquistou o bicampeonato da Ta\u00e7a dos Campe\u00f5es, ao vencer Salvador do Sul por 4 a 0, fora de casa. Campe\u00e3 da 4\u00aa Copa Rota da Serra Sicoob de Futsal, Westf\u00e1lia enfrentou a sele\u00e7\u00e3o vencedora [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":216377,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,530],"tags":[20813,46,20855,25],"class_list":["post-216376","post","type-post","status-publish","format-standard","has-post-thumbnail","category-esportes","category-futsal","tag-7a-copa-transcitrus","tag-paverama","tag-rota-da-serra-sicoob","tag-westfalia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Sele\u00e7\u00e3o de Westf\u00e1lia voltou a levantar um trof\u00e9u regional. Na noite da \u00faltima sexta-feira, dia 10 de julho, a equipe conquistou o bicampeonato da Ta\u00e7a dos Campe\u00f5es, ao vencer Salvador do Sul por 4 a 0, fora de casa. Campe\u00e3 da 4\u00aa Copa Rota da Serra Sicoob de Futsal, Westf\u00e1lia enfrentou a sele\u00e7\u00e3o vencedora [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-13T22:57:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T23:27:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es\",\"datePublished\":\"2026-07-13T22:57:41+00:00\",\"dateModified\":\"2026-07-13T23:27:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/\"},\"wordCount\":712,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp\",\"keywords\":[\"7\u00aa Copa Transcitrus\",\"Paverama\",\"Rota da Serra Sicoob\",\"Westf\u00e1lia\"],\"articleSection\":[\"Esportes\",\"Futsal\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/\",\"name\":\"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp\",\"datePublished\":\"2026-07-13T22:57:41+00:00\",\"dateModified\":\"2026-07-13T23:27:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp\",\"width\":2048,\"height\":1536,\"caption\":\"Assim como em 2025, Westf\u00e1lia venceu a Ta\u00e7a dos Campe\u00f5es na categoria For\u00e7a Livre \\\/\\\/ Cr\u00e9dito: Leandro Hamester\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/13\\\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es - Folha Popular","og_description":"A Sele\u00e7\u00e3o de Westf\u00e1lia voltou a levantar um trof\u00e9u regional. Na noite da \u00faltima sexta-feira, dia 10 de julho, a equipe conquistou o bicampeonato da Ta\u00e7a dos Campe\u00f5es, ao vencer Salvador do Sul por 4 a 0, fora de casa. Campe\u00e3 da 4\u00aa Copa Rota da Serra Sicoob de Futsal, Westf\u00e1lia enfrentou a sele\u00e7\u00e3o vencedora [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/","og_site_name":"Folha Popular","article_published_time":"2026-07-13T22:57:41+00:00","article_modified_time":"2026-07-13T23:27:26+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es","datePublished":"2026-07-13T22:57:41+00:00","dateModified":"2026-07-13T23:27:26+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/"},"wordCount":712,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp","keywords":["7\u00aa Copa Transcitrus","Paverama","Rota da Serra Sicoob","Westf\u00e1lia"],"articleSection":["Esportes","Futsal"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/","name":"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp","datePublished":"2026-07-13T22:57:41+00:00","dateModified":"2026-07-13T23:27:26+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp","width":2048,"height":1536,"caption":"Assim como em 2025, Westf\u00e1lia venceu a Ta\u00e7a dos Campe\u00f5es na categoria For\u00e7a Livre \/\/ Cr\u00e9dito: Leandro Hamester"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/13\/westfalia-conquista-o-bicampeonato-da-taca-dos-campeoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Westf\u00e1lia conquista o bicampeonato da Ta\u00e7a dos Campe\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/Assim-como-em-2025-Westfalia-venceu-a-Taca-dos-Campeoes-na-categoria-Forca-Livre_Leandro-Hamester.webp","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/216376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=216376"}],"version-history":[{"count":1,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/216376\/revisions"}],"predecessor-version":[{"id":216380,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/216376\/revisions\/216380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/216377"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=216376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=216376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=216376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}