{"id":216442,"date":"2026-07-15T07:16:02","date_gmt":"2026-07-15T10:16:02","guid":{"rendered":"https:\/\/folhapopular.info\/?p=216442"},"modified":"2026-07-15T07:16:05","modified_gmt":"2026-07-15T10:16:05","slug":"fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/","title":{"rendered":"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Prefeitura de Fazenda Vilanova formalizou nesta ter\u00e7a-feira (14\/7) \u00e0 tarde o termo de ced\u00eancia de uma \u00e1rea de 3,6 hectares para a instala\u00e7\u00e3o do complexo log\u00edstico e industrial da Diamond Construtora e Incorporadora. A cerim\u00f4nia ocorreu no gabinete do prefeito Amarildo Luis da Silva e representou mais um avan\u00e7o na implanta\u00e7\u00e3o de um dos maiores investimentos privados anunciados pelo munic\u00edpio nos \u00faltimos anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ato oficializou a concess\u00e3o de uso do terreno localizado \u00e0s margens da BR-386, no quil\u00f4metro 370. Em junho, o projeto de lei que autorizou a ced\u00eancia da \u00e1rea foi aprovado, por unanimidade, na C\u00e2mara de Vereadores. O empreendimento prev\u00ea investimentos de aproximadamente R$ 45 milh\u00f5es ao longo de 6 anos e faturamento estimado em R$ 62 milh\u00f5es no mesmo per\u00edodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prefeito de Fazenda Vilanova, Amarildo Luis da Silva afirma que a chegada da Diamond ao munic\u00edpio ter\u00e1 um efeito de atra\u00e7\u00e3o de novos investimentos para o munic\u00edpio. \u201cA log\u00edstica \u00e9 um grande diferencial do munic\u00edpio, mas ter a marca instalada \u00e0s margens da rodovia representa uma excelente vitrine para o empreendedor\u201d, destaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diretor da Diamond, Gustavo Schmidt afirma que o centro log\u00edstico da Diamond reunir\u00e1 f\u00e1brica de pr\u00e9-moldados, central de produ\u00e7\u00e3o de concreto, centro de distribui\u00e7\u00e3o e estrutura administrativa. \u201cFazenda Vilanova est\u00e1 em uma posi\u00e7\u00e3o estrat\u00e9gica para nossas opera\u00e7\u00f5es. A localiza\u00e7\u00e3o facilita o acesso a todas as regi\u00f5es em que atuamos\u201d, refor\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A implanta\u00e7\u00e3o ocorrer\u00e1 em tr\u00eas etapas. Nos dois primeiros anos est\u00e3o previstos investimentos de R$ 15 milh\u00f5es, com gera\u00e7\u00e3o de 30 a 50 empregos diretos. Entre o segundo e o quarto ano ser\u00e1 realizado novo aporte de R$ 15 milh\u00f5es, criando outras 10 a 20 vagas. A terceira fase, entre o quarto e o sexto ano, contempla mais R$ 15 milh\u00f5es em investimentos e a abertura de 20 a 30 postos de trabalho, totalizando entre 60 e 100 empregos diretos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Opera\u00e7\u00f5es centralizadas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m da estrutura industrial, a empresa pretende transferir gradualmente para Fazenda Vilanova setores como ferragem, serralheria, marmoraria e estoque de materiais. Em uma segunda fase, est\u00e1 prevista a implanta\u00e7\u00e3o de uma escola de qualifica\u00e7\u00e3o voltada \u00e0 forma\u00e7\u00e3o de m\u00e3o de obra para a constru\u00e7\u00e3o civil, considerada uma das principais demandas do setor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Schmidt, a nova estrutura permitir\u00e1 ampliar a capacidade operacional da empresa e dar suporte ao crescimento dos empreendimentos desenvolvidos no Vale do Taquari, Serra, Regi\u00e3o Metropolitana e Litoral Norte de Santa Catarina. \u201cEstamos organizando nossa opera\u00e7\u00e3o para sustentar um novo ciclo de expans\u00e3o. A ideia \u00e9 concentrar a produ\u00e7\u00e3o, ganhar efici\u00eancia log\u00edstica e preparar a empresa para novos investimentos\u201d, afirma.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-1024x768.webp\" alt=\"\" class=\"wp-image-216444\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-1024x768.webp 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-300x225.webp 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-768x576.webp 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-1536x1152.webp 1536w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-2048x1536.webp 2048w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-560x420.webp 560w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-80x60.webp 80w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-696x522.webp 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-1068x801.webp 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.27.14-1920x1440.webp 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Lideran\u00e7as municipais e dirigentes da Diamond prestigiaram o ato \/\/ Cr\u00e9dito: Anderson Lopes<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Fazenda Vilanova formalizou nesta ter\u00e7a-feira (14\/7) \u00e0 tarde o termo de ced\u00eancia de uma \u00e1rea de 3,6 hectares para a instala\u00e7\u00e3o do complexo log\u00edstico e industrial da Diamond Construtora e Incorporadora. A cerim\u00f4nia ocorreu no gabinete do prefeito Amarildo Luis da Silva e representou mais um avan\u00e7o na implanta\u00e7\u00e3o de um dos [&hellip;]<\/p>\n","protected":false},"author":771,"featured_media":216443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,10991,10993,12473],"tags":[19386,801],"class_list":["post-216442","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-economia","category-empreender","category-negocios","tag-diamond-construtora","tag-fazenda-vilanova","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Fazenda Vilanova formalizou nesta ter\u00e7a-feira (14\/7) \u00e0 tarde o termo de ced\u00eancia de uma \u00e1rea de 3,6 hectares para a instala\u00e7\u00e3o do complexo log\u00edstico e industrial da Diamond Construtora e Incorporadora. A cerim\u00f4nia ocorreu no gabinete do prefeito Amarildo Luis da Silva e representou mais um avan\u00e7o na implanta\u00e7\u00e3o de um dos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T10:16:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T10:16:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Thiago Maurique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thiago Maurique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/\"},\"author\":{\"name\":\"Thiago Maurique\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/da0b2794f793376cb5dd908e88ca6911\"},\"headline\":\"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond\",\"datePublished\":\"2026-07-15T10:16:02+00:00\",\"dateModified\":\"2026-07-15T10:16:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/\"},\"wordCount\":479,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp\",\"keywords\":[\"Diamond Construtora\",\"Fazenda Vilanova\"],\"articleSection\":[\"Destaques\",\"Economia\",\"Empreender\",\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/\",\"name\":\"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp\",\"datePublished\":\"2026-07-15T10:16:02+00:00\",\"dateModified\":\"2026-07-15T10:16:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/da0b2794f793376cb5dd908e88ca6911\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp\",\"width\":2560,\"height\":1476,\"caption\":\"Prefeito Amarildo da Silva e diretor Gustavo Schmidt assinaram o termo \\\/\\\/ Cr\u00e9dito: Anderson Lopes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/07\\\/15\\\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/da0b2794f793376cb5dd908e88ca6911\",\"name\":\"Thiago Maurique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/THIAGO-MAURIQUE-1-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/THIAGO-MAURIQUE-1-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/THIAGO-MAURIQUE-1-1.webp\",\"caption\":\"Thiago Maurique\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/thiago-maurique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/","og_locale":"pt_BR","og_type":"article","og_title":"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond - Folha Popular","og_description":"A Prefeitura de Fazenda Vilanova formalizou nesta ter\u00e7a-feira (14\/7) \u00e0 tarde o termo de ced\u00eancia de uma \u00e1rea de 3,6 hectares para a instala\u00e7\u00e3o do complexo log\u00edstico e industrial da Diamond Construtora e Incorporadora. A cerim\u00f4nia ocorreu no gabinete do prefeito Amarildo Luis da Silva e representou mais um avan\u00e7o na implanta\u00e7\u00e3o de um dos [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/","og_site_name":"Folha Popular","article_published_time":"2026-07-15T10:16:02+00:00","article_modified_time":"2026-07-15T10:16:05+00:00","og_image":[{"width":2560,"height":1476,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp","type":"image\/webp"}],"author":"Thiago Maurique","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Thiago Maurique","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/"},"author":{"name":"Thiago Maurique","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/da0b2794f793376cb5dd908e88ca6911"},"headline":"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond","datePublished":"2026-07-15T10:16:02+00:00","dateModified":"2026-07-15T10:16:05+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/"},"wordCount":479,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp","keywords":["Diamond Construtora","Fazenda Vilanova"],"articleSection":["Destaques","Economia","Empreender","Neg\u00f3cios"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/","name":"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp","datePublished":"2026-07-15T10:16:02+00:00","dateModified":"2026-07-15T10:16:05+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/da0b2794f793376cb5dd908e88ca6911"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp","width":2560,"height":1476,"caption":"Prefeito Amarildo da Silva e diretor Gustavo Schmidt assinaram o termo \/\/ Cr\u00e9dito: Anderson Lopes"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/07\/15\/fazenda-vilanova-formaliza-cessao-de-area-para-complexo-logistico-da-diamond\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Fazenda Vilanova formaliza cess\u00e3o de \u00e1rea para complexo log\u00edstico da Diamond"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/da0b2794f793376cb5dd908e88ca6911","name":"Thiago Maurique","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/THIAGO-MAURIQUE-1-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/THIAGO-MAURIQUE-1-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/THIAGO-MAURIQUE-1-1.webp","caption":"Thiago Maurique"},"url":"https:\/\/folhapopular.info\/index.php\/author\/thiago-maurique\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-17.31.42-scaled-e1784110466887.webp","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/216442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/771"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=216442"}],"version-history":[{"count":1,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/216442\/revisions"}],"predecessor-version":[{"id":216445,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/216442\/revisions\/216445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/216443"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=216442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=216442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=216442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}