{"id":220245,"date":"2026-09-02T09:00:00","date_gmt":"2026-09-02T12:00:00","guid":{"rendered":"https:\/\/folhapopular.info\/?p=220245"},"modified":"2026-09-02T16:38:56","modified_gmt":"2026-09-02T19:38:56","slug":"amnesia-eleitoral","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/","title":{"rendered":"Amn\u00e9sia Eleitoral"},"content":{"rendered":"<p>Voc\u00ea lembra em quem votou em 2022? Quem foram os candidatos que mereceram o seu voto? Se a resposta foi positiva, parab\u00e9ns, voc\u00ea faz parte do pequeno eleitorado brasileiro com mem\u00f3ria eleitoral. J\u00e1 o outro lado, dos que n\u00e3o recordam, \u00e9 bem maior. \u00c9 o que nos revela uma pesquisa do Datafolha, realizada em junho&#8230; <\/p>\n<div class=\"pmpro\">\n<div class=\"pmpro_card pmpro_content_message\">\n<div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular &#8211; Conte\u00fado Total Anual e Grupo Popular &#8211; Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div>\n<div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2026%2F09%2F02%2Famnesia-eleitoral%2F\">Acesse aqui<\/a><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea lembra em quem votou em 2022? Quem foram os candidatos que mereceram o seu voto? Se a resposta foi positiva, parab\u00e9ns, voc\u00ea faz parte do pequeno eleitorado brasileiro com mem\u00f3ria eleitoral. J\u00e1 o outro lado, dos que n\u00e3o recordam, \u00e9 bem maior. \u00c9 o que nos revela uma pesquisa do Datafolha, realizada em junho... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Este conte\u00fado \u00e9 apenas para associados Grupo Popular - Conte\u00fado Total Anual e Grupo Popular - Conte\u00fado Total Mensal. <br \/><a href=\"https:\/\/folhapopular.info\/wp-login.php?action=register\">Cadastre-se<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">J\u00e1 se associou? <a href=\"https:\/\/folhapopular.info\/wp-login.php?redirect_to=https%3A%2F%2Ffolhapopular.info%2Findex.php%2F2026%2F09%2F02%2Famnesia-eleitoral%2F\">Acesse aqui<\/a><\/div><\/div><\/div>","protected":false},"author":662,"featured_media":219084,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11078,5495],"tags":[3167,3559,21795,21794],"class_list":["post-220245","post","type-post","status-publish","format-standard","has-post-thumbnail","category-assinantes","category-colunistas","tag-eleicoes","tag-folha-popular","tag-mauricio-wermann","tag-observatorio-politico","pmpro-level-required","pmpro-level-2","pmpro-level-4","pmpro-level-5","pmpro-no-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amn\u00e9sia Eleitoral - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amn\u00e9sia Eleitoral - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea lembra em quem votou em 2022? Quem foram os candidatos que mereceram o seu voto? Se a resposta foi positiva, parab\u00e9ns, voc\u00ea faz parte do pequeno eleitorado brasileiro com mem\u00f3ria eleitoral. J\u00e1 o outro lado, dos que n\u00e3o recordam, \u00e9 bem maior. \u00c9 o que nos revela uma pesquisa do Datafolha, realizada em junho [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T19:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"745\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Maur\u00edcio Wermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maur\u00edcio Wermann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/\"},\"author\":{\"name\":\"Maur\u00edcio Wermann\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/00d897128b7c45f410893419a4a09e6d\"},\"headline\":\"Amn\u00e9sia Eleitoral\",\"datePublished\":\"2026-09-02T12:00:00+00:00\",\"dateModified\":\"2026-09-02T19:38:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/\"},\"wordCount\":414,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp\",\"keywords\":[\"Elei\u00e7\u00f5es\",\"Folha Popular\",\"Maur\u00edcio Wermann\",\"Observat\u00f3rio Pol\u00edtico\"],\"articleSection\":[\"Assinantes\",\"Colunistas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/\",\"name\":\"Amn\u00e9sia Eleitoral - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp\",\"datePublished\":\"2026-09-02T12:00:00+00:00\",\"dateModified\":\"2026-09-02T19:38:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/00d897128b7c45f410893419a4a09e6d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp\",\"width\":745,\"height\":530,\"caption\":\"Maur\u00edcio Wermann - Cientista pol\u00edtico \\\/ Cr\u00e9dito: Rafaela Dannebrock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2026\\\/09\\\/02\\\/amnesia-eleitoral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amn\u00e9sia Eleitoral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/00d897128b7c45f410893419a4a09e6d\",\"name\":\"Maur\u00edcio Wermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3478416d4c7b80060bbd1cb42ff29ae923a464eaf2b5b780c6e90890c774190b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3478416d4c7b80060bbd1cb42ff29ae923a464eaf2b5b780c6e90890c774190b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3478416d4c7b80060bbd1cb42ff29ae923a464eaf2b5b780c6e90890c774190b?s=96&d=mm&r=g\",\"caption\":\"Maur\u00edcio Wermann\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/mauricio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amn\u00e9sia Eleitoral - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/","og_locale":"pt_BR","og_type":"article","og_title":"Amn\u00e9sia Eleitoral - Folha Popular","og_description":"Voc\u00ea lembra em quem votou em 2022? Quem foram os candidatos que mereceram o seu voto? Se a resposta foi positiva, parab\u00e9ns, voc\u00ea faz parte do pequeno eleitorado brasileiro com mem\u00f3ria eleitoral. J\u00e1 o outro lado, dos que n\u00e3o recordam, \u00e9 bem maior. \u00c9 o que nos revela uma pesquisa do Datafolha, realizada em junho [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/","og_site_name":"Folha Popular","article_published_time":"2026-09-02T12:00:00+00:00","article_modified_time":"2026-09-02T19:38:56+00:00","og_image":[{"width":745,"height":530,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp","type":"image\/webp"}],"author":"Maur\u00edcio Wermann","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maur\u00edcio Wermann","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/"},"author":{"name":"Maur\u00edcio Wermann","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/00d897128b7c45f410893419a4a09e6d"},"headline":"Amn\u00e9sia Eleitoral","datePublished":"2026-09-02T12:00:00+00:00","dateModified":"2026-09-02T19:38:56+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/"},"wordCount":414,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp","keywords":["Elei\u00e7\u00f5es","Folha Popular","Maur\u00edcio Wermann","Observat\u00f3rio Pol\u00edtico"],"articleSection":["Assinantes","Colunistas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/","url":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/","name":"Amn\u00e9sia Eleitoral - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp","datePublished":"2026-09-02T12:00:00+00:00","dateModified":"2026-09-02T19:38:56+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/00d897128b7c45f410893419a4a09e6d"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp","width":745,"height":530,"caption":"Maur\u00edcio Wermann - Cientista pol\u00edtico \/ Cr\u00e9dito: Rafaela Dannebrock"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2026\/09\/02\/amnesia-eleitoral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Amn\u00e9sia Eleitoral"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/00d897128b7c45f410893419a4a09e6d","name":"Maur\u00edcio Wermann","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3478416d4c7b80060bbd1cb42ff29ae923a464eaf2b5b780c6e90890c774190b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3478416d4c7b80060bbd1cb42ff29ae923a464eaf2b5b780c6e90890c774190b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3478416d4c7b80060bbd1cb42ff29ae923a464eaf2b5b780c6e90890c774190b?s=96&d=mm&r=g","caption":"Maur\u00edcio Wermann"},"url":"https:\/\/folhapopular.info\/index.php\/author\/mauricio\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-19-at-10.57.33-e1787147959401.webp","_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/220245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/662"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=220245"}],"version-history":[{"count":2,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/220245\/revisions"}],"predecessor-version":[{"id":220268,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/220245\/revisions\/220268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/219084"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=220245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=220245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=220245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}