{"id":32607,"date":"2017-07-17T17:26:07","date_gmt":"2017-07-17T20:26:07","guid":{"rendered":"http:\/\/folhapopular.info\/?p=32607"},"modified":"2017-07-17T17:26:07","modified_gmt":"2017-07-17T20:26:07","slug":"quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/","title":{"rendered":"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado"},"content":{"rendered":"<p>Uma quadrilha foi presa pela Brigada Miliar e Pol\u00edcia Civil na manh\u00e3 desta segunda-feira (17\/07). Os bandidos tentaram assaltar uma joalheria localizada na esquina das ruas Padre Anchieta e J\u00falio de Castilhos, no Centro de Encantado. Tr\u00eas criminosos, armados com rev\u00f3lveres, invadiram o local por volta das 8h30min. Eles renderem os atendentes do estabelecimento e pediram joias e dinheiro. No momento da a\u00e7\u00e3o, dois policiais \u00e0 paisanas, um militar e um civil, impediram que os bandidos levassem os materiais. Foi registrada troca de tiros, mas nenhuma pessoa ficou ferida. Os tr\u00eas suspeitos foram presos e encaminhados para delegacia. Mais tarde, por volta das 11h, outros dois homens que teriam participa\u00e7\u00e3o na tentativa de assalto tamb\u00e9m foram presos. Todos foram encaminhados ao Pres\u00eddio Estadual de Encantado. Al\u00e9m dos bandidos, foram apreendidos tr\u00eas rev\u00f3lveres municiados, estojos deflagrados, toucas-ninja e um ve\u00edculo Clio com placas clonadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma quadrilha foi presa pela Brigada Miliar e Pol\u00edcia Civil na manh\u00e3 desta segunda-feira (17\/07). Os bandidos tentaram assaltar uma joalheria localizada na esquina das ruas Padre Anchieta e J\u00falio de Castilhos, no Centro de Encantado. Tr\u00eas criminosos, armados com rev\u00f3lveres, invadiram o local por volta das 8h30min. Eles renderem os atendentes do estabelecimento e [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":31970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[466,106,107,467,316],"class_list":["post-32607","post","type-post","status-publish","format-standard","has-post-thumbnail","category-seguranca","tag-encantado","tag-policia","tag-prisao","tag-quadrilha","tag-tentativa-de-assalto","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Uma quadrilha foi presa pela Brigada Miliar e Pol\u00edcia Civil na manh\u00e3 desta segunda-feira (17\/07). Os bandidos tentaram assaltar uma joalheria localizada na esquina das ruas Padre Anchieta e J\u00falio de Castilhos, no Centro de Encantado. Tr\u00eas criminosos, armados com rev\u00f3lveres, invadiram o local por volta das 8h30min. Eles renderem os atendentes do estabelecimento e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-17T20:26:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado\",\"datePublished\":\"2017-07-17T20:26:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/\"},\"wordCount\":166,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"keywords\":[\"Encantado\",\"Pol\u00edcia\",\"Pris\u00e3o\",\"Quadrilha\",\"Tentativa de assalto\"],\"articleSection\":[\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/\",\"name\":\"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"datePublished\":\"2017-07-17T20:26:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Pol\u00edcia_SITE-e1544690850833.jpg\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/07\\\/17\\\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/","og_locale":"pt_BR","og_type":"article","og_title":"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado - Folha Popular","og_description":"Uma quadrilha foi presa pela Brigada Miliar e Pol\u00edcia Civil na manh\u00e3 desta segunda-feira (17\/07). Os bandidos tentaram assaltar uma joalheria localizada na esquina das ruas Padre Anchieta e J\u00falio de Castilhos, no Centro de Encantado. Tr\u00eas criminosos, armados com rev\u00f3lveres, invadiram o local por volta das 8h30min. Eles renderem os atendentes do estabelecimento e [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/","og_site_name":"Folha Popular","article_published_time":"2017-07-17T20:26:07+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado","datePublished":"2017-07-17T20:26:07+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/"},"wordCount":166,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","keywords":["Encantado","Pol\u00edcia","Pris\u00e3o","Quadrilha","Tentativa de assalto"],"articleSection":["Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/","url":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/","name":"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","datePublished":"2017-07-17T20:26:07+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2017\/07\/17\/quadrilha-e-presa-apos-tentativa-de-assalto-em-joalheria-de-encantado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Quadrilha \u00e9 presa ap\u00f3s tentativa de assalto em joalheria de Encantado"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/07\/Pol\u00edcia_SITE-e1544690850833.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/32607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=32607"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/32607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/31970"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=32607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=32607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=32607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}