{"id":34614,"date":"2017-08-30T15:00:54","date_gmt":"2017-08-30T18:00:54","guid":{"rendered":"http:\/\/folhapopular.info\/?p=34614"},"modified":"2017-08-30T14:24:22","modified_gmt":"2017-08-30T17:24:22","slug":"feira-do-livro-2017-divulga-slogan-vencedor","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/","title":{"rendered":"Feira do Livro 2017 divulga slogan vencedor"},"content":{"rendered":"<p>A Feira do Livro de Garibaldi j\u00e1 possui seu slogan. Expressando a import\u00e2ncia da leitura e o tema do evento \u201cEncontro com as artes\u201d, a edi\u00e7\u00e3o de 2017 elegeu a frase \u201cLiberdade e arte sem censura libertam a cultura\u201d, de autoria de Pedro Baruffi Ferret, para divulgar e integrar o material gr\u00e1fico do evento. A feira ocorrer\u00e1 de 17 a\u00a022 de outubro, na Pra\u00e7a Loureiro da Silva.<\/p>\n<p>Pedro, de 14 anos, \u00e9 aluno da Escola Municipal de Ensino Fundamental Visconde de Cairu. Crit\u00e9rios como originalidade, criatividade, coer\u00eancia e coes\u00e3o de ideias, al\u00e9m de refletir o tema do evento, foram levados em considera\u00e7\u00e3o na an\u00e1lise. Durante o evento, haver\u00e1 a entrega do pr\u00eamio, um passeio de Maria Fuma\u00e7a com acompanhante e um vale-livro, ao vencedor.\u00a0\u00a0Em breve, a programa\u00e7\u00e3o da Feira ser\u00e1 divulgada.<\/p>\n<p>De acordo com o secret\u00e1rio de Turismo e Cultura, Paulo Salvi, a ideia \u00e9 que a comunidade abrace a Feira, dando vida ao evento. \u201cEstamos preparando uma feira que desperte a curiosidade nas crian\u00e7as e jovens, e que, ao mesmo tempo, atraia o p\u00fablico adulto com as op\u00e7\u00f5es de livreiros e com uma programa\u00e7\u00e3o para todas as idades. Queremos que a Pra\u00e7a seja sin\u00f4nimo de um local caloroso de cultura e lazer\u201d, define.<\/p>\n<p>A Feira do Livro \u00e9 uma promo\u00e7\u00e3o da Prefeitura Municipal, por meio da Secretaria Municipal de Turismo e Cultura e Biblioteca P\u00fablica Municipal Frei Miguel. A Secretaria Municipal de Educa\u00e7\u00e3o e o Conselho Municipal de Pol\u00edticas Culturais (Concult) apoiam o evento.\u00a0Mais informa\u00e7\u00f5es no telefone\u00a0(54) 3462 8235.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Feira do Livro de Garibaldi j\u00e1 possui seu slogan. Expressando a import\u00e2ncia da leitura e o tema do evento \u201cEncontro com as artes\u201d, a edi\u00e7\u00e3o de 2017 elegeu a frase \u201cLiberdade e arte sem censura libertam a cultura\u201d, de autoria de Pedro Baruffi Ferret, para divulgar e integrar o material gr\u00e1fico do evento. A [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":34615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[322,28],"class_list":["post-34614","post","type-post","status-publish","format-standard","has-post-thumbnail","category-inclusive","tag-feira-do-livro","tag-garibaldi","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feira do Livro 2017 divulga slogan vencedor - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feira do Livro 2017 divulga slogan vencedor - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"A Feira do Livro de Garibaldi j\u00e1 possui seu slogan. Expressando a import\u00e2ncia da leitura e o tema do evento \u201cEncontro com as artes\u201d, a edi\u00e7\u00e3o de 2017 elegeu a frase \u201cLiberdade e arte sem censura libertam a cultura\u201d, de autoria de Pedro Baruffi Ferret, para divulgar e integrar o material gr\u00e1fico do evento. A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-30T18:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/08\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Feira do Livro 2017 divulga slogan vencedor\",\"datePublished\":\"2017-08-30T18:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/\"},\"wordCount\":275,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg\",\"keywords\":[\"Feira do Livro\",\"Garibaldi\"],\"articleSection\":[\"Inclusive\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/\",\"name\":\"Feira do Livro 2017 divulga slogan vencedor - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg\",\"datePublished\":\"2017-08-30T18:00:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/08\\\/30\\\/feira-do-livro-2017-divulga-slogan-vencedor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feira do Livro 2017 divulga slogan vencedor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feira do Livro 2017 divulga slogan vencedor - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/","og_locale":"pt_BR","og_type":"article","og_title":"Feira do Livro 2017 divulga slogan vencedor - Folha Popular","og_description":"A Feira do Livro de Garibaldi j\u00e1 possui seu slogan. Expressando a import\u00e2ncia da leitura e o tema do evento \u201cEncontro com as artes\u201d, a edi\u00e7\u00e3o de 2017 elegeu a frase \u201cLiberdade e arte sem censura libertam a cultura\u201d, de autoria de Pedro Baruffi Ferret, para divulgar e integrar o material gr\u00e1fico do evento. A [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/","og_site_name":"Folha Popular","article_published_time":"2017-08-30T18:00:54+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/08\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Feira do Livro 2017 divulga slogan vencedor","datePublished":"2017-08-30T18:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/"},"wordCount":275,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/08\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg","keywords":["Feira do Livro","Garibaldi"],"articleSection":["Inclusive"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/","url":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/","name":"Feira do Livro 2017 divulga slogan vencedor - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/08\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg","datePublished":"2017-08-30T18:00:54+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/08\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/08\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2017\/08\/30\/feira-do-livro-2017-divulga-slogan-vencedor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Feira do Livro 2017 divulga slogan vencedor"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/08\/Slogan-escolhido-Cr\u00e9ditos-da-foto-Alexandra-Ungaratto-e1504113426583.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/34614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=34614"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/34614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/34615"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=34614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=34614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=34614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}