{"id":36722,"date":"2017-10-24T09:05:16","date_gmt":"2017-10-24T11:05:16","guid":{"rendered":"http:\/\/folhapopular.info\/?p=36722"},"modified":"2017-10-24T13:38:57","modified_gmt":"2017-10-24T15:38:57","slug":"bm-realiza-acao-e-prende-dois-em-paverama","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/","title":{"rendered":"BM prende dois indiv\u00edduos em Paverama"},"content":{"rendered":"<p>Duas pessoas foram presas em opera\u00e7\u00e3o da Brigada Militar\u00a0na manh\u00e3 desta ter\u00e7a-feira (24\/10) no Munic\u00edpio de Paverama. Os policiais militares tamb\u00e9m apreenderam armas, drogas, dinheiro e muni\u00e7\u00f5es em uma resid\u00eancia na localidade de Morro Bonito.<\/p>\n<p>O comandante do 40\u00ba BPM, major Marcelo de Abreu Fernandes, informa que est\u00e3o sendo feitas v\u00e1rios a\u00e7\u00f5es ostensivas e discretas h\u00e1 cerca de tr\u00eas semanas em Paverama. &#8220;Hoje pela manh\u00e3, os policiais visualizaram dois indiv\u00edduos com caracter\u00edsticas semelhantes a de indiv\u00edduos que trocaram tiros com policiais em Paverama&#8221;, explicou.<\/p>\n<p>A BM acompanhou os dois homens, que tentaram fugir. Ao serem abordados, com eles foram encontrados armas, drogas, dinheiro e muni\u00e7\u00f5es.\u00a0H\u00e1 possibilidade de serem autores e armas utilizadas nos crimes recentes cometidos em Paverama.<\/p>\n<p>Os indiv\u00edduos ser\u00e3o apresentados pela BM na Delegacia de Pol\u00edcia de Teut\u00f4nia, e os policiais de Paverama far\u00e3o o encaminhamento. A tend\u00eancia \u00e9 que sejam presos em flagrante.<\/p>\n<figure id=\"attachment_36723\" aria-describedby=\"caption-attachment-36723\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-36723\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-1024x576.jpeg\" alt=\"\" width=\"696\" height=\"392\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-1024x576.jpeg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-300x169.jpeg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-768x432.jpeg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-696x392.jpeg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37.jpeg 1032w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-746x420.jpeg 746w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-36723\" class=\"wp-caption-text\">A\u00e7\u00e3o da BM em Morro Bonito resultou em duas pris\u00f5es<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Duas pessoas foram presas em opera\u00e7\u00e3o da Brigada Militar\u00a0na manh\u00e3 desta ter\u00e7a-feira (24\/10) no Munic\u00edpio de Paverama. Os policiais militares tamb\u00e9m apreenderam armas, drogas, dinheiro e muni\u00e7\u00f5es em uma resid\u00eancia na localidade de Morro Bonito. O comandante do 40\u00ba BPM, major Marcelo de Abreu Fernandes, informa que est\u00e3o sendo feitas v\u00e1rios a\u00e7\u00f5es ostensivas e discretas [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":36724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3,7],"tags":[46,250,269],"class_list":["post-36722","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-geral","category-seguranca","tag-paverama","tag-prisoes","tag-seguranca-publica","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BM prende dois indiv\u00edduos em Paverama - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BM prende dois indiv\u00edduos em Paverama - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Duas pessoas foram presas em opera\u00e7\u00e3o da Brigada Militar\u00a0na manh\u00e3 desta ter\u00e7a-feira (24\/10) no Munic\u00edpio de Paverama. Os policiais militares tamb\u00e9m apreenderam armas, drogas, dinheiro e muni\u00e7\u00f5es em uma resid\u00eancia na localidade de Morro Bonito. O comandante do 40\u00ba BPM, major Marcelo de Abreu Fernandes, informa que est\u00e3o sendo feitas v\u00e1rios a\u00e7\u00f5es ostensivas e discretas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-24T11:05:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-24T15:38:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1251\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucas Leandro Brune\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Leandro Brune\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/\"},\"author\":{\"name\":\"Lucas Leandro Brune\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\"},\"headline\":\"BM prende dois indiv\u00edduos em Paverama\",\"datePublished\":\"2017-10-24T11:05:16+00:00\",\"dateModified\":\"2017-10-24T15:38:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/\"},\"wordCount\":191,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg\",\"keywords\":[\"Paverama\",\"Pris\u00f5es\",\"Seguran\u00e7a P\u00fablica\"],\"articleSection\":[\"Destaques\",\"Geral\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/\",\"name\":\"BM prende dois indiv\u00edduos em Paverama - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg\",\"datePublished\":\"2017-10-24T11:05:16+00:00\",\"dateModified\":\"2017-10-24T15:38:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg\",\"width\":1251,\"height\":646,\"caption\":\"Armas, muni\u00e7\u00f5es, drogas e dinheiro foram apreendidos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/bm-realiza-acao-e-prende-dois-em-paverama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BM prende dois indiv\u00edduos em Paverama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/533a15f60cd49e81ab3a90b4ca33cb36\",\"name\":\"Lucas Leandro Brune\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/LUCAS-1-1.webp\",\"caption\":\"Lucas Leandro Brune\"},\"description\":\"Jornalista Profissional Diplomado MTB\\\/RS 14.333\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/lucas-brune\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BM prende dois indiv\u00edduos em Paverama - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/","og_locale":"pt_BR","og_type":"article","og_title":"BM prende dois indiv\u00edduos em Paverama - Folha Popular","og_description":"Duas pessoas foram presas em opera\u00e7\u00e3o da Brigada Militar\u00a0na manh\u00e3 desta ter\u00e7a-feira (24\/10) no Munic\u00edpio de Paverama. Os policiais militares tamb\u00e9m apreenderam armas, drogas, dinheiro e muni\u00e7\u00f5es em uma resid\u00eancia na localidade de Morro Bonito. O comandante do 40\u00ba BPM, major Marcelo de Abreu Fernandes, informa que est\u00e3o sendo feitas v\u00e1rios a\u00e7\u00f5es ostensivas e discretas [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/","og_site_name":"Folha Popular","article_published_time":"2017-10-24T11:05:16+00:00","article_modified_time":"2017-10-24T15:38:57+00:00","og_image":[{"width":1251,"height":646,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg","type":"image\/jpeg"}],"author":"Lucas Leandro Brune","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lucas Leandro Brune","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/"},"author":{"name":"Lucas Leandro Brune","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36"},"headline":"BM prende dois indiv\u00edduos em Paverama","datePublished":"2017-10-24T11:05:16+00:00","dateModified":"2017-10-24T15:38:57+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/"},"wordCount":191,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg","keywords":["Paverama","Pris\u00f5es","Seguran\u00e7a P\u00fablica"],"articleSection":["Destaques","Geral","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/","url":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/","name":"BM prende dois indiv\u00edduos em Paverama - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg","datePublished":"2017-10-24T11:05:16+00:00","dateModified":"2017-10-24T15:38:57+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg","width":1251,"height":646,"caption":"Armas, muni\u00e7\u00f5es, drogas e dinheiro foram apreendidos"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/bm-realiza-acao-e-prende-dois-em-paverama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"BM prende dois indiv\u00edduos em Paverama"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/533a15f60cd49e81ab3a90b4ca33cb36","name":"Lucas Leandro Brune","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/LUCAS-1-1.webp","caption":"Lucas Leandro Brune"},"description":"Jornalista Profissional Diplomado MTB\/RS 14.333","url":"https:\/\/folhapopular.info\/index.php\/author\/lucas-brune\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-08.38.37-1-e1508859495772.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/36722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=36722"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/36722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/36724"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=36722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=36722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=36722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}