{"id":36776,"date":"2017-10-24T16:44:17","date_gmt":"2017-10-24T18:44:17","guid":{"rendered":"http:\/\/folhapopular.info\/?p=36776"},"modified":"2017-10-24T17:19:55","modified_gmt":"2017-10-24T19:19:55","slug":"homem-pede-carona-anuncia-assalto-em-fazenda-vilanova","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/","title":{"rendered":"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova"},"content":{"rendered":"<p>Um homem foi preso na tarde desta ter\u00e7a-feira (24\/10), pela Pol\u00edcia Civil em Fazenda Vilanova.\u00a0<span style=\"font-family: arial, sans-serif\">O suspeito ofereceu R$ 50,00 e pediu para um morador de Fazenda Vilanova lev\u00e1-lo de moto da Rodovi\u00e1ria do munic\u00edpio at\u00e9 o trevo da BR-386 com a ERS-128 (Via L\u00e1ctea), no acesso a Teut\u00f4nia. <\/span><\/p>\n<p><span style=\"font-family: arial, sans-serif\">Pr\u00f3ximo ao trevo, o caroneiro anunciou o assalto e agrediu o condutor com um capacete. Dois rapazes que conheciam a v\u00edtima perceberam a a\u00e7\u00e3o, interferiram e contiveram o assaltante at\u00e9 a chegada da pol\u00edcia. <\/span><\/p>\n<p><span style=\"font-family: arial, sans-serif\">Todos foram encaminhados para depoimento na Delegacia de Pol\u00edcia de Fazenda Vilanova onde a ocorr\u00eancia est\u00e1 sendo registrada. Em breve mais informa\u00e7\u00f5es. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem foi preso na tarde desta ter\u00e7a-feira (24\/10), pela Pol\u00edcia Civil em Fazenda Vilanova.\u00a0O suspeito ofereceu R$ 50,00 e pediu para um morador de Fazenda Vilanova lev\u00e1-lo de moto da Rodovi\u00e1ria do munic\u00edpio at\u00e9 o trevo da BR-386 com a ERS-128 (Via L\u00e1ctea), no acesso a Teut\u00f4nia. Pr\u00f3ximo ao trevo, o caroneiro anunciou o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":36777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,7],"tags":[429,801,106],"class_list":["post-36776","post","type-post","status-publish","format-standard","has-post-thumbnail","category-featured","category-seguranca","tag-assalto","tag-fazenda-vilanova","tag-policia","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Um homem foi preso na tarde desta ter\u00e7a-feira (24\/10), pela Pol\u00edcia Civil em Fazenda Vilanova.\u00a0O suspeito ofereceu R$ 50,00 e pediu para um morador de Fazenda Vilanova lev\u00e1-lo de moto da Rodovi\u00e1ria do munic\u00edpio at\u00e9 o trevo da BR-386 com a ERS-128 (Via L\u00e1ctea), no acesso a Teut\u00f4nia. Pr\u00f3ximo ao trevo, o caroneiro anunciou o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-24T18:44:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-24T19:19:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova\",\"datePublished\":\"2017-10-24T18:44:17+00:00\",\"dateModified\":\"2017-10-24T19:19:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/\"},\"wordCount\":127,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg\",\"keywords\":[\"Assalto\",\"Fazenda Vilanova\",\"Pol\u00edcia\"],\"articleSection\":[\"Destaques\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/\",\"name\":\"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg\",\"datePublished\":\"2017-10-24T18:44:17+00:00\",\"dateModified\":\"2017-10-24T19:19:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg\",\"width\":200,\"height\":414,\"caption\":\"Homem foi preso pela Pol\u00edcia Civil e conduzido \u00e0 Delegacia \\\/ Cr\u00e9dito da foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/10\\\/24\\\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/","og_locale":"pt_BR","og_type":"article","og_title":"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova - Folha Popular","og_description":"Um homem foi preso na tarde desta ter\u00e7a-feira (24\/10), pela Pol\u00edcia Civil em Fazenda Vilanova.\u00a0O suspeito ofereceu R$ 50,00 e pediu para um morador de Fazenda Vilanova lev\u00e1-lo de moto da Rodovi\u00e1ria do munic\u00edpio at\u00e9 o trevo da BR-386 com a ERS-128 (Via L\u00e1ctea), no acesso a Teut\u00f4nia. Pr\u00f3ximo ao trevo, o caroneiro anunciou o [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/","og_site_name":"Folha Popular","article_published_time":"2017-10-24T18:44:17+00:00","article_modified_time":"2017-10-24T19:19:55+00:00","og_image":[{"width":200,"height":414,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova","datePublished":"2017-10-24T18:44:17+00:00","dateModified":"2017-10-24T19:19:55+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/"},"wordCount":127,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg","keywords":["Assalto","Fazenda Vilanova","Pol\u00edcia"],"articleSection":["Destaques","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/","url":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/","name":"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg","datePublished":"2017-10-24T18:44:17+00:00","dateModified":"2017-10-24T19:19:55+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg","width":200,"height":414,"caption":"Homem foi preso pela Pol\u00edcia Civil e conduzido \u00e0 Delegacia \/ Cr\u00e9dito da foto: Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2017\/10\/24\/homem-pede-carona-anuncia-assalto-em-fazenda-vilanova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Homem pede carona, anuncia assalto e \u00e9 preso em Fazenda Vilanova"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/10\/WhatsApp-Image-2017-10-24-at-16.29.21-e1508870784325.jpeg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/36776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=36776"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/36776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/36777"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=36776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=36776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=36776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}