{"id":37426,"date":"2017-11-11T11:00:02","date_gmt":"2017-11-11T13:00:02","guid":{"rendered":"http:\/\/folhapopular.info\/?p=37426"},"modified":"2017-11-10T14:37:46","modified_gmt":"2017-11-10T16:37:46","slug":"sobe-demanda-por-carteiras-de-identidade-em-estrela","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/","title":{"rendered":"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0"},"content":{"rendered":"<p>Em 2017, j\u00e1 foram confeccionadas 1.057 carteiras de identidade na unidade do Poupa Tempo, servi\u00e7o disponibilizado pelo Governo de Estrela que tem por objetivo tornar mais f\u00e1cil a vida do cidad\u00e3o. Na manh\u00e3 desta sexta-feira (10), a 1.058\u00aa e 1.059\u00aa unidades do Registro Geral (RG), como tamb\u00e9m \u00e9 conhecido o documento, foram as solicitadas pelos irm\u00e3os Gabriel (9) e Micael (7) da Silva Gamb\u00e1. Acompanhados da m\u00e3e, Michele, os meninos do Bairro Boa Uni\u00e3o foram encaminhar o documento para realizarem a matr\u00edcula na rede de educa\u00e7\u00e3o, um dos motivos que deve fazer com que a demanda cres\u00e7a nos pr\u00f3ximos dias. O Poupa Tempo funciona na Rua 13 de Maio, n\u00ba 261, ao lado do pr\u00e9dio da Prefeitura de Estrela. O hor\u00e1rio \u00e9 das 8h \u00e0s 14h, sem fechar ao meio-dia. Informa\u00e7\u00f5es pelo telefone 3190-1253.<\/p>\n<p>Segundo Rafael Jair Gon\u00e7alves, servidor do setor respons\u00e1vel pela opera\u00e7\u00e3o, com a chegada das f\u00e9rias estudantis e maior contrata\u00e7\u00e3o de pessoas por parte do com\u00e9rcio, a procura pelo servi\u00e7o deve crescer nos pr\u00f3ximos dias. \u201cO movimento j\u00e1 foi um pouco maior nos \u00faltimos dias. Temos hoje uma m\u00e9dia de cem unidades por m\u00eas. N\u00famero que sempre tende a aumentar nesta \u00e9poca do ano, quando as pessoas aproveitam o per\u00edodo de f\u00e9rias para encaminhar uma nova carteira, ou a primeira dos filhos\u201d, diz. Foi o caso dos irm\u00e3os Gabriel e Micael. O ca\u00e7ula assinou seu nome com todo cuidado. J\u00e1 Gabriel achou engra\u00e7ado coletar as digitais. Quando questionado se havia gostado da sua foto 3&#215;4, sempre um trauma para muita gente no RG, analisou. \u201cAcho que est\u00e1 bonita.\u201d<\/p>\n<p><strong>Documentos necess\u00e1rios<\/strong><\/p>\n<p>Para a confec\u00e7\u00e3o do RG, \u00e9 necess\u00e1rio levar: foto 3&#215;4; CPF e Certid\u00e3o de Nascimento\u00a0original\u00a0(se solteiro); Certid\u00e3o Casamento\u00a0original\u00a0(no caso de uni\u00e3o civil); Certid\u00e3o de Casamento\u00a0original\u00a0com averba\u00e7\u00e3o do div\u00f3rcio (caso divorciado). Em caso de menores de 16 anos, estes devem estar acompanhados de respons\u00e1veis, como pais ou av\u00f3s, guardi\u00e3o, tutor ou curador, estando estes com posse do seu RG. A primeira emiss\u00e3o \u00e9 isenta de taxa. A segunda via tem uma taxa de R$ 64. A confec\u00e7\u00e3o das carteiras de identidade estar\u00e1 suspensa entre os dias 26 de dezembro e nove de janeiro, em virtude das f\u00e9rias do servidor respons\u00e1vel. A entrega das carteiras confeccionadas no per\u00edodo anterior a este leva 35 dias em m\u00e9dia para ser entregue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 2017, j\u00e1 foram confeccionadas 1.057 carteiras de identidade na unidade do Poupa Tempo, servi\u00e7o disponibilizado pelo Governo de Estrela que tem por objetivo tornar mais f\u00e1cil a vida do cidad\u00e3o. Na manh\u00e3 desta sexta-feira (10), a 1.058\u00aa e 1.059\u00aa unidades do Registro Geral (RG), como tamb\u00e9m \u00e9 conhecido o documento, foram as solicitadas pelos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":37427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[1454,1453,8,1455,1452],"class_list":["post-37426","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geral","tag-carteira-de-identidade","tag-documentos","tag-estrela","tag-poupa-tempo","tag-rg","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0 - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0 - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Em 2017, j\u00e1 foram confeccionadas 1.057 carteiras de identidade na unidade do Poupa Tempo, servi\u00e7o disponibilizado pelo Governo de Estrela que tem por objetivo tornar mais f\u00e1cil a vida do cidad\u00e3o. Na manh\u00e3 desta sexta-feira (10), a 1.058\u00aa e 1.059\u00aa unidades do Registro Geral (RG), como tamb\u00e9m \u00e9 conhecido o documento, foram as solicitadas pelos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-11T13:00:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/11\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0\",\"datePublished\":\"2017-11-11T13:00:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/\"},\"wordCount\":425,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg\",\"keywords\":[\"Carteira de Identidade\",\"Documentos\",\"Estrela\",\"Poupa Tempo\",\"RG\"],\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/\",\"name\":\"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0 - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg\",\"datePublished\":\"2017-11-11T13:00:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg\",\"width\":1000,\"height\":563,\"caption\":\"Gabriel achou divertido coletar as digitais\\\/Cr\u00e9dito da foto: Rodrigo Angeli\\\/Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/11\\\/11\\\/sobe-demanda-por-carteiras-de-identidade-em-estrela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0 - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/","og_locale":"pt_BR","og_type":"article","og_title":"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0 - Folha Popular","og_description":"Em 2017, j\u00e1 foram confeccionadas 1.057 carteiras de identidade na unidade do Poupa Tempo, servi\u00e7o disponibilizado pelo Governo de Estrela que tem por objetivo tornar mais f\u00e1cil a vida do cidad\u00e3o. Na manh\u00e3 desta sexta-feira (10), a 1.058\u00aa e 1.059\u00aa unidades do Registro Geral (RG), como tamb\u00e9m \u00e9 conhecido o documento, foram as solicitadas pelos [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/","og_site_name":"Folha Popular","article_published_time":"2017-11-11T13:00:02+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/11\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0","datePublished":"2017-11-11T13:00:02+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/"},"wordCount":425,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/11\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg","keywords":["Carteira de Identidade","Documentos","Estrela","Poupa Tempo","RG"],"articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/","url":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/","name":"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0 - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/11\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg","datePublished":"2017-11-11T13:00:02+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/11\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/11\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg","width":1000,"height":563,"caption":"Gabriel achou divertido coletar as digitais\/Cr\u00e9dito da foto: Rodrigo Angeli\/Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2017\/11\/11\/sobe-demanda-por-carteiras-de-identidade-em-estrela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Sobe demanda por Carteiras de Identidade em Estrela\u00a0\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/11\/Carteira-de-Identidade-Gabriel-e1510331806686.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/37426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=37426"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/37426\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/37427"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=37426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=37426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=37426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}