{"id":38437,"date":"2017-12-08T15:00:00","date_gmt":"2017-12-08T17:00:00","guid":{"rendered":"http:\/\/folhapopular.info\/?p=38437"},"modified":"2017-12-08T15:36:10","modified_gmt":"2017-12-08T17:36:10","slug":"obras-no-loteamento-morada-novo-paraiso-avancam","status":"publish","type":"post","link":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/","title":{"rendered":"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela"},"content":{"rendered":"<p>Quarenta dias depois de ser lan\u00e7ado oficialmente, as obras no Morada Novo Para\u00edso, novo empreendimento habitacional de Estrela, avan\u00e7am em ritmo acelerado. A avalia\u00e7\u00e3o \u00e9 do vice-prefeito Valmor Griebeler e do secret\u00e1rio da pasta do Desenvolvimento Social, Trabalho e Habita\u00e7\u00e3o (Sedesth), Jos\u00e9 Itamar Alves, ap\u00f3s visita ao local realizada nesta quinta-feira (07\/12). Localizado junto ao Nova Morada I e II, ser\u00e3o 126 moradias dispon\u00edveis, em mais uma oportunidade que o Governo de Estrela, em parceria com a Uni\u00e3o, d\u00e1 para fam\u00edlias estrelenses de baixa renda adquirirem sua casa pr\u00f3pria. Dependendo do interesse, poder\u00e3o ser constru\u00eddas mais 20 casas.<\/p>\n<p>Os primeiros 14 blocos, com duas casas geminadas cada, come\u00e7am a ser erguidos. A previs\u00e3o \u00e9 de que as primeiras 28 casas estejam com alvenaria levantada e cobertura pronta at\u00e9 a virada do ano, restando depois os acabamentos. O projeto \u00e9 da empresa Tercon Terraplenagem e Constru\u00e7\u00f5es Ltda., em parceria com o Governo de Estrela, e ser\u00e1 financiado pela Caixa Econ\u00f4mica Federal, por meio do Programa Minha Casa, Minha Vida. O valor dos im\u00f3veis \u00e9 de R$ 80 mil, com subs\u00eddio de at\u00e9 R$ 12.665,00 e prazo de 30 anos pra pagar. As presta\u00e7\u00f5es variam de R$ 360,00 a R$ 460,00. \u201cExemplo de como Estrela cresce, avan\u00e7a em todas as \u00e1reas, e est\u00e1 tamb\u00e9m oportunizando o crescimento para seus cidad\u00e3os, para o bem estar de suas fam\u00edlias\u201d, avalia Griebeler.<\/p>\n<p>Conforme o engenheiro Fernando Machado, da Tercon, os im\u00f3veis ter\u00e3o 46 metros quadrados e possuem alguns diferenciais em rela\u00e7\u00e3o ao Nova Morada. Neste, os interessados poder\u00e3o escolher o terreno de sua casa \u2013 no Nova Morada foi sorteio \u2013 as esquadrias ser\u00e3o de madeira, o que acresce valor ao im\u00f3vel, e a \u00e1rea de servi\u00e7o ser\u00e1 na parte interna, integrada com a cozinha. O engenheiro da Tercon explica que a constru\u00e7\u00e3o das unidades ser\u00e1 feita por m\u00f3dulos, de acordo com a implanta\u00e7\u00e3o da infraestrutura, pois todas as ruas ser\u00e3o pavimentadas e receber\u00e3o saneamento, passeio p\u00fablico e sinaliza\u00e7\u00e3o. A previs\u00e3o \u00e9 de que estas obras, sob responsabilidade da prefeitura \u2013 parceira no empreendimento \u2013 sejam feitas gradativamente com o avan\u00e7o das constru\u00e7\u00f5es. Segundo ele, assim que uma rua estiver conclu\u00edda, come\u00e7a a constru\u00e7\u00e3o das casas. A previs\u00e3o de entrega do loteamento completo \u00e9 de 18 meses.<\/p>\n<figure id=\"attachment_38439\" aria-describedby=\"caption-attachment-38439\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38439 size-large\" src=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-8-1024x683.jpg\" alt=\"\" width=\"696\" height=\"464\" srcset=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-8-1024x683.jpg 1024w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-8-300x200.jpg 300w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-8-768x512.jpg 768w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-8-696x464.jpg 696w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-8-1068x712.jpg 1068w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-8-630x420.jpg 630w, https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-8-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-38439\" class=\"wp-caption-text\">Casas ter\u00e3o alguns diferenciais em rela\u00e7\u00e3o \u00e0s primeiras constru\u00eddas no Nova Morada I e II\/Cr\u00e9dito da foto: Rodrigo Angeli\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p><strong>J\u00e1 aprovadas<\/strong><\/p>\n<p>No dia 27 de outubro o projeto foi apresentado \u00e0s fam\u00edlias interessadas, sendo que algumas j\u00e1 tiveram a an\u00e1lise de cr\u00e9dito aprovada pela institui\u00e7\u00e3o financeira federal. Conforme Alves, desde ent\u00e3o 52 fam\u00edlias j\u00e1 tiveram cadastro aprovado. Outras 12 est\u00e3o em adiantada fase de avalia\u00e7\u00e3o. \u201cMuitas fam\u00edlias que n\u00e3o foram beneficiadas antes, pois n\u00e3o havia unidades para todos, afinal a procura foi grande, poder\u00e3o ser beneficiadas agora. Muitas que viram a qualidade da obra, a beleza do lugar, e agora desejam morar perto de familiares e amigos que aqui j\u00e1 est\u00e3o\u201d, destaca o secret\u00e1rio.<\/p>\n<p>Este \u00e9 o segundo projeto habitacional do governo do prefeito Rafael Mallmann e do vice-prefeito Valmor Griebeler, que est\u00e3o em sua segunda gest\u00e3o. No final de 2016 foram entregues aos contemplados as 250 moradias do conjunto habitacional Nova Morada I e II, tamb\u00e9m constru\u00eddo por meio do programa Minha Casa, Minha Vida. \u201cTrata-se de uma grande oportunidade de muitas fam\u00edlias, em condi\u00e7\u00f5es especiais, realizarem uma importante conquista, melhorarem suas condi\u00e7\u00f5es de vida, bem-estar. Mesmo em um ano de muitas crises, dificuldades para quase todos, o Governo de Estrela fecha o ano construindo, crescendo, e isso \u00e9 governar com gest\u00e3o\u201d, frisa Mallmann.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quarenta dias depois de ser lan\u00e7ado oficialmente, as obras no Morada Novo Para\u00edso, novo empreendimento habitacional de Estrela, avan\u00e7am em ritmo acelerado. A avalia\u00e7\u00e3o \u00e9 do vice-prefeito Valmor Griebeler e do secret\u00e1rio da pasta do Desenvolvimento Social, Trabalho e Habita\u00e7\u00e3o (Sedesth), Jos\u00e9 Itamar Alves, ap\u00f3s visita ao local realizada nesta quinta-feira (07\/12). Localizado junto ao [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":38438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[8,1334],"class_list":["post-38437","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geral","tag-estrela","tag-morada-novo-paraiso","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela - Folha Popular<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela - Folha Popular\" \/>\n<meta property=\"og:description\" content=\"Quarenta dias depois de ser lan\u00e7ado oficialmente, as obras no Morada Novo Para\u00edso, novo empreendimento habitacional de Estrela, avan\u00e7am em ritmo acelerado. A avalia\u00e7\u00e3o \u00e9 do vice-prefeito Valmor Griebeler e do secret\u00e1rio da pasta do Desenvolvimento Social, Trabalho e Habita\u00e7\u00e3o (Sedesth), Jos\u00e9 Itamar Alves, ap\u00f3s visita ao local realizada nesta quinta-feira (07\/12). Localizado junto ao [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha Popular\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-08T17:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-08T17:36:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Folha Popular\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"headline\":\"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela\",\"datePublished\":\"2017-12-08T17:00:00+00:00\",\"dateModified\":\"2017-12-08T17:36:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/\"},\"wordCount\":651,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4.jpg\",\"keywords\":[\"Estrela\",\"Morada Novo Para\u00edso\"],\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/\",\"name\":\"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela - Folha Popular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4.jpg\",\"datePublished\":\"2017-12-08T17:00:00+00:00\",\"dateModified\":\"2017-12-08T17:36:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4.jpg\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4.jpg\",\"width\":2592,\"height\":1728,\"caption\":\"Primeiros blocos come\u00e7am a tomar forma\\\/Cr\u00e9dito da foto: Rodrigo Angeli\\\/Divulga\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/2017\\\/12\\\/08\\\/obras-no-loteamento-morada-novo-paraiso-avancam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhapopular.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#website\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/\",\"name\":\"Folha Popular\",\"description\":\"Onde voc\u00ea tem vez e voz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhapopular.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/#\\\/schema\\\/person\\\/2814e8a0df7643585a9ca38bc6eb9d4b\",\"name\":\"Reda\u00e7\u00e3o Folha Popular\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"url\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"contentUrl\":\"https:\\\/\\\/folhapopular.info\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Folha-1.webp\",\"caption\":\"Reda\u00e7\u00e3o Folha Popular\"},\"url\":\"https:\\\/\\\/folhapopular.info\\\/index.php\\\/author\\\/redacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela - Folha Popular","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/","og_locale":"pt_BR","og_type":"article","og_title":"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela - Folha Popular","og_description":"Quarenta dias depois de ser lan\u00e7ado oficialmente, as obras no Morada Novo Para\u00edso, novo empreendimento habitacional de Estrela, avan\u00e7am em ritmo acelerado. A avalia\u00e7\u00e3o \u00e9 do vice-prefeito Valmor Griebeler e do secret\u00e1rio da pasta do Desenvolvimento Social, Trabalho e Habita\u00e7\u00e3o (Sedesth), Jos\u00e9 Itamar Alves, ap\u00f3s visita ao local realizada nesta quinta-feira (07\/12). Localizado junto ao [&hellip;]","og_url":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/","og_site_name":"Folha Popular","article_published_time":"2017-12-08T17:00:00+00:00","article_modified_time":"2017-12-08T17:36:10+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4-1024x683.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Folha Popular","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Folha Popular","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/#article","isPartOf":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/"},"author":{"name":"Reda\u00e7\u00e3o Folha Popular","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"headline":"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela","datePublished":"2017-12-08T17:00:00+00:00","dateModified":"2017-12-08T17:36:10+00:00","mainEntityOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/"},"wordCount":651,"commentCount":0,"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4.jpg","keywords":["Estrela","Morada Novo Para\u00edso"],"articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/","url":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/","name":"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela - Folha Popular","isPartOf":{"@id":"https:\/\/folhapopular.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/#primaryimage"},"image":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/#primaryimage"},"thumbnailUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4.jpg","datePublished":"2017-12-08T17:00:00+00:00","dateModified":"2017-12-08T17:36:10+00:00","author":{"@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b"},"breadcrumb":{"@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/#primaryimage","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4.jpg","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4.jpg","width":2592,"height":1728,"caption":"Primeiros blocos come\u00e7am a tomar forma\/Cr\u00e9dito da foto: Rodrigo Angeli\/Divulga\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhapopular.info\/index.php\/2017\/12\/08\/obras-no-loteamento-morada-novo-paraiso-avancam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhapopular.info\/"},{"@type":"ListItem","position":2,"name":"Obras no loteamento Morada Novo Para\u00edso avan\u00e7am em Estrela"}]},{"@type":"WebSite","@id":"https:\/\/folhapopular.info\/#website","url":"https:\/\/folhapopular.info\/","name":"Folha Popular","description":"Onde voc\u00ea tem vez e voz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhapopular.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/folhapopular.info\/#\/schema\/person\/2814e8a0df7643585a9ca38bc6eb9d4b","name":"Reda\u00e7\u00e3o Folha Popular","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","contentUrl":"https:\/\/folhapopular.info\/wp-content\/uploads\/2026\/04\/Folha-1.webp","caption":"Reda\u00e7\u00e3o Folha Popular"},"url":"https:\/\/folhapopular.info\/index.php\/author\/redacao\/"}]}},"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/folhapopular.info\/wp-content\/uploads\/2017\/12\/Loteameno-Novo-Para\u00edso-constru\u00e7\u00e3o-dezembro-2017-Angeli-4.jpg","_links":{"self":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/38437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/comments?post=38437"}],"version-history":[{"count":0,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/posts\/38437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media\/38438"}],"wp:attachment":[{"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/media?parent=38437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/categories?post=38437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhapopular.info\/index.php\/wp-json\/wp\/v2\/tags?post=38437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}